{"id":1871,"count":1,"description":"","link":"https:\/\/ideastalento.com\/en\/category\/general\/","name":"General","slug":"general","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>General archivos - Ideas Talento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ideastalento.com\/en\/category\/general\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"General archivos - Ideas Talento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ideastalento.com\/en\/category\/general\/\" \/>\n<meta property=\"og:site_name\" content=\"Ideas Talento\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/04\/2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/ideastalento.com\/en\/category\/general\/\",\"url\":\"https:\/\/ideastalento.com\/en\/category\/general\/\",\"name\":\"General archivos - Ideas Talento\",\"isPartOf\":{\"@id\":\"https:\/\/ideastalento.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/ideastalento.com\/en\/category\/general\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ideastalento.com\/en\/category\/general\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ideastalento.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ideastalento.com\/en\/#website\",\"url\":\"https:\/\/ideastalento.com\/en\/\",\"name\":\"Ideas Talento\",\"description\":\"Especialistas en desarrollo humano y transformaci\u00f3n digital\",\"publisher\":{\"@id\":\"https:\/\/ideastalento.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ideastalento.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ideastalento.com\/en\/#organization\",\"name\":\"IdeasTALENTO\",\"url\":\"https:\/\/ideastalento.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ideastalento.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ideastalento.com\/wp-content\/uploads\/job-manager-uploads\/company_logo\/2021\/10\/ISOTIPO-ROJO-1.png\",\"contentUrl\":\"https:\/\/ideastalento.com\/wp-content\/uploads\/job-manager-uploads\/company_logo\/2021\/10\/ISOTIPO-ROJO-1.png\",\"width\":913,\"height\":897,\"caption\":\"IdeasTALENTO\"},\"image\":{\"@id\":\"https:\/\/ideastalento.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/m.facebook.com\/Ideastalento\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"General archivos - Ideas Talento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ideastalento.com\/en\/category\/general\/","og_locale":"en_US","og_type":"article","og_title":"General archivos - Ideas Talento","og_url":"https:\/\/ideastalento.com\/en\/category\/general\/","og_site_name":"Ideas Talento","og_image":[{"width":1200,"height":675,"url":"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/04\/2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ideastalento.com\/en\/category\/general\/","url":"https:\/\/ideastalento.com\/en\/category\/general\/","name":"General archivos - Ideas Talento","isPartOf":{"@id":"https:\/\/ideastalento.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ideastalento.com\/en\/category\/general\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ideastalento.com\/en\/category\/general\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ideastalento.com\/en\/"},{"@type":"ListItem","position":2,"name":"General"}]},{"@type":"WebSite","@id":"https:\/\/ideastalento.com\/en\/#website","url":"https:\/\/ideastalento.com\/en\/","name":"Ideas Talento","description":"Especialistas en desarrollo humano y transformaci\u00f3n digital","publisher":{"@id":"https:\/\/ideastalento.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ideastalento.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ideastalento.com\/en\/#organization","name":"IdeasTALENTO","url":"https:\/\/ideastalento.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ideastalento.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ideastalento.com\/wp-content\/uploads\/job-manager-uploads\/company_logo\/2021\/10\/ISOTIPO-ROJO-1.png","contentUrl":"https:\/\/ideastalento.com\/wp-content\/uploads\/job-manager-uploads\/company_logo\/2021\/10\/ISOTIPO-ROJO-1.png","width":913,"height":897,"caption":"IdeasTALENTO"},"image":{"@id":"https:\/\/ideastalento.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/Ideastalento\/"]}]}},"_links":{"self":[{"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/categories\/1871"}],"collection":[{"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/posts?categories=1871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}