{"id":8112,"date":"2022-01-05T00:30:11","date_gmt":"2022-01-05T00:30:11","guid":{"rendered":"https:\/\/ideastalento.com\/nuestros-servicios\/"},"modified":"2025-05-05T18:23:12","modified_gmt":"2025-05-05T18:23:12","slug":"our-services","status":"publish","type":"page","link":"https:\/\/ideastalento.com\/en\/our-services\/","title":{"rendered":"OUR SERVICES"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8112\" class=\"elementor elementor-8112 elementor-7970\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4589435 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4589435\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bec8d2f\" data-id=\"bec8d2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-944d20d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"944d20d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7ac734a\" data-id=\"7ac734a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a1993e elementor-widget elementor-widget-heading\" data-id=\"1a1993e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">OUR SERVICES<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-53914e6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"53914e6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-21016ed\" data-id=\"21016ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f807471 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"f807471\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"478\" height=\"476\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv1.png\" class=\"attachment-full size-full wp-image-7841\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv1.png 478w, https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv1-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv1-150x150.png 150w\" sizes=\"(max-width: 478px) 100vw, 478px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">TALENT MANAGEMENT<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-816abab\" data-id=\"816abab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7fcbb9 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"b7fcbb9\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"406\" height=\"407\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2025\/05\/payroll@4x.png\" class=\"attachment-full size-full wp-image-14227\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2025\/05\/payroll@4x.png 406w, https:\/\/ideastalento.com\/wp-content\/uploads\/2025\/05\/payroll@4x-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2025\/05\/payroll@4x-150x150.png 150w\" sizes=\"(max-width: 406px) 100vw, 406px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Executive Payroll Management<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-7834da9\" data-id=\"7834da9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a1e994 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"6a1e994\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"478\" height=\"475\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv2.png\" class=\"attachment-full size-full wp-image-7915\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv2.png 478w, https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv2-300x298.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv2-150x150.png 150w\" sizes=\"(max-width: 478px) 100vw, 478px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">CULTURAL TRANSFORMATION<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-70bf70c\" data-id=\"70bf70c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea52dfe elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"ea52dfe\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"478\" height=\"476\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv3.png\" class=\"attachment-full size-full wp-image-7917\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv3.png 478w, https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv3-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv3-150x150.png 150w\" sizes=\"(max-width: 478px) 100vw, 478px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">CHANGE MANAGEMENT<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-da79228\" data-id=\"da79228\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28956a3 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"28956a3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"478\" height=\"476\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv4.png\" class=\"attachment-full size-full wp-image-7919\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv4.png 478w, https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv4-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv4-150x150.png 150w\" sizes=\"(max-width: 478px) 100vw, 478px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">EXPERIENCE DESIGN<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f744200 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f744200\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-9ff8848\" data-id=\"9ff8848\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b464c6 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"5b464c6\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"477\" height=\"476\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv5.png\" class=\"attachment-full size-full wp-image-12327\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv5.png 477w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv5-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv5-150x150.png 150w\" sizes=\"(max-width: 477px) 100vw, 477px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">HEADHUNTING<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-6ca9b55\" data-id=\"6ca9b55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dadbe1d elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"dadbe1d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"476\" height=\"475\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv6.png\" class=\"attachment-full size-full wp-image-12329\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv6.png 476w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv6-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv6-150x150.png 150w\" sizes=\"(max-width: 476px) 100vw, 476px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">PSYCHOMETRIC ASSESSMENT<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a87d0e3\" data-id=\"a87d0e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62e7d22 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"62e7d22\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"476\" height=\"475\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv7.png\" class=\"attachment-full size-full wp-image-12331\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv7.png 476w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv7-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv7-150x150.png 150w\" sizes=\"(max-width: 476px) 100vw, 476px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ORGANIZATIONAL CLIMATE AND CULTURE ASSESSMENT<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e031d45\" data-id=\"e031d45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a4fddb elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"5a4fddb\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"477\" height=\"475\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv8.png\" class=\"attachment-full size-full wp-image-12333\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv8.png 477w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv8-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv8-150x150.png 150w\" sizes=\"(max-width: 477px) 100vw, 477px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">PROFESSIONAL COACHING<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-79ff6b8\" data-id=\"79ff6b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ee8135 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"8ee8135\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"477\" height=\"475\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv9-1.png\" class=\"attachment-full size-full wp-image-12335\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv9-1.png 477w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv9-1-300x300.png 300w, https:\/\/ideastalento.com\/wp-content\/uploads\/2024\/03\/srv9-1-150x150.png 150w\" sizes=\"(max-width: 477px) 100vw, 477px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Scalingsoft<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3954579 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3954579\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a938303\" data-id=\"a938303\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b4a4a9c elementor-section-height-min-height elementor-section-items-top elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default\" data-id=\"5b4a4a9c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5fb6fa\" data-id=\"a5fb6fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ef7aa27 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2ef7aa27\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-770ed4f7\" data-id=\"770ed4f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-617d67d3 elementor-widget elementor-widget-heading\" data-id=\"617d67d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HEADHUNTING & EXECUTIVE SEARCH<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71178070 elementor-widget elementor-widget-text-editor\" data-id=\"71178070\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>We believe talent makes a difference.<\/p><p>We use top-level local and international databases to help you find the best talent.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64e1ba4 elementor-section-height-min-height elementor-section-items-top elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default\" data-id=\"64e1ba4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f4374d\" data-id=\"8f4374d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e30b781 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e30b781\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e9cffd0\" data-id=\"e9cffd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4abebd elementor-widget elementor-widget-heading\" data-id=\"e4abebd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Executive Payroll Management:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-259cd65 elementor-widget elementor-widget-text-editor\" data-id=\"259cd65\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We offer comprehensive solutions for managing executive payroll, ensuring accuracy, legal compliance, and confidentiality. We take care of the details so you can focus on what matters most: your business.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f943d31 elementor-section-height-min-height elementor-section-items-top elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default\" data-id=\"5f943d31\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5275320d\" data-id=\"5275320d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50b08b3c elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"50b08b3c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-627f674d\" data-id=\"627f674d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17157b17 elementor-widget elementor-widget-text-editor\" data-id=\"17157b17\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Outplacement \/ Professional Coaching<\/p><p style=\"text-align: center;\"><strong>Reinvent Your Career.<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f603dad elementor-widget elementor-widget-text-editor\" data-id=\"4f603dad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Get ready to land your dream job:<\/strong><\/p><p style=\"text-align: center;\">know yourself, update your CV, and train for<br \/>an interview, unlocking your full potential<br \/>to find new opportunities.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33edd41e elementor-section-height-min-height elementor-section-items-top elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default\" data-id=\"33edd41e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f31fec4\" data-id=\"7f31fec4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-415731d0 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"415731d0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-56ce5ac6\" data-id=\"56ce5ac6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e090877 elementor-widget elementor-widget-heading\" data-id=\"4e090877\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TALENT MANAGEMENT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50473239 content-align-left icon-box-vertical-align-top icon-position-left icon-vertical-align-start elementor-widget elementor-widget-the7_icon_box_widget\" data-id=\"50473239\" data-element_type=\"widget\" data-widget_type=\"the7_icon_box_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"the7-box-wrapper the7-elementor-widget the7_icon_box_widget-50473239\">\t\t\t<div class=\"box-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-icon-div\" >\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"svg\" width=\"400\" height=\"392.9901423877327\" viewBox=\"0, 0, 400,392.9901423877327\"><g id=\"svgg\"><path id=\"path0\" d=\"M193.314 43.309 C 155.007 46.203,120.494 64.039,96.738 93.218 C 63.997 133.435,60.098 195.681,87.593 239.239 C 101.091 260.622,119.818 277.760,140.610 287.759 L 145.919 290.312 145.919 291.792 C 145.919 295.513,148.402 299.901,151.320 301.338 L 153.196 302.262 200.393 302.228 L 247.591 302.194 249.593 301.172 C 252.890 299.487,254.370 297.363,255.041 293.354 C 255.271 291.978,255.414 291.867,258.516 290.641 C 328.287 263.078,338.631 183.447,275.516 159.768 C 256.823 152.755,243.679 150.783,209.440 149.855 C 164.379 148.633,143.627 142.430,140.276 129.180 C 137.228 117.133,141.711 105.293,152.011 98.184 C 169.276 86.268,201.577 81.428,228.122 86.779 C 247.528 90.691,268.207 103.598,276.483 116.965 C 287.486 134.737,312.441 132.616,316.478 113.565 C 318.974 101.788,308.991 87.784,285.939 70.730 C 255.989 48.573,229.081 40.607,193.314 43.309 M123.012 166.263 C 140.965 181.228,163.506 186.888,205.703 187.026 C 224.731 187.088,226.988 187.241,240.708 189.388 C 279.914 195.525,290.904 214.942,268.035 237.671 C 224.252 281.187,139.987 265.243,117.384 209.166 C 111.200 193.823,108.954 172.543,111.943 157.611 C 112.160 156.525,112.175 156.533,115.373 159.546 C 117.139 161.211,120.577 164.233,123.012 166.263 M156.932 307.613 C 150.346 311.561,149.524 321.652,155.467 325.585 L 157.071 326.647 201.019 326.647 L 244.967 326.647 246.663 325.455 C 253.221 320.846,252.177 310.416,244.850 307.354 C 242.285 306.283,158.742 306.528,156.932 307.613 M163.516 332.724 C 157.360 336.628,157.289 347.240,163.394 351.019 C 165.262 352.175,165.493 352.216,170.765 352.340 L 176.208 352.469 177.358 354.140 C 187.438 368.792,216.115 368.604,224.773 353.830 L 225.837 352.016 231.247 352.016 C 236.571 352.016,236.681 351.998,238.205 350.894 C 244.474 346.353,245.358 338.771,240.174 334.011 C 237.376 331.442,239.336 331.563,200.838 331.563 L 165.346 331.563 163.516 332.724 \" stroke=\"none\" fill=\"#f42444\" fill-rule=\"evenodd\"><\/path><path id=\"path1\" d=\"M188.201 0.421 C 184.956 0.587,180.294 0.928,177.842 1.179 C 175.390 1.431,173.282 1.535,173.159 1.412 C 173.035 1.288,172.701 1.380,172.416 1.617 C 171.936 2.015,170.708 2.238,167.748 2.466 C 167.099 2.516,166.346 2.701,166.073 2.877 C 165.801 3.053,165.226 3.085,164.795 2.949 C 164.310 2.795,164.012 2.880,164.012 3.171 C 164.012 3.491,163.566 3.570,162.626 3.418 C 161.864 3.294,161.319 3.319,161.414 3.474 C 161.510 3.628,159.293 4.180,156.487 4.699 C 153.682 5.219,151.295 5.793,151.183 5.975 C 151.070 6.157,150.806 6.199,150.595 6.069 C 150.384 5.939,149.976 6.027,149.688 6.266 C 149.401 6.505,148.878 6.589,148.526 6.454 C 148.150 6.310,147.886 6.407,147.886 6.690 C 147.886 6.978,147.569 7.089,147.099 6.966 C 146.667 6.853,146.313 6.941,146.313 7.162 C 146.313 7.384,145.959 7.472,145.526 7.359 C 145.093 7.246,144.739 7.281,144.739 7.436 C 144.739 7.592,143.142 8.131,141.189 8.634 C 139.236 9.138,137.549 9.694,137.440 9.871 C 137.331 10.047,136.981 10.092,136.664 9.970 C 136.346 9.848,136.087 9.964,136.087 10.226 C 136.087 10.489,135.821 10.602,135.497 10.477 C 135.172 10.353,134.907 10.390,134.907 10.560 C 134.907 10.730,133.535 11.286,131.858 11.796 C 130.182 12.307,128.236 12.961,127.534 13.250 C 126.832 13.539,126.144 13.758,126.005 13.737 C 125.865 13.716,125.622 13.908,125.464 14.164 C 125.306 14.420,124.711 14.656,124.142 14.689 C 123.573 14.722,123.108 14.858,123.107 14.992 C 123.107 15.125,122.001 15.631,120.649 16.117 C 119.297 16.603,117.616 17.349,116.912 17.775 C 116.209 18.201,115.634 18.434,115.634 18.293 C 115.634 18.152,115.342 18.328,114.986 18.685 C 114.629 19.042,114.009 19.248,113.608 19.143 C 113.208 19.038,112.967 19.093,113.073 19.265 C 113.179 19.437,112.250 19.985,111.009 20.482 C 109.767 20.980,108.660 21.518,108.549 21.678 C 108.437 21.838,106.844 22.747,105.009 23.697 C 100.301 26.135,95.583 28.785,94.199 29.770 C 92.039 31.306,89.483 32.815,89.184 32.729 C 89.022 32.683,88.889 32.809,88.889 33.010 C 88.889 33.211,87.871 33.995,86.627 34.754 C 85.383 35.512,82.153 37.837,79.449 39.919 C 76.745 42.001,73.544 44.455,72.335 45.373 C 71.126 46.290,69.575 47.615,68.888 48.318 C 68.201 49.021,67.459 49.486,67.241 49.351 C 67.023 49.216,66.891 49.252,66.948 49.430 C 67.146 50.041,63.238 53.433,62.613 53.193 C 62.269 53.061,62.118 53.131,62.257 53.356 C 62.536 53.807,58.110 58.338,57.697 58.024 C 57.547 57.910,57.514 57.936,57.623 58.082 C 57.733 58.228,56.450 59.777,54.772 61.524 C 53.094 63.271,50.934 65.618,49.973 66.741 C 49.011 67.863,48.038 68.676,47.809 68.546 C 47.581 68.416,47.514 68.443,47.659 68.606 C 47.898 68.872,45.576 72.283,44.830 72.763 C 44.661 72.871,43.724 74.022,42.747 75.320 C 41.769 76.618,39.631 79.449,37.994 81.613 C 36.358 83.776,35.016 85.689,35.012 85.864 C 35.008 86.039,34.801 86.056,34.551 85.901 C 34.262 85.723,34.204 85.794,34.390 86.096 C 34.563 86.375,34.140 87.289,33.370 88.306 C 32.647 89.260,31.266 91.273,30.302 92.780 C 29.337 94.287,28.381 95.417,28.176 95.290 C 27.971 95.164,27.930 95.265,28.085 95.516 C 28.392 96.013,26.816 99.115,26.256 99.115 C 26.067 99.115,26.009 99.271,26.127 99.462 C 26.245 99.653,26.015 100.228,25.615 100.740 C 25.216 101.253,23.645 104.095,22.125 107.058 C 20.604 110.021,19.224 112.321,19.057 112.171 C 18.890 112.021,18.868 112.099,19.008 112.344 C 19.320 112.891,18.546 115.241,18.054 115.241 C 17.859 115.241,17.730 115.374,17.769 115.536 C 17.807 115.698,17.390 116.813,16.842 118.013 C 16.294 119.214,15.629 120.851,15.365 121.652 C 15.101 122.452,14.711 123.107,14.499 123.107 C 14.287 123.107,14.219 123.279,14.349 123.489 C 14.479 123.700,14.333 124.275,14.024 124.768 C 13.715 125.260,12.974 127.168,12.376 129.007 C 11.778 130.846,11.148 132.406,10.976 132.474 C 10.804 132.542,10.761 132.852,10.880 133.162 C 10.999 133.473,10.907 133.727,10.674 133.727 C 10.441 133.727,10.353 133.992,10.477 134.317 C 10.602 134.641,10.541 134.907,10.342 134.907 C 10.143 134.907,9.567 136.511,9.061 138.473 C 8.430 140.920,8.029 141.876,7.783 141.521 C 7.554 141.190,7.516 141.464,7.677 142.281 C 7.824 143.029,7.768 143.559,7.541 143.559 C 7.328 143.559,7.246 143.913,7.359 144.346 C 7.472 144.779,7.384 145.133,7.162 145.133 C 6.941 145.133,6.853 145.487,6.966 145.919 C 7.089 146.389,6.978 146.706,6.690 146.706 C 6.407 146.706,6.310 146.970,6.454 147.346 C 6.589 147.698,6.495 148.233,6.244 148.535 C 5.993 148.838,5.900 149.197,6.037 149.334 C 6.174 149.471,6.133 149.777,5.946 150.013 C 5.759 150.249,5.286 152.168,4.894 154.277 C 4.503 156.386,4.068 158.112,3.929 158.112 C 3.790 158.112,3.754 158.643,3.849 159.292 C 3.951 159.986,3.846 160.472,3.594 160.472 C 3.328 160.472,3.256 160.919,3.402 161.652 C 3.554 162.413,3.478 162.832,3.188 162.832 C 2.904 162.832,2.830 163.196,2.986 163.820 C 3.126 164.377,3.029 165.056,2.765 165.375 C 2.506 165.686,2.406 166.292,2.543 166.722 C 2.679 167.151,2.616 167.823,2.402 168.215 C 1.307 170.226,0.243 188.749,0.520 200.983 C 0.757 211.453,1.765 224.046,2.431 224.858 C 2.644 225.118,2.700 225.702,2.557 226.155 C 2.413 226.609,2.506 227.234,2.765 227.546 C 3.029 227.864,3.126 228.543,2.986 229.100 C 2.831 229.720,2.904 230.088,3.184 230.088 C 3.455 230.088,3.561 230.550,3.456 231.268 C 3.361 231.917,3.449 232.448,3.653 232.448 C 3.856 232.448,3.944 232.979,3.849 233.628 C 3.754 234.277,3.789 234.808,3.927 234.808 C 4.065 234.808,4.503 236.584,4.899 238.753 C 5.296 240.923,5.774 242.794,5.963 242.910 C 6.152 243.027,6.199 243.295,6.069 243.506 C 5.939 243.716,6.027 244.124,6.266 244.412 C 6.505 244.699,6.589 245.223,6.454 245.575 C 6.310 245.951,6.407 246.214,6.690 246.214 C 6.974 246.214,7.089 246.530,6.971 246.982 C 6.860 247.404,6.938 247.806,7.143 247.874 C 7.348 247.943,7.551 248.658,7.593 249.465 C 7.635 250.271,7.768 250.931,7.889 250.932 C 8.009 250.933,8.430 252.177,8.824 253.695 C 9.218 255.214,9.687 256.547,9.866 256.658 C 10.045 256.768,10.092 257.119,9.970 257.436 C 9.848 257.754,9.964 258.014,10.226 258.014 C 10.489 258.014,10.602 258.279,10.477 258.604 C 10.353 258.928,10.441 259.194,10.674 259.194 C 10.907 259.194,10.995 259.459,10.871 259.784 C 10.746 260.108,10.782 260.374,10.951 260.374 C 11.119 260.374,11.586 261.480,11.988 262.832 C 12.391 264.184,12.957 265.864,13.247 266.566 C 13.537 267.268,13.758 267.957,13.737 268.096 C 13.716 268.235,13.860 268.457,14.057 268.589 C 14.254 268.722,15.093 270.600,15.922 272.763 C 16.750 274.926,17.560 276.785,17.721 276.893 C 17.882 277.001,18.076 277.443,18.151 277.876 C 18.227 278.309,18.521 278.907,18.803 279.205 C 19.086 279.503,19.210 280.029,19.078 280.373 C 18.946 280.717,18.959 280.877,19.108 280.728 C 19.380 280.457,21.821 285.091,21.698 285.644 C 21.662 285.806,21.820 285.939,22.049 285.939 C 22.278 285.939,22.365 286.101,22.243 286.299 C 22.121 286.497,22.167 286.718,22.347 286.790 C 22.526 286.863,23.295 288.073,24.056 289.479 C 27.443 295.739,31.656 302.714,33.000 304.285 C 33.211 304.532,33.277 304.842,33.146 304.973 C 33.015 305.104,33.099 305.211,33.334 305.211 C 33.569 305.211,34.163 305.875,34.654 306.686 C 35.145 307.498,36.320 309.179,37.265 310.423 C 38.211 311.667,38.872 312.866,38.735 313.088 C 38.598 313.309,38.662 313.442,38.876 313.382 C 39.228 313.285,40.418 314.647,45.313 320.747 C 46.180 321.829,47.712 323.678,48.716 324.856 C 51.642 328.292,64.365 341.035,66.799 342.970 C 68.024 343.943,69.259 345.050,69.542 345.430 C 69.826 345.810,70.534 346.372,71.115 346.680 C 71.697 346.988,72.714 347.739,73.375 348.350 C 75.620 350.422,81.851 355.111,85.644 357.582 C 86.996 358.463,88.116 359.473,88.133 359.828 C 88.150 360.182,88.248 360.269,88.349 360.020 C 88.529 359.582,92.330 361.844,92.866 362.708 C 92.998 362.921,93.220 363.081,93.358 363.062 C 94.058 362.968,94.384 363.073,94.859 363.543 C 95.588 364.265,101.460 367.615,105.211 369.449 C 106.942 370.296,108.623 371.204,108.948 371.468 C 109.272 371.733,110.733 372.459,112.193 373.083 C 113.653 373.706,114.848 374.364,114.848 374.545 C 114.848 374.726,115.025 374.765,115.241 374.631 C 115.457 374.498,115.634 374.576,115.634 374.805 C 115.634 375.034,115.767 375.188,115.929 375.148 C 116.091 375.108,116.932 375.388,117.797 375.771 C 118.663 376.153,120.610 376.915,122.124 377.464 C 123.638 378.012,125.231 378.655,125.664 378.892 C 126.096 379.129,126.539 379.336,126.647 379.351 C 126.755 379.366,127.198 379.562,127.630 379.785 C 128.063 380.008,129.789 380.608,131.465 381.118 C 133.142 381.629,134.513 382.186,134.513 382.358 C 134.513 382.529,134.779 382.568,135.103 382.443 C 135.428 382.318,135.693 382.431,135.693 382.694 C 135.693 382.957,135.953 383.072,136.271 382.950 C 136.588 382.828,136.935 382.869,137.040 383.040 C 137.146 383.211,139.143 383.854,141.478 384.469 C 143.813 385.084,145.775 385.714,145.840 385.869 C 145.904 386.024,146.303 386.060,146.725 385.950 C 147.147 385.839,147.493 385.930,147.493 386.151 C 147.493 386.373,147.847 386.461,148.279 386.348 C 148.739 386.228,149.066 386.336,149.066 386.608 C 149.066 386.888,149.367 386.978,149.819 386.834 C 150.234 386.703,150.678 386.765,150.806 386.973 C 150.934 387.180,153.250 387.754,155.952 388.248 C 158.654 388.742,160.865 389.283,160.865 389.450 C 160.865 389.617,161.396 389.648,162.045 389.518 C 162.695 389.388,163.225 389.450,163.225 389.657 C 163.225 389.862,163.756 389.953,164.405 389.858 C 165.124 389.752,165.585 389.859,165.585 390.130 C 165.585 390.409,165.954 390.483,166.573 390.327 C 167.117 390.191,167.799 390.276,168.089 390.517 C 168.379 390.758,169.041 390.953,169.559 390.951 C 170.077 390.949,172.537 391.201,175.025 391.510 C 188.507 393.187,209.683 393.280,223.009 391.721 C 226.578 391.304,229.923 390.960,230.441 390.958 C 230.959 390.956,231.622 390.756,231.914 390.514 C 232.206 390.272,232.834 390.176,233.311 390.301 C 233.787 390.426,234.407 390.337,234.687 390.104 C 234.968 389.871,235.552 389.774,235.986 389.887 C 236.420 390.001,236.775 389.933,236.775 389.737 C 236.775 389.541,237.121 389.381,237.544 389.381 C 239.004 389.381,249.165 387.295,249.392 386.948 C 249.518 386.757,249.916 386.714,250.277 386.853 C 250.661 387.000,250.934 386.913,250.934 386.643 C 250.934 386.360,251.239 386.278,251.721 386.431 C 252.205 386.584,252.507 386.501,252.507 386.215 C 252.507 385.943,252.834 385.834,253.294 385.955 C 253.727 386.068,254.081 386.032,254.081 385.876 C 254.081 385.719,255.452 385.270,257.129 384.877 C 258.805 384.485,260.531 384.031,260.964 383.869 C 261.396 383.707,261.927 383.539,262.144 383.494 C 262.360 383.450,262.750 383.237,263.011 383.020 C 263.272 382.804,263.670 382.741,263.896 382.880 C 264.122 383.020,264.307 382.928,264.307 382.675 C 264.307 382.423,264.572 382.319,264.897 382.443 C 265.221 382.568,265.487 382.536,265.487 382.374 C 265.487 382.211,267.168 381.572,269.223 380.955 C 271.278 380.338,272.960 379.650,272.960 379.428 C 272.960 379.205,273.076 379.140,273.218 379.282 C 273.361 379.424,273.671 379.389,273.907 379.204 C 274.143 379.019,275.841 378.293,277.679 377.592 C 279.518 376.890,281.664 375.989,282.449 375.589 C 283.233 375.189,283.985 374.972,284.120 375.107 C 284.255 375.242,284.366 375.170,284.366 374.948 C 284.366 374.726,285.737 373.970,287.414 373.269 C 289.090 372.568,290.668 371.827,290.919 371.622 C 291.170 371.418,292.851 370.493,294.655 369.567 C 299.407 367.129,304.461 364.295,305.179 363.666 C 305.521 363.366,306.805 362.560,308.031 361.875 C 309.257 361.190,310.472 360.375,310.730 360.063 C 310.989 359.752,311.357 359.594,311.549 359.713 C 311.741 359.831,311.898 359.746,311.898 359.522 C 311.898 359.298,312.466 358.822,313.160 358.463 C 313.854 358.104,316.155 356.511,318.273 354.923 C 320.391 353.335,322.124 352.106,322.124 352.192 C 322.124 352.278,322.625 351.875,323.237 351.297 C 323.849 350.719,325.370 349.449,326.616 348.476 C 335.692 341.385,346.987 330.269,354.769 320.770 C 355.959 319.318,357.419 317.599,358.014 316.950 C 358.609 316.301,359.095 315.682,359.095 315.574 C 359.095 315.466,359.936 314.299,360.964 312.981 C 362.767 310.668,365.287 307.040,367.793 303.147 C 368.454 302.119,369.168 301.278,369.378 301.278 C 369.589 301.278,369.665 301.122,369.547 300.931 C 369.429 300.740,369.699 300.118,370.147 299.549 C 371.042 298.411,373.212 294.639,375.942 289.479 C 376.914 287.640,377.859 286.076,378.041 286.004 C 378.224 285.931,378.273 285.710,378.150 285.512 C 378.028 285.314,378.082 285.152,378.269 285.152 C 378.457 285.152,379.209 283.736,379.941 282.006 C 380.673 280.275,381.425 278.859,381.613 278.859 C 381.800 278.859,381.845 278.682,381.711 278.466 C 381.577 278.250,381.618 278.073,381.803 278.073 C 381.987 278.073,382.732 276.480,383.459 274.533 C 384.186 272.586,384.941 270.993,385.137 270.993 C 385.333 270.993,385.394 270.832,385.272 270.635 C 385.151 270.438,385.476 269.420,385.995 268.373 C 386.515 267.327,387.255 265.452,387.642 264.208 C 388.028 262.965,388.499 261.947,388.689 261.947 C 388.879 261.947,388.919 261.762,388.780 261.536 C 388.640 261.311,388.740 260.868,389.002 260.553 C 389.263 260.238,389.345 259.980,389.184 259.980 C 389.023 259.980,389.075 259.759,389.299 259.489 C 389.523 259.218,389.745 258.820,389.790 258.604 C 389.836 258.387,389.935 258.033,390.009 257.817 C 390.084 257.601,390.690 255.477,391.356 253.097 C 392.023 250.718,392.676 248.505,392.807 248.181 C 392.938 247.856,393.011 247.440,392.969 247.255 C 392.927 247.070,393.091 246.679,393.334 246.387 C 393.576 246.095,393.668 245.683,393.538 245.472 C 393.407 245.261,393.460 244.990,393.654 244.870 C 393.849 244.750,394.418 242.526,394.918 239.927 C 395.419 237.328,395.940 235.202,396.076 235.202 C 396.212 235.202,396.246 234.671,396.151 234.022 C 396.049 233.327,396.154 232.842,396.406 232.842 C 396.672 232.842,396.744 232.395,396.598 231.662 C 396.446 230.901,396.522 230.482,396.812 230.482 C 397.096 230.482,397.170 230.118,397.014 229.493 C 396.877 228.950,396.947 228.286,397.168 228.018 C 397.390 227.751,397.577 227.089,397.584 226.549 C 397.591 226.008,397.856 223.707,398.172 221.436 C 400.082 207.708,399.985 180.691,397.986 169.752 C 397.745 168.434,397.553 166.912,397.559 166.372 C 397.566 165.831,397.402 165.184,397.195 164.934 C 396.989 164.685,396.935 164.021,397.076 163.459 C 397.247 162.777,397.173 162.439,396.850 162.439 C 396.548 162.439,396.439 162.071,396.556 161.455 C 396.660 160.914,396.569 160.472,396.354 160.472 C 396.125 160.472,396.060 159.883,396.195 159.047 C 396.322 158.263,396.316 157.732,396.180 157.868 C 396.045 158.003,395.440 155.680,394.837 152.705 C 394.234 149.730,393.550 146.979,393.317 146.592 C 393.084 146.204,392.989 145.733,393.106 145.544 C 393.223 145.355,393.131 145.137,392.901 145.061 C 392.672 144.984,392.449 144.262,392.407 143.456 C 392.365 142.649,392.235 141.989,392.118 141.988 C 392.001 141.987,391.477 140.393,390.954 138.446 C 390.431 136.500,389.844 134.907,389.649 134.907 C 389.455 134.907,389.398 134.641,389.523 134.317 C 389.647 133.992,389.559 133.727,389.326 133.727 C 389.093 133.727,389.001 133.473,389.120 133.162 C 389.239 132.852,389.214 132.542,389.063 132.474 C 388.913 132.406,388.187 130.580,387.450 128.417 C 386.713 126.254,385.939 124.263,385.731 123.992 C 385.522 123.722,385.505 123.498,385.694 123.494 C 385.883 123.491,385.849 123.358,385.620 123.199 C 385.390 123.041,384.786 121.849,384.278 120.551 C 383.770 119.253,382.321 116.030,381.058 113.389 C 379.795 110.749,378.761 108.403,378.761 108.178 C 378.761 107.952,378.574 107.768,378.345 107.768 C 378.115 107.768,378.037 107.591,378.171 107.375 C 378.305 107.158,378.216 106.981,377.974 106.981 C 377.733 106.981,377.635 106.819,377.757 106.622 C 377.879 106.424,377.823 106.203,377.632 106.130 C 377.441 106.057,376.635 104.759,375.840 103.245 C 373.209 98.228,367.459 88.815,366.872 88.561 C 366.705 88.489,366.568 88.194,366.568 87.906 C 366.568 87.617,366.423 87.322,366.246 87.250 C 366.069 87.178,365.205 86.053,364.326 84.750 C 362.686 82.320,356.953 74.763,355.678 73.350 C 355.286 72.916,354.169 71.588,353.196 70.400 C 350.436 67.031,348.951 65.381,345.030 61.329 C 343.026 59.258,341.522 57.429,341.687 57.265 C 341.851 57.100,341.792 57.024,341.555 57.096 C 340.913 57.291,337.394 53.920,337.709 53.411 C 337.866 53.156,337.799 53.086,337.547 53.242 C 337.310 53.389,335.822 52.333,334.241 50.897 C 332.660 49.460,330.526 47.649,329.499 46.871 C 328.471 46.093,327.630 45.317,327.630 45.147 C 327.630 44.977,327.359 44.838,327.028 44.838 C 326.697 44.838,326.330 44.589,326.214 44.285 C 326.097 43.981,325.041 43.094,323.866 42.314 C 322.692 41.535,321.731 40.750,321.731 40.570 C 321.731 40.391,321.326 40.060,320.832 39.835 C 320.338 39.610,318.790 38.556,317.391 37.493 C 315.992 36.430,314.007 35.074,312.979 34.479 C 311.952 33.885,311.111 33.219,311.111 32.999 C 311.111 32.779,310.949 32.699,310.751 32.821 C 310.554 32.943,310.332 32.909,310.260 32.746 C 310.098 32.382,303.820 28.450,300.983 26.936 C 299.848 26.330,298.918 25.685,298.918 25.503 C 298.918 25.321,298.786 25.207,298.623 25.250 C 298.198 25.362,292.454 22.388,292.297 21.975 C 292.224 21.784,292.003 21.727,291.805 21.850 C 291.607 21.972,291.445 21.929,291.444 21.754 C 291.443 21.579,290.395 20.997,289.116 20.461 C 287.837 19.924,286.892 19.322,287.016 19.121 C 287.139 18.921,287.057 18.871,286.832 19.010 C 286.323 19.324,283.972 18.538,283.972 18.054 C 283.972 17.859,283.840 17.728,283.677 17.763 C 283.515 17.799,282.586 17.472,281.613 17.036 C 280.639 16.601,279.179 16.028,278.368 15.762 C 277.557 15.496,276.893 15.105,276.893 14.892 C 276.893 14.680,276.719 14.613,276.508 14.744 C 276.296 14.875,275.721 14.759,275.229 14.486 C 274.738 14.214,274.248 13.968,274.140 13.941 C 274.031 13.914,273.324 13.616,272.566 13.279 C 271.809 12.943,270.438 12.444,269.518 12.171 C 268.599 11.898,267.847 11.542,267.847 11.381 C 267.847 11.219,267.493 11.179,267.060 11.292 C 266.627 11.405,266.273 11.306,266.273 11.071 C 266.273 10.836,266.008 10.746,265.683 10.871 C 265.359 10.995,265.093 10.907,265.093 10.674 C 265.093 10.441,264.828 10.353,264.503 10.477 C 264.179 10.602,263.913 10.489,263.913 10.226 C 263.913 9.964,263.654 9.848,263.336 9.970 C 263.019 10.092,262.672 10.052,262.566 9.880 C 262.460 9.709,260.464 9.066,258.129 8.451 C 255.794 7.837,253.831 7.207,253.767 7.052 C 253.702 6.897,253.304 6.860,252.882 6.971 C 252.429 7.089,252.114 6.974,252.114 6.690 C 252.114 6.407,251.850 6.310,251.474 6.454 C 251.122 6.589,250.610 6.514,250.336 6.286 C 250.061 6.058,249.686 5.906,249.501 5.948 C 249.316 5.990,248.899 5.917,248.574 5.787 C 247.677 5.424,240.081 3.933,239.134 3.933 C 238.676 3.933,238.409 3.759,238.541 3.546 C 238.690 3.305,238.325 3.249,237.581 3.398 C 236.775 3.559,236.382 3.483,236.382 3.164 C 236.382 2.846,236.007 2.773,235.239 2.942 C 234.558 3.091,233.987 3.015,233.825 2.753 C 233.666 2.496,233.095 2.414,232.448 2.557 C 231.799 2.699,231.231 2.617,231.070 2.357 C 230.920 2.114,230.328 1.952,229.755 1.997 C 229.181 2.043,228.446 1.980,228.122 1.859 C 224.834 0.632,200.925 -0.230,188.201 0.421 M218.682 42.875 C 224.914 43.339,229.812 43.957,231.465 44.489 C 232.114 44.698,233.945 45.138,235.535 45.467 C 239.072 46.199,244.814 47.826,246.411 48.548 C 247.060 48.841,248.918 49.549,250.541 50.120 C 255.840 51.986,266.175 57.107,271.830 60.669 C 273.461 61.696,274.919 62.537,275.070 62.537 C 275.394 62.537,280.853 66.294,284.041 68.711 C 285.268 69.642,286.463 70.403,286.696 70.403 C 286.929 70.403,287.119 70.582,287.119 70.801 C 287.119 71.020,288.048 71.794,289.184 72.521 C 293.841 75.503,305.912 86.900,309.852 92.035 C 310.764 93.225,311.686 94.412,311.901 94.674 C 312.116 94.935,312.291 95.333,312.291 95.559 C 312.291 95.784,312.450 95.969,312.643 95.969 C 312.837 95.969,313.332 96.632,313.744 97.443 C 314.156 98.255,315.095 100.059,315.831 101.452 C 317.731 105.049,317.950 113.610,316.222 116.749 C 316.024 117.109,315.413 118.394,314.864 119.603 C 310.740 128.695,294.952 132.472,285.469 126.637 C 284.423 125.993,283.428 125.467,283.258 125.467 C 282.660 125.467,278.649 121.626,278.077 120.505 C 277.077 118.545,273.676 113.558,271.856 111.385 C 269.164 108.170,258.824 99.903,256.382 99.013 C 256.025 98.883,254.344 97.917,252.645 96.865 C 233.017 84.714,199.055 81.368,174.041 89.120 C 172.311 89.656,169.390 90.559,167.552 91.127 C 165.713 91.694,164.031 92.284,163.815 92.439 C 163.599 92.593,161.829 93.421,159.882 94.279 C 150.963 98.208,143.490 105.654,141.143 112.950 C 139.790 117.157,139.786 126.259,141.135 130.556 C 142.003 133.320,145.742 138.053,147.058 138.053 C 147.240 138.053,148.785 138.834,150.489 139.787 C 156.217 142.992,168.961 146.406,178.564 147.309 C 179.971 147.442,181.475 147.704,181.908 147.893 C 183.203 148.458,193.596 149.052,209.243 149.454 C 217.355 149.663,225.674 149.932,227.729 150.051 C 236.805 150.580,242.676 151.103,245.231 151.610 C 246.745 151.911,249.843 152.450,252.114 152.808 C 257.124 153.599,262.443 154.779,264.307 155.515 C 265.064 155.814,267.610 156.622,269.966 157.310 C 272.321 157.999,274.884 158.903,275.663 159.320 C 276.441 159.737,277.257 160.077,277.477 160.075 C 277.933 160.072,284.067 162.522,284.366 162.828 C 284.474 162.938,285.359 163.455,286.332 163.977 C 287.306 164.498,289.043 165.560,290.192 166.337 C 291.342 167.113,292.659 167.958,293.119 168.215 C 295.272 169.417,304.031 177.590,304.031 178.397 C 304.031 178.659,304.283 178.970,304.591 179.088 C 306.477 179.812,313.462 192.452,315.061 198.033 C 315.557 199.764,316.086 201.357,316.238 201.573 C 318.085 204.207,318.074 228.277,316.225 230.678 C 316.058 230.895,315.800 231.691,315.650 232.448 C 315.281 234.322,313.078 241.204,312.692 241.691 C 312.520 241.908,311.813 243.455,311.120 245.131 C 310.427 246.806,309.440 248.794,308.928 249.549 C 308.416 250.304,307.532 251.765,306.963 252.796 C 303.138 259.735,284.374 278.859,281.393 278.859 C 281.223 278.859,280.759 279.154,280.362 279.513 C 279.313 280.463,273.988 283.720,270.808 285.357 C 269.300 286.134,267.530 287.099,266.875 287.502 C 266.220 287.905,264.356 288.768,262.734 289.419 C 261.111 290.070,259.040 290.969,258.131 291.417 C 257.222 291.865,256.316 292.232,256.117 292.232 C 255.918 292.232,255.638 293.073,255.495 294.100 C 255.094 296.985,252.850 299.994,249.951 301.534 L 247.591 302.788 200.683 302.820 C 172.948 302.838,153.496 302.704,153.092 302.491 C 152.716 302.293,151.828 301.915,151.117 301.651 C 148.298 300.605,146.283 297.275,145.686 292.677 L 145.412 290.565 143.208 289.611 C 139.934 288.195,134.152 285.201,132.277 283.951 C 131.372 283.347,130.024 282.566,129.282 282.213 C 127.557 281.395,117.393 273.865,115.809 272.232 C 115.148 271.551,114.396 270.993,114.137 270.993 C 113.495 270.993,99.508 256.963,99.508 256.318 C 99.508 256.034,98.977 255.409,98.328 254.929 C 97.679 254.450,97.148 253.860,97.148 253.620 C 97.148 253.379,96.384 252.278,95.449 251.173 C 93.732 249.145,89.266 242.948,88.014 240.857 C 87.641 240.234,86.357 238.132,85.161 236.185 C 83.964 234.238,82.718 232.068,82.391 231.364 C 82.064 230.659,81.169 228.800,80.402 227.234 C 79.636 225.667,78.470 222.970,77.813 221.239 C 77.156 219.508,76.276 217.354,75.858 216.452 C 75.440 215.549,74.433 212.185,73.620 208.976 C 72.806 205.766,72.033 202.965,71.902 202.750 C 70.707 200.793,69.226 185.114,69.225 174.399 C 69.223 163.630,70.871 145.980,71.958 145.133 C 72.097 145.025,72.442 143.697,72.725 142.183 C 73.373 138.715,75.581 130.056,75.884 129.794 C 76.009 129.685,76.622 128.004,77.247 126.057 C 77.872 124.110,78.694 121.898,79.073 121.141 C 79.452 120.383,81.041 117.152,82.603 113.959 C 84.166 110.766,86.756 106.252,88.358 103.929 C 89.960 101.606,91.575 99.191,91.948 98.564 C 95.921 91.871,114.620 73.320,121.987 68.762 C 122.994 68.139,123.918 67.369,124.040 67.050 C 124.162 66.731,124.448 66.470,124.674 66.470 C 124.901 66.470,126.278 65.605,127.735 64.548 C 129.192 63.491,131.357 62.094,132.547 61.444 C 133.736 60.794,136.450 59.270,138.578 58.056 C 140.705 56.843,142.556 55.851,142.691 55.851 C 142.970 55.851,148.839 53.426,151.229 52.324 C 152.094 51.925,154.218 51.155,155.949 50.613 C 157.679 50.071,159.980 49.328,161.062 48.962 C 162.144 48.596,165.772 47.686,169.125 46.941 C 172.478 46.195,176.726 45.247,178.564 44.832 C 187.530 42.813,205.844 41.919,218.682 42.875 M112.127 158.644 C 110.939 162.358,110.697 177.745,111.708 185.251 C 112.458 190.818,115.318 203.165,116.298 205.058 C 116.629 205.700,117.225 207.125,117.623 208.225 C 118.020 209.326,118.606 210.940,118.925 211.813 C 119.559 213.547,122.776 219.258,124.668 222.007 C 125.324 222.960,125.860 223.854,125.860 223.992 C 125.860 224.130,127.053 225.771,128.512 227.639 C 135.059 236.024,145.323 244.545,154.472 249.193 C 155.933 249.936,157.306 250.675,157.522 250.837 C 157.738 250.999,158.977 251.606,160.275 252.187 C 161.573 252.769,163.786 253.762,165.192 254.395 C 166.598 255.027,169.607 256.110,171.878 256.799 C 174.149 257.489,176.663 258.305,177.464 258.613 C 189.252 263.141,219.453 263.148,230.482 258.625 C 231.239 258.315,233.628 257.502,235.792 256.819 C 251.106 251.983,266.854 240.556,274.921 228.424 C 281.680 218.261,279.922 206.384,270.814 200.682 C 269.939 200.134,269.135 199.557,269.027 199.399 C 268.614 198.798,260.856 194.779,258.604 193.999 C 250.836 191.309,248.866 190.897,234.415 188.942 C 230.413 188.401,225.988 187.800,224.582 187.608 C 223.176 187.415,214.503 187.248,205.310 187.237 C 196.116 187.225,186.205 187.040,183.284 186.826 C 173.756 186.126,163.599 184.815,161.849 184.058 C 161.416 183.871,160.000 183.519,158.702 183.276 C 155.478 182.672,148.565 180.887,148.083 180.534 C 147.866 180.376,146.362 179.791,144.739 179.233 C 139.580 177.460,138.720 177.091,134.984 175.054 C 132.972 173.956,131.158 173.058,130.953 173.058 C 130.748 173.058,130.580 172.889,130.580 172.683 C 130.580 172.477,129.978 172.023,129.243 171.674 C 127.667 170.926,120.333 164.840,115.750 160.478 L 112.522 157.406 112.127 158.644 M245.244 306.961 C 253.113 310.249,253.675 322.620,246.132 326.489 C 244.341 327.407,159.116 327.683,156.523 326.779 C 149.499 324.331,149.181 312.136,156.024 307.603 L 157.854 306.391 200.867 306.391 C 237.535 306.391,244.081 306.475,245.244 306.961 M238.902 332.290 C 240.180 333.092,241.419 334.090,241.655 334.509 C 241.891 334.928,242.526 335.985,243.066 336.858 C 244.342 338.921,244.460 343.639,243.284 345.526 C 241.222 348.835,240.431 349.792,238.725 351.044 L 236.866 352.409 231.412 352.419 L 225.959 352.429 225.248 353.972 C 220.338 364.625,200.029 368.942,186.234 362.265 C 182.722 360.565,177.033 355.580,176.428 353.672 C 176.161 352.832,175.972 352.802,170.942 352.802 C 164.236 352.802,161.642 351.614,159.357 347.493 C 158.394 345.758,158.436 338.178,159.418 336.361 C 160.392 334.560,163.005 332.027,164.198 331.727 C 164.745 331.590,165.192 331.320,165.192 331.127 C 165.192 330.924,180.224 330.788,200.885 330.804 L 236.578 330.832 238.902 332.290 \" stroke=\"none\" fill=\"#fcfbfb\" fill-rule=\"evenodd\"><\/path><path id=\"path2\" d=\"M203.048 42.771 C 204.941 42.843,208.038 42.843,209.931 42.771 C 211.824 42.699,210.275 42.640,206.490 42.640 C 202.704 42.640,201.155 42.699,203.048 42.771 M194.206 43.156 C 194.913 43.244,195.975 43.242,196.566 43.152 C 197.157 43.062,196.578 42.991,195.280 42.993 C 193.982 42.995,193.499 43.069,194.206 43.156 M216.421 43.153 C 217.016 43.243,217.989 43.243,218.584 43.153 C 219.179 43.063,218.692 42.989,217.502 42.989 C 216.313 42.989,215.826 43.063,216.421 43.153 M236.185 45.973 C 237.392 46.488,239.838 46.907,239.135 46.479 C 238.810 46.281,237.837 46.010,236.971 45.878 C 235.947 45.721,235.672 45.754,236.185 45.973 M171.288 46.429 C 170.740 46.678,170.978 46.713,172.075 46.546 C 172.940 46.414,173.722 46.242,173.812 46.162 C 174.150 45.864,172.043 46.087,171.288 46.429 M244.051 48.378 C 244.484 48.563,245.103 48.716,245.428 48.716 C 245.800 48.716,245.727 48.591,245.231 48.378 C 244.798 48.192,244.179 48.040,243.854 48.040 C 243.483 48.040,243.555 48.165,244.051 48.378 M246.608 49.098 C 246.932 49.298,247.640 49.581,248.181 49.725 C 248.864 49.908,248.984 49.877,248.574 49.624 C 248.250 49.423,247.542 49.141,247.001 48.996 C 246.318 48.814,246.198 48.845,246.608 49.098 M148.476 53.661 C 145.892 54.906,146.396 54.944,149.114 53.710 C 150.277 53.182,151.052 52.741,150.836 52.732 C 150.619 52.722,149.558 53.140,148.476 53.661 M257.227 53.491 C 257.984 53.905,258.781 54.244,258.997 54.244 C 259.213 54.244,258.771 53.905,258.014 53.491 C 257.257 53.076,256.460 52.737,256.244 52.737 C 256.028 52.737,256.470 53.076,257.227 53.491 M260.374 54.880 C 260.374 54.976,261.834 55.767,263.618 56.638 C 265.403 57.509,266.467 57.933,265.982 57.581 C 264.944 56.826,260.374 54.625,260.374 54.880 M140.708 57.057 C 139.897 57.486,139.233 57.924,139.233 58.031 C 139.233 58.206,142.340 56.755,142.740 56.392 C 143.193 55.983,142.011 56.369,140.708 57.057 M134.402 60.512 C 133.367 61.121,132.305 61.845,132.042 62.120 C 131.779 62.395,132.448 62.094,133.530 61.450 C 134.612 60.806,135.851 60.085,136.283 59.847 C 136.716 59.609,136.893 59.412,136.676 59.409 C 136.460 59.406,135.436 59.902,134.402 60.512 M274.533 62.653 C 274.533 62.742,275.772 63.639,277.286 64.646 C 278.800 65.652,280.039 66.393,280.039 66.291 C 280.039 66.189,279.022 65.422,277.778 64.587 C 275.023 62.736,274.533 62.444,274.533 62.653 M126.767 65.523 L 125.664 66.542 126.942 65.693 C 128.113 64.915,128.494 64.503,128.046 64.503 C 127.949 64.503,127.374 64.962,126.767 65.523 M120.810 69.834 C 118.429 71.685,116.247 73.494,115.960 73.855 C 115.673 74.216,116.765 73.446,118.387 72.145 C 120.010 70.844,122.266 69.108,123.402 68.288 C 125.281 66.931,125.763 66.470,125.302 66.470 C 125.212 66.470,123.190 67.984,120.810 69.834 M281.613 67.432 C 281.613 67.511,282.490 68.206,283.562 68.977 C 284.634 69.747,285.423 70.162,285.315 69.898 C 285.133 69.455,281.613 67.109,281.613 67.432 M286.579 71.105 C 287.040 71.476,289.419 73.370,291.866 75.313 C 299.930 81.714,308.266 90.268,312.091 96.067 C 313.717 98.533,314.235 99.006,313.275 97.150 C 310.580 91.938,288.529 70.302,286.029 70.416 C 285.871 70.423,286.119 70.733,286.579 71.105 M113.840 75.615 L 112.684 76.893 113.963 75.738 C 115.154 74.661,115.422 74.336,115.118 74.336 C 115.050 74.336,114.475 74.912,113.840 75.615 M110.521 78.466 C 109.566 79.440,108.873 80.236,108.981 80.236 C 109.089 80.236,109.959 79.440,110.914 78.466 C 111.870 77.493,112.563 76.696,112.455 76.696 C 112.347 76.696,111.477 77.493,110.521 78.466 M104.871 83.612 C 104.251 84.157,103.822 84.680,103.916 84.775 C 104.011 84.870,104.596 84.418,105.215 83.772 C 106.584 82.343,106.407 82.261,104.871 83.612 M198.530 84.841 C 199.019 84.935,199.727 84.931,200.103 84.833 C 200.479 84.734,200.079 84.657,199.213 84.662 C 198.348 84.666,198.040 84.747,198.530 84.841 M211.116 84.841 C 211.605 84.935,212.313 84.931,212.689 84.833 C 213.065 84.734,212.665 84.657,211.799 84.662 C 210.934 84.666,210.626 84.747,211.116 84.841 M181.121 86.922 C 180.061 87.192,180.041 87.223,180.924 87.230 C 181.465 87.234,182.350 87.096,182.891 86.922 C 184.213 86.499,182.785 86.499,181.121 86.922 M228.319 87.147 C 229.400 87.448,230.639 87.682,231.072 87.668 C 231.504 87.654,230.885 87.399,229.695 87.102 C 226.880 86.400,225.764 86.436,228.319 87.147 M100.295 88.692 C 99.340 89.666,98.646 90.462,98.755 90.462 C 98.863 90.462,99.733 89.666,100.688 88.692 C 101.644 87.719,102.337 86.922,102.229 86.922 C 102.121 86.922,101.250 87.719,100.295 88.692 M165.585 91.268 C 164.612 91.667,164.081 91.992,164.405 91.992 C 164.730 91.992,165.792 91.657,166.765 91.249 C 167.738 90.840,168.269 90.515,167.945 90.525 C 167.620 90.535,166.559 90.870,165.585 91.268 M240.708 90.669 C 240.708 90.898,241.961 91.406,243.461 91.785 C 244.002 91.922,243.736 91.693,242.871 91.277 C 241.201 90.474,240.708 90.335,240.708 90.669 M96.362 93.215 C 95.456 94.297,94.804 95.182,94.912 95.182 C 95.020 95.182,95.850 94.297,96.755 93.215 C 97.661 92.134,98.313 91.249,98.205 91.249 C 98.097 91.249,97.267 92.134,96.362 93.215 M157.758 94.613 C 157.022 94.933,156.519 95.293,156.639 95.414 C 156.866 95.640,159.292 94.520,159.292 94.189 C 159.292 93.945,159.310 93.939,157.758 94.613 M249.332 94.684 C 250.370 95.440,252.507 96.429,252.507 96.153 C 252.507 96.059,251.578 95.533,250.442 94.985 C 249.269 94.419,248.789 94.289,249.332 94.684 M93.754 96.460 C 92.278 98.139,89.502 102.262,89.848 102.262 C 89.954 102.262,90.779 101.155,91.684 99.803 C 92.588 98.451,93.687 96.947,94.127 96.460 C 94.566 95.973,94.837 95.575,94.729 95.575 C 94.621 95.575,94.182 95.973,93.754 96.460 M151.622 98.405 C 149.944 99.598,146.468 102.969,145.011 104.818 C 144.329 105.683,145.273 104.874,147.107 103.018 C 148.942 101.163,151.062 99.180,151.819 98.612 C 153.465 97.377,153.305 97.209,151.622 98.405 M255.261 98.033 C 256.121 98.853,261.294 102.009,261.000 101.534 C 260.863 101.312,259.383 100.307,257.711 99.300 C 256.039 98.293,254.936 97.723,255.261 98.033 M314.928 100.874 C 315.509 102.058,316.050 102.960,316.131 102.880 C 316.307 102.703,314.323 98.722,314.059 98.722 C 313.956 98.722,314.348 99.690,314.928 100.874 M262.734 102.778 C 262.734 102.875,263.383 103.450,264.177 104.056 C 264.972 104.662,265.497 104.957,265.345 104.711 C 265.034 104.208,262.734 102.505,262.734 102.778 M269.063 108.187 C 270.922 110.011,272.958 112.132,273.586 112.899 C 274.215 113.666,274.559 114.020,274.351 113.685 C 273.330 112.046,270.365 108.828,268.153 106.957 C 266.082 105.205,266.228 105.404,269.063 108.187 M85.183 109.231 C 84.409 110.468,83.776 111.662,83.777 111.885 C 83.778 112.109,84.151 111.672,84.605 110.914 C 85.060 110.157,85.782 108.963,86.209 108.260 C 86.637 107.557,86.897 106.981,86.788 106.981 C 86.679 106.981,85.957 107.993,85.183 109.231 M141.751 109.980 C 141.213 111.197,140.840 112.259,140.922 112.341 C 141.003 112.422,141.528 111.427,142.089 110.129 C 142.649 108.830,143.022 107.768,142.918 107.768 C 142.815 107.768,142.289 108.763,141.751 109.980 M80.764 117.823 C 80.213 119.026,79.831 120.080,79.914 120.164 C 79.998 120.247,80.533 119.263,81.102 117.975 C 81.671 116.688,82.053 115.634,81.951 115.634 C 81.849 115.634,81.315 116.619,80.764 117.823 M276.674 117.871 C 277.008 118.560,277.476 119.245,277.716 119.393 C 278.244 119.719,277.675 118.599,276.706 117.404 C 276.114 116.674,276.112 116.707,276.674 117.871 M314.642 118.965 C 314.097 120.126,313.790 120.990,313.960 120.885 C 314.430 120.594,315.894 117.589,315.756 117.198 C 315.689 117.009,315.188 117.804,314.642 118.965 M139.359 121.534 C 139.359 122.940,139.430 123.515,139.518 122.812 C 139.605 122.109,139.605 120.959,139.518 120.256 C 139.430 119.553,139.359 120.128,139.359 121.534 M278.794 121.007 C 279.993 122.750,284.772 126.647,285.710 126.647 C 285.921 126.647,285.292 126.139,284.312 125.518 C 283.333 124.896,281.498 123.348,280.235 122.076 C 278.897 120.729,278.296 120.283,278.794 121.007 M309.599 125.197 C 309.363 125.482,308.279 126.131,307.192 126.641 C 306.104 127.150,305.284 127.637,305.370 127.723 C 305.619 127.972,309.337 125.986,309.906 125.301 C 310.189 124.960,310.332 124.680,310.224 124.680 C 310.116 124.680,309.834 124.913,309.599 125.197 M77.380 125.736 C 77.280 125.913,77.093 126.588,76.964 127.237 C 76.730 128.411,76.732 128.410,77.322 127.093 C 77.837 125.945,77.883 124.846,77.380 125.736 M294.405 129.083 C 295.708 129.254,297.832 129.254,299.125 129.082 C 301.135 128.816,300.792 128.771,296.755 128.771 C 292.703 128.772,292.371 128.816,294.405 129.083 M75.741 130.805 C 75.596 131.381,75.554 131.929,75.647 132.021 C 75.739 132.114,75.933 131.718,76.078 131.142 C 76.223 130.566,76.265 130.018,76.173 129.925 C 76.080 129.833,75.886 130.228,75.741 130.805 M141.544 132.815 C 141.997 133.720,142.582 134.592,142.842 134.753 C 143.103 134.914,142.900 134.351,142.392 133.501 C 141.063 131.282,140.580 130.890,141.544 132.815 M145.100 137.027 C 145.407 137.399,146.027 137.899,146.477 138.139 C 147.222 138.536,147.246 138.514,146.738 137.899 C 146.432 137.528,145.812 137.027,145.362 136.787 C 144.617 136.390,144.593 136.412,145.100 137.027 M73.187 140.050 C 72.945 141.178,72.822 142.176,72.913 142.267 C 73.005 142.359,73.277 141.511,73.519 140.383 C 73.761 139.255,73.884 138.257,73.793 138.165 C 73.701 138.074,73.429 138.922,73.187 140.050 M148.673 139.489 C 148.673 139.751,154.612 142.471,154.792 142.291 C 154.872 142.211,153.528 141.505,151.805 140.722 C 150.082 139.940,148.673 139.385,148.673 139.489 M165.192 145.526 C 165.733 145.699,166.529 145.841,166.962 145.841 C 167.585 145.841,167.544 145.775,166.765 145.526 C 166.224 145.353,165.428 145.211,164.995 145.211 C 164.372 145.211,164.413 145.277,165.192 145.526 M184.169 148.550 C 184.548 148.649,185.167 148.649,185.546 148.550 C 185.924 148.451,185.615 148.371,184.857 148.371 C 184.100 148.371,183.791 148.451,184.169 148.550 M189.288 148.955 C 189.885 149.045,190.770 149.043,191.254 148.949 C 191.738 148.856,191.249 148.782,190.167 148.785 C 189.086 148.788,188.690 148.864,189.288 148.955 M197.050 149.465 C 201.916 149.771,213.413 149.945,213.143 149.709 C 213.053 149.630,208.378 149.479,202.753 149.373 C 196.750 149.260,194.395 149.298,197.050 149.465 M218.584 150.142 C 219.720 150.222,221.578 150.222,222.714 150.142 C 223.850 150.063,222.920 149.998,220.649 149.998 C 218.378 149.998,217.448 150.063,218.584 150.142 M248.771 152.606 C 249.420 152.771,250.482 152.907,251.131 152.907 C 252.123 152.908,252.060 152.857,250.737 152.583 C 248.745 152.171,247.135 152.190,248.771 152.606 M253.491 153.392 C 255.154 153.816,256.582 153.816,255.261 153.392 C 254.720 153.219,253.835 153.081,253.294 153.085 C 252.411 153.091,252.431 153.123,253.491 153.392 M266.667 156.735 C 267.424 157.027,268.309 157.266,268.633 157.266 C 268.958 157.266,268.604 157.027,267.847 156.735 C 267.089 156.444,266.205 156.205,265.880 156.205 C 265.556 156.205,265.910 156.444,266.667 156.735 M70.101 158.112 C 70.101 158.869,70.182 159.179,70.281 158.800 C 70.380 158.422,70.380 157.802,70.281 157.424 C 70.182 157.045,70.101 157.355,70.101 158.112 M114.095 158.800 C 114.334 159.179,114.999 159.826,115.574 160.239 C 116.401 160.834,116.337 160.691,115.262 159.551 C 113.771 157.968,113.433 157.751,114.095 158.800 M274.959 159.454 C 275.275 159.767,279.404 161.238,279.551 161.091 C 279.633 161.009,278.708 160.571,277.495 160.117 C 275.346 159.313,274.626 159.125,274.959 159.454 M69.480 163.119 C 69.342 164.583,69.254 167.198,69.284 168.928 C 69.326 171.323,69.417 170.717,69.664 166.394 C 70.006 160.410,69.906 158.616,69.480 163.119 M118.205 162.537 C 118.792 163.240,119.559 163.972,119.911 164.163 C 120.263 164.354,119.851 163.779,118.996 162.885 C 117.137 160.941,116.719 160.757,118.205 162.537 M283.612 162.971 C 284.138 163.418,287.512 165.233,287.512 165.070 C 287.512 164.829,284.144 162.832,283.739 162.832 C 283.579 162.832,283.522 162.894,283.612 162.971 M110.797 167.120 C 110.645 169.155,110.548 172.429,110.580 174.397 C 110.625 177.088,110.722 176.318,110.970 171.288 C 111.335 163.898,111.229 161.331,110.797 167.120 M123.107 166.495 C 123.107 166.603,123.992 167.433,125.074 168.338 C 126.155 169.244,127.040 169.896,127.040 169.788 C 127.040 169.680,126.155 168.851,125.074 167.945 C 123.992 167.039,123.107 166.387,123.107 166.495 M291.052 167.288 C 291.052 167.360,291.893 167.993,292.920 168.696 L 294.789 169.975 293.215 168.572 C 291.830 167.338,291.052 166.876,291.052 167.288 M128.195 170.720 C 129.317 171.671,133.769 174.327,133.946 174.150 C 134.012 174.083,132.530 173.102,130.652 171.968 C 128.774 170.835,127.668 170.273,128.195 170.720 M298.304 173.089 C 300.237 174.911,303.202 178.136,304.892 180.256 C 308.115 184.300,309.171 185.134,306.293 181.363 C 304.074 178.456,299.229 173.378,296.768 171.382 C 295.679 170.499,296.370 171.267,298.304 173.089 M134.513 174.433 C 134.513 174.696,139.281 177.074,139.457 176.898 C 139.536 176.819,138.456 176.190,137.057 175.500 C 135.658 174.810,134.513 174.330,134.513 174.433 M69.367 180.728 C 69.368 182.891,69.434 183.726,69.514 182.583 C 69.593 181.440,69.592 179.670,69.512 178.650 C 69.431 177.629,69.366 178.564,69.367 180.728 M111.044 180.728 C 111.045 182.242,111.116 182.813,111.201 181.997 C 111.287 181.181,111.285 179.942,111.198 179.244 C 111.111 178.546,111.042 179.213,111.044 180.728 M144.297 178.962 C 145.244 179.398,146.483 179.848,147.051 179.962 C 147.618 180.076,147.198 179.807,146.116 179.365 C 143.426 178.264,142.183 177.989,144.297 178.962 M156.342 182.705 C 157.207 182.990,158.269 183.221,158.702 183.219 C 159.135 183.216,158.604 182.968,157.522 182.667 C 155.061 181.982,154.230 182.009,156.342 182.705 M111.399 185.251 C 111.399 186.008,111.480 186.318,111.579 185.939 C 111.678 185.560,111.678 184.941,111.579 184.562 C 111.480 184.184,111.399 184.494,111.399 185.251 M69.729 186.627 C 69.732 187.709,69.808 188.105,69.899 187.507 C 69.989 186.909,69.987 186.024,69.893 185.540 C 69.800 185.057,69.726 185.546,69.729 186.627 M174.336 185.915 C 174.715 186.014,175.334 186.014,175.713 185.915 C 176.091 185.816,175.782 185.735,175.025 185.735 C 174.267 185.735,173.958 185.816,174.336 185.915 M179.154 186.436 C 181.161 186.762,185.908 186.941,185.611 186.680 C 185.521 186.601,183.589 186.442,181.318 186.327 C 178.533 186.186,177.828 186.222,179.154 186.436 M187.897 187.108 C 188.595 187.195,189.834 187.196,190.650 187.111 C 191.466 187.026,190.895 186.955,189.381 186.953 C 187.866 186.951,187.199 187.021,187.897 187.108 M210.718 187.117 C 212.502 187.189,215.423 187.189,217.207 187.117 C 218.992 187.044,217.532 186.984,213.963 186.984 C 210.393 186.984,208.933 187.044,210.718 187.117 M311.227 190.016 C 312.137 191.880,312.946 193.349,313.026 193.280 C 313.228 193.106,310.938 188.367,310.190 187.414 C 309.850 186.981,310.317 188.152,311.227 190.016 M223.500 187.488 C 223.879 187.587,224.499 187.587,224.877 187.488 C 225.256 187.389,224.946 187.309,224.189 187.309 C 223.432 187.309,223.122 187.389,223.500 187.488 M70.101 190.364 C 70.101 191.121,70.182 191.431,70.281 191.052 C 70.380 190.674,70.380 190.054,70.281 189.676 C 70.182 189.297,70.101 189.607,70.101 190.364 M244.838 190.364 C 245.487 190.529,246.460 190.664,247.001 190.664 C 247.878 190.664,247.857 190.632,246.804 190.364 C 246.155 190.199,245.182 190.064,244.641 190.064 C 243.764 190.064,243.785 190.096,244.838 190.364 M257.653 193.280 C 257.743 193.370,259.493 194.170,261.542 195.058 C 263.591 195.947,265.095 196.504,264.885 196.296 C 264.675 196.089,263.028 195.289,261.224 194.518 C 258.135 193.198,257.270 192.899,257.653 193.280 M314.121 196.264 C 314.570 198.035,315.489 200.199,315.226 198.863 C 315.102 198.238,314.748 197.176,314.437 196.504 C 314.012 195.583,313.934 195.524,314.121 196.264 M266.470 197.328 C 266.686 197.550,267.824 198.368,268.999 199.146 C 271.559 200.841,275.397 204.508,276.531 206.344 C 277.516 207.938,277.928 208.105,277.133 206.588 C 276.218 204.840,273.846 202.284,271.453 200.466 C 269.213 198.764,265.735 196.574,266.470 197.328 M114.694 201.573 C 115.018 203.019,115.243 203.333,115.235 202.327 C 115.232 201.912,115.049 201.308,114.830 200.983 C 114.538 200.552,114.502 200.712,114.694 201.573 M72.819 205.506 C 72.823 206.327,73.865 209.341,73.907 208.653 C 73.920 208.437,73.680 207.463,73.373 206.490 C 73.067 205.516,72.817 205.074,72.819 205.506 M117.742 210.029 C 118.040 211.134,120.467 216.341,120.615 216.193 C 120.696 216.112,120.047 214.559,119.173 212.743 C 118.298 210.926,117.655 209.705,117.742 210.029 M317.553 215.929 C 317.553 218.417,317.617 219.435,317.695 218.191 C 317.773 216.947,317.773 214.912,317.695 213.668 C 317.617 212.424,317.553 213.441,317.553 215.929 M76.911 218.781 C 77.058 219.267,77.340 219.839,77.538 220.050 C 77.736 220.261,77.698 219.863,77.455 219.165 C 76.957 217.736,76.497 217.412,76.911 218.781 M122.543 219.764 C 124.279 222.755,126.701 226.232,126.906 226.028 C 127.009 225.924,126.483 225.039,125.737 224.061 C 124.991 223.084,123.815 221.296,123.125 220.090 C 122.434 218.883,121.777 217.896,121.664 217.896 C 121.552 217.896,121.947 218.736,122.543 219.764 M78.691 222.812 C 78.691 223.029,78.944 223.648,79.253 224.189 C 79.562 224.730,79.815 224.995,79.815 224.779 C 79.815 224.562,79.562 223.943,79.253 223.402 C 78.944 222.861,78.691 222.596,78.691 222.812 M277.350 224.402 C 276.691 225.849,276.817 226.157,277.529 224.842 C 277.862 224.228,278.061 223.652,277.971 223.562 C 277.881 223.472,277.601 223.850,277.350 224.402 M79.843 225.537 C 79.843 225.986,82.999 232.193,83.458 232.645 C 83.809 232.991,80.379 225.819,79.994 225.402 C 79.911 225.311,79.843 225.372,79.843 225.537 M131.170 231.662 C 132.015 232.527,132.795 233.235,132.903 233.235 C 133.011 233.235,132.408 232.527,131.563 231.662 C 130.718 230.796,129.939 230.088,129.831 230.088 C 129.722 230.088,130.325 230.796,131.170 231.662 M272.250 232.547 C 269.860 235.548,263.739 241.506,260.669 243.819 C 258.271 245.625,257.524 246.499,259.685 244.970 C 264.292 241.711,275.779 230.088,274.393 230.088 C 274.291 230.088,273.327 231.195,272.250 232.547 M314.687 234.451 C 314.421 235.338,314.276 236.137,314.364 236.226 C 314.452 236.314,314.743 235.660,315.008 234.773 C 315.274 233.885,315.420 233.086,315.331 232.998 C 315.243 232.909,314.953 233.563,314.687 234.451 M84.366 234.415 C 84.701 235.064,85.064 235.595,85.173 235.595 C 85.281 235.595,85.095 235.064,84.759 234.415 C 84.424 233.766,84.060 233.235,83.952 233.235 C 83.844 233.235,84.030 233.766,84.366 234.415 M132.940 233.728 C 132.940 233.828,134.400 235.216,136.185 236.814 C 137.970 238.411,139.184 239.406,138.883 239.025 C 138.214 238.176,132.940 233.476,132.940 233.728 M87.300 239.382 C 87.792 240.276,88.621 241.515,89.144 242.136 C 89.666 242.756,89.376 242.125,88.499 240.732 C 86.619 237.745,86.040 237.094,87.300 239.382 M311.027 244.195 C 310.675 245.089,310.457 245.821,310.543 245.821 C 310.858 245.821,311.941 243.393,311.806 242.988 C 311.729 242.757,311.378 243.300,311.027 244.195 M145.133 243.995 C 145.133 244.200,149.293 246.930,151.607 248.245 C 154.014 249.612,153.098 248.896,148.756 246.017 C 145.658 243.962,145.133 243.669,145.133 243.995 M256.244 247.001 C 255.379 247.632,254.546 248.156,254.393 248.165 C 254.095 248.182,251.288 250.031,250.944 250.437 C 250.627 250.811,254.461 248.593,256.342 247.313 C 257.262 246.688,258.014 246.097,258.014 245.999 C 258.014 245.724,257.924 245.775,256.244 247.001 M158.112 251.721 C 159.735 252.565,161.239 253.255,161.455 253.255 C 161.672 253.255,160.521 252.565,158.899 251.721 C 157.276 250.877,155.772 250.186,155.556 250.186 C 155.339 250.186,156.490 250.877,158.112 251.721 M95.395 250.934 C 97.713 255.156,114.336 271.648,120.354 275.696 C 122.388 277.064,121.085 275.886,116.224 271.962 C 111.145 267.860,103.737 260.531,99.344 255.261 C 95.795 251.002,94.884 250.004,95.395 250.934 M246.608 252.507 C 244.553 253.567,243.007 254.443,243.174 254.454 C 243.592 254.482,250.541 250.972,250.541 250.734 C 250.541 250.466,250.745 250.374,246.608 252.507 M307.201 251.444 C 306.906 251.921,306.406 252.709,306.089 253.196 C 305.773 253.682,305.599 254.081,305.703 254.081 C 306.012 254.081,308.096 250.934,307.910 250.748 C 307.815 250.654,307.497 250.967,307.201 251.444 M163.618 254.277 C 164.159 254.586,164.779 254.839,164.995 254.839 C 165.211 254.839,164.946 254.586,164.405 254.277 C 163.864 253.968,163.245 253.715,163.029 253.715 C 162.812 253.715,163.078 253.968,163.618 254.277 M303.067 257.522 C 301.816 259.199,301.150 260.249,301.587 259.856 C 302.402 259.123,305.780 254.474,305.498 254.474 C 305.411 254.474,304.317 255.846,303.067 257.522 M167.552 255.737 C 167.660 255.843,168.364 256.138,169.116 256.393 C 169.868 256.647,170.311 256.686,170.099 256.479 C 169.888 256.272,169.184 255.977,168.535 255.823 C 167.886 255.669,167.443 255.630,167.552 255.737 M237.955 256.274 L 236.971 256.867 237.955 256.606 C 239.382 256.228,240.317 255.677,239.528 255.680 C 239.204 255.681,238.496 255.948,237.955 256.274 M231.858 258.407 C 231.363 258.620,231.290 258.745,231.662 258.745 C 231.986 258.745,232.606 258.593,233.038 258.407 C 233.534 258.194,233.607 258.069,233.235 258.069 C 232.911 258.069,232.291 258.221,231.858 258.407 M179.777 259.732 C 179.867 259.811,180.649 259.984,181.514 260.116 C 182.611 260.282,182.849 260.247,182.301 259.999 C 181.546 259.657,179.439 259.434,179.777 259.732 M224.975 260.177 C 224.002 260.459,223.471 260.704,223.795 260.721 C 224.120 260.738,225.270 260.506,226.352 260.205 C 227.434 259.904,227.965 259.659,227.532 259.661 C 227.099 259.663,225.949 259.895,224.975 260.177 M198.136 262.618 C 198.626 262.712,199.334 262.709,199.710 262.610 C 200.086 262.512,199.685 262.435,198.820 262.439 C 197.955 262.444,197.647 262.524,198.136 262.618 M208.756 262.618 C 209.245 262.712,209.953 262.709,210.329 262.610 C 210.705 262.512,210.305 262.435,209.440 262.439 C 208.574 262.444,208.267 262.524,208.756 262.618 M294.779 267.141 C 293.054 268.916,292.527 269.580,293.609 268.616 C 295.545 266.890,298.369 263.913,298.070 263.913 C 297.986 263.913,296.505 265.366,294.779 267.141 M289.651 271.878 L 288.496 273.156 289.774 272.001 C 290.477 271.366,291.052 270.791,291.052 270.723 C 291.052 270.419,290.728 270.687,289.651 271.878 M280.525 278.747 C 279.387 279.524,278.533 280.238,278.629 280.334 C 278.832 280.536,282.242 278.252,282.599 277.674 C 282.942 277.119,282.824 277.180,280.525 278.747 M123.500 277.838 C 123.500 277.946,124.297 278.583,125.270 279.253 C 126.244 279.922,127.040 280.382,127.040 280.274 C 127.040 280.166,126.244 279.529,125.270 278.859 C 124.297 278.190,123.500 277.730,123.500 277.838 M128.741 281.500 C 129.037 281.979,132.311 283.972,132.803 283.972 C 133.148 283.972,132.357 283.413,130.019 282.001 C 129.169 281.489,128.594 281.263,128.741 281.500 M272.468 283.804 C 270.998 284.602,271.087 284.934,272.566 284.169 C 273.215 283.834,273.746 283.475,273.746 283.372 C 273.746 283.119,273.704 283.134,272.468 283.804 M135.300 285.347 C 135.300 285.610,140.854 288.382,141.029 288.207 C 141.108 288.129,139.851 287.411,138.236 286.612 C 136.621 285.813,135.300 285.244,135.300 285.347 M267.060 286.726 C 265.438 287.570,264.218 288.269,264.351 288.279 C 264.837 288.319,269.763 285.945,270.004 285.555 C 270.340 285.012,270.404 284.987,267.060 286.726 M261.357 289.479 C 260.492 289.879,260.014 290.220,260.295 290.236 C 260.854 290.268,263.127 289.179,263.127 288.879 C 263.127 288.647,263.232 288.611,261.357 289.479 M144.227 289.762 C 145.156 290.225,145.526 290.708,145.639 291.605 L 145.793 292.822 145.856 291.554 C 145.916 290.359,144.499 289.014,143.284 289.111 C 143.111 289.125,143.536 289.418,144.227 289.762 M145.967 294.199 C 145.960 294.523,146.198 295.320,146.495 295.969 C 147.191 297.488,147.201 296.781,146.509 294.985 C 146.218 294.228,145.974 293.874,145.967 294.199 M254.081 296.885 C 254.081 297.137,253.423 298.096,252.620 299.016 C 251.234 300.603,251.225 300.628,252.457 299.508 C 253.884 298.211,254.664 297.010,254.309 296.656 C 254.183 296.530,254.081 296.633,254.081 296.885 M249.361 301.278 C 248.591 301.700,248.269 302.039,248.629 302.048 C 248.984 302.057,249.692 301.717,250.202 301.291 C 251.369 300.319,251.120 300.315,249.361 301.278 M154.671 302.351 C 155.482 302.436,156.809 302.436,157.620 302.351 C 158.432 302.267,157.768 302.197,156.146 302.197 C 154.523 302.197,153.859 302.267,154.671 302.351 M231.587 302.359 C 234.683 302.426,239.639 302.426,242.600 302.359 C 245.561 302.292,243.029 302.238,236.971 302.238 C 230.914 302.238,228.492 302.293,231.587 302.359 M179.843 306.686 C 191.470 306.744,210.497 306.744,222.124 306.686 C 233.751 306.628,224.238 306.581,200.983 306.581 C 177.729 306.581,168.215 306.628,179.843 306.686 M247.659 309.009 C 248.345 309.624,249.274 310.747,249.722 311.504 C 250.171 312.262,250.539 312.725,250.539 312.534 C 250.543 311.763,248.835 309.501,247.662 308.721 L 246.411 307.890 247.659 309.009 M154.103 309.046 C 152.905 310.441,152.914 310.880,154.118 309.759 C 154.801 309.124,155.359 308.549,155.359 308.481 C 155.359 308.114,154.616 308.449,154.103 309.046 M249.555 322.376 C 249.140 323.147,248.174 324.309,247.409 324.958 C 246.644 325.607,246.372 325.959,246.804 325.741 C 248.104 325.083,250.909 321.574,250.479 321.144 C 250.386 321.051,249.970 321.606,249.555 322.376 M152.606 322.870 C 152.606 323.562,155.506 326.451,156.198 326.448 C 156.493 326.446,156.205 326.098,155.556 325.673 C 154.907 325.248,153.977 324.325,153.491 323.622 C 153.004 322.918,152.606 322.580,152.606 322.870 M164.110 331.952 C 163.407 332.381,162.832 332.820,162.832 332.928 C 162.832 333.037,163.407 332.774,164.110 332.346 C 165.898 331.256,235.497 331.107,237.776 332.188 C 239.212 332.870,242.675 336.354,242.675 337.119 C 242.675 337.380,242.783 337.486,242.916 337.353 C 243.657 336.612,239.644 332.430,237.360 331.562 C 235.081 330.695,165.564 331.066,164.110 331.952 M243.574 341.200 C 243.577 342.281,243.653 342.677,243.743 342.079 C 243.834 341.481,243.831 340.596,243.738 340.113 C 243.645 339.629,243.571 340.118,243.574 341.200 M158.623 341.790 C 158.623 342.979,158.697 343.466,158.787 342.871 C 158.877 342.276,158.877 341.303,158.787 340.708 C 158.697 340.113,158.623 340.600,158.623 341.790 M159.294 346.345 C 159.295 346.787,160.780 349.263,161.043 349.263 C 161.147 349.263,160.852 348.599,160.388 347.788 C 159.347 345.971,159.292 345.897,159.294 346.345 M241.294 347.827 C 240.643 348.706,239.346 350.008,238.412 350.720 C 237.478 351.433,236.915 352.016,237.161 352.016 C 237.706 352.016,241.802 348.191,242.347 347.173 C 243.052 345.856,242.502 346.198,241.294 347.827 M163.170 351.206 C 163.681 351.651,164.286 352.016,164.514 352.016 C 164.998 352.016,164.975 351.996,163.422 351.087 L 162.242 350.396 163.170 351.206 M176.591 353.472 C 177.119 354.593,180.789 358.792,181.644 359.254 C 182.005 359.449,181.236 358.476,179.934 357.091 C 178.632 355.706,177.255 354.130,176.874 353.589 C 176.318 352.798,176.262 352.776,176.591 353.472 M222.374 357.012 C 221.541 358.030,221.064 358.735,221.315 358.580 C 221.850 358.249,224.341 355.162,224.073 355.162 C 223.972 355.162,223.208 355.995,222.374 357.012 M184.857 361.274 C 184.857 361.559,188.834 363.474,189.160 363.346 C 189.329 363.279,188.430 362.748,187.162 362.165 C 185.895 361.582,184.857 361.181,184.857 361.274 M215.536 362.045 C 214.562 362.566,214.011 363.001,214.310 363.011 C 214.847 363.028,217.502 361.544,217.502 361.227 C 217.502 360.993,217.494 360.997,215.536 362.045 M199.312 365.285 C 200.447 365.365,202.306 365.365,203.441 365.285 C 204.577 365.206,203.648 365.141,201.377 365.141 C 199.105 365.141,198.176 365.206,199.312 365.285 \" stroke=\"none\" fill=\"#fc7b8c\" fill-rule=\"evenodd\"><\/path><path id=\"path3\" d=\"M189.863 0.284 C 190.562 0.371,191.801 0.372,192.617 0.287 C 193.433 0.202,192.861 0.131,191.347 0.129 C 189.833 0.127,189.165 0.197,189.863 0.284 M207.169 0.284 C 207.867 0.371,209.106 0.372,209.922 0.287 C 210.738 0.202,210.167 0.131,208.653 0.129 C 207.139 0.127,206.471 0.197,207.169 0.284 M183.190 0.671 C 183.680 0.766,184.388 0.762,184.764 0.664 C 185.140 0.565,184.739 0.488,183.874 0.493 C 183.009 0.497,182.701 0.577,183.190 0.671 M215.442 0.671 C 215.931 0.766,216.639 0.762,217.015 0.664 C 217.391 0.565,216.991 0.488,216.126 0.493 C 215.261 0.497,214.953 0.577,215.442 0.671 M167.945 2.360 C 167.421 2.699,167.421 2.741,167.945 2.741 C 168.269 2.741,168.800 2.570,169.125 2.360 C 169.649 2.021,169.649 1.979,169.125 1.979 C 168.800 1.979,168.269 2.150,167.945 2.360 M231.072 2.360 C 231.205 2.576,231.580 2.753,231.905 2.753 C 232.229 2.753,232.385 2.576,232.252 2.360 C 232.118 2.144,231.743 1.967,231.419 1.967 C 231.094 1.967,230.938 2.144,231.072 2.360 M162.635 3.147 C 161.938 3.446,161.972 3.488,162.930 3.512 C 163.525 3.527,164.012 3.363,164.012 3.147 C 164.012 2.685,163.709 2.685,162.635 3.147 M236.382 3.147 C 236.382 3.363,236.780 3.537,237.266 3.534 C 237.982 3.529,238.039 3.455,237.561 3.147 C 236.799 2.654,236.382 2.654,236.382 3.147 M253.687 7.134 C 253.687 7.321,253.938 7.473,254.245 7.473 C 254.552 7.473,255.112 7.592,255.490 7.736 C 255.922 7.902,256.082 7.847,255.921 7.587 C 255.599 7.066,253.687 6.678,253.687 7.134 M132.842 10.772 C 132.247 10.988,131.760 11.326,131.760 11.524 C 131.760 11.722,132.042 11.775,132.387 11.643 C 132.731 11.511,133.439 11.296,133.960 11.165 C 134.946 10.918,135.271 10.349,134.415 10.368 C 134.145 10.374,133.437 10.556,132.842 10.772 M124.067 14.388 C 123.369 14.957,123.365 14.991,124.024 14.781 C 124.421 14.656,124.907 14.553,125.106 14.553 C 125.305 14.553,125.467 14.376,125.467 14.159 C 125.467 13.590,124.942 13.676,124.067 14.388 M275.100 14.368 C 275.520 14.686,276.051 14.940,276.280 14.933 C 276.509 14.927,276.353 14.661,275.933 14.343 C 275.513 14.026,274.982 13.772,274.753 13.778 C 274.524 13.785,274.680 14.051,275.100 14.368 M283.972 18.088 C 283.972 18.264,284.503 18.594,285.152 18.820 C 285.801 19.046,286.332 19.102,286.332 18.945 C 286.332 18.787,285.801 18.458,285.152 18.213 C 284.503 17.968,283.972 17.912,283.972 18.088 M114.356 18.390 C 113.977 18.475,113.668 18.707,113.668 18.908 C 113.668 19.369,114.094 19.364,114.836 18.894 C 115.543 18.448,115.290 18.183,114.356 18.390 M106.883 22.089 C 106.288 22.307,105.801 22.643,105.801 22.837 C 105.801 23.190,107.637 22.549,108.338 21.951 C 108.831 21.531,108.264 21.585,106.883 22.089 M292.232 21.971 C 292.232 22.148,292.675 22.494,293.215 22.741 C 293.756 22.987,294.199 23.044,294.199 22.867 C 294.199 22.690,293.756 22.344,293.215 22.097 C 292.675 21.851,292.232 21.794,292.232 21.971 M101.278 25.199 C 100.629 25.614,99.921 26.020,99.705 26.099 C 99.489 26.179,99.408 26.350,99.526 26.479 C 99.643 26.609,100.528 26.191,101.492 25.552 C 102.456 24.912,103.068 24.401,102.852 24.416 C 102.635 24.431,101.927 24.783,101.278 25.199 M299.312 25.979 C 300.354 26.689,302.065 27.558,302.065 27.377 C 302.065 27.124,299.478 25.564,299.069 25.571 C 298.878 25.575,298.987 25.758,299.312 25.979 M304.031 28.459 C 304.031 28.755,307.178 30.681,307.184 30.389 C 307.187 30.224,307.362 30.354,307.571 30.678 C 307.781 31.003,307.955 31.066,307.959 30.818 C 307.962 30.570,307.080 29.905,305.998 29.339 C 304.916 28.774,304.031 28.378,304.031 28.459 M93.684 29.484 C 92.969 29.884,92.544 30.310,92.741 30.431 C 92.937 30.553,93.690 30.216,94.413 29.682 C 95.950 28.548,95.552 28.440,93.684 29.484 M87.043 34.045 C 86.316 34.709,86.207 34.920,86.726 34.664 C 87.980 34.045,89.129 33.065,88.616 33.051 C 88.357 33.044,87.650 33.492,87.043 34.045 M311.701 33.670 C 313.206 34.830,314.115 35.101,312.957 34.045 C 312.350 33.492,311.643 33.044,311.384 33.051 C 311.126 33.058,311.268 33.336,311.701 33.670 M83.088 36.623 C 82.384 37.074,81.809 37.633,81.809 37.865 C 81.809 38.098,82.296 37.862,82.891 37.341 C 83.486 36.820,84.141 36.258,84.346 36.092 C 85.067 35.512,84.353 35.813,83.088 36.623 M316.618 36.890 C 317.375 37.542,318.082 37.989,318.190 37.884 C 318.402 37.678,317.291 36.767,316.028 36.113 C 315.595 35.889,315.860 36.238,316.618 36.890 M318.645 38.138 C 318.727 38.384,319.411 38.947,320.164 39.389 C 320.917 39.831,321.180 39.907,320.747 39.558 C 320.315 39.209,319.631 38.646,319.228 38.307 C 318.825 37.968,318.563 37.892,318.645 38.138 M78.128 40.339 C 77.077 41.083,76.458 41.685,76.752 41.676 C 77.046 41.668,77.994 41.052,78.859 40.306 C 80.848 38.592,80.580 38.604,78.128 40.339 M321.731 40.681 C 321.731 40.775,322.232 41.208,322.845 41.645 C 323.688 42.245,323.959 42.303,323.959 41.885 C 323.959 41.581,323.832 41.411,323.676 41.508 C 323.520 41.604,323.174 41.419,322.907 41.097 C 322.454 40.551,321.731 40.296,321.731 40.681 M74.533 43.265 C 73.716 43.913,72.902 44.444,72.723 44.444 C 72.544 44.444,72.190 44.833,71.936 45.307 C 71.572 45.987,71.829 45.882,73.145 44.816 C 74.065 44.071,75.195 43.155,75.658 42.782 C 76.121 42.408,76.391 42.098,76.259 42.093 C 76.126 42.088,75.350 42.616,74.533 43.265 M326.057 44.060 C 326.057 44.285,326.367 44.585,326.745 44.727 C 327.124 44.869,327.628 45.245,327.865 45.561 C 328.103 45.878,328.398 45.974,328.521 45.775 C 328.644 45.575,328.140 45.016,327.401 44.531 C 326.662 44.047,326.057 43.835,326.057 44.060 M180.138 44.458 C 179.503 44.669,179.921 44.706,181.318 44.562 C 182.507 44.439,183.555 44.273,183.645 44.195 C 183.960 43.919,181.112 44.132,180.138 44.458 M228.548 44.193 C 228.638 44.271,229.508 44.440,230.482 44.569 C 231.664 44.725,231.990 44.687,231.465 44.455 C 230.714 44.122,228.206 43.897,228.548 44.193 M331.563 48.574 C 332.071 49.115,332.664 49.558,332.880 49.558 C 333.097 49.558,332.858 49.115,332.350 48.574 C 331.842 48.033,331.249 47.591,331.033 47.591 C 330.817 47.591,331.055 48.033,331.563 48.574 M68.001 48.476 C 66.602 49.650,66.241 50.518,67.552 49.559 C 68.255 49.044,68.830 48.479,68.830 48.304 C 68.830 47.870,68.687 47.900,68.001 48.476 M63.738 52.126 C 63.208 52.647,62.863 53.161,62.970 53.268 C 63.161 53.460,65.290 51.664,65.290 51.312 C 65.290 50.897,64.639 51.238,63.738 52.126 M335.467 52.061 C 335.991 52.631,336.588 53.097,336.793 53.097 C 337.321 53.097,336.310 51.957,335.332 51.449 C 334.601 51.070,334.616 51.136,335.467 52.061 M338.643 54.794 C 338.643 54.861,339.218 55.437,339.921 56.072 L 341.200 57.227 340.044 55.949 C 338.968 54.757,338.643 54.490,338.643 54.794 M342.183 58.084 C 342.183 58.285,342.802 59.050,343.559 59.784 C 344.317 60.518,344.936 61.029,344.936 60.921 C 344.936 60.813,344.317 60.048,343.559 59.221 C 342.802 58.395,342.183 57.883,342.183 58.084 M268.437 58.808 C 268.869 59.160,269.577 59.622,270.010 59.834 L 270.796 60.220 270.010 59.580 C 269.577 59.228,268.869 58.766,268.437 58.553 L 267.650 58.167 268.437 58.808 M51.958 63.927 C 50.829 65.213,50.537 65.683,50.868 65.683 C 50.940 65.683,51.568 64.975,52.263 64.110 C 53.827 62.165,53.616 62.038,51.958 63.927 M274.959 62.664 C 275.049 62.734,275.742 63.191,276.500 63.680 L 277.876 64.568 276.696 63.555 C 276.047 62.997,275.354 62.540,275.156 62.539 C 274.957 62.538,274.869 62.594,274.959 62.664 M347.894 64.208 C 348.738 65.236,349.492 66.077,349.569 66.077 C 349.851 66.077,348.142 63.891,347.263 63.127 C 346.765 62.694,347.049 63.181,347.894 64.208 M350.442 67.055 C 350.767 67.486,351.455 68.282,351.973 68.825 L 352.913 69.813 352.089 68.598 C 351.636 67.930,350.948 67.134,350.559 66.828 C 349.900 66.310,349.892 66.326,350.442 67.055 M48.718 67.549 C 47.368 69.179,47.166 69.713,48.354 68.511 C 49.062 67.795,49.562 67.131,49.466 67.034 C 49.369 66.937,49.033 67.169,48.718 67.549 M119.174 70.830 L 117.404 72.434 119.272 70.978 C 120.910 69.701,121.396 69.220,121.042 69.224 C 120.988 69.225,120.147 69.947,119.174 70.830 M45.224 71.399 C 44.526 72.705,44.961 73.038,45.763 71.813 C 46.115 71.276,46.254 70.746,46.073 70.634 C 45.891 70.522,45.510 70.866,45.224 71.399 M354.006 71.508 C 354.534 72.174,355.105 72.729,355.274 72.741 C 355.845 72.781,354.760 71.213,353.899 70.752 C 353.087 70.317,353.092 70.353,354.006 71.508 M290.265 73.269 C 290.265 73.371,291.276 74.316,292.511 75.370 C 293.746 76.424,294.631 77.081,294.476 76.830 C 294.139 76.281,290.265 73.005,290.265 73.269 M41.832 76.008 C 40.751 77.360,39.555 78.997,39.175 79.646 C 38.496 80.806,38.497 80.809,39.203 79.852 C 39.598 79.316,40.376 78.343,40.931 77.689 C 42.409 75.948,44.171 73.550,43.972 73.550 C 43.877 73.550,42.914 74.656,41.832 76.008 M356.551 74.336 C 357.028 75.171,360.777 79.843,360.969 79.843 C 361.208 79.843,358.272 75.906,357.172 74.752 C 356.645 74.199,356.365 74.012,356.551 74.336 M296.165 78.466 C 296.899 79.223,297.588 79.843,297.696 79.843 C 297.804 79.843,297.292 79.223,296.559 78.466 C 295.825 77.709,295.136 77.089,295.028 77.089 C 294.919 77.089,295.431 77.709,296.165 78.466 M362.279 81.908 C 363.947 84.081,364.521 84.641,363.691 83.284 C 362.181 80.818,361.739 80.236,361.377 80.236 C 361.167 80.236,361.573 80.988,362.279 81.908 M37.014 82.142 C 35.850 83.778,35.980 84.079,37.217 82.609 C 37.785 81.935,38.158 81.291,38.047 81.180 C 37.935 81.069,37.471 81.502,37.014 82.142 M197.837 84.960 C 196.214 85.099,198.250 85.132,202.360 85.031 C 206.470 84.931,209.907 84.785,209.997 84.706 C 210.249 84.485,201.155 84.675,197.837 84.960 M210.456 85.098 C 210.546 85.176,212.566 85.331,214.946 85.443 C 217.709 85.573,218.633 85.532,217.502 85.330 C 215.733 85.014,210.146 84.830,210.456 85.098 M192.237 85.627 C 192.726 85.721,193.434 85.718,193.810 85.619 C 194.186 85.521,193.786 85.444,192.920 85.448 C 192.055 85.453,191.747 85.533,192.237 85.627 M34.156 86.431 C 32.920 87.905,32.031 89.567,32.879 88.817 C 33.614 88.167,35.202 85.742,34.891 85.742 C 34.805 85.742,34.474 86.052,34.156 86.431 M365.480 86.529 C 365.750 86.962,366.112 87.316,366.283 87.316 C 366.455 87.316,366.407 86.962,366.175 86.529 C 365.943 86.096,365.582 85.742,365.371 85.742 C 365.159 85.742,365.208 86.093,365.480 86.529 M172.075 89.465 C 170.524 90.175,170.874 90.187,173.058 89.499 C 174.031 89.192,174.474 88.938,174.041 88.933 C 173.609 88.928,172.724 89.167,172.075 89.465 M307.571 89.799 C 307.571 89.866,308.147 90.441,308.850 91.077 L 310.128 92.232 308.973 90.954 C 307.896 89.762,307.571 89.495,307.571 89.799 M29.537 93.314 C 28.690 94.901,28.687 94.936,29.476 94.002 C 30.613 92.658,31.167 91.642,30.765 91.642 C 30.581 91.642,30.028 92.394,29.537 93.314 M369.963 93.223 C 370.539 94.093,371.085 94.729,371.177 94.637 C 371.403 94.411,369.596 91.653,369.218 91.647 C 369.052 91.644,369.388 92.354,369.963 93.223 M244.674 92.575 C 245.079 92.937,247.394 94.002,247.394 93.826 C 247.394 93.599,245.214 92.429,244.792 92.429 C 244.637 92.429,244.584 92.495,244.674 92.575 M94.395 95.182 C 93.490 96.264,92.837 97.148,92.945 97.148 C 93.054 97.148,93.883 96.264,94.789 95.182 C 95.694 94.100,96.347 93.215,96.238 93.215 C 96.130 93.215,95.301 94.100,94.395 95.182 M252.507 96.774 C 253.872 97.700,254.649 97.970,253.687 97.184 C 253.147 96.741,252.527 96.378,252.311 96.377 C 252.094 96.375,252.183 96.554,252.507 96.774 M27.007 97.573 C 26.622 98.022,26.364 98.560,26.433 98.767 C 26.502 98.975,26.876 98.607,27.264 97.950 C 28.087 96.557,27.994 96.420,27.007 97.573 M373.438 99.090 C 374.309 100.774,374.962 100.995,374.172 99.339 C 373.804 98.567,373.354 97.935,373.172 97.935 C 372.990 97.935,373.110 98.455,373.438 99.090 M25.232 100.517 C 24.970 101.093,24.942 101.421,25.167 101.281 C 25.744 100.925,26.438 99.508,26.036 99.508 C 25.846 99.508,25.485 99.962,25.232 100.517 M148.068 101.967 L 146.116 104.031 148.181 102.080 C 149.317 101.006,150.246 100.077,150.246 100.015 C 150.246 99.721,149.881 100.048,148.068 101.967 M316.272 103.057 C 316.867 104.818,317.203 105.160,316.842 103.638 C 316.688 102.989,316.393 102.285,316.186 102.074 C 315.979 101.862,316.018 102.305,316.272 103.057 M376.866 105.211 C 377.112 105.752,377.459 106.195,377.636 106.195 C 377.813 106.195,377.756 105.752,377.510 105.211 C 377.263 104.671,376.917 104.228,376.740 104.228 C 376.563 104.228,376.620 104.671,376.866 105.211 M21.920 106.588 C 21.580 107.453,21.373 108.161,21.459 108.161 C 21.546 108.161,21.977 107.453,22.419 106.588 C 22.860 105.723,23.068 105.015,22.880 105.015 C 22.692 105.015,22.260 105.723,21.920 106.588 M86.567 106.415 C 86.113 107.185,85.920 107.705,86.138 107.570 C 86.564 107.307,87.841 105.015,87.561 105.015 C 87.469 105.015,87.022 105.645,86.567 106.415 M144.228 106.293 C 143.160 107.736,142.441 108.979,143.032 108.358 C 143.762 107.591,145.563 105.015,145.369 105.015 C 145.261 105.015,144.747 105.590,144.228 106.293 M270.010 109.341 C 271.075 110.423,272.035 111.308,272.143 111.308 C 272.252 111.308,271.468 110.423,270.403 109.341 C 269.338 108.260,268.378 107.375,268.269 107.375 C 268.161 107.375,268.944 108.260,270.010 109.341 M381.099 113.625 C 381.553 114.514,381.999 115.241,382.092 115.241 C 382.476 115.241,381.213 112.322,380.764 112.172 C 380.461 112.071,380.589 112.624,381.099 113.625 M18.213 114.061 C 17.968 114.710,17.912 115.241,18.088 115.241 C 18.264 115.241,18.594 114.710,18.820 114.061 C 19.046 113.412,19.102 112.881,18.945 112.881 C 18.787 112.881,18.458 113.412,18.213 114.061 M316.460 114.494 C 316.316 115.395,316.275 116.209,316.369 116.303 C 316.463 116.397,316.663 115.742,316.814 114.848 C 316.965 113.953,317.006 113.139,316.906 113.038 C 316.805 112.937,316.604 113.592,316.460 114.494 M139.872 116.863 C 139.549 118.479,139.607 125.869,139.949 126.729 C 140.096 127.098,140.216 124.753,140.216 121.517 C 140.216 115.043,140.222 115.116,139.872 116.863 M278.386 120.944 C 279.176 122.116,280.679 123.584,282.223 124.692 C 282.667 125.010,282.401 124.705,281.633 124.013 C 280.865 123.322,279.641 122.083,278.914 121.260 C 277.939 120.157,277.800 120.074,278.386 120.944 M14.945 121.339 C 14.716 121.941,14.435 122.585,14.321 122.771 C 14.206 122.956,14.283 123.107,14.491 123.107 C 14.908 123.107,15.848 120.731,15.549 120.432 C 15.446 120.329,15.174 120.737,14.945 121.339 M384.467 121.042 C 384.623 121.421,384.839 122.040,384.948 122.419 C 385.057 122.797,385.286 123.107,385.456 123.107 C 385.627 123.107,385.577 122.488,385.345 121.731 C 385.112 120.973,384.756 120.354,384.553 120.354 C 384.350 120.354,384.311 120.664,384.467 121.042 M78.727 121.747 C 78.068 123.194,78.193 123.502,78.906 122.187 C 79.239 121.573,79.437 120.997,79.347 120.908 C 79.257 120.818,78.978 121.196,78.727 121.747 M306.391 127.434 C 305.634 127.848,305.156 128.195,305.329 128.204 C 305.746 128.226,307.965 127.072,307.965 126.834 C 307.965 126.576,307.942 126.585,306.391 127.434 M388.498 131.563 C 388.601 132.104,388.836 132.547,389.021 132.547 C 389.205 132.547,389.254 132.812,389.129 133.137 C 389.005 133.461,389.083 133.727,389.304 133.727 C 389.719 133.727,389.707 133.476,389.203 131.662 C 388.827 130.310,388.243 130.229,388.498 131.563 M10.899 131.760 C 10.786 132.193,10.833 132.547,11.004 132.547 C 11.175 132.547,11.407 132.193,11.520 131.760 C 11.633 131.327,11.586 130.973,11.415 130.973 C 11.244 130.973,11.012 131.327,10.899 131.760 M148.673 139.016 C 148.673 139.124,149.204 139.487,149.853 139.823 C 150.501 140.159,151.032 140.345,151.032 140.237 C 151.032 140.128,150.501 139.765,149.853 139.430 C 149.204 139.094,148.673 138.908,148.673 139.016 M392.378 143.854 C 392.663 145.042,392.836 145.349,393.082 145.100 C 393.371 144.807,392.839 142.773,392.474 142.773 C 392.278 142.773,392.236 143.260,392.378 143.854 M176.111 147.377 C 176.600 147.472,177.308 147.468,177.684 147.370 C 178.060 147.271,177.660 147.194,176.794 147.198 C 175.929 147.203,175.622 147.283,176.111 147.377 M178.761 147.692 C 179.660 148.005,182.034 148.091,181.857 147.804 C 181.751 147.633,180.923 147.507,180.016 147.524 C 179.110 147.541,178.545 147.616,178.761 147.692 M236.676 150.917 C 237.163 151.010,237.960 151.010,238.446 150.917 C 238.933 150.823,238.535 150.746,237.561 150.746 C 236.588 150.746,236.190 150.823,236.676 150.917 M240.413 151.314 C 241.008 151.404,241.981 151.404,242.576 151.314 C 243.171 151.224,242.684 151.150,241.495 151.150 C 240.305 151.150,239.818 151.224,240.413 151.314 M261.357 154.966 C 261.790 155.151,262.498 155.298,262.930 155.292 C 263.563 155.283,263.524 155.219,262.734 154.966 C 261.389 154.535,260.355 154.535,261.357 154.966 M396.073 159.390 C 396.070 159.985,396.244 160.472,396.460 160.472 C 396.957 160.472,396.957 159.668,396.460 158.899 C 396.163 158.439,396.078 158.548,396.073 159.390 M396.466 161.554 C 396.463 162.040,396.637 162.439,396.853 162.439 C 397.346 162.439,397.346 162.021,396.853 161.259 C 396.545 160.782,396.471 160.838,396.466 161.554 M3.027 161.807 C 2.866 162.216,2.827 162.644,2.941 162.757 C 3.299 163.116,3.615 162.528,3.465 161.781 C 3.327 161.097,3.306 161.098,3.027 161.807 M2.643 164.142 C 2.205 165.257,2.276 165.826,2.790 165.312 C 3.027 165.076,3.154 164.553,3.073 164.152 C 2.932 163.448,2.917 163.447,2.643 164.142 M2.253 167.003 C 2.096 167.160,1.967 167.561,1.967 167.892 C 1.967 168.335,2.083 168.379,2.404 168.058 C 2.645 167.817,2.774 167.417,2.691 167.168 C 2.608 166.919,2.411 166.845,2.253 167.003 M293.553 168.642 C 293.864 169.145,296.165 170.848,296.165 170.575 C 296.165 170.478,295.515 169.903,294.721 169.297 C 293.927 168.691,293.402 168.396,293.553 168.642 M300.492 174.828 C 302.321 176.667,303.906 178.171,304.014 178.171 C 304.122 178.171,302.714 176.667,300.885 174.828 C 299.056 172.989,297.471 171.485,297.362 171.485 C 297.254 171.485,298.662 172.989,300.492 174.828 M138.227 176.773 C 138.647 177.109,139.266 177.370,139.603 177.353 C 140.133 177.327,140.136 177.293,139.626 177.104 C 139.302 176.983,138.682 176.722,138.250 176.523 C 137.476 176.167,137.475 176.171,138.227 176.773 M398.911 178.564 C 398.911 179.322,398.992 179.631,399.091 179.253 C 399.190 178.874,399.190 178.255,399.091 177.876 C 398.992 177.498,398.911 177.807,398.911 178.564 M0.878 178.958 C 0.878 179.715,0.959 180.025,1.058 179.646 C 1.157 179.267,1.157 178.648,1.058 178.269 C 0.959 177.891,0.878 178.201,0.878 178.958 M149.837 181.130 C 150.802 181.431,151.651 181.616,151.725 181.543 C 151.926 181.341,149.436 180.527,148.712 180.557 C 148.366 180.572,148.872 180.830,149.837 181.130 M399.320 184.071 C 399.320 185.044,399.397 185.442,399.491 184.956 C 399.585 184.469,399.585 183.673,399.491 183.186 C 399.397 182.699,399.320 183.097,399.320 184.071 M0.506 185.054 C 0.509 186.136,0.585 186.531,0.676 185.934 C 0.766 185.336,0.764 184.451,0.670 183.967 C 0.577 183.483,0.503 183.972,0.506 185.054 M165.388 184.857 C 167.052 185.281,168.480 185.281,167.158 184.857 C 166.618 184.684,165.733 184.546,165.192 184.550 C 164.309 184.556,164.329 184.588,165.388 184.857 M227.761 188.149 C 227.852 188.229,229.253 188.394,230.875 188.514 C 233.062 188.677,233.418 188.645,232.252 188.391 C 230.678 188.049,227.453 187.875,227.761 188.149 M112.180 189.381 C 112.184 189.813,112.323 190.698,112.488 191.347 C 112.757 192.407,112.789 192.427,112.795 191.544 C 112.799 191.003,112.661 190.118,112.488 189.577 C 112.241 188.807,112.174 188.764,112.180 189.381 M399.760 196.460 C 399.760 199.272,399.823 200.371,399.899 198.902 C 399.975 197.433,399.974 195.132,399.897 193.789 C 399.821 192.446,399.759 193.648,399.760 196.460 M254.065 192.536 C 255.030 192.837,255.880 193.022,255.953 192.949 C 256.154 192.748,253.664 191.933,252.940 191.963 C 252.594 191.978,253.100 192.236,254.065 192.536 M0.112 196.460 C 0.115 197.542,0.192 197.938,0.282 197.340 C 0.373 196.742,0.370 195.857,0.277 195.373 C 0.184 194.889,0.110 195.379,0.112 196.460 M269.420 199.823 C 270.784 200.749,271.561 201.018,270.600 200.232 C 270.059 199.789,269.440 199.426,269.223 199.425 C 269.007 199.423,269.095 199.602,269.420 199.823 M116.072 205.113 C 116.080 205.329,116.426 206.214,116.842 207.080 C 117.259 207.945,117.489 208.210,117.354 207.670 C 117.077 206.556,116.052 204.511,116.072 205.113 M0.506 207.866 C 0.509 208.948,0.585 209.344,0.676 208.746 C 0.766 208.148,0.764 207.263,0.670 206.779 C 0.577 206.296,0.503 206.785,0.506 207.866 M399.320 208.850 C 399.320 209.823,399.397 210.221,399.491 209.735 C 399.585 209.248,399.585 208.451,399.491 207.965 C 399.397 207.478,399.320 207.876,399.320 208.850 M279.056 215.733 C 279.056 218.029,279.171 219.500,279.312 219.001 C 279.453 218.501,279.568 217.030,279.568 215.733 C 279.568 214.435,279.453 212.964,279.312 212.464 C 279.171 211.965,279.056 213.436,279.056 215.733 M74.398 212.193 C 74.397 212.409,74.635 213.206,74.926 213.963 C 75.218 214.720,75.462 215.074,75.469 214.749 C 75.475 214.425,75.238 213.628,74.940 212.979 C 74.643 212.330,74.399 211.976,74.398 212.193 M0.878 213.963 C 0.878 214.720,0.959 215.029,1.058 214.651 C 1.157 214.272,1.157 213.653,1.058 213.274 C 0.959 212.896,0.878 213.206,0.878 213.963 M124.167 221.859 C 124.557 222.525,125.128 223.277,125.436 223.531 C 125.743 223.785,125.498 223.240,124.892 222.321 C 123.619 220.390,123.116 220.071,124.167 221.859 M1.967 225.126 C 1.967 225.450,2.144 225.825,2.360 225.959 C 2.576 226.092,2.753 225.936,2.753 225.612 C 2.753 225.287,2.576 224.912,2.360 224.779 C 2.144 224.645,1.967 224.801,1.967 225.126 M316.439 228.336 C 316.288 229.340,316.246 230.241,316.344 230.339 C 316.442 230.438,316.646 229.697,316.796 228.694 C 316.947 227.691,316.989 226.789,316.891 226.691 C 316.793 226.593,316.589 227.333,316.439 228.336 M2.366 227.804 C 2.377 228.791,3.134 229.605,3.140 228.637 C 3.144 228.163,2.970 227.666,2.753 227.532 C 2.537 227.398,2.363 227.521,2.366 227.804 M274.822 228.616 L 274.128 229.892 274.921 228.963 C 275.595 228.173,275.955 227.329,275.615 227.338 C 275.560 227.339,275.204 227.914,274.822 228.616 M397.140 227.966 C 396.983 228.124,396.859 228.622,396.865 229.072 C 396.876 229.829,396.909 229.838,397.287 229.189 C 397.727 228.433,397.614 227.492,397.140 227.966 M2.781 230.383 C 2.889 231.537,3.486 232.179,3.512 231.170 C 3.527 230.575,3.363 230.088,3.147 230.088 C 2.930 230.088,2.766 230.221,2.781 230.383 M396.466 231.367 C 396.471 232.082,396.545 232.139,396.853 231.662 C 397.346 230.899,397.346 230.482,396.853 230.482 C 396.637 230.482,396.463 230.880,396.466 231.367 M82.203 231.159 C 82.203 231.388,82.567 231.992,83.013 232.503 L 83.822 233.432 83.132 232.252 C 82.222 230.699,82.203 230.676,82.203 231.159 M270.772 233.892 C 270.166 234.686,269.871 235.212,270.117 235.060 C 270.620 234.749,272.323 232.448,272.050 232.448 C 271.953 232.448,271.378 233.098,270.772 233.892 M313.471 238.824 C 313.471 238.942,313.203 239.680,312.876 240.463 C 312.548 241.247,312.369 241.888,312.477 241.888 C 312.789 241.888,313.897 239.036,313.673 238.812 C 313.562 238.701,313.471 238.707,313.471 238.824 M262.119 242.380 L 260.964 243.658 262.242 242.503 C 262.945 241.867,263.520 241.292,263.520 241.224 C 263.520 240.920,263.196 241.188,262.119 242.380 M90.462 244.641 C 90.924 245.290,91.391 245.821,91.499 245.821 C 91.607 245.821,91.318 245.290,90.855 244.641 C 90.393 243.992,89.927 243.461,89.819 243.461 C 89.710 243.461,90.000 243.992,90.462 244.641 M148.279 245.571 C 148.279 245.679,148.810 246.146,149.459 246.608 C 150.108 247.070,150.639 247.359,150.639 247.251 C 150.639 247.143,150.108 246.676,149.459 246.214 C 148.810 245.752,148.279 245.463,148.279 245.571 M6.995 248.964 C 7.090 249.610,7.301 250.057,7.464 249.956 C 7.823 249.735,7.497 247.788,7.102 247.788 C 6.948 247.788,6.900 248.317,6.995 248.964 M392.768 248.223 C 392.673 248.524,392.404 249.373,392.168 250.108 C 391.651 251.725,391.651 251.721,392.102 251.721 C 392.469 251.721,393.391 248.127,393.098 247.835 C 393.011 247.747,392.862 247.922,392.768 248.223 M250.439 250.114 C 248.823 251.150,248.599 251.515,250.024 250.790 C 250.714 250.440,251.388 249.975,251.522 249.757 C 251.838 249.247,251.744 249.278,250.439 250.114 M304.818 255.654 C 304.356 256.303,304.066 256.834,304.175 256.834 C 304.283 256.834,304.749 256.303,305.211 255.654 C 305.674 255.005,305.963 254.474,305.855 254.474 C 305.747 254.474,305.280 255.005,304.818 255.654 M101.065 258.112 C 102.695 259.849,103.048 260.161,103.048 259.866 C 103.048 259.802,102.207 258.962,101.180 257.997 L 99.312 256.244 101.065 258.112 M10.917 261.357 C 11.020 261.898,11.280 262.340,11.494 262.340 C 11.708 262.340,11.776 262.060,11.645 261.718 C 11.514 261.376,11.406 260.933,11.406 260.735 C 11.406 260.536,11.254 260.374,11.067 260.374 C 10.881 260.374,10.813 260.816,10.917 261.357 M106.391 263.913 C 108.329 265.860,110.003 267.453,110.111 267.453 C 110.220 267.453,108.723 265.860,106.785 263.913 C 104.847 261.967,103.173 260.374,103.065 260.374 C 102.956 260.374,104.453 261.967,106.391 263.913 M192.429 261.825 C 192.807 261.924,193.427 261.924,193.805 261.825 C 194.184 261.726,193.874 261.645,193.117 261.645 C 192.360 261.645,192.050 261.726,192.429 261.825 M214.656 261.832 C 215.145 261.926,215.853 261.922,216.229 261.824 C 216.605 261.725,216.205 261.648,215.339 261.653 C 214.474 261.657,214.166 261.738,214.656 261.832 M197.837 262.346 C 201.353 262.671,208.310 262.836,208.030 262.588 C 207.940 262.508,204.857 262.352,201.180 262.240 C 196.621 262.102,195.557 262.136,197.837 262.346 M209.529 262.231 C 210.227 262.318,211.466 262.319,212.282 262.234 C 213.098 262.149,212.527 262.078,211.013 262.076 C 209.499 262.074,208.831 262.144,209.529 262.231 M112.078 269.125 C 113.708 270.861,114.061 271.174,114.061 270.878 C 114.061 270.815,113.220 269.975,112.193 269.010 L 110.324 267.257 112.078 269.125 M14.460 270.403 C 14.820 271.377,15.246 272.173,15.405 272.173 C 15.565 272.173,15.400 271.377,15.039 270.403 C 14.678 269.430,14.253 268.633,14.093 268.633 C 13.934 268.633,14.099 269.430,14.460 270.403 M385.447 269.420 C 385.196 269.890,385.079 270.362,385.187 270.471 C 385.295 270.579,385.589 270.283,385.841 269.813 C 386.092 269.343,386.209 268.871,386.101 268.763 C 385.993 268.654,385.699 268.950,385.447 269.420 M384.506 271.615 C 384.189 272.441,384.204 272.566,384.615 272.566 C 384.806 272.566,385.055 272.212,385.168 271.780 C 385.411 270.851,384.853 270.712,384.506 271.615 M284.562 276.346 L 282.989 277.754 284.661 276.504 C 286.099 275.428,286.618 274.909,286.234 274.932 C 286.180 274.935,285.428 275.572,284.562 276.346 M18.474 279.624 C 19.108 280.808,19.735 281.015,19.212 279.868 C 18.960 279.313,18.598 278.859,18.409 278.859 C 18.220 278.859,18.249 279.204,18.474 279.624 M380.787 280.039 C 380.560 280.688,380.504 281.219,380.662 281.219 C 380.820 281.219,381.149 280.688,381.394 280.039 C 381.639 279.390,381.695 278.859,381.519 278.859 C 381.342 278.859,381.013 279.390,380.787 280.039 M125.074 279.375 C 125.074 279.467,125.826 280.038,126.745 280.644 C 127.665 281.250,128.209 281.495,127.956 281.188 C 127.468 280.597,125.074 279.091,125.074 279.375 M20.452 283.298 C 20.452 283.860,21.392 285.546,21.704 285.546 C 21.891 285.546,21.739 285.059,21.367 284.464 C 20.483 283.052,20.452 283.012,20.452 283.298 M377.053 287.352 C 376.656 288.184,376.561 288.704,376.822 288.617 C 377.343 288.444,378.471 285.939,378.028 285.939 C 377.862 285.939,377.424 286.575,377.053 287.352 M265.093 288.102 C 264.553 288.411,264.287 288.664,264.503 288.664 C 264.720 288.664,265.339 288.411,265.880 288.102 C 266.421 287.793,266.686 287.540,266.470 287.540 C 266.254 287.540,265.634 287.793,265.093 288.102 M24.470 290.855 C 25.183 292.695,26.461 294.985,26.774 294.985 C 26.986 294.985,26.897 294.499,26.577 293.904 C 25.927 292.694,24.232 290.242,24.470 290.855 M257.227 291.417 C 255.642 292.057,255.452 292.271,255.406 293.460 C 255.356 294.752,255.359 294.755,255.525 293.566 C 255.667 292.546,255.955 292.259,257.268 291.825 C 258.132 291.540,258.930 291.161,259.040 290.983 C 259.291 290.576,259.341 290.564,257.227 291.417 M374.782 291.766 C 374.440 292.347,373.762 293.487,373.274 294.300 C 372.731 295.205,372.593 295.689,372.919 295.548 C 373.212 295.421,373.941 294.331,374.540 293.126 C 375.687 290.819,375.837 289.971,374.782 291.766 M28.712 298.281 C 28.712 298.762,30.482 301.269,30.825 301.273 C 31.014 301.276,31.001 301.057,30.797 300.787 C 30.593 300.516,30.040 299.784,29.569 299.160 C 29.098 298.536,28.712 298.141,28.712 298.281 M370.487 299.031 C 369.371 300.707,369.285 300.885,369.597 300.882 C 369.935 300.880,371.396 298.502,371.187 298.293 C 371.118 298.224,370.803 298.556,370.487 299.031 M153.335 302.558 C 153.498 302.721,174.861 302.810,200.808 302.755 L 247.984 302.655 200.511 302.458 C 174.401 302.350,153.172 302.395,153.335 302.558 M366.492 305.113 C 365.630 306.118,365.297 306.785,365.660 306.782 C 365.835 306.781,366.280 306.250,366.648 305.602 C 367.408 304.268,367.356 304.107,366.492 305.113 M33.432 305.814 C 33.432 306.145,33.696 306.518,34.019 306.642 C 34.343 306.766,34.492 307.053,34.352 307.280 C 34.204 307.520,34.285 307.576,34.546 307.415 C 34.870 307.215,34.820 306.868,34.365 306.174 C 33.633 305.057,33.432 304.979,33.432 305.814 M36.201 309.538 C 36.968 311.030,38.256 312.684,38.652 312.684 C 38.846 312.684,38.427 311.932,37.721 311.013 C 35.974 308.736,35.604 308.378,36.201 309.538 M362.520 310.914 C 361.916 311.672,361.543 312.291,361.690 312.291 C 361.982 312.291,362.806 311.320,363.442 310.226 C 364.068 309.151,363.719 309.411,362.520 310.914 M250.737 316.814 C 250.737 319.044,250.870 320.787,251.032 320.687 C 251.195 320.586,251.327 318.844,251.327 316.814 C 251.327 314.785,251.195 313.042,251.032 312.942 C 250.870 312.842,250.737 314.584,250.737 316.814 M359.956 314.242 C 359.483 314.882,359.095 315.536,359.095 315.695 C 359.095 315.854,359.538 315.384,360.079 314.651 C 360.619 313.918,361.062 313.264,361.062 313.198 C 361.062 312.877,360.742 313.178,359.956 314.242 M39.331 313.686 C 39.331 313.819,39.949 314.683,40.704 315.604 C 41.460 316.526,41.946 317.425,41.786 317.602 C 41.626 317.779,41.678 317.820,41.903 317.692 C 42.127 317.565,43.003 318.416,43.848 319.583 C 44.694 320.751,45.629 321.799,45.925 321.913 C 46.222 322.027,46.055 321.613,45.553 320.993 C 40.656 314.944,39.331 313.388,39.331 313.686 M357.840 316.912 C 356.856 318.058,356.637 318.597,357.252 318.361 C 357.558 318.244,358.006 317.715,358.247 317.186 C 358.765 316.049,358.648 315.971,357.840 316.912 M354.572 320.944 C 353.951 321.593,353.619 322.124,353.835 322.124 C 354.051 322.124,354.620 321.593,355.100 320.944 C 355.580 320.295,355.912 319.764,355.838 319.764 C 355.763 319.764,355.194 320.295,354.572 320.944 M48.378 324.694 C 48.378 325.174,49.647 326.794,50.186 327.001 C 50.525 327.131,50.332 326.653,49.722 325.854 C 48.718 324.537,48.378 324.243,48.378 324.694 M350.221 326.108 C 349.258 327.134,349.212 327.264,349.942 326.886 C 350.424 326.636,351.005 326.082,351.234 325.655 C 351.816 324.567,351.559 324.682,350.221 326.108 M182.989 331.072 C 192.886 331.130,209.081 331.130,218.977 331.072 C 228.874 331.013,220.777 330.965,200.983 330.965 C 181.190 330.965,173.092 331.013,182.989 331.072 M342.076 334.619 C 340.188 336.516,338.643 338.204,338.643 338.370 C 338.643 338.683,344.386 333.064,345.298 331.858 C 346.360 330.454,345.419 331.261,342.076 334.619 M55.457 332.581 C 55.457 332.708,56.410 333.725,57.575 334.842 C 61.172 338.292,61.699 338.567,58.614 335.383 C 55.660 332.337,55.457 332.156,55.457 332.581 M160.179 335.202 C 159.623 335.904,158.839 337.463,159.043 337.463 C 159.137 337.463,159.580 336.844,160.027 336.087 C 160.838 334.711,160.914 334.274,160.179 335.202 M243.916 340.610 C 243.878 341.367,243.762 342.694,243.660 343.559 L 243.473 345.133 243.877 343.559 C 244.098 342.694,244.214 341.367,244.133 340.610 L 243.987 339.233 243.916 340.610 M63.324 340.120 C 63.324 340.524,64.808 341.928,65.683 342.351 C 66.008 342.508,65.919 342.311,65.487 341.914 C 65.054 341.517,64.390 340.872,64.012 340.480 C 63.633 340.088,63.324 339.926,63.324 340.120 M334.907 341.504 C 334.132 342.283,333.998 342.549,334.518 342.277 C 335.434 341.797,336.971 340.192,336.442 340.267 C 336.247 340.295,335.556 340.852,334.907 341.504 M67.257 343.669 C 67.257 343.858,67.699 344.428,68.240 344.936 C 68.913 345.569,69.219 345.683,69.211 345.300 C 69.198 344.705,67.257 343.085,67.257 343.669 M331.170 344.739 C 330.662 345.280,330.423 345.723,330.640 345.723 C 330.856 345.723,331.449 345.280,331.957 344.739 C 332.465 344.199,332.703 343.756,332.487 343.756 C 332.271 343.756,331.678 344.199,331.170 344.739 M71.042 347.016 C 71.438 347.723,74.336 349.775,74.336 349.349 C 74.336 349.075,72.344 347.388,71.238 346.726 C 70.829 346.481,70.781 346.552,71.042 347.016 M159.489 347.689 C 159.824 348.338,160.187 348.869,160.296 348.869 C 160.404 348.869,160.218 348.338,159.882 347.689 C 159.546 347.040,159.183 346.509,159.075 346.509 C 158.967 346.509,159.153 347.040,159.489 347.689 M327.189 348.093 L 325.467 349.676 327.040 348.653 C 327.906 348.091,328.755 347.379,328.928 347.070 C 329.436 346.165,329.020 346.409,327.189 348.093 M323.682 350.812 C 322.726 351.625,322.554 351.909,323.107 351.768 C 323.540 351.658,324.212 351.137,324.600 350.612 C 325.521 349.366,325.338 349.406,323.682 350.812 M78.269 352.802 C 80.080 354.326,80.655 354.326,78.919 352.802 C 78.180 352.153,77.422 351.627,77.234 351.633 C 77.046 351.639,77.512 352.165,78.269 352.802 M165.143 352.519 C 165.313 352.688,167.827 352.776,170.730 352.714 L 176.008 352.603 170.422 352.408 C 167.349 352.300,164.974 352.350,165.143 352.519 M228.810 352.308 C 230.379 352.382,232.945 352.382,234.513 352.308 C 236.082 352.233,234.798 352.172,231.662 352.172 C 228.525 352.172,227.242 352.233,228.810 352.308 M320.551 353.277 C 319.794 353.929,319.528 354.268,319.961 354.032 C 321.149 353.383,322.284 352.438,322.095 352.255 C 322.003 352.166,321.308 352.626,320.551 353.277 M223.967 355.426 C 223.362 356.220,223.067 356.746,223.312 356.594 C 223.816 356.283,225.519 353.982,225.246 353.982 C 225.148 353.982,224.573 354.632,223.967 355.426 M316.924 355.854 C 315.902 356.639,315.132 357.347,315.212 357.427 C 315.436 357.652,318.519 355.421,318.749 354.867 C 319.013 354.231,319.082 354.194,316.924 355.854 M82.203 355.480 C 82.203 355.866,84.146 357.298,84.348 357.062 C 84.409 356.991,83.951 356.520,83.331 356.017 C 82.710 355.514,82.203 355.273,82.203 355.480 M86.499 358.651 C 87.239 359.325,87.947 359.775,88.071 359.651 C 88.308 359.414,87.286 358.546,85.939 357.838 C 85.506 357.610,85.758 357.976,86.499 358.651 M312.324 359.063 C 311.909 359.477,311.495 359.742,311.404 359.650 C 311.312 359.559,310.916 359.839,310.523 360.273 C 309.815 361.056,309.819 361.058,310.986 360.475 C 311.634 360.152,312.485 359.533,312.878 359.098 C 313.790 358.091,313.325 358.061,312.324 359.063 M219.272 360.137 C 218.088 361.196,217.999 361.342,218.914 360.731 C 220.001 360.004,221.369 358.679,220.992 358.717 C 220.912 358.725,220.138 359.364,219.272 360.137 M88.496 359.785 C 88.496 359.962,89.027 360.419,89.676 360.803 C 90.324 361.186,90.855 361.435,90.855 361.355 C 90.855 361.275,90.324 360.817,89.676 360.338 C 89.027 359.858,88.496 359.609,88.496 359.785 M93.215 362.952 C 93.215 363.244,94.120 363.813,95.765 364.554 C 95.977 364.650,95.885 364.462,95.560 364.137 C 94.728 363.305,93.215 362.540,93.215 362.952 M305.211 363.618 C 304.478 364.159,304.018 364.602,304.189 364.602 C 304.707 364.602,306.785 363.274,306.785 362.944 C 306.785 362.492,306.675 362.539,305.211 363.618 M211.013 364.023 C 210.147 364.308,209.794 364.547,210.226 364.554 C 210.659 364.561,211.544 364.323,212.193 364.026 C 213.679 363.345,213.073 363.344,211.013 364.023 M191.577 364.350 C 191.667 364.428,192.271 364.610,192.920 364.755 C 193.782 364.948,193.941 364.911,193.510 364.620 C 192.979 364.260,191.182 364.009,191.577 364.350 M99.115 366.480 C 99.115 366.659,99.956 367.198,100.983 367.679 C 102.143 368.222,102.553 368.315,102.065 367.924 C 100.879 366.976,99.115 366.112,99.115 366.480 M299.017 367.184 C 298.097 367.735,297.345 368.256,297.345 368.341 C 297.345 368.669,300.681 366.985,300.812 366.591 C 301.003 366.018,300.914 366.047,299.017 367.184 M105.872 370.206 C 106.595 370.891,109.452 372.179,109.145 371.682 C 108.899 371.285,106.065 369.715,105.592 369.715 C 105.460 369.715,105.586 369.936,105.872 370.206 M291.937 370.940 C 290.236 372.029,290.325 372.157,292.228 371.357 C 293.091 370.995,293.799 370.565,293.801 370.403 C 293.808 369.923,293.294 370.071,291.937 370.940 M285.152 374.238 C 284.582 374.564,284.417 374.801,284.759 374.801 C 285.084 374.802,285.693 374.543,286.113 374.225 C 287.084 373.491,286.445 373.499,285.152 374.238 M282.399 375.615 C 281.642 376.029,281.164 376.376,281.337 376.385 C 281.754 376.407,283.972 375.253,283.972 375.014 C 283.972 374.757,283.949 374.766,282.399 375.615 M123.500 378.342 C 123.500 378.522,123.810 378.758,124.189 378.867 C 124.567 378.976,125.216 379.204,125.630 379.373 C 126.129 379.578,126.295 379.539,126.122 379.260 C 125.785 378.714,123.500 377.914,123.500 378.342 M274.979 378.616 C 273.326 379.337,273.547 379.703,275.247 379.061 C 276.147 378.722,277.223 377.739,276.401 378.007 C 276.347 378.024,275.707 378.299,274.979 378.616 M132.547 381.820 C 132.547 382.034,132.989 382.294,133.530 382.397 C 134.071 382.501,134.513 382.433,134.513 382.246 C 134.513 382.060,134.351 381.908,134.152 381.908 C 133.953 381.908,133.511 381.800,133.169 381.669 C 132.827 381.538,132.547 381.605,132.547 381.820 M266.175 381.785 C 265.796 381.884,265.487 382.114,265.487 382.295 C 265.487 382.476,265.796 382.565,266.175 382.493 C 266.554 382.420,266.996 382.348,267.158 382.331 C 267.321 382.314,267.453 382.124,267.453 381.908 C 267.453 381.499,267.321 381.486,266.175 381.785 M238.741 389.381 C 238.262 389.690,238.313 389.763,239.013 389.768 C 239.487 389.771,239.984 389.597,240.118 389.381 C 240.427 388.880,239.516 388.880,238.741 389.381 M162.045 389.774 C 162.045 389.990,162.311 390.167,162.635 390.167 C 162.960 390.167,163.225 389.990,163.225 389.774 C 163.225 389.558,162.960 389.381,162.635 389.381 C 162.311 389.381,162.045 389.558,162.045 389.774 M236.775 389.774 C 236.775 389.990,237.040 390.167,237.365 390.167 C 237.689 390.167,237.955 389.990,237.955 389.774 C 237.955 389.558,237.689 389.381,237.365 389.381 C 237.040 389.381,236.775 389.558,236.775 389.774 M164.208 390.167 C 165.283 390.629,165.585 390.629,165.585 390.167 C 165.585 389.951,165.098 389.786,164.503 389.801 C 163.545 389.826,163.511 389.868,164.208 390.167 M234.612 390.167 C 234.324 390.632,234.709 390.632,235.792 390.167 C 236.550 389.841,236.547 389.828,235.716 389.801 C 235.242 389.786,234.745 389.951,234.612 390.167 M166.765 390.560 C 167.540 391.061,168.451 391.061,168.142 390.560 C 168.008 390.344,167.511 390.170,167.037 390.173 C 166.336 390.178,166.285 390.251,166.765 390.560 M231.858 390.560 C 231.549 391.061,232.460 391.061,233.235 390.560 C 233.715 390.251,233.664 390.178,232.963 390.173 C 232.489 390.170,231.992 390.344,231.858 390.560 M181.416 392.405 C 181.794 392.504,182.414 392.504,182.793 392.405 C 183.171 392.306,182.861 392.225,182.104 392.225 C 181.347 392.225,181.037 392.306,181.416 392.405 M187.321 392.809 C 187.919 392.900,188.804 392.897,189.288 392.804 C 189.771 392.711,189.282 392.637,188.201 392.640 C 187.119 392.642,186.723 392.719,187.321 392.809 M210.920 392.809 C 211.518 392.900,212.403 392.897,212.886 392.804 C 213.370 392.711,212.881 392.637,211.799 392.640 C 210.718 392.642,210.322 392.719,210.920 392.809 \" stroke=\"none\" fill=\"#fcb6c0\" fill-rule=\"evenodd\"><\/path><path id=\"path4\" d=\"M186.922 0.271 C 187.301 0.370,187.920 0.370,188.299 0.271 C 188.677 0.172,188.368 0.091,187.611 0.091 C 186.853 0.091,186.544 0.172,186.922 0.271 M211.701 0.271 C 212.080 0.370,212.699 0.370,213.078 0.271 C 213.456 0.172,213.147 0.091,212.389 0.091 C 211.632 0.091,211.323 0.172,211.701 0.271 M197.935 42.749 C 198.314 42.848,198.933 42.848,199.312 42.749 C 199.690 42.650,199.381 42.569,198.623 42.569 C 197.866 42.569,197.557 42.650,197.935 42.749 M213.668 42.749 C 214.046 42.848,214.666 42.848,215.044 42.749 C 215.423 42.650,215.113 42.569,214.356 42.569 C 213.599 42.569,213.289 42.650,213.668 42.749 M188.889 43.536 C 189.267 43.635,189.887 43.635,190.265 43.536 C 190.644 43.437,190.334 43.356,189.577 43.356 C 188.820 43.356,188.510 43.437,188.889 43.536 M222.321 43.536 C 222.699 43.635,223.319 43.635,223.697 43.536 C 224.076 43.437,223.766 43.356,223.009 43.356 C 222.252 43.356,221.942 43.437,222.321 43.536 M68.775 47.613 C 67.895 48.379,67.892 48.400,68.710 48.004 C 69.184 47.775,69.682 47.411,69.814 47.196 C 70.201 46.570,69.777 46.740,68.775 47.613 M333.498 50.094 C 334.021 50.739,335.497 51.714,335.497 51.415 C 335.497 51.340,334.921 50.858,334.218 50.343 C 333.427 49.764,333.153 49.669,333.498 50.094 M338.438 54.404 C 339.298 55.174,340.515 56.390,341.143 57.106 L 342.284 58.407 341.318 57.056 C 340.787 56.313,339.569 55.097,338.612 54.355 L 336.873 53.004 338.438 54.404 M56.932 58.596 C 55.039 60.528,53.491 62.221,53.491 62.358 C 53.491 62.612,58.590 57.547,59.943 55.949 C 61.502 54.107,60.252 55.206,56.932 58.596 M138.151 58.256 C 136.811 59.114,136.377 59.691,137.561 59.040 C 138.464 58.544,139.878 57.450,139.626 57.443 C 139.518 57.440,138.854 57.805,138.151 58.256 M345.297 61.500 C 345.821 62.145,347.296 63.120,347.296 62.821 C 347.296 62.746,346.721 62.264,346.018 61.749 C 345.227 61.170,344.952 61.075,345.297 61.500 M49.503 66.492 C 48.623 67.259,48.620 67.279,49.437 66.883 C 49.912 66.654,50.409 66.290,50.542 66.075 C 50.929 65.449,50.505 65.619,49.503 66.492 M108.948 79.646 C 107.336 81.268,106.106 82.596,106.214 82.596 C 106.323 82.596,107.730 81.268,109.341 79.646 C 110.953 78.024,112.183 76.696,112.075 76.696 C 111.967 76.696,110.559 78.024,108.948 79.646 M101.070 87.611 L 98.525 90.265 101.180 87.720 C 103.646 85.356,104.015 84.956,103.725 84.956 C 103.665 84.956,102.470 86.150,101.070 87.611 M317.146 108.751 C 317.147 110.482,317.216 111.141,317.299 110.216 C 317.382 109.291,317.381 107.875,317.297 107.069 C 317.212 106.264,317.144 107.021,317.146 108.751 M214.066 149.741 C 214.664 149.832,215.549 149.829,216.033 149.736 C 216.517 149.643,216.028 149.569,214.946 149.572 C 213.864 149.575,213.469 149.651,214.066 149.741 M225.275 150.131 C 225.764 150.225,226.472 150.221,226.848 150.123 C 227.224 150.024,226.824 149.947,225.959 149.952 C 225.093 149.956,224.786 150.037,225.275 150.131 M229.799 150.528 C 230.397 150.618,231.282 150.616,231.765 150.523 C 232.249 150.429,231.760 150.355,230.678 150.358 C 229.597 150.361,229.201 150.438,229.799 150.528 M70.655 151.902 C 70.522 152.397,70.429 153.156,70.448 153.589 C 70.467 154.022,70.644 153.685,70.842 152.841 C 71.226 151.207,71.062 150.384,70.655 151.902 M116.421 160.988 C 116.421 161.056,116.996 161.631,117.699 162.267 L 118.977 163.422 117.822 162.144 C 116.745 160.952,116.421 160.685,116.421 160.988 M122.321 166.101 C 122.321 166.169,122.896 166.744,123.599 167.380 L 124.877 168.535 123.722 167.257 C 122.645 166.065,122.321 165.798,122.321 166.101 M399.719 189.774 C 399.722 190.855,399.799 191.251,399.889 190.653 C 399.979 190.056,399.977 189.171,399.884 188.687 C 399.790 188.203,399.716 188.692,399.719 189.774 M0.132 191.937 C 0.132 193.559,0.202 194.223,0.287 193.412 C 0.371 192.601,0.371 191.273,0.287 190.462 C 0.202 189.651,0.132 190.315,0.132 191.937 M0.132 200.983 C 0.132 202.606,0.202 203.269,0.287 202.458 C 0.371 201.647,0.371 200.320,0.287 199.508 C 0.202 198.697,0.132 199.361,0.132 200.983 M399.719 203.147 C 399.722 204.228,399.799 204.624,399.889 204.026 C 399.979 203.428,399.977 202.543,399.884 202.059 C 399.790 201.576,399.716 202.065,399.719 203.147 M317.503 210.226 C 317.508 211.091,317.588 211.399,317.682 210.910 C 317.776 210.421,317.773 209.713,317.674 209.337 C 317.576 208.961,317.499 209.361,317.503 210.226 M317.495 221.436 C 317.495 222.193,317.576 222.502,317.675 222.124 C 317.774 221.745,317.774 221.126,317.675 220.747 C 317.576 220.369,317.495 220.678,317.495 221.436 M84.905 235.792 C 85.118 236.224,85.580 236.932,85.932 237.365 L 86.572 238.151 86.186 237.365 C 85.974 236.932,85.512 236.224,85.160 235.792 L 84.519 235.005 84.905 235.792 M298.132 263.913 C 296.789 265.428,295.779 266.667,295.888 266.667 C 295.996 266.667,297.183 265.428,298.525 263.913 C 299.868 262.399,300.877 261.160,300.769 261.160 C 300.661 261.160,299.474 262.399,298.132 263.913 M293.590 268.732 L 292.035 270.403 293.707 268.848 C 295.262 267.402,295.559 267.060,295.262 267.060 C 295.197 267.060,294.445 267.812,293.590 268.732 M290.244 271.681 L 288.889 273.156 290.364 271.801 C 291.175 271.055,291.839 270.392,291.839 270.326 C 291.839 270.026,291.506 270.309,290.244 271.681 M133.138 284.368 C 133.401 284.794,135.693 286.071,135.693 285.791 C 135.693 285.699,135.063 285.252,134.293 284.797 C 133.523 284.343,133.003 284.150,133.138 284.368 M368.606 302.262 C 368.360 302.802,368.223 303.245,368.301 303.245 C 368.380 303.245,368.734 302.802,369.089 302.262 C 369.443 301.721,369.580 301.278,369.394 301.278 C 369.207 301.278,368.853 301.721,368.606 302.262 M361.019 313.176 C 360.557 314.056,360.559 314.057,361.398 313.312 C 362.336 312.479,362.421 312.291,361.862 312.291 C 361.654 312.291,361.274 312.689,361.019 313.176 M151.154 316.814 C 151.157 318.112,151.230 318.596,151.317 317.889 C 151.405 317.182,151.403 316.120,151.313 315.529 C 151.224 314.938,151.152 315.516,151.154 316.814 M354.475 321.574 C 353.988 322.128,353.796 322.514,354.048 322.430 C 354.472 322.289,355.831 320.542,355.505 320.558 C 355.425 320.562,354.961 321.019,354.475 321.574 M352.333 323.992 C 351.640 324.799,351.121 325.664,351.329 325.664 C 351.409 325.664,351.867 325.133,352.347 324.484 C 353.295 323.202,353.286 322.883,352.333 323.992 M47.984 324.877 C 48.446 325.526,48.913 326.057,49.021 326.057 C 49.129 326.057,48.840 325.526,48.378 324.877 C 47.915 324.228,47.449 323.697,47.341 323.697 C 47.233 323.697,47.522 324.228,47.984 324.877 M157.268 326.944 C 157.431 327.107,177.201 327.195,201.201 327.140 L 244.838 327.040 200.905 326.844 C 176.741 326.735,157.105 326.781,157.268 326.944 M347.860 329.007 C 346.775 330.197,346.001 331.170,346.140 331.170 C 346.278 331.170,347.283 330.197,348.373 329.007 C 349.463 327.817,350.237 326.844,350.093 326.844 C 349.950 326.844,348.945 327.817,347.860 329.007 M51.524 328.723 C 51.524 328.854,52.498 329.889,53.687 331.024 C 54.877 332.158,55.851 332.986,55.851 332.864 C 55.851 332.742,54.877 331.707,53.687 330.563 C 52.498 329.420,51.524 328.592,51.524 328.723 M61.308 338.584 C 62.977 340.167,63.609 340.603,63.145 339.852 C 63.021 339.651,62.170 338.917,61.253 338.220 L 59.587 336.952 61.308 338.584 M337.620 339.135 C 335.897 341.122,335.385 341.790,335.585 341.790 C 335.701 341.790,336.448 340.993,337.245 340.020 C 338.723 338.217,339.015 337.525,337.620 339.135 M177.778 355.679 C 177.778 355.746,178.353 356.322,179.056 356.957 L 180.334 358.112 179.179 356.834 C 178.102 355.642,177.778 355.375,177.778 355.679 M196.342 393.213 C 198.224 393.285,201.410 393.285,203.422 393.214 C 205.434 393.142,203.894 393.083,200.000 393.083 C 196.106 393.082,194.460 393.141,196.342 393.213 \" stroke=\"none\" fill=\"#fcacb4\" fill-rule=\"evenodd\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\t\t\t\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"box-heading\">\n\t\t\t\t\t\t\t<a >\t\t\t\t\t\t\t\tPsychometric Assessments\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-695f01e4 content-align-left icon-box-vertical-align-top icon-position-left icon-vertical-align-start elementor-widget elementor-widget-the7_icon_box_widget\" data-id=\"695f01e4\" data-element_type=\"widget\" data-widget_type=\"the7_icon_box_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"the7-box-wrapper the7-elementor-widget the7_icon_box_widget-695f01e4\">\t\t\t<div class=\"box-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-icon-div\" >\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"svg\" width=\"400\" height=\"392.9901423877327\" viewBox=\"0, 0, 400,392.9901423877327\"><g id=\"svgg\"><path id=\"path0\" d=\"M193.314 43.309 C 155.007 46.203,120.494 64.039,96.738 93.218 C 63.997 133.435,60.098 195.681,87.593 239.239 C 101.091 260.622,119.818 277.760,140.610 287.759 L 145.919 290.312 145.919 291.792 C 145.919 295.513,148.402 299.901,151.320 301.338 L 153.196 302.262 200.393 302.228 L 247.591 302.194 249.593 301.172 C 252.890 299.487,254.370 297.363,255.041 293.354 C 255.271 291.978,255.414 291.867,258.516 290.641 C 328.287 263.078,338.631 183.447,275.516 159.768 C 256.823 152.755,243.679 150.783,209.440 149.855 C 164.379 148.633,143.627 142.430,140.276 129.180 C 137.228 117.133,141.711 105.293,152.011 98.184 C 169.276 86.268,201.577 81.428,228.122 86.779 C 247.528 90.691,268.207 103.598,276.483 116.965 C 287.486 134.737,312.441 132.616,316.478 113.565 C 318.974 101.788,308.991 87.784,285.939 70.730 C 255.989 48.573,229.081 40.607,193.314 43.309 M123.012 166.263 C 140.965 181.228,163.506 186.888,205.703 187.026 C 224.731 187.088,226.988 187.241,240.708 189.388 C 279.914 195.525,290.904 214.942,268.035 237.671 C 224.252 281.187,139.987 265.243,117.384 209.166 C 111.200 193.823,108.954 172.543,111.943 157.611 C 112.160 156.525,112.175 156.533,115.373 159.546 C 117.139 161.211,120.577 164.233,123.012 166.263 M156.932 307.613 C 150.346 311.561,149.524 321.652,155.467 325.585 L 157.071 326.647 201.019 326.647 L 244.967 326.647 246.663 325.455 C 253.221 320.846,252.177 310.416,244.850 307.354 C 242.285 306.283,158.742 306.528,156.932 307.613 M163.516 332.724 C 157.360 336.628,157.289 347.240,163.394 351.019 C 165.262 352.175,165.493 352.216,170.765 352.340 L 176.208 352.469 177.358 354.140 C 187.438 368.792,216.115 368.604,224.773 353.830 L 225.837 352.016 231.247 352.016 C 236.571 352.016,236.681 351.998,238.205 350.894 C 244.474 346.353,245.358 338.771,240.174 334.011 C 237.376 331.442,239.336 331.563,200.838 331.563 L 165.346 331.563 163.516 332.724 \" stroke=\"none\" fill=\"#f42444\" fill-rule=\"evenodd\"><\/path><path id=\"path1\" d=\"M188.201 0.421 C 184.956 0.587,180.294 0.928,177.842 1.179 C 175.390 1.431,173.282 1.535,173.159 1.412 C 173.035 1.288,172.701 1.380,172.416 1.617 C 171.936 2.015,170.708 2.238,167.748 2.466 C 167.099 2.516,166.346 2.701,166.073 2.877 C 165.801 3.053,165.226 3.085,164.795 2.949 C 164.310 2.795,164.012 2.880,164.012 3.171 C 164.012 3.491,163.566 3.570,162.626 3.418 C 161.864 3.294,161.319 3.319,161.414 3.474 C 161.510 3.628,159.293 4.180,156.487 4.699 C 153.682 5.219,151.295 5.793,151.183 5.975 C 151.070 6.157,150.806 6.199,150.595 6.069 C 150.384 5.939,149.976 6.027,149.688 6.266 C 149.401 6.505,148.878 6.589,148.526 6.454 C 148.150 6.310,147.886 6.407,147.886 6.690 C 147.886 6.978,147.569 7.089,147.099 6.966 C 146.667 6.853,146.313 6.941,146.313 7.162 C 146.313 7.384,145.959 7.472,145.526 7.359 C 145.093 7.246,144.739 7.281,144.739 7.436 C 144.739 7.592,143.142 8.131,141.189 8.634 C 139.236 9.138,137.549 9.694,137.440 9.871 C 137.331 10.047,136.981 10.092,136.664 9.970 C 136.346 9.848,136.087 9.964,136.087 10.226 C 136.087 10.489,135.821 10.602,135.497 10.477 C 135.172 10.353,134.907 10.390,134.907 10.560 C 134.907 10.730,133.535 11.286,131.858 11.796 C 130.182 12.307,128.236 12.961,127.534 13.250 C 126.832 13.539,126.144 13.758,126.005 13.737 C 125.865 13.716,125.622 13.908,125.464 14.164 C 125.306 14.420,124.711 14.656,124.142 14.689 C 123.573 14.722,123.108 14.858,123.107 14.992 C 123.107 15.125,122.001 15.631,120.649 16.117 C 119.297 16.603,117.616 17.349,116.912 17.775 C 116.209 18.201,115.634 18.434,115.634 18.293 C 115.634 18.152,115.342 18.328,114.986 18.685 C 114.629 19.042,114.009 19.248,113.608 19.143 C 113.208 19.038,112.967 19.093,113.073 19.265 C 113.179 19.437,112.250 19.985,111.009 20.482 C 109.767 20.980,108.660 21.518,108.549 21.678 C 108.437 21.838,106.844 22.747,105.009 23.697 C 100.301 26.135,95.583 28.785,94.199 29.770 C 92.039 31.306,89.483 32.815,89.184 32.729 C 89.022 32.683,88.889 32.809,88.889 33.010 C 88.889 33.211,87.871 33.995,86.627 34.754 C 85.383 35.512,82.153 37.837,79.449 39.919 C 76.745 42.001,73.544 44.455,72.335 45.373 C 71.126 46.290,69.575 47.615,68.888 48.318 C 68.201 49.021,67.459 49.486,67.241 49.351 C 67.023 49.216,66.891 49.252,66.948 49.430 C 67.146 50.041,63.238 53.433,62.613 53.193 C 62.269 53.061,62.118 53.131,62.257 53.356 C 62.536 53.807,58.110 58.338,57.697 58.024 C 57.547 57.910,57.514 57.936,57.623 58.082 C 57.733 58.228,56.450 59.777,54.772 61.524 C 53.094 63.271,50.934 65.618,49.973 66.741 C 49.011 67.863,48.038 68.676,47.809 68.546 C 47.581 68.416,47.514 68.443,47.659 68.606 C 47.898 68.872,45.576 72.283,44.830 72.763 C 44.661 72.871,43.724 74.022,42.747 75.320 C 41.769 76.618,39.631 79.449,37.994 81.613 C 36.358 83.776,35.016 85.689,35.012 85.864 C 35.008 86.039,34.801 86.056,34.551 85.901 C 34.262 85.723,34.204 85.794,34.390 86.096 C 34.563 86.375,34.140 87.289,33.370 88.306 C 32.647 89.260,31.266 91.273,30.302 92.780 C 29.337 94.287,28.381 95.417,28.176 95.290 C 27.971 95.164,27.930 95.265,28.085 95.516 C 28.392 96.013,26.816 99.115,26.256 99.115 C 26.067 99.115,26.009 99.271,26.127 99.462 C 26.245 99.653,26.015 100.228,25.615 100.740 C 25.216 101.253,23.645 104.095,22.125 107.058 C 20.604 110.021,19.224 112.321,19.057 112.171 C 18.890 112.021,18.868 112.099,19.008 112.344 C 19.320 112.891,18.546 115.241,18.054 115.241 C 17.859 115.241,17.730 115.374,17.769 115.536 C 17.807 115.698,17.390 116.813,16.842 118.013 C 16.294 119.214,15.629 120.851,15.365 121.652 C 15.101 122.452,14.711 123.107,14.499 123.107 C 14.287 123.107,14.219 123.279,14.349 123.489 C 14.479 123.700,14.333 124.275,14.024 124.768 C 13.715 125.260,12.974 127.168,12.376 129.007 C 11.778 130.846,11.148 132.406,10.976 132.474 C 10.804 132.542,10.761 132.852,10.880 133.162 C 10.999 133.473,10.907 133.727,10.674 133.727 C 10.441 133.727,10.353 133.992,10.477 134.317 C 10.602 134.641,10.541 134.907,10.342 134.907 C 10.143 134.907,9.567 136.511,9.061 138.473 C 8.430 140.920,8.029 141.876,7.783 141.521 C 7.554 141.190,7.516 141.464,7.677 142.281 C 7.824 143.029,7.768 143.559,7.541 143.559 C 7.328 143.559,7.246 143.913,7.359 144.346 C 7.472 144.779,7.384 145.133,7.162 145.133 C 6.941 145.133,6.853 145.487,6.966 145.919 C 7.089 146.389,6.978 146.706,6.690 146.706 C 6.407 146.706,6.310 146.970,6.454 147.346 C 6.589 147.698,6.495 148.233,6.244 148.535 C 5.993 148.838,5.900 149.197,6.037 149.334 C 6.174 149.471,6.133 149.777,5.946 150.013 C 5.759 150.249,5.286 152.168,4.894 154.277 C 4.503 156.386,4.068 158.112,3.929 158.112 C 3.790 158.112,3.754 158.643,3.849 159.292 C 3.951 159.986,3.846 160.472,3.594 160.472 C 3.328 160.472,3.256 160.919,3.402 161.652 C 3.554 162.413,3.478 162.832,3.188 162.832 C 2.904 162.832,2.830 163.196,2.986 163.820 C 3.126 164.377,3.029 165.056,2.765 165.375 C 2.506 165.686,2.406 166.292,2.543 166.722 C 2.679 167.151,2.616 167.823,2.402 168.215 C 1.307 170.226,0.243 188.749,0.520 200.983 C 0.757 211.453,1.765 224.046,2.431 224.858 C 2.644 225.118,2.700 225.702,2.557 226.155 C 2.413 226.609,2.506 227.234,2.765 227.546 C 3.029 227.864,3.126 228.543,2.986 229.100 C 2.831 229.720,2.904 230.088,3.184 230.088 C 3.455 230.088,3.561 230.550,3.456 231.268 C 3.361 231.917,3.449 232.448,3.653 232.448 C 3.856 232.448,3.944 232.979,3.849 233.628 C 3.754 234.277,3.789 234.808,3.927 234.808 C 4.065 234.808,4.503 236.584,4.899 238.753 C 5.296 240.923,5.774 242.794,5.963 242.910 C 6.152 243.027,6.199 243.295,6.069 243.506 C 5.939 243.716,6.027 244.124,6.266 244.412 C 6.505 244.699,6.589 245.223,6.454 245.575 C 6.310 245.951,6.407 246.214,6.690 246.214 C 6.974 246.214,7.089 246.530,6.971 246.982 C 6.860 247.404,6.938 247.806,7.143 247.874 C 7.348 247.943,7.551 248.658,7.593 249.465 C 7.635 250.271,7.768 250.931,7.889 250.932 C 8.009 250.933,8.430 252.177,8.824 253.695 C 9.218 255.214,9.687 256.547,9.866 256.658 C 10.045 256.768,10.092 257.119,9.970 257.436 C 9.848 257.754,9.964 258.014,10.226 258.014 C 10.489 258.014,10.602 258.279,10.477 258.604 C 10.353 258.928,10.441 259.194,10.674 259.194 C 10.907 259.194,10.995 259.459,10.871 259.784 C 10.746 260.108,10.782 260.374,10.951 260.374 C 11.119 260.374,11.586 261.480,11.988 262.832 C 12.391 264.184,12.957 265.864,13.247 266.566 C 13.537 267.268,13.758 267.957,13.737 268.096 C 13.716 268.235,13.860 268.457,14.057 268.589 C 14.254 268.722,15.093 270.600,15.922 272.763 C 16.750 274.926,17.560 276.785,17.721 276.893 C 17.882 277.001,18.076 277.443,18.151 277.876 C 18.227 278.309,18.521 278.907,18.803 279.205 C 19.086 279.503,19.210 280.029,19.078 280.373 C 18.946 280.717,18.959 280.877,19.108 280.728 C 19.380 280.457,21.821 285.091,21.698 285.644 C 21.662 285.806,21.820 285.939,22.049 285.939 C 22.278 285.939,22.365 286.101,22.243 286.299 C 22.121 286.497,22.167 286.718,22.347 286.790 C 22.526 286.863,23.295 288.073,24.056 289.479 C 27.443 295.739,31.656 302.714,33.000 304.285 C 33.211 304.532,33.277 304.842,33.146 304.973 C 33.015 305.104,33.099 305.211,33.334 305.211 C 33.569 305.211,34.163 305.875,34.654 306.686 C 35.145 307.498,36.320 309.179,37.265 310.423 C 38.211 311.667,38.872 312.866,38.735 313.088 C 38.598 313.309,38.662 313.442,38.876 313.382 C 39.228 313.285,40.418 314.647,45.313 320.747 C 46.180 321.829,47.712 323.678,48.716 324.856 C 51.642 328.292,64.365 341.035,66.799 342.970 C 68.024 343.943,69.259 345.050,69.542 345.430 C 69.826 345.810,70.534 346.372,71.115 346.680 C 71.697 346.988,72.714 347.739,73.375 348.350 C 75.620 350.422,81.851 355.111,85.644 357.582 C 86.996 358.463,88.116 359.473,88.133 359.828 C 88.150 360.182,88.248 360.269,88.349 360.020 C 88.529 359.582,92.330 361.844,92.866 362.708 C 92.998 362.921,93.220 363.081,93.358 363.062 C 94.058 362.968,94.384 363.073,94.859 363.543 C 95.588 364.265,101.460 367.615,105.211 369.449 C 106.942 370.296,108.623 371.204,108.948 371.468 C 109.272 371.733,110.733 372.459,112.193 373.083 C 113.653 373.706,114.848 374.364,114.848 374.545 C 114.848 374.726,115.025 374.765,115.241 374.631 C 115.457 374.498,115.634 374.576,115.634 374.805 C 115.634 375.034,115.767 375.188,115.929 375.148 C 116.091 375.108,116.932 375.388,117.797 375.771 C 118.663 376.153,120.610 376.915,122.124 377.464 C 123.638 378.012,125.231 378.655,125.664 378.892 C 126.096 379.129,126.539 379.336,126.647 379.351 C 126.755 379.366,127.198 379.562,127.630 379.785 C 128.063 380.008,129.789 380.608,131.465 381.118 C 133.142 381.629,134.513 382.186,134.513 382.358 C 134.513 382.529,134.779 382.568,135.103 382.443 C 135.428 382.318,135.693 382.431,135.693 382.694 C 135.693 382.957,135.953 383.072,136.271 382.950 C 136.588 382.828,136.935 382.869,137.040 383.040 C 137.146 383.211,139.143 383.854,141.478 384.469 C 143.813 385.084,145.775 385.714,145.840 385.869 C 145.904 386.024,146.303 386.060,146.725 385.950 C 147.147 385.839,147.493 385.930,147.493 386.151 C 147.493 386.373,147.847 386.461,148.279 386.348 C 148.739 386.228,149.066 386.336,149.066 386.608 C 149.066 386.888,149.367 386.978,149.819 386.834 C 150.234 386.703,150.678 386.765,150.806 386.973 C 150.934 387.180,153.250 387.754,155.952 388.248 C 158.654 388.742,160.865 389.283,160.865 389.450 C 160.865 389.617,161.396 389.648,162.045 389.518 C 162.695 389.388,163.225 389.450,163.225 389.657 C 163.225 389.862,163.756 389.953,164.405 389.858 C 165.124 389.752,165.585 389.859,165.585 390.130 C 165.585 390.409,165.954 390.483,166.573 390.327 C 167.117 390.191,167.799 390.276,168.089 390.517 C 168.379 390.758,169.041 390.953,169.559 390.951 C 170.077 390.949,172.537 391.201,175.025 391.510 C 188.507 393.187,209.683 393.280,223.009 391.721 C 226.578 391.304,229.923 390.960,230.441 390.958 C 230.959 390.956,231.622 390.756,231.914 390.514 C 232.206 390.272,232.834 390.176,233.311 390.301 C 233.787 390.426,234.407 390.337,234.687 390.104 C 234.968 389.871,235.552 389.774,235.986 389.887 C 236.420 390.001,236.775 389.933,236.775 389.737 C 236.775 389.541,237.121 389.381,237.544 389.381 C 239.004 389.381,249.165 387.295,249.392 386.948 C 249.518 386.757,249.916 386.714,250.277 386.853 C 250.661 387.000,250.934 386.913,250.934 386.643 C 250.934 386.360,251.239 386.278,251.721 386.431 C 252.205 386.584,252.507 386.501,252.507 386.215 C 252.507 385.943,252.834 385.834,253.294 385.955 C 253.727 386.068,254.081 386.032,254.081 385.876 C 254.081 385.719,255.452 385.270,257.129 384.877 C 258.805 384.485,260.531 384.031,260.964 383.869 C 261.396 383.707,261.927 383.539,262.144 383.494 C 262.360 383.450,262.750 383.237,263.011 383.020 C 263.272 382.804,263.670 382.741,263.896 382.880 C 264.122 383.020,264.307 382.928,264.307 382.675 C 264.307 382.423,264.572 382.319,264.897 382.443 C 265.221 382.568,265.487 382.536,265.487 382.374 C 265.487 382.211,267.168 381.572,269.223 380.955 C 271.278 380.338,272.960 379.650,272.960 379.428 C 272.960 379.205,273.076 379.140,273.218 379.282 C 273.361 379.424,273.671 379.389,273.907 379.204 C 274.143 379.019,275.841 378.293,277.679 377.592 C 279.518 376.890,281.664 375.989,282.449 375.589 C 283.233 375.189,283.985 374.972,284.120 375.107 C 284.255 375.242,284.366 375.170,284.366 374.948 C 284.366 374.726,285.737 373.970,287.414 373.269 C 289.090 372.568,290.668 371.827,290.919 371.622 C 291.170 371.418,292.851 370.493,294.655 369.567 C 299.407 367.129,304.461 364.295,305.179 363.666 C 305.521 363.366,306.805 362.560,308.031 361.875 C 309.257 361.190,310.472 360.375,310.730 360.063 C 310.989 359.752,311.357 359.594,311.549 359.713 C 311.741 359.831,311.898 359.746,311.898 359.522 C 311.898 359.298,312.466 358.822,313.160 358.463 C 313.854 358.104,316.155 356.511,318.273 354.923 C 320.391 353.335,322.124 352.106,322.124 352.192 C 322.124 352.278,322.625 351.875,323.237 351.297 C 323.849 350.719,325.370 349.449,326.616 348.476 C 335.692 341.385,346.987 330.269,354.769 320.770 C 355.959 319.318,357.419 317.599,358.014 316.950 C 358.609 316.301,359.095 315.682,359.095 315.574 C 359.095 315.466,359.936 314.299,360.964 312.981 C 362.767 310.668,365.287 307.040,367.793 303.147 C 368.454 302.119,369.168 301.278,369.378 301.278 C 369.589 301.278,369.665 301.122,369.547 300.931 C 369.429 300.740,369.699 300.118,370.147 299.549 C 371.042 298.411,373.212 294.639,375.942 289.479 C 376.914 287.640,377.859 286.076,378.041 286.004 C 378.224 285.931,378.273 285.710,378.150 285.512 C 378.028 285.314,378.082 285.152,378.269 285.152 C 378.457 285.152,379.209 283.736,379.941 282.006 C 380.673 280.275,381.425 278.859,381.613 278.859 C 381.800 278.859,381.845 278.682,381.711 278.466 C 381.577 278.250,381.618 278.073,381.803 278.073 C 381.987 278.073,382.732 276.480,383.459 274.533 C 384.186 272.586,384.941 270.993,385.137 270.993 C 385.333 270.993,385.394 270.832,385.272 270.635 C 385.151 270.438,385.476 269.420,385.995 268.373 C 386.515 267.327,387.255 265.452,387.642 264.208 C 388.028 262.965,388.499 261.947,388.689 261.947 C 388.879 261.947,388.919 261.762,388.780 261.536 C 388.640 261.311,388.740 260.868,389.002 260.553 C 389.263 260.238,389.345 259.980,389.184 259.980 C 389.023 259.980,389.075 259.759,389.299 259.489 C 389.523 259.218,389.745 258.820,389.790 258.604 C 389.836 258.387,389.935 258.033,390.009 257.817 C 390.084 257.601,390.690 255.477,391.356 253.097 C 392.023 250.718,392.676 248.505,392.807 248.181 C 392.938 247.856,393.011 247.440,392.969 247.255 C 392.927 247.070,393.091 246.679,393.334 246.387 C 393.576 246.095,393.668 245.683,393.538 245.472 C 393.407 245.261,393.460 244.990,393.654 244.870 C 393.849 244.750,394.418 242.526,394.918 239.927 C 395.419 237.328,395.940 235.202,396.076 235.202 C 396.212 235.202,396.246 234.671,396.151 234.022 C 396.049 233.327,396.154 232.842,396.406 232.842 C 396.672 232.842,396.744 232.395,396.598 231.662 C 396.446 230.901,396.522 230.482,396.812 230.482 C 397.096 230.482,397.170 230.118,397.014 229.493 C 396.877 228.950,396.947 228.286,397.168 228.018 C 397.390 227.751,397.577 227.089,397.584 226.549 C 397.591 226.008,397.856 223.707,398.172 221.436 C 400.082 207.708,399.985 180.691,397.986 169.752 C 397.745 168.434,397.553 166.912,397.559 166.372 C 397.566 165.831,397.402 165.184,397.195 164.934 C 396.989 164.685,396.935 164.021,397.076 163.459 C 397.247 162.777,397.173 162.439,396.850 162.439 C 396.548 162.439,396.439 162.071,396.556 161.455 C 396.660 160.914,396.569 160.472,396.354 160.472 C 396.125 160.472,396.060 159.883,396.195 159.047 C 396.322 158.263,396.316 157.732,396.180 157.868 C 396.045 158.003,395.440 155.680,394.837 152.705 C 394.234 149.730,393.550 146.979,393.317 146.592 C 393.084 146.204,392.989 145.733,393.106 145.544 C 393.223 145.355,393.131 145.137,392.901 145.061 C 392.672 144.984,392.449 144.262,392.407 143.456 C 392.365 142.649,392.235 141.989,392.118 141.988 C 392.001 141.987,391.477 140.393,390.954 138.446 C 390.431 136.500,389.844 134.907,389.649 134.907 C 389.455 134.907,389.398 134.641,389.523 134.317 C 389.647 133.992,389.559 133.727,389.326 133.727 C 389.093 133.727,389.001 133.473,389.120 133.162 C 389.239 132.852,389.214 132.542,389.063 132.474 C 388.913 132.406,388.187 130.580,387.450 128.417 C 386.713 126.254,385.939 124.263,385.731 123.992 C 385.522 123.722,385.505 123.498,385.694 123.494 C 385.883 123.491,385.849 123.358,385.620 123.199 C 385.390 123.041,384.786 121.849,384.278 120.551 C 383.770 119.253,382.321 116.030,381.058 113.389 C 379.795 110.749,378.761 108.403,378.761 108.178 C 378.761 107.952,378.574 107.768,378.345 107.768 C 378.115 107.768,378.037 107.591,378.171 107.375 C 378.305 107.158,378.216 106.981,377.974 106.981 C 377.733 106.981,377.635 106.819,377.757 106.622 C 377.879 106.424,377.823 106.203,377.632 106.130 C 377.441 106.057,376.635 104.759,375.840 103.245 C 373.209 98.228,367.459 88.815,366.872 88.561 C 366.705 88.489,366.568 88.194,366.568 87.906 C 366.568 87.617,366.423 87.322,366.246 87.250 C 366.069 87.178,365.205 86.053,364.326 84.750 C 362.686 82.320,356.953 74.763,355.678 73.350 C 355.286 72.916,354.169 71.588,353.196 70.400 C 350.436 67.031,348.951 65.381,345.030 61.329 C 343.026 59.258,341.522 57.429,341.687 57.265 C 341.851 57.100,341.792 57.024,341.555 57.096 C 340.913 57.291,337.394 53.920,337.709 53.411 C 337.866 53.156,337.799 53.086,337.547 53.242 C 337.310 53.389,335.822 52.333,334.241 50.897 C 332.660 49.460,330.526 47.649,329.499 46.871 C 328.471 46.093,327.630 45.317,327.630 45.147 C 327.630 44.977,327.359 44.838,327.028 44.838 C 326.697 44.838,326.330 44.589,326.214 44.285 C 326.097 43.981,325.041 43.094,323.866 42.314 C 322.692 41.535,321.731 40.750,321.731 40.570 C 321.731 40.391,321.326 40.060,320.832 39.835 C 320.338 39.610,318.790 38.556,317.391 37.493 C 315.992 36.430,314.007 35.074,312.979 34.479 C 311.952 33.885,311.111 33.219,311.111 32.999 C 311.111 32.779,310.949 32.699,310.751 32.821 C 310.554 32.943,310.332 32.909,310.260 32.746 C 310.098 32.382,303.820 28.450,300.983 26.936 C 299.848 26.330,298.918 25.685,298.918 25.503 C 298.918 25.321,298.786 25.207,298.623 25.250 C 298.198 25.362,292.454 22.388,292.297 21.975 C 292.224 21.784,292.003 21.727,291.805 21.850 C 291.607 21.972,291.445 21.929,291.444 21.754 C 291.443 21.579,290.395 20.997,289.116 20.461 C 287.837 19.924,286.892 19.322,287.016 19.121 C 287.139 18.921,287.057 18.871,286.832 19.010 C 286.323 19.324,283.972 18.538,283.972 18.054 C 283.972 17.859,283.840 17.728,283.677 17.763 C 283.515 17.799,282.586 17.472,281.613 17.036 C 280.639 16.601,279.179 16.028,278.368 15.762 C 277.557 15.496,276.893 15.105,276.893 14.892 C 276.893 14.680,276.719 14.613,276.508 14.744 C 276.296 14.875,275.721 14.759,275.229 14.486 C 274.738 14.214,274.248 13.968,274.140 13.941 C 274.031 13.914,273.324 13.616,272.566 13.279 C 271.809 12.943,270.438 12.444,269.518 12.171 C 268.599 11.898,267.847 11.542,267.847 11.381 C 267.847 11.219,267.493 11.179,267.060 11.292 C 266.627 11.405,266.273 11.306,266.273 11.071 C 266.273 10.836,266.008 10.746,265.683 10.871 C 265.359 10.995,265.093 10.907,265.093 10.674 C 265.093 10.441,264.828 10.353,264.503 10.477 C 264.179 10.602,263.913 10.489,263.913 10.226 C 263.913 9.964,263.654 9.848,263.336 9.970 C 263.019 10.092,262.672 10.052,262.566 9.880 C 262.460 9.709,260.464 9.066,258.129 8.451 C 255.794 7.837,253.831 7.207,253.767 7.052 C 253.702 6.897,253.304 6.860,252.882 6.971 C 252.429 7.089,252.114 6.974,252.114 6.690 C 252.114 6.407,251.850 6.310,251.474 6.454 C 251.122 6.589,250.610 6.514,250.336 6.286 C 250.061 6.058,249.686 5.906,249.501 5.948 C 249.316 5.990,248.899 5.917,248.574 5.787 C 247.677 5.424,240.081 3.933,239.134 3.933 C 238.676 3.933,238.409 3.759,238.541 3.546 C 238.690 3.305,238.325 3.249,237.581 3.398 C 236.775 3.559,236.382 3.483,236.382 3.164 C 236.382 2.846,236.007 2.773,235.239 2.942 C 234.558 3.091,233.987 3.015,233.825 2.753 C 233.666 2.496,233.095 2.414,232.448 2.557 C 231.799 2.699,231.231 2.617,231.070 2.357 C 230.920 2.114,230.328 1.952,229.755 1.997 C 229.181 2.043,228.446 1.980,228.122 1.859 C 224.834 0.632,200.925 -0.230,188.201 0.421 M218.682 42.875 C 224.914 43.339,229.812 43.957,231.465 44.489 C 232.114 44.698,233.945 45.138,235.535 45.467 C 239.072 46.199,244.814 47.826,246.411 48.548 C 247.060 48.841,248.918 49.549,250.541 50.120 C 255.840 51.986,266.175 57.107,271.830 60.669 C 273.461 61.696,274.919 62.537,275.070 62.537 C 275.394 62.537,280.853 66.294,284.041 68.711 C 285.268 69.642,286.463 70.403,286.696 70.403 C 286.929 70.403,287.119 70.582,287.119 70.801 C 287.119 71.020,288.048 71.794,289.184 72.521 C 293.841 75.503,305.912 86.900,309.852 92.035 C 310.764 93.225,311.686 94.412,311.901 94.674 C 312.116 94.935,312.291 95.333,312.291 95.559 C 312.291 95.784,312.450 95.969,312.643 95.969 C 312.837 95.969,313.332 96.632,313.744 97.443 C 314.156 98.255,315.095 100.059,315.831 101.452 C 317.731 105.049,317.950 113.610,316.222 116.749 C 316.024 117.109,315.413 118.394,314.864 119.603 C 310.740 128.695,294.952 132.472,285.469 126.637 C 284.423 125.993,283.428 125.467,283.258 125.467 C 282.660 125.467,278.649 121.626,278.077 120.505 C 277.077 118.545,273.676 113.558,271.856 111.385 C 269.164 108.170,258.824 99.903,256.382 99.013 C 256.025 98.883,254.344 97.917,252.645 96.865 C 233.017 84.714,199.055 81.368,174.041 89.120 C 172.311 89.656,169.390 90.559,167.552 91.127 C 165.713 91.694,164.031 92.284,163.815 92.439 C 163.599 92.593,161.829 93.421,159.882 94.279 C 150.963 98.208,143.490 105.654,141.143 112.950 C 139.790 117.157,139.786 126.259,141.135 130.556 C 142.003 133.320,145.742 138.053,147.058 138.053 C 147.240 138.053,148.785 138.834,150.489 139.787 C 156.217 142.992,168.961 146.406,178.564 147.309 C 179.971 147.442,181.475 147.704,181.908 147.893 C 183.203 148.458,193.596 149.052,209.243 149.454 C 217.355 149.663,225.674 149.932,227.729 150.051 C 236.805 150.580,242.676 151.103,245.231 151.610 C 246.745 151.911,249.843 152.450,252.114 152.808 C 257.124 153.599,262.443 154.779,264.307 155.515 C 265.064 155.814,267.610 156.622,269.966 157.310 C 272.321 157.999,274.884 158.903,275.663 159.320 C 276.441 159.737,277.257 160.077,277.477 160.075 C 277.933 160.072,284.067 162.522,284.366 162.828 C 284.474 162.938,285.359 163.455,286.332 163.977 C 287.306 164.498,289.043 165.560,290.192 166.337 C 291.342 167.113,292.659 167.958,293.119 168.215 C 295.272 169.417,304.031 177.590,304.031 178.397 C 304.031 178.659,304.283 178.970,304.591 179.088 C 306.477 179.812,313.462 192.452,315.061 198.033 C 315.557 199.764,316.086 201.357,316.238 201.573 C 318.085 204.207,318.074 228.277,316.225 230.678 C 316.058 230.895,315.800 231.691,315.650 232.448 C 315.281 234.322,313.078 241.204,312.692 241.691 C 312.520 241.908,311.813 243.455,311.120 245.131 C 310.427 246.806,309.440 248.794,308.928 249.549 C 308.416 250.304,307.532 251.765,306.963 252.796 C 303.138 259.735,284.374 278.859,281.393 278.859 C 281.223 278.859,280.759 279.154,280.362 279.513 C 279.313 280.463,273.988 283.720,270.808 285.357 C 269.300 286.134,267.530 287.099,266.875 287.502 C 266.220 287.905,264.356 288.768,262.734 289.419 C 261.111 290.070,259.040 290.969,258.131 291.417 C 257.222 291.865,256.316 292.232,256.117 292.232 C 255.918 292.232,255.638 293.073,255.495 294.100 C 255.094 296.985,252.850 299.994,249.951 301.534 L 247.591 302.788 200.683 302.820 C 172.948 302.838,153.496 302.704,153.092 302.491 C 152.716 302.293,151.828 301.915,151.117 301.651 C 148.298 300.605,146.283 297.275,145.686 292.677 L 145.412 290.565 143.208 289.611 C 139.934 288.195,134.152 285.201,132.277 283.951 C 131.372 283.347,130.024 282.566,129.282 282.213 C 127.557 281.395,117.393 273.865,115.809 272.232 C 115.148 271.551,114.396 270.993,114.137 270.993 C 113.495 270.993,99.508 256.963,99.508 256.318 C 99.508 256.034,98.977 255.409,98.328 254.929 C 97.679 254.450,97.148 253.860,97.148 253.620 C 97.148 253.379,96.384 252.278,95.449 251.173 C 93.732 249.145,89.266 242.948,88.014 240.857 C 87.641 240.234,86.357 238.132,85.161 236.185 C 83.964 234.238,82.718 232.068,82.391 231.364 C 82.064 230.659,81.169 228.800,80.402 227.234 C 79.636 225.667,78.470 222.970,77.813 221.239 C 77.156 219.508,76.276 217.354,75.858 216.452 C 75.440 215.549,74.433 212.185,73.620 208.976 C 72.806 205.766,72.033 202.965,71.902 202.750 C 70.707 200.793,69.226 185.114,69.225 174.399 C 69.223 163.630,70.871 145.980,71.958 145.133 C 72.097 145.025,72.442 143.697,72.725 142.183 C 73.373 138.715,75.581 130.056,75.884 129.794 C 76.009 129.685,76.622 128.004,77.247 126.057 C 77.872 124.110,78.694 121.898,79.073 121.141 C 79.452 120.383,81.041 117.152,82.603 113.959 C 84.166 110.766,86.756 106.252,88.358 103.929 C 89.960 101.606,91.575 99.191,91.948 98.564 C 95.921 91.871,114.620 73.320,121.987 68.762 C 122.994 68.139,123.918 67.369,124.040 67.050 C 124.162 66.731,124.448 66.470,124.674 66.470 C 124.901 66.470,126.278 65.605,127.735 64.548 C 129.192 63.491,131.357 62.094,132.547 61.444 C 133.736 60.794,136.450 59.270,138.578 58.056 C 140.705 56.843,142.556 55.851,142.691 55.851 C 142.970 55.851,148.839 53.426,151.229 52.324 C 152.094 51.925,154.218 51.155,155.949 50.613 C 157.679 50.071,159.980 49.328,161.062 48.962 C 162.144 48.596,165.772 47.686,169.125 46.941 C 172.478 46.195,176.726 45.247,178.564 44.832 C 187.530 42.813,205.844 41.919,218.682 42.875 M112.127 158.644 C 110.939 162.358,110.697 177.745,111.708 185.251 C 112.458 190.818,115.318 203.165,116.298 205.058 C 116.629 205.700,117.225 207.125,117.623 208.225 C 118.020 209.326,118.606 210.940,118.925 211.813 C 119.559 213.547,122.776 219.258,124.668 222.007 C 125.324 222.960,125.860 223.854,125.860 223.992 C 125.860 224.130,127.053 225.771,128.512 227.639 C 135.059 236.024,145.323 244.545,154.472 249.193 C 155.933 249.936,157.306 250.675,157.522 250.837 C 157.738 250.999,158.977 251.606,160.275 252.187 C 161.573 252.769,163.786 253.762,165.192 254.395 C 166.598 255.027,169.607 256.110,171.878 256.799 C 174.149 257.489,176.663 258.305,177.464 258.613 C 189.252 263.141,219.453 263.148,230.482 258.625 C 231.239 258.315,233.628 257.502,235.792 256.819 C 251.106 251.983,266.854 240.556,274.921 228.424 C 281.680 218.261,279.922 206.384,270.814 200.682 C 269.939 200.134,269.135 199.557,269.027 199.399 C 268.614 198.798,260.856 194.779,258.604 193.999 C 250.836 191.309,248.866 190.897,234.415 188.942 C 230.413 188.401,225.988 187.800,224.582 187.608 C 223.176 187.415,214.503 187.248,205.310 187.237 C 196.116 187.225,186.205 187.040,183.284 186.826 C 173.756 186.126,163.599 184.815,161.849 184.058 C 161.416 183.871,160.000 183.519,158.702 183.276 C 155.478 182.672,148.565 180.887,148.083 180.534 C 147.866 180.376,146.362 179.791,144.739 179.233 C 139.580 177.460,138.720 177.091,134.984 175.054 C 132.972 173.956,131.158 173.058,130.953 173.058 C 130.748 173.058,130.580 172.889,130.580 172.683 C 130.580 172.477,129.978 172.023,129.243 171.674 C 127.667 170.926,120.333 164.840,115.750 160.478 L 112.522 157.406 112.127 158.644 M245.244 306.961 C 253.113 310.249,253.675 322.620,246.132 326.489 C 244.341 327.407,159.116 327.683,156.523 326.779 C 149.499 324.331,149.181 312.136,156.024 307.603 L 157.854 306.391 200.867 306.391 C 237.535 306.391,244.081 306.475,245.244 306.961 M238.902 332.290 C 240.180 333.092,241.419 334.090,241.655 334.509 C 241.891 334.928,242.526 335.985,243.066 336.858 C 244.342 338.921,244.460 343.639,243.284 345.526 C 241.222 348.835,240.431 349.792,238.725 351.044 L 236.866 352.409 231.412 352.419 L 225.959 352.429 225.248 353.972 C 220.338 364.625,200.029 368.942,186.234 362.265 C 182.722 360.565,177.033 355.580,176.428 353.672 C 176.161 352.832,175.972 352.802,170.942 352.802 C 164.236 352.802,161.642 351.614,159.357 347.493 C 158.394 345.758,158.436 338.178,159.418 336.361 C 160.392 334.560,163.005 332.027,164.198 331.727 C 164.745 331.590,165.192 331.320,165.192 331.127 C 165.192 330.924,180.224 330.788,200.885 330.804 L 236.578 330.832 238.902 332.290 \" stroke=\"none\" fill=\"#fcfbfb\" fill-rule=\"evenodd\"><\/path><path id=\"path2\" d=\"M203.048 42.771 C 204.941 42.843,208.038 42.843,209.931 42.771 C 211.824 42.699,210.275 42.640,206.490 42.640 C 202.704 42.640,201.155 42.699,203.048 42.771 M194.206 43.156 C 194.913 43.244,195.975 43.242,196.566 43.152 C 197.157 43.062,196.578 42.991,195.280 42.993 C 193.982 42.995,193.499 43.069,194.206 43.156 M216.421 43.153 C 217.016 43.243,217.989 43.243,218.584 43.153 C 219.179 43.063,218.692 42.989,217.502 42.989 C 216.313 42.989,215.826 43.063,216.421 43.153 M236.185 45.973 C 237.392 46.488,239.838 46.907,239.135 46.479 C 238.810 46.281,237.837 46.010,236.971 45.878 C 235.947 45.721,235.672 45.754,236.185 45.973 M171.288 46.429 C 170.740 46.678,170.978 46.713,172.075 46.546 C 172.940 46.414,173.722 46.242,173.812 46.162 C 174.150 45.864,172.043 46.087,171.288 46.429 M244.051 48.378 C 244.484 48.563,245.103 48.716,245.428 48.716 C 245.800 48.716,245.727 48.591,245.231 48.378 C 244.798 48.192,244.179 48.040,243.854 48.040 C 243.483 48.040,243.555 48.165,244.051 48.378 M246.608 49.098 C 246.932 49.298,247.640 49.581,248.181 49.725 C 248.864 49.908,248.984 49.877,248.574 49.624 C 248.250 49.423,247.542 49.141,247.001 48.996 C 246.318 48.814,246.198 48.845,246.608 49.098 M148.476 53.661 C 145.892 54.906,146.396 54.944,149.114 53.710 C 150.277 53.182,151.052 52.741,150.836 52.732 C 150.619 52.722,149.558 53.140,148.476 53.661 M257.227 53.491 C 257.984 53.905,258.781 54.244,258.997 54.244 C 259.213 54.244,258.771 53.905,258.014 53.491 C 257.257 53.076,256.460 52.737,256.244 52.737 C 256.028 52.737,256.470 53.076,257.227 53.491 M260.374 54.880 C 260.374 54.976,261.834 55.767,263.618 56.638 C 265.403 57.509,266.467 57.933,265.982 57.581 C 264.944 56.826,260.374 54.625,260.374 54.880 M140.708 57.057 C 139.897 57.486,139.233 57.924,139.233 58.031 C 139.233 58.206,142.340 56.755,142.740 56.392 C 143.193 55.983,142.011 56.369,140.708 57.057 M134.402 60.512 C 133.367 61.121,132.305 61.845,132.042 62.120 C 131.779 62.395,132.448 62.094,133.530 61.450 C 134.612 60.806,135.851 60.085,136.283 59.847 C 136.716 59.609,136.893 59.412,136.676 59.409 C 136.460 59.406,135.436 59.902,134.402 60.512 M274.533 62.653 C 274.533 62.742,275.772 63.639,277.286 64.646 C 278.800 65.652,280.039 66.393,280.039 66.291 C 280.039 66.189,279.022 65.422,277.778 64.587 C 275.023 62.736,274.533 62.444,274.533 62.653 M126.767 65.523 L 125.664 66.542 126.942 65.693 C 128.113 64.915,128.494 64.503,128.046 64.503 C 127.949 64.503,127.374 64.962,126.767 65.523 M120.810 69.834 C 118.429 71.685,116.247 73.494,115.960 73.855 C 115.673 74.216,116.765 73.446,118.387 72.145 C 120.010 70.844,122.266 69.108,123.402 68.288 C 125.281 66.931,125.763 66.470,125.302 66.470 C 125.212 66.470,123.190 67.984,120.810 69.834 M281.613 67.432 C 281.613 67.511,282.490 68.206,283.562 68.977 C 284.634 69.747,285.423 70.162,285.315 69.898 C 285.133 69.455,281.613 67.109,281.613 67.432 M286.579 71.105 C 287.040 71.476,289.419 73.370,291.866 75.313 C 299.930 81.714,308.266 90.268,312.091 96.067 C 313.717 98.533,314.235 99.006,313.275 97.150 C 310.580 91.938,288.529 70.302,286.029 70.416 C 285.871 70.423,286.119 70.733,286.579 71.105 M113.840 75.615 L 112.684 76.893 113.963 75.738 C 115.154 74.661,115.422 74.336,115.118 74.336 C 115.050 74.336,114.475 74.912,113.840 75.615 M110.521 78.466 C 109.566 79.440,108.873 80.236,108.981 80.236 C 109.089 80.236,109.959 79.440,110.914 78.466 C 111.870 77.493,112.563 76.696,112.455 76.696 C 112.347 76.696,111.477 77.493,110.521 78.466 M104.871 83.612 C 104.251 84.157,103.822 84.680,103.916 84.775 C 104.011 84.870,104.596 84.418,105.215 83.772 C 106.584 82.343,106.407 82.261,104.871 83.612 M198.530 84.841 C 199.019 84.935,199.727 84.931,200.103 84.833 C 200.479 84.734,200.079 84.657,199.213 84.662 C 198.348 84.666,198.040 84.747,198.530 84.841 M211.116 84.841 C 211.605 84.935,212.313 84.931,212.689 84.833 C 213.065 84.734,212.665 84.657,211.799 84.662 C 210.934 84.666,210.626 84.747,211.116 84.841 M181.121 86.922 C 180.061 87.192,180.041 87.223,180.924 87.230 C 181.465 87.234,182.350 87.096,182.891 86.922 C 184.213 86.499,182.785 86.499,181.121 86.922 M228.319 87.147 C 229.400 87.448,230.639 87.682,231.072 87.668 C 231.504 87.654,230.885 87.399,229.695 87.102 C 226.880 86.400,225.764 86.436,228.319 87.147 M100.295 88.692 C 99.340 89.666,98.646 90.462,98.755 90.462 C 98.863 90.462,99.733 89.666,100.688 88.692 C 101.644 87.719,102.337 86.922,102.229 86.922 C 102.121 86.922,101.250 87.719,100.295 88.692 M165.585 91.268 C 164.612 91.667,164.081 91.992,164.405 91.992 C 164.730 91.992,165.792 91.657,166.765 91.249 C 167.738 90.840,168.269 90.515,167.945 90.525 C 167.620 90.535,166.559 90.870,165.585 91.268 M240.708 90.669 C 240.708 90.898,241.961 91.406,243.461 91.785 C 244.002 91.922,243.736 91.693,242.871 91.277 C 241.201 90.474,240.708 90.335,240.708 90.669 M96.362 93.215 C 95.456 94.297,94.804 95.182,94.912 95.182 C 95.020 95.182,95.850 94.297,96.755 93.215 C 97.661 92.134,98.313 91.249,98.205 91.249 C 98.097 91.249,97.267 92.134,96.362 93.215 M157.758 94.613 C 157.022 94.933,156.519 95.293,156.639 95.414 C 156.866 95.640,159.292 94.520,159.292 94.189 C 159.292 93.945,159.310 93.939,157.758 94.613 M249.332 94.684 C 250.370 95.440,252.507 96.429,252.507 96.153 C 252.507 96.059,251.578 95.533,250.442 94.985 C 249.269 94.419,248.789 94.289,249.332 94.684 M93.754 96.460 C 92.278 98.139,89.502 102.262,89.848 102.262 C 89.954 102.262,90.779 101.155,91.684 99.803 C 92.588 98.451,93.687 96.947,94.127 96.460 C 94.566 95.973,94.837 95.575,94.729 95.575 C 94.621 95.575,94.182 95.973,93.754 96.460 M151.622 98.405 C 149.944 99.598,146.468 102.969,145.011 104.818 C 144.329 105.683,145.273 104.874,147.107 103.018 C 148.942 101.163,151.062 99.180,151.819 98.612 C 153.465 97.377,153.305 97.209,151.622 98.405 M255.261 98.033 C 256.121 98.853,261.294 102.009,261.000 101.534 C 260.863 101.312,259.383 100.307,257.711 99.300 C 256.039 98.293,254.936 97.723,255.261 98.033 M314.928 100.874 C 315.509 102.058,316.050 102.960,316.131 102.880 C 316.307 102.703,314.323 98.722,314.059 98.722 C 313.956 98.722,314.348 99.690,314.928 100.874 M262.734 102.778 C 262.734 102.875,263.383 103.450,264.177 104.056 C 264.972 104.662,265.497 104.957,265.345 104.711 C 265.034 104.208,262.734 102.505,262.734 102.778 M269.063 108.187 C 270.922 110.011,272.958 112.132,273.586 112.899 C 274.215 113.666,274.559 114.020,274.351 113.685 C 273.330 112.046,270.365 108.828,268.153 106.957 C 266.082 105.205,266.228 105.404,269.063 108.187 M85.183 109.231 C 84.409 110.468,83.776 111.662,83.777 111.885 C 83.778 112.109,84.151 111.672,84.605 110.914 C 85.060 110.157,85.782 108.963,86.209 108.260 C 86.637 107.557,86.897 106.981,86.788 106.981 C 86.679 106.981,85.957 107.993,85.183 109.231 M141.751 109.980 C 141.213 111.197,140.840 112.259,140.922 112.341 C 141.003 112.422,141.528 111.427,142.089 110.129 C 142.649 108.830,143.022 107.768,142.918 107.768 C 142.815 107.768,142.289 108.763,141.751 109.980 M80.764 117.823 C 80.213 119.026,79.831 120.080,79.914 120.164 C 79.998 120.247,80.533 119.263,81.102 117.975 C 81.671 116.688,82.053 115.634,81.951 115.634 C 81.849 115.634,81.315 116.619,80.764 117.823 M276.674 117.871 C 277.008 118.560,277.476 119.245,277.716 119.393 C 278.244 119.719,277.675 118.599,276.706 117.404 C 276.114 116.674,276.112 116.707,276.674 117.871 M314.642 118.965 C 314.097 120.126,313.790 120.990,313.960 120.885 C 314.430 120.594,315.894 117.589,315.756 117.198 C 315.689 117.009,315.188 117.804,314.642 118.965 M139.359 121.534 C 139.359 122.940,139.430 123.515,139.518 122.812 C 139.605 122.109,139.605 120.959,139.518 120.256 C 139.430 119.553,139.359 120.128,139.359 121.534 M278.794 121.007 C 279.993 122.750,284.772 126.647,285.710 126.647 C 285.921 126.647,285.292 126.139,284.312 125.518 C 283.333 124.896,281.498 123.348,280.235 122.076 C 278.897 120.729,278.296 120.283,278.794 121.007 M309.599 125.197 C 309.363 125.482,308.279 126.131,307.192 126.641 C 306.104 127.150,305.284 127.637,305.370 127.723 C 305.619 127.972,309.337 125.986,309.906 125.301 C 310.189 124.960,310.332 124.680,310.224 124.680 C 310.116 124.680,309.834 124.913,309.599 125.197 M77.380 125.736 C 77.280 125.913,77.093 126.588,76.964 127.237 C 76.730 128.411,76.732 128.410,77.322 127.093 C 77.837 125.945,77.883 124.846,77.380 125.736 M294.405 129.083 C 295.708 129.254,297.832 129.254,299.125 129.082 C 301.135 128.816,300.792 128.771,296.755 128.771 C 292.703 128.772,292.371 128.816,294.405 129.083 M75.741 130.805 C 75.596 131.381,75.554 131.929,75.647 132.021 C 75.739 132.114,75.933 131.718,76.078 131.142 C 76.223 130.566,76.265 130.018,76.173 129.925 C 76.080 129.833,75.886 130.228,75.741 130.805 M141.544 132.815 C 141.997 133.720,142.582 134.592,142.842 134.753 C 143.103 134.914,142.900 134.351,142.392 133.501 C 141.063 131.282,140.580 130.890,141.544 132.815 M145.100 137.027 C 145.407 137.399,146.027 137.899,146.477 138.139 C 147.222 138.536,147.246 138.514,146.738 137.899 C 146.432 137.528,145.812 137.027,145.362 136.787 C 144.617 136.390,144.593 136.412,145.100 137.027 M73.187 140.050 C 72.945 141.178,72.822 142.176,72.913 142.267 C 73.005 142.359,73.277 141.511,73.519 140.383 C 73.761 139.255,73.884 138.257,73.793 138.165 C 73.701 138.074,73.429 138.922,73.187 140.050 M148.673 139.489 C 148.673 139.751,154.612 142.471,154.792 142.291 C 154.872 142.211,153.528 141.505,151.805 140.722 C 150.082 139.940,148.673 139.385,148.673 139.489 M165.192 145.526 C 165.733 145.699,166.529 145.841,166.962 145.841 C 167.585 145.841,167.544 145.775,166.765 145.526 C 166.224 145.353,165.428 145.211,164.995 145.211 C 164.372 145.211,164.413 145.277,165.192 145.526 M184.169 148.550 C 184.548 148.649,185.167 148.649,185.546 148.550 C 185.924 148.451,185.615 148.371,184.857 148.371 C 184.100 148.371,183.791 148.451,184.169 148.550 M189.288 148.955 C 189.885 149.045,190.770 149.043,191.254 148.949 C 191.738 148.856,191.249 148.782,190.167 148.785 C 189.086 148.788,188.690 148.864,189.288 148.955 M197.050 149.465 C 201.916 149.771,213.413 149.945,213.143 149.709 C 213.053 149.630,208.378 149.479,202.753 149.373 C 196.750 149.260,194.395 149.298,197.050 149.465 M218.584 150.142 C 219.720 150.222,221.578 150.222,222.714 150.142 C 223.850 150.063,222.920 149.998,220.649 149.998 C 218.378 149.998,217.448 150.063,218.584 150.142 M248.771 152.606 C 249.420 152.771,250.482 152.907,251.131 152.907 C 252.123 152.908,252.060 152.857,250.737 152.583 C 248.745 152.171,247.135 152.190,248.771 152.606 M253.491 153.392 C 255.154 153.816,256.582 153.816,255.261 153.392 C 254.720 153.219,253.835 153.081,253.294 153.085 C 252.411 153.091,252.431 153.123,253.491 153.392 M266.667 156.735 C 267.424 157.027,268.309 157.266,268.633 157.266 C 268.958 157.266,268.604 157.027,267.847 156.735 C 267.089 156.444,266.205 156.205,265.880 156.205 C 265.556 156.205,265.910 156.444,266.667 156.735 M70.101 158.112 C 70.101 158.869,70.182 159.179,70.281 158.800 C 70.380 158.422,70.380 157.802,70.281 157.424 C 70.182 157.045,70.101 157.355,70.101 158.112 M114.095 158.800 C 114.334 159.179,114.999 159.826,115.574 160.239 C 116.401 160.834,116.337 160.691,115.262 159.551 C 113.771 157.968,113.433 157.751,114.095 158.800 M274.959 159.454 C 275.275 159.767,279.404 161.238,279.551 161.091 C 279.633 161.009,278.708 160.571,277.495 160.117 C 275.346 159.313,274.626 159.125,274.959 159.454 M69.480 163.119 C 69.342 164.583,69.254 167.198,69.284 168.928 C 69.326 171.323,69.417 170.717,69.664 166.394 C 70.006 160.410,69.906 158.616,69.480 163.119 M118.205 162.537 C 118.792 163.240,119.559 163.972,119.911 164.163 C 120.263 164.354,119.851 163.779,118.996 162.885 C 117.137 160.941,116.719 160.757,118.205 162.537 M283.612 162.971 C 284.138 163.418,287.512 165.233,287.512 165.070 C 287.512 164.829,284.144 162.832,283.739 162.832 C 283.579 162.832,283.522 162.894,283.612 162.971 M110.797 167.120 C 110.645 169.155,110.548 172.429,110.580 174.397 C 110.625 177.088,110.722 176.318,110.970 171.288 C 111.335 163.898,111.229 161.331,110.797 167.120 M123.107 166.495 C 123.107 166.603,123.992 167.433,125.074 168.338 C 126.155 169.244,127.040 169.896,127.040 169.788 C 127.040 169.680,126.155 168.851,125.074 167.945 C 123.992 167.039,123.107 166.387,123.107 166.495 M291.052 167.288 C 291.052 167.360,291.893 167.993,292.920 168.696 L 294.789 169.975 293.215 168.572 C 291.830 167.338,291.052 166.876,291.052 167.288 M128.195 170.720 C 129.317 171.671,133.769 174.327,133.946 174.150 C 134.012 174.083,132.530 173.102,130.652 171.968 C 128.774 170.835,127.668 170.273,128.195 170.720 M298.304 173.089 C 300.237 174.911,303.202 178.136,304.892 180.256 C 308.115 184.300,309.171 185.134,306.293 181.363 C 304.074 178.456,299.229 173.378,296.768 171.382 C 295.679 170.499,296.370 171.267,298.304 173.089 M134.513 174.433 C 134.513 174.696,139.281 177.074,139.457 176.898 C 139.536 176.819,138.456 176.190,137.057 175.500 C 135.658 174.810,134.513 174.330,134.513 174.433 M69.367 180.728 C 69.368 182.891,69.434 183.726,69.514 182.583 C 69.593 181.440,69.592 179.670,69.512 178.650 C 69.431 177.629,69.366 178.564,69.367 180.728 M111.044 180.728 C 111.045 182.242,111.116 182.813,111.201 181.997 C 111.287 181.181,111.285 179.942,111.198 179.244 C 111.111 178.546,111.042 179.213,111.044 180.728 M144.297 178.962 C 145.244 179.398,146.483 179.848,147.051 179.962 C 147.618 180.076,147.198 179.807,146.116 179.365 C 143.426 178.264,142.183 177.989,144.297 178.962 M156.342 182.705 C 157.207 182.990,158.269 183.221,158.702 183.219 C 159.135 183.216,158.604 182.968,157.522 182.667 C 155.061 181.982,154.230 182.009,156.342 182.705 M111.399 185.251 C 111.399 186.008,111.480 186.318,111.579 185.939 C 111.678 185.560,111.678 184.941,111.579 184.562 C 111.480 184.184,111.399 184.494,111.399 185.251 M69.729 186.627 C 69.732 187.709,69.808 188.105,69.899 187.507 C 69.989 186.909,69.987 186.024,69.893 185.540 C 69.800 185.057,69.726 185.546,69.729 186.627 M174.336 185.915 C 174.715 186.014,175.334 186.014,175.713 185.915 C 176.091 185.816,175.782 185.735,175.025 185.735 C 174.267 185.735,173.958 185.816,174.336 185.915 M179.154 186.436 C 181.161 186.762,185.908 186.941,185.611 186.680 C 185.521 186.601,183.589 186.442,181.318 186.327 C 178.533 186.186,177.828 186.222,179.154 186.436 M187.897 187.108 C 188.595 187.195,189.834 187.196,190.650 187.111 C 191.466 187.026,190.895 186.955,189.381 186.953 C 187.866 186.951,187.199 187.021,187.897 187.108 M210.718 187.117 C 212.502 187.189,215.423 187.189,217.207 187.117 C 218.992 187.044,217.532 186.984,213.963 186.984 C 210.393 186.984,208.933 187.044,210.718 187.117 M311.227 190.016 C 312.137 191.880,312.946 193.349,313.026 193.280 C 313.228 193.106,310.938 188.367,310.190 187.414 C 309.850 186.981,310.317 188.152,311.227 190.016 M223.500 187.488 C 223.879 187.587,224.499 187.587,224.877 187.488 C 225.256 187.389,224.946 187.309,224.189 187.309 C 223.432 187.309,223.122 187.389,223.500 187.488 M70.101 190.364 C 70.101 191.121,70.182 191.431,70.281 191.052 C 70.380 190.674,70.380 190.054,70.281 189.676 C 70.182 189.297,70.101 189.607,70.101 190.364 M244.838 190.364 C 245.487 190.529,246.460 190.664,247.001 190.664 C 247.878 190.664,247.857 190.632,246.804 190.364 C 246.155 190.199,245.182 190.064,244.641 190.064 C 243.764 190.064,243.785 190.096,244.838 190.364 M257.653 193.280 C 257.743 193.370,259.493 194.170,261.542 195.058 C 263.591 195.947,265.095 196.504,264.885 196.296 C 264.675 196.089,263.028 195.289,261.224 194.518 C 258.135 193.198,257.270 192.899,257.653 193.280 M314.121 196.264 C 314.570 198.035,315.489 200.199,315.226 198.863 C 315.102 198.238,314.748 197.176,314.437 196.504 C 314.012 195.583,313.934 195.524,314.121 196.264 M266.470 197.328 C 266.686 197.550,267.824 198.368,268.999 199.146 C 271.559 200.841,275.397 204.508,276.531 206.344 C 277.516 207.938,277.928 208.105,277.133 206.588 C 276.218 204.840,273.846 202.284,271.453 200.466 C 269.213 198.764,265.735 196.574,266.470 197.328 M114.694 201.573 C 115.018 203.019,115.243 203.333,115.235 202.327 C 115.232 201.912,115.049 201.308,114.830 200.983 C 114.538 200.552,114.502 200.712,114.694 201.573 M72.819 205.506 C 72.823 206.327,73.865 209.341,73.907 208.653 C 73.920 208.437,73.680 207.463,73.373 206.490 C 73.067 205.516,72.817 205.074,72.819 205.506 M117.742 210.029 C 118.040 211.134,120.467 216.341,120.615 216.193 C 120.696 216.112,120.047 214.559,119.173 212.743 C 118.298 210.926,117.655 209.705,117.742 210.029 M317.553 215.929 C 317.553 218.417,317.617 219.435,317.695 218.191 C 317.773 216.947,317.773 214.912,317.695 213.668 C 317.617 212.424,317.553 213.441,317.553 215.929 M76.911 218.781 C 77.058 219.267,77.340 219.839,77.538 220.050 C 77.736 220.261,77.698 219.863,77.455 219.165 C 76.957 217.736,76.497 217.412,76.911 218.781 M122.543 219.764 C 124.279 222.755,126.701 226.232,126.906 226.028 C 127.009 225.924,126.483 225.039,125.737 224.061 C 124.991 223.084,123.815 221.296,123.125 220.090 C 122.434 218.883,121.777 217.896,121.664 217.896 C 121.552 217.896,121.947 218.736,122.543 219.764 M78.691 222.812 C 78.691 223.029,78.944 223.648,79.253 224.189 C 79.562 224.730,79.815 224.995,79.815 224.779 C 79.815 224.562,79.562 223.943,79.253 223.402 C 78.944 222.861,78.691 222.596,78.691 222.812 M277.350 224.402 C 276.691 225.849,276.817 226.157,277.529 224.842 C 277.862 224.228,278.061 223.652,277.971 223.562 C 277.881 223.472,277.601 223.850,277.350 224.402 M79.843 225.537 C 79.843 225.986,82.999 232.193,83.458 232.645 C 83.809 232.991,80.379 225.819,79.994 225.402 C 79.911 225.311,79.843 225.372,79.843 225.537 M131.170 231.662 C 132.015 232.527,132.795 233.235,132.903 233.235 C 133.011 233.235,132.408 232.527,131.563 231.662 C 130.718 230.796,129.939 230.088,129.831 230.088 C 129.722 230.088,130.325 230.796,131.170 231.662 M272.250 232.547 C 269.860 235.548,263.739 241.506,260.669 243.819 C 258.271 245.625,257.524 246.499,259.685 244.970 C 264.292 241.711,275.779 230.088,274.393 230.088 C 274.291 230.088,273.327 231.195,272.250 232.547 M314.687 234.451 C 314.421 235.338,314.276 236.137,314.364 236.226 C 314.452 236.314,314.743 235.660,315.008 234.773 C 315.274 233.885,315.420 233.086,315.331 232.998 C 315.243 232.909,314.953 233.563,314.687 234.451 M84.366 234.415 C 84.701 235.064,85.064 235.595,85.173 235.595 C 85.281 235.595,85.095 235.064,84.759 234.415 C 84.424 233.766,84.060 233.235,83.952 233.235 C 83.844 233.235,84.030 233.766,84.366 234.415 M132.940 233.728 C 132.940 233.828,134.400 235.216,136.185 236.814 C 137.970 238.411,139.184 239.406,138.883 239.025 C 138.214 238.176,132.940 233.476,132.940 233.728 M87.300 239.382 C 87.792 240.276,88.621 241.515,89.144 242.136 C 89.666 242.756,89.376 242.125,88.499 240.732 C 86.619 237.745,86.040 237.094,87.300 239.382 M311.027 244.195 C 310.675 245.089,310.457 245.821,310.543 245.821 C 310.858 245.821,311.941 243.393,311.806 242.988 C 311.729 242.757,311.378 243.300,311.027 244.195 M145.133 243.995 C 145.133 244.200,149.293 246.930,151.607 248.245 C 154.014 249.612,153.098 248.896,148.756 246.017 C 145.658 243.962,145.133 243.669,145.133 243.995 M256.244 247.001 C 255.379 247.632,254.546 248.156,254.393 248.165 C 254.095 248.182,251.288 250.031,250.944 250.437 C 250.627 250.811,254.461 248.593,256.342 247.313 C 257.262 246.688,258.014 246.097,258.014 245.999 C 258.014 245.724,257.924 245.775,256.244 247.001 M158.112 251.721 C 159.735 252.565,161.239 253.255,161.455 253.255 C 161.672 253.255,160.521 252.565,158.899 251.721 C 157.276 250.877,155.772 250.186,155.556 250.186 C 155.339 250.186,156.490 250.877,158.112 251.721 M95.395 250.934 C 97.713 255.156,114.336 271.648,120.354 275.696 C 122.388 277.064,121.085 275.886,116.224 271.962 C 111.145 267.860,103.737 260.531,99.344 255.261 C 95.795 251.002,94.884 250.004,95.395 250.934 M246.608 252.507 C 244.553 253.567,243.007 254.443,243.174 254.454 C 243.592 254.482,250.541 250.972,250.541 250.734 C 250.541 250.466,250.745 250.374,246.608 252.507 M307.201 251.444 C 306.906 251.921,306.406 252.709,306.089 253.196 C 305.773 253.682,305.599 254.081,305.703 254.081 C 306.012 254.081,308.096 250.934,307.910 250.748 C 307.815 250.654,307.497 250.967,307.201 251.444 M163.618 254.277 C 164.159 254.586,164.779 254.839,164.995 254.839 C 165.211 254.839,164.946 254.586,164.405 254.277 C 163.864 253.968,163.245 253.715,163.029 253.715 C 162.812 253.715,163.078 253.968,163.618 254.277 M303.067 257.522 C 301.816 259.199,301.150 260.249,301.587 259.856 C 302.402 259.123,305.780 254.474,305.498 254.474 C 305.411 254.474,304.317 255.846,303.067 257.522 M167.552 255.737 C 167.660 255.843,168.364 256.138,169.116 256.393 C 169.868 256.647,170.311 256.686,170.099 256.479 C 169.888 256.272,169.184 255.977,168.535 255.823 C 167.886 255.669,167.443 255.630,167.552 255.737 M237.955 256.274 L 236.971 256.867 237.955 256.606 C 239.382 256.228,240.317 255.677,239.528 255.680 C 239.204 255.681,238.496 255.948,237.955 256.274 M231.858 258.407 C 231.363 258.620,231.290 258.745,231.662 258.745 C 231.986 258.745,232.606 258.593,233.038 258.407 C 233.534 258.194,233.607 258.069,233.235 258.069 C 232.911 258.069,232.291 258.221,231.858 258.407 M179.777 259.732 C 179.867 259.811,180.649 259.984,181.514 260.116 C 182.611 260.282,182.849 260.247,182.301 259.999 C 181.546 259.657,179.439 259.434,179.777 259.732 M224.975 260.177 C 224.002 260.459,223.471 260.704,223.795 260.721 C 224.120 260.738,225.270 260.506,226.352 260.205 C 227.434 259.904,227.965 259.659,227.532 259.661 C 227.099 259.663,225.949 259.895,224.975 260.177 M198.136 262.618 C 198.626 262.712,199.334 262.709,199.710 262.610 C 200.086 262.512,199.685 262.435,198.820 262.439 C 197.955 262.444,197.647 262.524,198.136 262.618 M208.756 262.618 C 209.245 262.712,209.953 262.709,210.329 262.610 C 210.705 262.512,210.305 262.435,209.440 262.439 C 208.574 262.444,208.267 262.524,208.756 262.618 M294.779 267.141 C 293.054 268.916,292.527 269.580,293.609 268.616 C 295.545 266.890,298.369 263.913,298.070 263.913 C 297.986 263.913,296.505 265.366,294.779 267.141 M289.651 271.878 L 288.496 273.156 289.774 272.001 C 290.477 271.366,291.052 270.791,291.052 270.723 C 291.052 270.419,290.728 270.687,289.651 271.878 M280.525 278.747 C 279.387 279.524,278.533 280.238,278.629 280.334 C 278.832 280.536,282.242 278.252,282.599 277.674 C 282.942 277.119,282.824 277.180,280.525 278.747 M123.500 277.838 C 123.500 277.946,124.297 278.583,125.270 279.253 C 126.244 279.922,127.040 280.382,127.040 280.274 C 127.040 280.166,126.244 279.529,125.270 278.859 C 124.297 278.190,123.500 277.730,123.500 277.838 M128.741 281.500 C 129.037 281.979,132.311 283.972,132.803 283.972 C 133.148 283.972,132.357 283.413,130.019 282.001 C 129.169 281.489,128.594 281.263,128.741 281.500 M272.468 283.804 C 270.998 284.602,271.087 284.934,272.566 284.169 C 273.215 283.834,273.746 283.475,273.746 283.372 C 273.746 283.119,273.704 283.134,272.468 283.804 M135.300 285.347 C 135.300 285.610,140.854 288.382,141.029 288.207 C 141.108 288.129,139.851 287.411,138.236 286.612 C 136.621 285.813,135.300 285.244,135.300 285.347 M267.060 286.726 C 265.438 287.570,264.218 288.269,264.351 288.279 C 264.837 288.319,269.763 285.945,270.004 285.555 C 270.340 285.012,270.404 284.987,267.060 286.726 M261.357 289.479 C 260.492 289.879,260.014 290.220,260.295 290.236 C 260.854 290.268,263.127 289.179,263.127 288.879 C 263.127 288.647,263.232 288.611,261.357 289.479 M144.227 289.762 C 145.156 290.225,145.526 290.708,145.639 291.605 L 145.793 292.822 145.856 291.554 C 145.916 290.359,144.499 289.014,143.284 289.111 C 143.111 289.125,143.536 289.418,144.227 289.762 M145.967 294.199 C 145.960 294.523,146.198 295.320,146.495 295.969 C 147.191 297.488,147.201 296.781,146.509 294.985 C 146.218 294.228,145.974 293.874,145.967 294.199 M254.081 296.885 C 254.081 297.137,253.423 298.096,252.620 299.016 C 251.234 300.603,251.225 300.628,252.457 299.508 C 253.884 298.211,254.664 297.010,254.309 296.656 C 254.183 296.530,254.081 296.633,254.081 296.885 M249.361 301.278 C 248.591 301.700,248.269 302.039,248.629 302.048 C 248.984 302.057,249.692 301.717,250.202 301.291 C 251.369 300.319,251.120 300.315,249.361 301.278 M154.671 302.351 C 155.482 302.436,156.809 302.436,157.620 302.351 C 158.432 302.267,157.768 302.197,156.146 302.197 C 154.523 302.197,153.859 302.267,154.671 302.351 M231.587 302.359 C 234.683 302.426,239.639 302.426,242.600 302.359 C 245.561 302.292,243.029 302.238,236.971 302.238 C 230.914 302.238,228.492 302.293,231.587 302.359 M179.843 306.686 C 191.470 306.744,210.497 306.744,222.124 306.686 C 233.751 306.628,224.238 306.581,200.983 306.581 C 177.729 306.581,168.215 306.628,179.843 306.686 M247.659 309.009 C 248.345 309.624,249.274 310.747,249.722 311.504 C 250.171 312.262,250.539 312.725,250.539 312.534 C 250.543 311.763,248.835 309.501,247.662 308.721 L 246.411 307.890 247.659 309.009 M154.103 309.046 C 152.905 310.441,152.914 310.880,154.118 309.759 C 154.801 309.124,155.359 308.549,155.359 308.481 C 155.359 308.114,154.616 308.449,154.103 309.046 M249.555 322.376 C 249.140 323.147,248.174 324.309,247.409 324.958 C 246.644 325.607,246.372 325.959,246.804 325.741 C 248.104 325.083,250.909 321.574,250.479 321.144 C 250.386 321.051,249.970 321.606,249.555 322.376 M152.606 322.870 C 152.606 323.562,155.506 326.451,156.198 326.448 C 156.493 326.446,156.205 326.098,155.556 325.673 C 154.907 325.248,153.977 324.325,153.491 323.622 C 153.004 322.918,152.606 322.580,152.606 322.870 M164.110 331.952 C 163.407 332.381,162.832 332.820,162.832 332.928 C 162.832 333.037,163.407 332.774,164.110 332.346 C 165.898 331.256,235.497 331.107,237.776 332.188 C 239.212 332.870,242.675 336.354,242.675 337.119 C 242.675 337.380,242.783 337.486,242.916 337.353 C 243.657 336.612,239.644 332.430,237.360 331.562 C 235.081 330.695,165.564 331.066,164.110 331.952 M243.574 341.200 C 243.577 342.281,243.653 342.677,243.743 342.079 C 243.834 341.481,243.831 340.596,243.738 340.113 C 243.645 339.629,243.571 340.118,243.574 341.200 M158.623 341.790 C 158.623 342.979,158.697 343.466,158.787 342.871 C 158.877 342.276,158.877 341.303,158.787 340.708 C 158.697 340.113,158.623 340.600,158.623 341.790 M159.294 346.345 C 159.295 346.787,160.780 349.263,161.043 349.263 C 161.147 349.263,160.852 348.599,160.388 347.788 C 159.347 345.971,159.292 345.897,159.294 346.345 M241.294 347.827 C 240.643 348.706,239.346 350.008,238.412 350.720 C 237.478 351.433,236.915 352.016,237.161 352.016 C 237.706 352.016,241.802 348.191,242.347 347.173 C 243.052 345.856,242.502 346.198,241.294 347.827 M163.170 351.206 C 163.681 351.651,164.286 352.016,164.514 352.016 C 164.998 352.016,164.975 351.996,163.422 351.087 L 162.242 350.396 163.170 351.206 M176.591 353.472 C 177.119 354.593,180.789 358.792,181.644 359.254 C 182.005 359.449,181.236 358.476,179.934 357.091 C 178.632 355.706,177.255 354.130,176.874 353.589 C 176.318 352.798,176.262 352.776,176.591 353.472 M222.374 357.012 C 221.541 358.030,221.064 358.735,221.315 358.580 C 221.850 358.249,224.341 355.162,224.073 355.162 C 223.972 355.162,223.208 355.995,222.374 357.012 M184.857 361.274 C 184.857 361.559,188.834 363.474,189.160 363.346 C 189.329 363.279,188.430 362.748,187.162 362.165 C 185.895 361.582,184.857 361.181,184.857 361.274 M215.536 362.045 C 214.562 362.566,214.011 363.001,214.310 363.011 C 214.847 363.028,217.502 361.544,217.502 361.227 C 217.502 360.993,217.494 360.997,215.536 362.045 M199.312 365.285 C 200.447 365.365,202.306 365.365,203.441 365.285 C 204.577 365.206,203.648 365.141,201.377 365.141 C 199.105 365.141,198.176 365.206,199.312 365.285 \" stroke=\"none\" fill=\"#fc7b8c\" fill-rule=\"evenodd\"><\/path><path id=\"path3\" d=\"M189.863 0.284 C 190.562 0.371,191.801 0.372,192.617 0.287 C 193.433 0.202,192.861 0.131,191.347 0.129 C 189.833 0.127,189.165 0.197,189.863 0.284 M207.169 0.284 C 207.867 0.371,209.106 0.372,209.922 0.287 C 210.738 0.202,210.167 0.131,208.653 0.129 C 207.139 0.127,206.471 0.197,207.169 0.284 M183.190 0.671 C 183.680 0.766,184.388 0.762,184.764 0.664 C 185.140 0.565,184.739 0.488,183.874 0.493 C 183.009 0.497,182.701 0.577,183.190 0.671 M215.442 0.671 C 215.931 0.766,216.639 0.762,217.015 0.664 C 217.391 0.565,216.991 0.488,216.126 0.493 C 215.261 0.497,214.953 0.577,215.442 0.671 M167.945 2.360 C 167.421 2.699,167.421 2.741,167.945 2.741 C 168.269 2.741,168.800 2.570,169.125 2.360 C 169.649 2.021,169.649 1.979,169.125 1.979 C 168.800 1.979,168.269 2.150,167.945 2.360 M231.072 2.360 C 231.205 2.576,231.580 2.753,231.905 2.753 C 232.229 2.753,232.385 2.576,232.252 2.360 C 232.118 2.144,231.743 1.967,231.419 1.967 C 231.094 1.967,230.938 2.144,231.072 2.360 M162.635 3.147 C 161.938 3.446,161.972 3.488,162.930 3.512 C 163.525 3.527,164.012 3.363,164.012 3.147 C 164.012 2.685,163.709 2.685,162.635 3.147 M236.382 3.147 C 236.382 3.363,236.780 3.537,237.266 3.534 C 237.982 3.529,238.039 3.455,237.561 3.147 C 236.799 2.654,236.382 2.654,236.382 3.147 M253.687 7.134 C 253.687 7.321,253.938 7.473,254.245 7.473 C 254.552 7.473,255.112 7.592,255.490 7.736 C 255.922 7.902,256.082 7.847,255.921 7.587 C 255.599 7.066,253.687 6.678,253.687 7.134 M132.842 10.772 C 132.247 10.988,131.760 11.326,131.760 11.524 C 131.760 11.722,132.042 11.775,132.387 11.643 C 132.731 11.511,133.439 11.296,133.960 11.165 C 134.946 10.918,135.271 10.349,134.415 10.368 C 134.145 10.374,133.437 10.556,132.842 10.772 M124.067 14.388 C 123.369 14.957,123.365 14.991,124.024 14.781 C 124.421 14.656,124.907 14.553,125.106 14.553 C 125.305 14.553,125.467 14.376,125.467 14.159 C 125.467 13.590,124.942 13.676,124.067 14.388 M275.100 14.368 C 275.520 14.686,276.051 14.940,276.280 14.933 C 276.509 14.927,276.353 14.661,275.933 14.343 C 275.513 14.026,274.982 13.772,274.753 13.778 C 274.524 13.785,274.680 14.051,275.100 14.368 M283.972 18.088 C 283.972 18.264,284.503 18.594,285.152 18.820 C 285.801 19.046,286.332 19.102,286.332 18.945 C 286.332 18.787,285.801 18.458,285.152 18.213 C 284.503 17.968,283.972 17.912,283.972 18.088 M114.356 18.390 C 113.977 18.475,113.668 18.707,113.668 18.908 C 113.668 19.369,114.094 19.364,114.836 18.894 C 115.543 18.448,115.290 18.183,114.356 18.390 M106.883 22.089 C 106.288 22.307,105.801 22.643,105.801 22.837 C 105.801 23.190,107.637 22.549,108.338 21.951 C 108.831 21.531,108.264 21.585,106.883 22.089 M292.232 21.971 C 292.232 22.148,292.675 22.494,293.215 22.741 C 293.756 22.987,294.199 23.044,294.199 22.867 C 294.199 22.690,293.756 22.344,293.215 22.097 C 292.675 21.851,292.232 21.794,292.232 21.971 M101.278 25.199 C 100.629 25.614,99.921 26.020,99.705 26.099 C 99.489 26.179,99.408 26.350,99.526 26.479 C 99.643 26.609,100.528 26.191,101.492 25.552 C 102.456 24.912,103.068 24.401,102.852 24.416 C 102.635 24.431,101.927 24.783,101.278 25.199 M299.312 25.979 C 300.354 26.689,302.065 27.558,302.065 27.377 C 302.065 27.124,299.478 25.564,299.069 25.571 C 298.878 25.575,298.987 25.758,299.312 25.979 M304.031 28.459 C 304.031 28.755,307.178 30.681,307.184 30.389 C 307.187 30.224,307.362 30.354,307.571 30.678 C 307.781 31.003,307.955 31.066,307.959 30.818 C 307.962 30.570,307.080 29.905,305.998 29.339 C 304.916 28.774,304.031 28.378,304.031 28.459 M93.684 29.484 C 92.969 29.884,92.544 30.310,92.741 30.431 C 92.937 30.553,93.690 30.216,94.413 29.682 C 95.950 28.548,95.552 28.440,93.684 29.484 M87.043 34.045 C 86.316 34.709,86.207 34.920,86.726 34.664 C 87.980 34.045,89.129 33.065,88.616 33.051 C 88.357 33.044,87.650 33.492,87.043 34.045 M311.701 33.670 C 313.206 34.830,314.115 35.101,312.957 34.045 C 312.350 33.492,311.643 33.044,311.384 33.051 C 311.126 33.058,311.268 33.336,311.701 33.670 M83.088 36.623 C 82.384 37.074,81.809 37.633,81.809 37.865 C 81.809 38.098,82.296 37.862,82.891 37.341 C 83.486 36.820,84.141 36.258,84.346 36.092 C 85.067 35.512,84.353 35.813,83.088 36.623 M316.618 36.890 C 317.375 37.542,318.082 37.989,318.190 37.884 C 318.402 37.678,317.291 36.767,316.028 36.113 C 315.595 35.889,315.860 36.238,316.618 36.890 M318.645 38.138 C 318.727 38.384,319.411 38.947,320.164 39.389 C 320.917 39.831,321.180 39.907,320.747 39.558 C 320.315 39.209,319.631 38.646,319.228 38.307 C 318.825 37.968,318.563 37.892,318.645 38.138 M78.128 40.339 C 77.077 41.083,76.458 41.685,76.752 41.676 C 77.046 41.668,77.994 41.052,78.859 40.306 C 80.848 38.592,80.580 38.604,78.128 40.339 M321.731 40.681 C 321.731 40.775,322.232 41.208,322.845 41.645 C 323.688 42.245,323.959 42.303,323.959 41.885 C 323.959 41.581,323.832 41.411,323.676 41.508 C 323.520 41.604,323.174 41.419,322.907 41.097 C 322.454 40.551,321.731 40.296,321.731 40.681 M74.533 43.265 C 73.716 43.913,72.902 44.444,72.723 44.444 C 72.544 44.444,72.190 44.833,71.936 45.307 C 71.572 45.987,71.829 45.882,73.145 44.816 C 74.065 44.071,75.195 43.155,75.658 42.782 C 76.121 42.408,76.391 42.098,76.259 42.093 C 76.126 42.088,75.350 42.616,74.533 43.265 M326.057 44.060 C 326.057 44.285,326.367 44.585,326.745 44.727 C 327.124 44.869,327.628 45.245,327.865 45.561 C 328.103 45.878,328.398 45.974,328.521 45.775 C 328.644 45.575,328.140 45.016,327.401 44.531 C 326.662 44.047,326.057 43.835,326.057 44.060 M180.138 44.458 C 179.503 44.669,179.921 44.706,181.318 44.562 C 182.507 44.439,183.555 44.273,183.645 44.195 C 183.960 43.919,181.112 44.132,180.138 44.458 M228.548 44.193 C 228.638 44.271,229.508 44.440,230.482 44.569 C 231.664 44.725,231.990 44.687,231.465 44.455 C 230.714 44.122,228.206 43.897,228.548 44.193 M331.563 48.574 C 332.071 49.115,332.664 49.558,332.880 49.558 C 333.097 49.558,332.858 49.115,332.350 48.574 C 331.842 48.033,331.249 47.591,331.033 47.591 C 330.817 47.591,331.055 48.033,331.563 48.574 M68.001 48.476 C 66.602 49.650,66.241 50.518,67.552 49.559 C 68.255 49.044,68.830 48.479,68.830 48.304 C 68.830 47.870,68.687 47.900,68.001 48.476 M63.738 52.126 C 63.208 52.647,62.863 53.161,62.970 53.268 C 63.161 53.460,65.290 51.664,65.290 51.312 C 65.290 50.897,64.639 51.238,63.738 52.126 M335.467 52.061 C 335.991 52.631,336.588 53.097,336.793 53.097 C 337.321 53.097,336.310 51.957,335.332 51.449 C 334.601 51.070,334.616 51.136,335.467 52.061 M338.643 54.794 C 338.643 54.861,339.218 55.437,339.921 56.072 L 341.200 57.227 340.044 55.949 C 338.968 54.757,338.643 54.490,338.643 54.794 M342.183 58.084 C 342.183 58.285,342.802 59.050,343.559 59.784 C 344.317 60.518,344.936 61.029,344.936 60.921 C 344.936 60.813,344.317 60.048,343.559 59.221 C 342.802 58.395,342.183 57.883,342.183 58.084 M268.437 58.808 C 268.869 59.160,269.577 59.622,270.010 59.834 L 270.796 60.220 270.010 59.580 C 269.577 59.228,268.869 58.766,268.437 58.553 L 267.650 58.167 268.437 58.808 M51.958 63.927 C 50.829 65.213,50.537 65.683,50.868 65.683 C 50.940 65.683,51.568 64.975,52.263 64.110 C 53.827 62.165,53.616 62.038,51.958 63.927 M274.959 62.664 C 275.049 62.734,275.742 63.191,276.500 63.680 L 277.876 64.568 276.696 63.555 C 276.047 62.997,275.354 62.540,275.156 62.539 C 274.957 62.538,274.869 62.594,274.959 62.664 M347.894 64.208 C 348.738 65.236,349.492 66.077,349.569 66.077 C 349.851 66.077,348.142 63.891,347.263 63.127 C 346.765 62.694,347.049 63.181,347.894 64.208 M350.442 67.055 C 350.767 67.486,351.455 68.282,351.973 68.825 L 352.913 69.813 352.089 68.598 C 351.636 67.930,350.948 67.134,350.559 66.828 C 349.900 66.310,349.892 66.326,350.442 67.055 M48.718 67.549 C 47.368 69.179,47.166 69.713,48.354 68.511 C 49.062 67.795,49.562 67.131,49.466 67.034 C 49.369 66.937,49.033 67.169,48.718 67.549 M119.174 70.830 L 117.404 72.434 119.272 70.978 C 120.910 69.701,121.396 69.220,121.042 69.224 C 120.988 69.225,120.147 69.947,119.174 70.830 M45.224 71.399 C 44.526 72.705,44.961 73.038,45.763 71.813 C 46.115 71.276,46.254 70.746,46.073 70.634 C 45.891 70.522,45.510 70.866,45.224 71.399 M354.006 71.508 C 354.534 72.174,355.105 72.729,355.274 72.741 C 355.845 72.781,354.760 71.213,353.899 70.752 C 353.087 70.317,353.092 70.353,354.006 71.508 M290.265 73.269 C 290.265 73.371,291.276 74.316,292.511 75.370 C 293.746 76.424,294.631 77.081,294.476 76.830 C 294.139 76.281,290.265 73.005,290.265 73.269 M41.832 76.008 C 40.751 77.360,39.555 78.997,39.175 79.646 C 38.496 80.806,38.497 80.809,39.203 79.852 C 39.598 79.316,40.376 78.343,40.931 77.689 C 42.409 75.948,44.171 73.550,43.972 73.550 C 43.877 73.550,42.914 74.656,41.832 76.008 M356.551 74.336 C 357.028 75.171,360.777 79.843,360.969 79.843 C 361.208 79.843,358.272 75.906,357.172 74.752 C 356.645 74.199,356.365 74.012,356.551 74.336 M296.165 78.466 C 296.899 79.223,297.588 79.843,297.696 79.843 C 297.804 79.843,297.292 79.223,296.559 78.466 C 295.825 77.709,295.136 77.089,295.028 77.089 C 294.919 77.089,295.431 77.709,296.165 78.466 M362.279 81.908 C 363.947 84.081,364.521 84.641,363.691 83.284 C 362.181 80.818,361.739 80.236,361.377 80.236 C 361.167 80.236,361.573 80.988,362.279 81.908 M37.014 82.142 C 35.850 83.778,35.980 84.079,37.217 82.609 C 37.785 81.935,38.158 81.291,38.047 81.180 C 37.935 81.069,37.471 81.502,37.014 82.142 M197.837 84.960 C 196.214 85.099,198.250 85.132,202.360 85.031 C 206.470 84.931,209.907 84.785,209.997 84.706 C 210.249 84.485,201.155 84.675,197.837 84.960 M210.456 85.098 C 210.546 85.176,212.566 85.331,214.946 85.443 C 217.709 85.573,218.633 85.532,217.502 85.330 C 215.733 85.014,210.146 84.830,210.456 85.098 M192.237 85.627 C 192.726 85.721,193.434 85.718,193.810 85.619 C 194.186 85.521,193.786 85.444,192.920 85.448 C 192.055 85.453,191.747 85.533,192.237 85.627 M34.156 86.431 C 32.920 87.905,32.031 89.567,32.879 88.817 C 33.614 88.167,35.202 85.742,34.891 85.742 C 34.805 85.742,34.474 86.052,34.156 86.431 M365.480 86.529 C 365.750 86.962,366.112 87.316,366.283 87.316 C 366.455 87.316,366.407 86.962,366.175 86.529 C 365.943 86.096,365.582 85.742,365.371 85.742 C 365.159 85.742,365.208 86.093,365.480 86.529 M172.075 89.465 C 170.524 90.175,170.874 90.187,173.058 89.499 C 174.031 89.192,174.474 88.938,174.041 88.933 C 173.609 88.928,172.724 89.167,172.075 89.465 M307.571 89.799 C 307.571 89.866,308.147 90.441,308.850 91.077 L 310.128 92.232 308.973 90.954 C 307.896 89.762,307.571 89.495,307.571 89.799 M29.537 93.314 C 28.690 94.901,28.687 94.936,29.476 94.002 C 30.613 92.658,31.167 91.642,30.765 91.642 C 30.581 91.642,30.028 92.394,29.537 93.314 M369.963 93.223 C 370.539 94.093,371.085 94.729,371.177 94.637 C 371.403 94.411,369.596 91.653,369.218 91.647 C 369.052 91.644,369.388 92.354,369.963 93.223 M244.674 92.575 C 245.079 92.937,247.394 94.002,247.394 93.826 C 247.394 93.599,245.214 92.429,244.792 92.429 C 244.637 92.429,244.584 92.495,244.674 92.575 M94.395 95.182 C 93.490 96.264,92.837 97.148,92.945 97.148 C 93.054 97.148,93.883 96.264,94.789 95.182 C 95.694 94.100,96.347 93.215,96.238 93.215 C 96.130 93.215,95.301 94.100,94.395 95.182 M252.507 96.774 C 253.872 97.700,254.649 97.970,253.687 97.184 C 253.147 96.741,252.527 96.378,252.311 96.377 C 252.094 96.375,252.183 96.554,252.507 96.774 M27.007 97.573 C 26.622 98.022,26.364 98.560,26.433 98.767 C 26.502 98.975,26.876 98.607,27.264 97.950 C 28.087 96.557,27.994 96.420,27.007 97.573 M373.438 99.090 C 374.309 100.774,374.962 100.995,374.172 99.339 C 373.804 98.567,373.354 97.935,373.172 97.935 C 372.990 97.935,373.110 98.455,373.438 99.090 M25.232 100.517 C 24.970 101.093,24.942 101.421,25.167 101.281 C 25.744 100.925,26.438 99.508,26.036 99.508 C 25.846 99.508,25.485 99.962,25.232 100.517 M148.068 101.967 L 146.116 104.031 148.181 102.080 C 149.317 101.006,150.246 100.077,150.246 100.015 C 150.246 99.721,149.881 100.048,148.068 101.967 M316.272 103.057 C 316.867 104.818,317.203 105.160,316.842 103.638 C 316.688 102.989,316.393 102.285,316.186 102.074 C 315.979 101.862,316.018 102.305,316.272 103.057 M376.866 105.211 C 377.112 105.752,377.459 106.195,377.636 106.195 C 377.813 106.195,377.756 105.752,377.510 105.211 C 377.263 104.671,376.917 104.228,376.740 104.228 C 376.563 104.228,376.620 104.671,376.866 105.211 M21.920 106.588 C 21.580 107.453,21.373 108.161,21.459 108.161 C 21.546 108.161,21.977 107.453,22.419 106.588 C 22.860 105.723,23.068 105.015,22.880 105.015 C 22.692 105.015,22.260 105.723,21.920 106.588 M86.567 106.415 C 86.113 107.185,85.920 107.705,86.138 107.570 C 86.564 107.307,87.841 105.015,87.561 105.015 C 87.469 105.015,87.022 105.645,86.567 106.415 M144.228 106.293 C 143.160 107.736,142.441 108.979,143.032 108.358 C 143.762 107.591,145.563 105.015,145.369 105.015 C 145.261 105.015,144.747 105.590,144.228 106.293 M270.010 109.341 C 271.075 110.423,272.035 111.308,272.143 111.308 C 272.252 111.308,271.468 110.423,270.403 109.341 C 269.338 108.260,268.378 107.375,268.269 107.375 C 268.161 107.375,268.944 108.260,270.010 109.341 M381.099 113.625 C 381.553 114.514,381.999 115.241,382.092 115.241 C 382.476 115.241,381.213 112.322,380.764 112.172 C 380.461 112.071,380.589 112.624,381.099 113.625 M18.213 114.061 C 17.968 114.710,17.912 115.241,18.088 115.241 C 18.264 115.241,18.594 114.710,18.820 114.061 C 19.046 113.412,19.102 112.881,18.945 112.881 C 18.787 112.881,18.458 113.412,18.213 114.061 M316.460 114.494 C 316.316 115.395,316.275 116.209,316.369 116.303 C 316.463 116.397,316.663 115.742,316.814 114.848 C 316.965 113.953,317.006 113.139,316.906 113.038 C 316.805 112.937,316.604 113.592,316.460 114.494 M139.872 116.863 C 139.549 118.479,139.607 125.869,139.949 126.729 C 140.096 127.098,140.216 124.753,140.216 121.517 C 140.216 115.043,140.222 115.116,139.872 116.863 M278.386 120.944 C 279.176 122.116,280.679 123.584,282.223 124.692 C 282.667 125.010,282.401 124.705,281.633 124.013 C 280.865 123.322,279.641 122.083,278.914 121.260 C 277.939 120.157,277.800 120.074,278.386 120.944 M14.945 121.339 C 14.716 121.941,14.435 122.585,14.321 122.771 C 14.206 122.956,14.283 123.107,14.491 123.107 C 14.908 123.107,15.848 120.731,15.549 120.432 C 15.446 120.329,15.174 120.737,14.945 121.339 M384.467 121.042 C 384.623 121.421,384.839 122.040,384.948 122.419 C 385.057 122.797,385.286 123.107,385.456 123.107 C 385.627 123.107,385.577 122.488,385.345 121.731 C 385.112 120.973,384.756 120.354,384.553 120.354 C 384.350 120.354,384.311 120.664,384.467 121.042 M78.727 121.747 C 78.068 123.194,78.193 123.502,78.906 122.187 C 79.239 121.573,79.437 120.997,79.347 120.908 C 79.257 120.818,78.978 121.196,78.727 121.747 M306.391 127.434 C 305.634 127.848,305.156 128.195,305.329 128.204 C 305.746 128.226,307.965 127.072,307.965 126.834 C 307.965 126.576,307.942 126.585,306.391 127.434 M388.498 131.563 C 388.601 132.104,388.836 132.547,389.021 132.547 C 389.205 132.547,389.254 132.812,389.129 133.137 C 389.005 133.461,389.083 133.727,389.304 133.727 C 389.719 133.727,389.707 133.476,389.203 131.662 C 388.827 130.310,388.243 130.229,388.498 131.563 M10.899 131.760 C 10.786 132.193,10.833 132.547,11.004 132.547 C 11.175 132.547,11.407 132.193,11.520 131.760 C 11.633 131.327,11.586 130.973,11.415 130.973 C 11.244 130.973,11.012 131.327,10.899 131.760 M148.673 139.016 C 148.673 139.124,149.204 139.487,149.853 139.823 C 150.501 140.159,151.032 140.345,151.032 140.237 C 151.032 140.128,150.501 139.765,149.853 139.430 C 149.204 139.094,148.673 138.908,148.673 139.016 M392.378 143.854 C 392.663 145.042,392.836 145.349,393.082 145.100 C 393.371 144.807,392.839 142.773,392.474 142.773 C 392.278 142.773,392.236 143.260,392.378 143.854 M176.111 147.377 C 176.600 147.472,177.308 147.468,177.684 147.370 C 178.060 147.271,177.660 147.194,176.794 147.198 C 175.929 147.203,175.622 147.283,176.111 147.377 M178.761 147.692 C 179.660 148.005,182.034 148.091,181.857 147.804 C 181.751 147.633,180.923 147.507,180.016 147.524 C 179.110 147.541,178.545 147.616,178.761 147.692 M236.676 150.917 C 237.163 151.010,237.960 151.010,238.446 150.917 C 238.933 150.823,238.535 150.746,237.561 150.746 C 236.588 150.746,236.190 150.823,236.676 150.917 M240.413 151.314 C 241.008 151.404,241.981 151.404,242.576 151.314 C 243.171 151.224,242.684 151.150,241.495 151.150 C 240.305 151.150,239.818 151.224,240.413 151.314 M261.357 154.966 C 261.790 155.151,262.498 155.298,262.930 155.292 C 263.563 155.283,263.524 155.219,262.734 154.966 C 261.389 154.535,260.355 154.535,261.357 154.966 M396.073 159.390 C 396.070 159.985,396.244 160.472,396.460 160.472 C 396.957 160.472,396.957 159.668,396.460 158.899 C 396.163 158.439,396.078 158.548,396.073 159.390 M396.466 161.554 C 396.463 162.040,396.637 162.439,396.853 162.439 C 397.346 162.439,397.346 162.021,396.853 161.259 C 396.545 160.782,396.471 160.838,396.466 161.554 M3.027 161.807 C 2.866 162.216,2.827 162.644,2.941 162.757 C 3.299 163.116,3.615 162.528,3.465 161.781 C 3.327 161.097,3.306 161.098,3.027 161.807 M2.643 164.142 C 2.205 165.257,2.276 165.826,2.790 165.312 C 3.027 165.076,3.154 164.553,3.073 164.152 C 2.932 163.448,2.917 163.447,2.643 164.142 M2.253 167.003 C 2.096 167.160,1.967 167.561,1.967 167.892 C 1.967 168.335,2.083 168.379,2.404 168.058 C 2.645 167.817,2.774 167.417,2.691 167.168 C 2.608 166.919,2.411 166.845,2.253 167.003 M293.553 168.642 C 293.864 169.145,296.165 170.848,296.165 170.575 C 296.165 170.478,295.515 169.903,294.721 169.297 C 293.927 168.691,293.402 168.396,293.553 168.642 M300.492 174.828 C 302.321 176.667,303.906 178.171,304.014 178.171 C 304.122 178.171,302.714 176.667,300.885 174.828 C 299.056 172.989,297.471 171.485,297.362 171.485 C 297.254 171.485,298.662 172.989,300.492 174.828 M138.227 176.773 C 138.647 177.109,139.266 177.370,139.603 177.353 C 140.133 177.327,140.136 177.293,139.626 177.104 C 139.302 176.983,138.682 176.722,138.250 176.523 C 137.476 176.167,137.475 176.171,138.227 176.773 M398.911 178.564 C 398.911 179.322,398.992 179.631,399.091 179.253 C 399.190 178.874,399.190 178.255,399.091 177.876 C 398.992 177.498,398.911 177.807,398.911 178.564 M0.878 178.958 C 0.878 179.715,0.959 180.025,1.058 179.646 C 1.157 179.267,1.157 178.648,1.058 178.269 C 0.959 177.891,0.878 178.201,0.878 178.958 M149.837 181.130 C 150.802 181.431,151.651 181.616,151.725 181.543 C 151.926 181.341,149.436 180.527,148.712 180.557 C 148.366 180.572,148.872 180.830,149.837 181.130 M399.320 184.071 C 399.320 185.044,399.397 185.442,399.491 184.956 C 399.585 184.469,399.585 183.673,399.491 183.186 C 399.397 182.699,399.320 183.097,399.320 184.071 M0.506 185.054 C 0.509 186.136,0.585 186.531,0.676 185.934 C 0.766 185.336,0.764 184.451,0.670 183.967 C 0.577 183.483,0.503 183.972,0.506 185.054 M165.388 184.857 C 167.052 185.281,168.480 185.281,167.158 184.857 C 166.618 184.684,165.733 184.546,165.192 184.550 C 164.309 184.556,164.329 184.588,165.388 184.857 M227.761 188.149 C 227.852 188.229,229.253 188.394,230.875 188.514 C 233.062 188.677,233.418 188.645,232.252 188.391 C 230.678 188.049,227.453 187.875,227.761 188.149 M112.180 189.381 C 112.184 189.813,112.323 190.698,112.488 191.347 C 112.757 192.407,112.789 192.427,112.795 191.544 C 112.799 191.003,112.661 190.118,112.488 189.577 C 112.241 188.807,112.174 188.764,112.180 189.381 M399.760 196.460 C 399.760 199.272,399.823 200.371,399.899 198.902 C 399.975 197.433,399.974 195.132,399.897 193.789 C 399.821 192.446,399.759 193.648,399.760 196.460 M254.065 192.536 C 255.030 192.837,255.880 193.022,255.953 192.949 C 256.154 192.748,253.664 191.933,252.940 191.963 C 252.594 191.978,253.100 192.236,254.065 192.536 M0.112 196.460 C 0.115 197.542,0.192 197.938,0.282 197.340 C 0.373 196.742,0.370 195.857,0.277 195.373 C 0.184 194.889,0.110 195.379,0.112 196.460 M269.420 199.823 C 270.784 200.749,271.561 201.018,270.600 200.232 C 270.059 199.789,269.440 199.426,269.223 199.425 C 269.007 199.423,269.095 199.602,269.420 199.823 M116.072 205.113 C 116.080 205.329,116.426 206.214,116.842 207.080 C 117.259 207.945,117.489 208.210,117.354 207.670 C 117.077 206.556,116.052 204.511,116.072 205.113 M0.506 207.866 C 0.509 208.948,0.585 209.344,0.676 208.746 C 0.766 208.148,0.764 207.263,0.670 206.779 C 0.577 206.296,0.503 206.785,0.506 207.866 M399.320 208.850 C 399.320 209.823,399.397 210.221,399.491 209.735 C 399.585 209.248,399.585 208.451,399.491 207.965 C 399.397 207.478,399.320 207.876,399.320 208.850 M279.056 215.733 C 279.056 218.029,279.171 219.500,279.312 219.001 C 279.453 218.501,279.568 217.030,279.568 215.733 C 279.568 214.435,279.453 212.964,279.312 212.464 C 279.171 211.965,279.056 213.436,279.056 215.733 M74.398 212.193 C 74.397 212.409,74.635 213.206,74.926 213.963 C 75.218 214.720,75.462 215.074,75.469 214.749 C 75.475 214.425,75.238 213.628,74.940 212.979 C 74.643 212.330,74.399 211.976,74.398 212.193 M0.878 213.963 C 0.878 214.720,0.959 215.029,1.058 214.651 C 1.157 214.272,1.157 213.653,1.058 213.274 C 0.959 212.896,0.878 213.206,0.878 213.963 M124.167 221.859 C 124.557 222.525,125.128 223.277,125.436 223.531 C 125.743 223.785,125.498 223.240,124.892 222.321 C 123.619 220.390,123.116 220.071,124.167 221.859 M1.967 225.126 C 1.967 225.450,2.144 225.825,2.360 225.959 C 2.576 226.092,2.753 225.936,2.753 225.612 C 2.753 225.287,2.576 224.912,2.360 224.779 C 2.144 224.645,1.967 224.801,1.967 225.126 M316.439 228.336 C 316.288 229.340,316.246 230.241,316.344 230.339 C 316.442 230.438,316.646 229.697,316.796 228.694 C 316.947 227.691,316.989 226.789,316.891 226.691 C 316.793 226.593,316.589 227.333,316.439 228.336 M2.366 227.804 C 2.377 228.791,3.134 229.605,3.140 228.637 C 3.144 228.163,2.970 227.666,2.753 227.532 C 2.537 227.398,2.363 227.521,2.366 227.804 M274.822 228.616 L 274.128 229.892 274.921 228.963 C 275.595 228.173,275.955 227.329,275.615 227.338 C 275.560 227.339,275.204 227.914,274.822 228.616 M397.140 227.966 C 396.983 228.124,396.859 228.622,396.865 229.072 C 396.876 229.829,396.909 229.838,397.287 229.189 C 397.727 228.433,397.614 227.492,397.140 227.966 M2.781 230.383 C 2.889 231.537,3.486 232.179,3.512 231.170 C 3.527 230.575,3.363 230.088,3.147 230.088 C 2.930 230.088,2.766 230.221,2.781 230.383 M396.466 231.367 C 396.471 232.082,396.545 232.139,396.853 231.662 C 397.346 230.899,397.346 230.482,396.853 230.482 C 396.637 230.482,396.463 230.880,396.466 231.367 M82.203 231.159 C 82.203 231.388,82.567 231.992,83.013 232.503 L 83.822 233.432 83.132 232.252 C 82.222 230.699,82.203 230.676,82.203 231.159 M270.772 233.892 C 270.166 234.686,269.871 235.212,270.117 235.060 C 270.620 234.749,272.323 232.448,272.050 232.448 C 271.953 232.448,271.378 233.098,270.772 233.892 M313.471 238.824 C 313.471 238.942,313.203 239.680,312.876 240.463 C 312.548 241.247,312.369 241.888,312.477 241.888 C 312.789 241.888,313.897 239.036,313.673 238.812 C 313.562 238.701,313.471 238.707,313.471 238.824 M262.119 242.380 L 260.964 243.658 262.242 242.503 C 262.945 241.867,263.520 241.292,263.520 241.224 C 263.520 240.920,263.196 241.188,262.119 242.380 M90.462 244.641 C 90.924 245.290,91.391 245.821,91.499 245.821 C 91.607 245.821,91.318 245.290,90.855 244.641 C 90.393 243.992,89.927 243.461,89.819 243.461 C 89.710 243.461,90.000 243.992,90.462 244.641 M148.279 245.571 C 148.279 245.679,148.810 246.146,149.459 246.608 C 150.108 247.070,150.639 247.359,150.639 247.251 C 150.639 247.143,150.108 246.676,149.459 246.214 C 148.810 245.752,148.279 245.463,148.279 245.571 M6.995 248.964 C 7.090 249.610,7.301 250.057,7.464 249.956 C 7.823 249.735,7.497 247.788,7.102 247.788 C 6.948 247.788,6.900 248.317,6.995 248.964 M392.768 248.223 C 392.673 248.524,392.404 249.373,392.168 250.108 C 391.651 251.725,391.651 251.721,392.102 251.721 C 392.469 251.721,393.391 248.127,393.098 247.835 C 393.011 247.747,392.862 247.922,392.768 248.223 M250.439 250.114 C 248.823 251.150,248.599 251.515,250.024 250.790 C 250.714 250.440,251.388 249.975,251.522 249.757 C 251.838 249.247,251.744 249.278,250.439 250.114 M304.818 255.654 C 304.356 256.303,304.066 256.834,304.175 256.834 C 304.283 256.834,304.749 256.303,305.211 255.654 C 305.674 255.005,305.963 254.474,305.855 254.474 C 305.747 254.474,305.280 255.005,304.818 255.654 M101.065 258.112 C 102.695 259.849,103.048 260.161,103.048 259.866 C 103.048 259.802,102.207 258.962,101.180 257.997 L 99.312 256.244 101.065 258.112 M10.917 261.357 C 11.020 261.898,11.280 262.340,11.494 262.340 C 11.708 262.340,11.776 262.060,11.645 261.718 C 11.514 261.376,11.406 260.933,11.406 260.735 C 11.406 260.536,11.254 260.374,11.067 260.374 C 10.881 260.374,10.813 260.816,10.917 261.357 M106.391 263.913 C 108.329 265.860,110.003 267.453,110.111 267.453 C 110.220 267.453,108.723 265.860,106.785 263.913 C 104.847 261.967,103.173 260.374,103.065 260.374 C 102.956 260.374,104.453 261.967,106.391 263.913 M192.429 261.825 C 192.807 261.924,193.427 261.924,193.805 261.825 C 194.184 261.726,193.874 261.645,193.117 261.645 C 192.360 261.645,192.050 261.726,192.429 261.825 M214.656 261.832 C 215.145 261.926,215.853 261.922,216.229 261.824 C 216.605 261.725,216.205 261.648,215.339 261.653 C 214.474 261.657,214.166 261.738,214.656 261.832 M197.837 262.346 C 201.353 262.671,208.310 262.836,208.030 262.588 C 207.940 262.508,204.857 262.352,201.180 262.240 C 196.621 262.102,195.557 262.136,197.837 262.346 M209.529 262.231 C 210.227 262.318,211.466 262.319,212.282 262.234 C 213.098 262.149,212.527 262.078,211.013 262.076 C 209.499 262.074,208.831 262.144,209.529 262.231 M112.078 269.125 C 113.708 270.861,114.061 271.174,114.061 270.878 C 114.061 270.815,113.220 269.975,112.193 269.010 L 110.324 267.257 112.078 269.125 M14.460 270.403 C 14.820 271.377,15.246 272.173,15.405 272.173 C 15.565 272.173,15.400 271.377,15.039 270.403 C 14.678 269.430,14.253 268.633,14.093 268.633 C 13.934 268.633,14.099 269.430,14.460 270.403 M385.447 269.420 C 385.196 269.890,385.079 270.362,385.187 270.471 C 385.295 270.579,385.589 270.283,385.841 269.813 C 386.092 269.343,386.209 268.871,386.101 268.763 C 385.993 268.654,385.699 268.950,385.447 269.420 M384.506 271.615 C 384.189 272.441,384.204 272.566,384.615 272.566 C 384.806 272.566,385.055 272.212,385.168 271.780 C 385.411 270.851,384.853 270.712,384.506 271.615 M284.562 276.346 L 282.989 277.754 284.661 276.504 C 286.099 275.428,286.618 274.909,286.234 274.932 C 286.180 274.935,285.428 275.572,284.562 276.346 M18.474 279.624 C 19.108 280.808,19.735 281.015,19.212 279.868 C 18.960 279.313,18.598 278.859,18.409 278.859 C 18.220 278.859,18.249 279.204,18.474 279.624 M380.787 280.039 C 380.560 280.688,380.504 281.219,380.662 281.219 C 380.820 281.219,381.149 280.688,381.394 280.039 C 381.639 279.390,381.695 278.859,381.519 278.859 C 381.342 278.859,381.013 279.390,380.787 280.039 M125.074 279.375 C 125.074 279.467,125.826 280.038,126.745 280.644 C 127.665 281.250,128.209 281.495,127.956 281.188 C 127.468 280.597,125.074 279.091,125.074 279.375 M20.452 283.298 C 20.452 283.860,21.392 285.546,21.704 285.546 C 21.891 285.546,21.739 285.059,21.367 284.464 C 20.483 283.052,20.452 283.012,20.452 283.298 M377.053 287.352 C 376.656 288.184,376.561 288.704,376.822 288.617 C 377.343 288.444,378.471 285.939,378.028 285.939 C 377.862 285.939,377.424 286.575,377.053 287.352 M265.093 288.102 C 264.553 288.411,264.287 288.664,264.503 288.664 C 264.720 288.664,265.339 288.411,265.880 288.102 C 266.421 287.793,266.686 287.540,266.470 287.540 C 266.254 287.540,265.634 287.793,265.093 288.102 M24.470 290.855 C 25.183 292.695,26.461 294.985,26.774 294.985 C 26.986 294.985,26.897 294.499,26.577 293.904 C 25.927 292.694,24.232 290.242,24.470 290.855 M257.227 291.417 C 255.642 292.057,255.452 292.271,255.406 293.460 C 255.356 294.752,255.359 294.755,255.525 293.566 C 255.667 292.546,255.955 292.259,257.268 291.825 C 258.132 291.540,258.930 291.161,259.040 290.983 C 259.291 290.576,259.341 290.564,257.227 291.417 M374.782 291.766 C 374.440 292.347,373.762 293.487,373.274 294.300 C 372.731 295.205,372.593 295.689,372.919 295.548 C 373.212 295.421,373.941 294.331,374.540 293.126 C 375.687 290.819,375.837 289.971,374.782 291.766 M28.712 298.281 C 28.712 298.762,30.482 301.269,30.825 301.273 C 31.014 301.276,31.001 301.057,30.797 300.787 C 30.593 300.516,30.040 299.784,29.569 299.160 C 29.098 298.536,28.712 298.141,28.712 298.281 M370.487 299.031 C 369.371 300.707,369.285 300.885,369.597 300.882 C 369.935 300.880,371.396 298.502,371.187 298.293 C 371.118 298.224,370.803 298.556,370.487 299.031 M153.335 302.558 C 153.498 302.721,174.861 302.810,200.808 302.755 L 247.984 302.655 200.511 302.458 C 174.401 302.350,153.172 302.395,153.335 302.558 M366.492 305.113 C 365.630 306.118,365.297 306.785,365.660 306.782 C 365.835 306.781,366.280 306.250,366.648 305.602 C 367.408 304.268,367.356 304.107,366.492 305.113 M33.432 305.814 C 33.432 306.145,33.696 306.518,34.019 306.642 C 34.343 306.766,34.492 307.053,34.352 307.280 C 34.204 307.520,34.285 307.576,34.546 307.415 C 34.870 307.215,34.820 306.868,34.365 306.174 C 33.633 305.057,33.432 304.979,33.432 305.814 M36.201 309.538 C 36.968 311.030,38.256 312.684,38.652 312.684 C 38.846 312.684,38.427 311.932,37.721 311.013 C 35.974 308.736,35.604 308.378,36.201 309.538 M362.520 310.914 C 361.916 311.672,361.543 312.291,361.690 312.291 C 361.982 312.291,362.806 311.320,363.442 310.226 C 364.068 309.151,363.719 309.411,362.520 310.914 M250.737 316.814 C 250.737 319.044,250.870 320.787,251.032 320.687 C 251.195 320.586,251.327 318.844,251.327 316.814 C 251.327 314.785,251.195 313.042,251.032 312.942 C 250.870 312.842,250.737 314.584,250.737 316.814 M359.956 314.242 C 359.483 314.882,359.095 315.536,359.095 315.695 C 359.095 315.854,359.538 315.384,360.079 314.651 C 360.619 313.918,361.062 313.264,361.062 313.198 C 361.062 312.877,360.742 313.178,359.956 314.242 M39.331 313.686 C 39.331 313.819,39.949 314.683,40.704 315.604 C 41.460 316.526,41.946 317.425,41.786 317.602 C 41.626 317.779,41.678 317.820,41.903 317.692 C 42.127 317.565,43.003 318.416,43.848 319.583 C 44.694 320.751,45.629 321.799,45.925 321.913 C 46.222 322.027,46.055 321.613,45.553 320.993 C 40.656 314.944,39.331 313.388,39.331 313.686 M357.840 316.912 C 356.856 318.058,356.637 318.597,357.252 318.361 C 357.558 318.244,358.006 317.715,358.247 317.186 C 358.765 316.049,358.648 315.971,357.840 316.912 M354.572 320.944 C 353.951 321.593,353.619 322.124,353.835 322.124 C 354.051 322.124,354.620 321.593,355.100 320.944 C 355.580 320.295,355.912 319.764,355.838 319.764 C 355.763 319.764,355.194 320.295,354.572 320.944 M48.378 324.694 C 48.378 325.174,49.647 326.794,50.186 327.001 C 50.525 327.131,50.332 326.653,49.722 325.854 C 48.718 324.537,48.378 324.243,48.378 324.694 M350.221 326.108 C 349.258 327.134,349.212 327.264,349.942 326.886 C 350.424 326.636,351.005 326.082,351.234 325.655 C 351.816 324.567,351.559 324.682,350.221 326.108 M182.989 331.072 C 192.886 331.130,209.081 331.130,218.977 331.072 C 228.874 331.013,220.777 330.965,200.983 330.965 C 181.190 330.965,173.092 331.013,182.989 331.072 M342.076 334.619 C 340.188 336.516,338.643 338.204,338.643 338.370 C 338.643 338.683,344.386 333.064,345.298 331.858 C 346.360 330.454,345.419 331.261,342.076 334.619 M55.457 332.581 C 55.457 332.708,56.410 333.725,57.575 334.842 C 61.172 338.292,61.699 338.567,58.614 335.383 C 55.660 332.337,55.457 332.156,55.457 332.581 M160.179 335.202 C 159.623 335.904,158.839 337.463,159.043 337.463 C 159.137 337.463,159.580 336.844,160.027 336.087 C 160.838 334.711,160.914 334.274,160.179 335.202 M243.916 340.610 C 243.878 341.367,243.762 342.694,243.660 343.559 L 243.473 345.133 243.877 343.559 C 244.098 342.694,244.214 341.367,244.133 340.610 L 243.987 339.233 243.916 340.610 M63.324 340.120 C 63.324 340.524,64.808 341.928,65.683 342.351 C 66.008 342.508,65.919 342.311,65.487 341.914 C 65.054 341.517,64.390 340.872,64.012 340.480 C 63.633 340.088,63.324 339.926,63.324 340.120 M334.907 341.504 C 334.132 342.283,333.998 342.549,334.518 342.277 C 335.434 341.797,336.971 340.192,336.442 340.267 C 336.247 340.295,335.556 340.852,334.907 341.504 M67.257 343.669 C 67.257 343.858,67.699 344.428,68.240 344.936 C 68.913 345.569,69.219 345.683,69.211 345.300 C 69.198 344.705,67.257 343.085,67.257 343.669 M331.170 344.739 C 330.662 345.280,330.423 345.723,330.640 345.723 C 330.856 345.723,331.449 345.280,331.957 344.739 C 332.465 344.199,332.703 343.756,332.487 343.756 C 332.271 343.756,331.678 344.199,331.170 344.739 M71.042 347.016 C 71.438 347.723,74.336 349.775,74.336 349.349 C 74.336 349.075,72.344 347.388,71.238 346.726 C 70.829 346.481,70.781 346.552,71.042 347.016 M159.489 347.689 C 159.824 348.338,160.187 348.869,160.296 348.869 C 160.404 348.869,160.218 348.338,159.882 347.689 C 159.546 347.040,159.183 346.509,159.075 346.509 C 158.967 346.509,159.153 347.040,159.489 347.689 M327.189 348.093 L 325.467 349.676 327.040 348.653 C 327.906 348.091,328.755 347.379,328.928 347.070 C 329.436 346.165,329.020 346.409,327.189 348.093 M323.682 350.812 C 322.726 351.625,322.554 351.909,323.107 351.768 C 323.540 351.658,324.212 351.137,324.600 350.612 C 325.521 349.366,325.338 349.406,323.682 350.812 M78.269 352.802 C 80.080 354.326,80.655 354.326,78.919 352.802 C 78.180 352.153,77.422 351.627,77.234 351.633 C 77.046 351.639,77.512 352.165,78.269 352.802 M165.143 352.519 C 165.313 352.688,167.827 352.776,170.730 352.714 L 176.008 352.603 170.422 352.408 C 167.349 352.300,164.974 352.350,165.143 352.519 M228.810 352.308 C 230.379 352.382,232.945 352.382,234.513 352.308 C 236.082 352.233,234.798 352.172,231.662 352.172 C 228.525 352.172,227.242 352.233,228.810 352.308 M320.551 353.277 C 319.794 353.929,319.528 354.268,319.961 354.032 C 321.149 353.383,322.284 352.438,322.095 352.255 C 322.003 352.166,321.308 352.626,320.551 353.277 M223.967 355.426 C 223.362 356.220,223.067 356.746,223.312 356.594 C 223.816 356.283,225.519 353.982,225.246 353.982 C 225.148 353.982,224.573 354.632,223.967 355.426 M316.924 355.854 C 315.902 356.639,315.132 357.347,315.212 357.427 C 315.436 357.652,318.519 355.421,318.749 354.867 C 319.013 354.231,319.082 354.194,316.924 355.854 M82.203 355.480 C 82.203 355.866,84.146 357.298,84.348 357.062 C 84.409 356.991,83.951 356.520,83.331 356.017 C 82.710 355.514,82.203 355.273,82.203 355.480 M86.499 358.651 C 87.239 359.325,87.947 359.775,88.071 359.651 C 88.308 359.414,87.286 358.546,85.939 357.838 C 85.506 357.610,85.758 357.976,86.499 358.651 M312.324 359.063 C 311.909 359.477,311.495 359.742,311.404 359.650 C 311.312 359.559,310.916 359.839,310.523 360.273 C 309.815 361.056,309.819 361.058,310.986 360.475 C 311.634 360.152,312.485 359.533,312.878 359.098 C 313.790 358.091,313.325 358.061,312.324 359.063 M219.272 360.137 C 218.088 361.196,217.999 361.342,218.914 360.731 C 220.001 360.004,221.369 358.679,220.992 358.717 C 220.912 358.725,220.138 359.364,219.272 360.137 M88.496 359.785 C 88.496 359.962,89.027 360.419,89.676 360.803 C 90.324 361.186,90.855 361.435,90.855 361.355 C 90.855 361.275,90.324 360.817,89.676 360.338 C 89.027 359.858,88.496 359.609,88.496 359.785 M93.215 362.952 C 93.215 363.244,94.120 363.813,95.765 364.554 C 95.977 364.650,95.885 364.462,95.560 364.137 C 94.728 363.305,93.215 362.540,93.215 362.952 M305.211 363.618 C 304.478 364.159,304.018 364.602,304.189 364.602 C 304.707 364.602,306.785 363.274,306.785 362.944 C 306.785 362.492,306.675 362.539,305.211 363.618 M211.013 364.023 C 210.147 364.308,209.794 364.547,210.226 364.554 C 210.659 364.561,211.544 364.323,212.193 364.026 C 213.679 363.345,213.073 363.344,211.013 364.023 M191.577 364.350 C 191.667 364.428,192.271 364.610,192.920 364.755 C 193.782 364.948,193.941 364.911,193.510 364.620 C 192.979 364.260,191.182 364.009,191.577 364.350 M99.115 366.480 C 99.115 366.659,99.956 367.198,100.983 367.679 C 102.143 368.222,102.553 368.315,102.065 367.924 C 100.879 366.976,99.115 366.112,99.115 366.480 M299.017 367.184 C 298.097 367.735,297.345 368.256,297.345 368.341 C 297.345 368.669,300.681 366.985,300.812 366.591 C 301.003 366.018,300.914 366.047,299.017 367.184 M105.872 370.206 C 106.595 370.891,109.452 372.179,109.145 371.682 C 108.899 371.285,106.065 369.715,105.592 369.715 C 105.460 369.715,105.586 369.936,105.872 370.206 M291.937 370.940 C 290.236 372.029,290.325 372.157,292.228 371.357 C 293.091 370.995,293.799 370.565,293.801 370.403 C 293.808 369.923,293.294 370.071,291.937 370.940 M285.152 374.238 C 284.582 374.564,284.417 374.801,284.759 374.801 C 285.084 374.802,285.693 374.543,286.113 374.225 C 287.084 373.491,286.445 373.499,285.152 374.238 M282.399 375.615 C 281.642 376.029,281.164 376.376,281.337 376.385 C 281.754 376.407,283.972 375.253,283.972 375.014 C 283.972 374.757,283.949 374.766,282.399 375.615 M123.500 378.342 C 123.500 378.522,123.810 378.758,124.189 378.867 C 124.567 378.976,125.216 379.204,125.630 379.373 C 126.129 379.578,126.295 379.539,126.122 379.260 C 125.785 378.714,123.500 377.914,123.500 378.342 M274.979 378.616 C 273.326 379.337,273.547 379.703,275.247 379.061 C 276.147 378.722,277.223 377.739,276.401 378.007 C 276.347 378.024,275.707 378.299,274.979 378.616 M132.547 381.820 C 132.547 382.034,132.989 382.294,133.530 382.397 C 134.071 382.501,134.513 382.433,134.513 382.246 C 134.513 382.060,134.351 381.908,134.152 381.908 C 133.953 381.908,133.511 381.800,133.169 381.669 C 132.827 381.538,132.547 381.605,132.547 381.820 M266.175 381.785 C 265.796 381.884,265.487 382.114,265.487 382.295 C 265.487 382.476,265.796 382.565,266.175 382.493 C 266.554 382.420,266.996 382.348,267.158 382.331 C 267.321 382.314,267.453 382.124,267.453 381.908 C 267.453 381.499,267.321 381.486,266.175 381.785 M238.741 389.381 C 238.262 389.690,238.313 389.763,239.013 389.768 C 239.487 389.771,239.984 389.597,240.118 389.381 C 240.427 388.880,239.516 388.880,238.741 389.381 M162.045 389.774 C 162.045 389.990,162.311 390.167,162.635 390.167 C 162.960 390.167,163.225 389.990,163.225 389.774 C 163.225 389.558,162.960 389.381,162.635 389.381 C 162.311 389.381,162.045 389.558,162.045 389.774 M236.775 389.774 C 236.775 389.990,237.040 390.167,237.365 390.167 C 237.689 390.167,237.955 389.990,237.955 389.774 C 237.955 389.558,237.689 389.381,237.365 389.381 C 237.040 389.381,236.775 389.558,236.775 389.774 M164.208 390.167 C 165.283 390.629,165.585 390.629,165.585 390.167 C 165.585 389.951,165.098 389.786,164.503 389.801 C 163.545 389.826,163.511 389.868,164.208 390.167 M234.612 390.167 C 234.324 390.632,234.709 390.632,235.792 390.167 C 236.550 389.841,236.547 389.828,235.716 389.801 C 235.242 389.786,234.745 389.951,234.612 390.167 M166.765 390.560 C 167.540 391.061,168.451 391.061,168.142 390.560 C 168.008 390.344,167.511 390.170,167.037 390.173 C 166.336 390.178,166.285 390.251,166.765 390.560 M231.858 390.560 C 231.549 391.061,232.460 391.061,233.235 390.560 C 233.715 390.251,233.664 390.178,232.963 390.173 C 232.489 390.170,231.992 390.344,231.858 390.560 M181.416 392.405 C 181.794 392.504,182.414 392.504,182.793 392.405 C 183.171 392.306,182.861 392.225,182.104 392.225 C 181.347 392.225,181.037 392.306,181.416 392.405 M187.321 392.809 C 187.919 392.900,188.804 392.897,189.288 392.804 C 189.771 392.711,189.282 392.637,188.201 392.640 C 187.119 392.642,186.723 392.719,187.321 392.809 M210.920 392.809 C 211.518 392.900,212.403 392.897,212.886 392.804 C 213.370 392.711,212.881 392.637,211.799 392.640 C 210.718 392.642,210.322 392.719,210.920 392.809 \" stroke=\"none\" fill=\"#fcb6c0\" fill-rule=\"evenodd\"><\/path><path id=\"path4\" d=\"M186.922 0.271 C 187.301 0.370,187.920 0.370,188.299 0.271 C 188.677 0.172,188.368 0.091,187.611 0.091 C 186.853 0.091,186.544 0.172,186.922 0.271 M211.701 0.271 C 212.080 0.370,212.699 0.370,213.078 0.271 C 213.456 0.172,213.147 0.091,212.389 0.091 C 211.632 0.091,211.323 0.172,211.701 0.271 M197.935 42.749 C 198.314 42.848,198.933 42.848,199.312 42.749 C 199.690 42.650,199.381 42.569,198.623 42.569 C 197.866 42.569,197.557 42.650,197.935 42.749 M213.668 42.749 C 214.046 42.848,214.666 42.848,215.044 42.749 C 215.423 42.650,215.113 42.569,214.356 42.569 C 213.599 42.569,213.289 42.650,213.668 42.749 M188.889 43.536 C 189.267 43.635,189.887 43.635,190.265 43.536 C 190.644 43.437,190.334 43.356,189.577 43.356 C 188.820 43.356,188.510 43.437,188.889 43.536 M222.321 43.536 C 222.699 43.635,223.319 43.635,223.697 43.536 C 224.076 43.437,223.766 43.356,223.009 43.356 C 222.252 43.356,221.942 43.437,222.321 43.536 M68.775 47.613 C 67.895 48.379,67.892 48.400,68.710 48.004 C 69.184 47.775,69.682 47.411,69.814 47.196 C 70.201 46.570,69.777 46.740,68.775 47.613 M333.498 50.094 C 334.021 50.739,335.497 51.714,335.497 51.415 C 335.497 51.340,334.921 50.858,334.218 50.343 C 333.427 49.764,333.153 49.669,333.498 50.094 M338.438 54.404 C 339.298 55.174,340.515 56.390,341.143 57.106 L 342.284 58.407 341.318 57.056 C 340.787 56.313,339.569 55.097,338.612 54.355 L 336.873 53.004 338.438 54.404 M56.932 58.596 C 55.039 60.528,53.491 62.221,53.491 62.358 C 53.491 62.612,58.590 57.547,59.943 55.949 C 61.502 54.107,60.252 55.206,56.932 58.596 M138.151 58.256 C 136.811 59.114,136.377 59.691,137.561 59.040 C 138.464 58.544,139.878 57.450,139.626 57.443 C 139.518 57.440,138.854 57.805,138.151 58.256 M345.297 61.500 C 345.821 62.145,347.296 63.120,347.296 62.821 C 347.296 62.746,346.721 62.264,346.018 61.749 C 345.227 61.170,344.952 61.075,345.297 61.500 M49.503 66.492 C 48.623 67.259,48.620 67.279,49.437 66.883 C 49.912 66.654,50.409 66.290,50.542 66.075 C 50.929 65.449,50.505 65.619,49.503 66.492 M108.948 79.646 C 107.336 81.268,106.106 82.596,106.214 82.596 C 106.323 82.596,107.730 81.268,109.341 79.646 C 110.953 78.024,112.183 76.696,112.075 76.696 C 111.967 76.696,110.559 78.024,108.948 79.646 M101.070 87.611 L 98.525 90.265 101.180 87.720 C 103.646 85.356,104.015 84.956,103.725 84.956 C 103.665 84.956,102.470 86.150,101.070 87.611 M317.146 108.751 C 317.147 110.482,317.216 111.141,317.299 110.216 C 317.382 109.291,317.381 107.875,317.297 107.069 C 317.212 106.264,317.144 107.021,317.146 108.751 M214.066 149.741 C 214.664 149.832,215.549 149.829,216.033 149.736 C 216.517 149.643,216.028 149.569,214.946 149.572 C 213.864 149.575,213.469 149.651,214.066 149.741 M225.275 150.131 C 225.764 150.225,226.472 150.221,226.848 150.123 C 227.224 150.024,226.824 149.947,225.959 149.952 C 225.093 149.956,224.786 150.037,225.275 150.131 M229.799 150.528 C 230.397 150.618,231.282 150.616,231.765 150.523 C 232.249 150.429,231.760 150.355,230.678 150.358 C 229.597 150.361,229.201 150.438,229.799 150.528 M70.655 151.902 C 70.522 152.397,70.429 153.156,70.448 153.589 C 70.467 154.022,70.644 153.685,70.842 152.841 C 71.226 151.207,71.062 150.384,70.655 151.902 M116.421 160.988 C 116.421 161.056,116.996 161.631,117.699 162.267 L 118.977 163.422 117.822 162.144 C 116.745 160.952,116.421 160.685,116.421 160.988 M122.321 166.101 C 122.321 166.169,122.896 166.744,123.599 167.380 L 124.877 168.535 123.722 167.257 C 122.645 166.065,122.321 165.798,122.321 166.101 M399.719 189.774 C 399.722 190.855,399.799 191.251,399.889 190.653 C 399.979 190.056,399.977 189.171,399.884 188.687 C 399.790 188.203,399.716 188.692,399.719 189.774 M0.132 191.937 C 0.132 193.559,0.202 194.223,0.287 193.412 C 0.371 192.601,0.371 191.273,0.287 190.462 C 0.202 189.651,0.132 190.315,0.132 191.937 M0.132 200.983 C 0.132 202.606,0.202 203.269,0.287 202.458 C 0.371 201.647,0.371 200.320,0.287 199.508 C 0.202 198.697,0.132 199.361,0.132 200.983 M399.719 203.147 C 399.722 204.228,399.799 204.624,399.889 204.026 C 399.979 203.428,399.977 202.543,399.884 202.059 C 399.790 201.576,399.716 202.065,399.719 203.147 M317.503 210.226 C 317.508 211.091,317.588 211.399,317.682 210.910 C 317.776 210.421,317.773 209.713,317.674 209.337 C 317.576 208.961,317.499 209.361,317.503 210.226 M317.495 221.436 C 317.495 222.193,317.576 222.502,317.675 222.124 C 317.774 221.745,317.774 221.126,317.675 220.747 C 317.576 220.369,317.495 220.678,317.495 221.436 M84.905 235.792 C 85.118 236.224,85.580 236.932,85.932 237.365 L 86.572 238.151 86.186 237.365 C 85.974 236.932,85.512 236.224,85.160 235.792 L 84.519 235.005 84.905 235.792 M298.132 263.913 C 296.789 265.428,295.779 266.667,295.888 266.667 C 295.996 266.667,297.183 265.428,298.525 263.913 C 299.868 262.399,300.877 261.160,300.769 261.160 C 300.661 261.160,299.474 262.399,298.132 263.913 M293.590 268.732 L 292.035 270.403 293.707 268.848 C 295.262 267.402,295.559 267.060,295.262 267.060 C 295.197 267.060,294.445 267.812,293.590 268.732 M290.244 271.681 L 288.889 273.156 290.364 271.801 C 291.175 271.055,291.839 270.392,291.839 270.326 C 291.839 270.026,291.506 270.309,290.244 271.681 M133.138 284.368 C 133.401 284.794,135.693 286.071,135.693 285.791 C 135.693 285.699,135.063 285.252,134.293 284.797 C 133.523 284.343,133.003 284.150,133.138 284.368 M368.606 302.262 C 368.360 302.802,368.223 303.245,368.301 303.245 C 368.380 303.245,368.734 302.802,369.089 302.262 C 369.443 301.721,369.580 301.278,369.394 301.278 C 369.207 301.278,368.853 301.721,368.606 302.262 M361.019 313.176 C 360.557 314.056,360.559 314.057,361.398 313.312 C 362.336 312.479,362.421 312.291,361.862 312.291 C 361.654 312.291,361.274 312.689,361.019 313.176 M151.154 316.814 C 151.157 318.112,151.230 318.596,151.317 317.889 C 151.405 317.182,151.403 316.120,151.313 315.529 C 151.224 314.938,151.152 315.516,151.154 316.814 M354.475 321.574 C 353.988 322.128,353.796 322.514,354.048 322.430 C 354.472 322.289,355.831 320.542,355.505 320.558 C 355.425 320.562,354.961 321.019,354.475 321.574 M352.333 323.992 C 351.640 324.799,351.121 325.664,351.329 325.664 C 351.409 325.664,351.867 325.133,352.347 324.484 C 353.295 323.202,353.286 322.883,352.333 323.992 M47.984 324.877 C 48.446 325.526,48.913 326.057,49.021 326.057 C 49.129 326.057,48.840 325.526,48.378 324.877 C 47.915 324.228,47.449 323.697,47.341 323.697 C 47.233 323.697,47.522 324.228,47.984 324.877 M157.268 326.944 C 157.431 327.107,177.201 327.195,201.201 327.140 L 244.838 327.040 200.905 326.844 C 176.741 326.735,157.105 326.781,157.268 326.944 M347.860 329.007 C 346.775 330.197,346.001 331.170,346.140 331.170 C 346.278 331.170,347.283 330.197,348.373 329.007 C 349.463 327.817,350.237 326.844,350.093 326.844 C 349.950 326.844,348.945 327.817,347.860 329.007 M51.524 328.723 C 51.524 328.854,52.498 329.889,53.687 331.024 C 54.877 332.158,55.851 332.986,55.851 332.864 C 55.851 332.742,54.877 331.707,53.687 330.563 C 52.498 329.420,51.524 328.592,51.524 328.723 M61.308 338.584 C 62.977 340.167,63.609 340.603,63.145 339.852 C 63.021 339.651,62.170 338.917,61.253 338.220 L 59.587 336.952 61.308 338.584 M337.620 339.135 C 335.897 341.122,335.385 341.790,335.585 341.790 C 335.701 341.790,336.448 340.993,337.245 340.020 C 338.723 338.217,339.015 337.525,337.620 339.135 M177.778 355.679 C 177.778 355.746,178.353 356.322,179.056 356.957 L 180.334 358.112 179.179 356.834 C 178.102 355.642,177.778 355.375,177.778 355.679 M196.342 393.213 C 198.224 393.285,201.410 393.285,203.422 393.214 C 205.434 393.142,203.894 393.083,200.000 393.083 C 196.106 393.082,194.460 393.141,196.342 393.213 \" stroke=\"none\" fill=\"#fcacb4\" fill-rule=\"evenodd\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\t\t\t\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"box-heading\">\n\t\t\t\t\t\t\t<a >\t\t\t\t\t\t\t\tOn-line Competency Assessments\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-719413b0 content-align-left icon-box-vertical-align-top icon-position-left icon-vertical-align-start elementor-widget elementor-widget-the7_icon_box_widget\" data-id=\"719413b0\" data-element_type=\"widget\" data-widget_type=\"the7_icon_box_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"the7-box-wrapper the7-elementor-widget the7_icon_box_widget-719413b0\">\t\t\t<div class=\"box-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-icon-div\" >\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"svg\" width=\"400\" height=\"392.9901423877327\" viewBox=\"0, 0, 400,392.9901423877327\"><g id=\"svgg\"><path id=\"path0\" d=\"M193.314 43.309 C 155.007 46.203,120.494 64.039,96.738 93.218 C 63.997 133.435,60.098 195.681,87.593 239.239 C 101.091 260.622,119.818 277.760,140.610 287.759 L 145.919 290.312 145.919 291.792 C 145.919 295.513,148.402 299.901,151.320 301.338 L 153.196 302.262 200.393 302.228 L 247.591 302.194 249.593 301.172 C 252.890 299.487,254.370 297.363,255.041 293.354 C 255.271 291.978,255.414 291.867,258.516 290.641 C 328.287 263.078,338.631 183.447,275.516 159.768 C 256.823 152.755,243.679 150.783,209.440 149.855 C 164.379 148.633,143.627 142.430,140.276 129.180 C 137.228 117.133,141.711 105.293,152.011 98.184 C 169.276 86.268,201.577 81.428,228.122 86.779 C 247.528 90.691,268.207 103.598,276.483 116.965 C 287.486 134.737,312.441 132.616,316.478 113.565 C 318.974 101.788,308.991 87.784,285.939 70.730 C 255.989 48.573,229.081 40.607,193.314 43.309 M123.012 166.263 C 140.965 181.228,163.506 186.888,205.703 187.026 C 224.731 187.088,226.988 187.241,240.708 189.388 C 279.914 195.525,290.904 214.942,268.035 237.671 C 224.252 281.187,139.987 265.243,117.384 209.166 C 111.200 193.823,108.954 172.543,111.943 157.611 C 112.160 156.525,112.175 156.533,115.373 159.546 C 117.139 161.211,120.577 164.233,123.012 166.263 M156.932 307.613 C 150.346 311.561,149.524 321.652,155.467 325.585 L 157.071 326.647 201.019 326.647 L 244.967 326.647 246.663 325.455 C 253.221 320.846,252.177 310.416,244.850 307.354 C 242.285 306.283,158.742 306.528,156.932 307.613 M163.516 332.724 C 157.360 336.628,157.289 347.240,163.394 351.019 C 165.262 352.175,165.493 352.216,170.765 352.340 L 176.208 352.469 177.358 354.140 C 187.438 368.792,216.115 368.604,224.773 353.830 L 225.837 352.016 231.247 352.016 C 236.571 352.016,236.681 351.998,238.205 350.894 C 244.474 346.353,245.358 338.771,240.174 334.011 C 237.376 331.442,239.336 331.563,200.838 331.563 L 165.346 331.563 163.516 332.724 \" stroke=\"none\" fill=\"#f42444\" fill-rule=\"evenodd\"><\/path><path id=\"path1\" d=\"M188.201 0.421 C 184.956 0.587,180.294 0.928,177.842 1.179 C 175.390 1.431,173.282 1.535,173.159 1.412 C 173.035 1.288,172.701 1.380,172.416 1.617 C 171.936 2.015,170.708 2.238,167.748 2.466 C 167.099 2.516,166.346 2.701,166.073 2.877 C 165.801 3.053,165.226 3.085,164.795 2.949 C 164.310 2.795,164.012 2.880,164.012 3.171 C 164.012 3.491,163.566 3.570,162.626 3.418 C 161.864 3.294,161.319 3.319,161.414 3.474 C 161.510 3.628,159.293 4.180,156.487 4.699 C 153.682 5.219,151.295 5.793,151.183 5.975 C 151.070 6.157,150.806 6.199,150.595 6.069 C 150.384 5.939,149.976 6.027,149.688 6.266 C 149.401 6.505,148.878 6.589,148.526 6.454 C 148.150 6.310,147.886 6.407,147.886 6.690 C 147.886 6.978,147.569 7.089,147.099 6.966 C 146.667 6.853,146.313 6.941,146.313 7.162 C 146.313 7.384,145.959 7.472,145.526 7.359 C 145.093 7.246,144.739 7.281,144.739 7.436 C 144.739 7.592,143.142 8.131,141.189 8.634 C 139.236 9.138,137.549 9.694,137.440 9.871 C 137.331 10.047,136.981 10.092,136.664 9.970 C 136.346 9.848,136.087 9.964,136.087 10.226 C 136.087 10.489,135.821 10.602,135.497 10.477 C 135.172 10.353,134.907 10.390,134.907 10.560 C 134.907 10.730,133.535 11.286,131.858 11.796 C 130.182 12.307,128.236 12.961,127.534 13.250 C 126.832 13.539,126.144 13.758,126.005 13.737 C 125.865 13.716,125.622 13.908,125.464 14.164 C 125.306 14.420,124.711 14.656,124.142 14.689 C 123.573 14.722,123.108 14.858,123.107 14.992 C 123.107 15.125,122.001 15.631,120.649 16.117 C 119.297 16.603,117.616 17.349,116.912 17.775 C 116.209 18.201,115.634 18.434,115.634 18.293 C 115.634 18.152,115.342 18.328,114.986 18.685 C 114.629 19.042,114.009 19.248,113.608 19.143 C 113.208 19.038,112.967 19.093,113.073 19.265 C 113.179 19.437,112.250 19.985,111.009 20.482 C 109.767 20.980,108.660 21.518,108.549 21.678 C 108.437 21.838,106.844 22.747,105.009 23.697 C 100.301 26.135,95.583 28.785,94.199 29.770 C 92.039 31.306,89.483 32.815,89.184 32.729 C 89.022 32.683,88.889 32.809,88.889 33.010 C 88.889 33.211,87.871 33.995,86.627 34.754 C 85.383 35.512,82.153 37.837,79.449 39.919 C 76.745 42.001,73.544 44.455,72.335 45.373 C 71.126 46.290,69.575 47.615,68.888 48.318 C 68.201 49.021,67.459 49.486,67.241 49.351 C 67.023 49.216,66.891 49.252,66.948 49.430 C 67.146 50.041,63.238 53.433,62.613 53.193 C 62.269 53.061,62.118 53.131,62.257 53.356 C 62.536 53.807,58.110 58.338,57.697 58.024 C 57.547 57.910,57.514 57.936,57.623 58.082 C 57.733 58.228,56.450 59.777,54.772 61.524 C 53.094 63.271,50.934 65.618,49.973 66.741 C 49.011 67.863,48.038 68.676,47.809 68.546 C 47.581 68.416,47.514 68.443,47.659 68.606 C 47.898 68.872,45.576 72.283,44.830 72.763 C 44.661 72.871,43.724 74.022,42.747 75.320 C 41.769 76.618,39.631 79.449,37.994 81.613 C 36.358 83.776,35.016 85.689,35.012 85.864 C 35.008 86.039,34.801 86.056,34.551 85.901 C 34.262 85.723,34.204 85.794,34.390 86.096 C 34.563 86.375,34.140 87.289,33.370 88.306 C 32.647 89.260,31.266 91.273,30.302 92.780 C 29.337 94.287,28.381 95.417,28.176 95.290 C 27.971 95.164,27.930 95.265,28.085 95.516 C 28.392 96.013,26.816 99.115,26.256 99.115 C 26.067 99.115,26.009 99.271,26.127 99.462 C 26.245 99.653,26.015 100.228,25.615 100.740 C 25.216 101.253,23.645 104.095,22.125 107.058 C 20.604 110.021,19.224 112.321,19.057 112.171 C 18.890 112.021,18.868 112.099,19.008 112.344 C 19.320 112.891,18.546 115.241,18.054 115.241 C 17.859 115.241,17.730 115.374,17.769 115.536 C 17.807 115.698,17.390 116.813,16.842 118.013 C 16.294 119.214,15.629 120.851,15.365 121.652 C 15.101 122.452,14.711 123.107,14.499 123.107 C 14.287 123.107,14.219 123.279,14.349 123.489 C 14.479 123.700,14.333 124.275,14.024 124.768 C 13.715 125.260,12.974 127.168,12.376 129.007 C 11.778 130.846,11.148 132.406,10.976 132.474 C 10.804 132.542,10.761 132.852,10.880 133.162 C 10.999 133.473,10.907 133.727,10.674 133.727 C 10.441 133.727,10.353 133.992,10.477 134.317 C 10.602 134.641,10.541 134.907,10.342 134.907 C 10.143 134.907,9.567 136.511,9.061 138.473 C 8.430 140.920,8.029 141.876,7.783 141.521 C 7.554 141.190,7.516 141.464,7.677 142.281 C 7.824 143.029,7.768 143.559,7.541 143.559 C 7.328 143.559,7.246 143.913,7.359 144.346 C 7.472 144.779,7.384 145.133,7.162 145.133 C 6.941 145.133,6.853 145.487,6.966 145.919 C 7.089 146.389,6.978 146.706,6.690 146.706 C 6.407 146.706,6.310 146.970,6.454 147.346 C 6.589 147.698,6.495 148.233,6.244 148.535 C 5.993 148.838,5.900 149.197,6.037 149.334 C 6.174 149.471,6.133 149.777,5.946 150.013 C 5.759 150.249,5.286 152.168,4.894 154.277 C 4.503 156.386,4.068 158.112,3.929 158.112 C 3.790 158.112,3.754 158.643,3.849 159.292 C 3.951 159.986,3.846 160.472,3.594 160.472 C 3.328 160.472,3.256 160.919,3.402 161.652 C 3.554 162.413,3.478 162.832,3.188 162.832 C 2.904 162.832,2.830 163.196,2.986 163.820 C 3.126 164.377,3.029 165.056,2.765 165.375 C 2.506 165.686,2.406 166.292,2.543 166.722 C 2.679 167.151,2.616 167.823,2.402 168.215 C 1.307 170.226,0.243 188.749,0.520 200.983 C 0.757 211.453,1.765 224.046,2.431 224.858 C 2.644 225.118,2.700 225.702,2.557 226.155 C 2.413 226.609,2.506 227.234,2.765 227.546 C 3.029 227.864,3.126 228.543,2.986 229.100 C 2.831 229.720,2.904 230.088,3.184 230.088 C 3.455 230.088,3.561 230.550,3.456 231.268 C 3.361 231.917,3.449 232.448,3.653 232.448 C 3.856 232.448,3.944 232.979,3.849 233.628 C 3.754 234.277,3.789 234.808,3.927 234.808 C 4.065 234.808,4.503 236.584,4.899 238.753 C 5.296 240.923,5.774 242.794,5.963 242.910 C 6.152 243.027,6.199 243.295,6.069 243.506 C 5.939 243.716,6.027 244.124,6.266 244.412 C 6.505 244.699,6.589 245.223,6.454 245.575 C 6.310 245.951,6.407 246.214,6.690 246.214 C 6.974 246.214,7.089 246.530,6.971 246.982 C 6.860 247.404,6.938 247.806,7.143 247.874 C 7.348 247.943,7.551 248.658,7.593 249.465 C 7.635 250.271,7.768 250.931,7.889 250.932 C 8.009 250.933,8.430 252.177,8.824 253.695 C 9.218 255.214,9.687 256.547,9.866 256.658 C 10.045 256.768,10.092 257.119,9.970 257.436 C 9.848 257.754,9.964 258.014,10.226 258.014 C 10.489 258.014,10.602 258.279,10.477 258.604 C 10.353 258.928,10.441 259.194,10.674 259.194 C 10.907 259.194,10.995 259.459,10.871 259.784 C 10.746 260.108,10.782 260.374,10.951 260.374 C 11.119 260.374,11.586 261.480,11.988 262.832 C 12.391 264.184,12.957 265.864,13.247 266.566 C 13.537 267.268,13.758 267.957,13.737 268.096 C 13.716 268.235,13.860 268.457,14.057 268.589 C 14.254 268.722,15.093 270.600,15.922 272.763 C 16.750 274.926,17.560 276.785,17.721 276.893 C 17.882 277.001,18.076 277.443,18.151 277.876 C 18.227 278.309,18.521 278.907,18.803 279.205 C 19.086 279.503,19.210 280.029,19.078 280.373 C 18.946 280.717,18.959 280.877,19.108 280.728 C 19.380 280.457,21.821 285.091,21.698 285.644 C 21.662 285.806,21.820 285.939,22.049 285.939 C 22.278 285.939,22.365 286.101,22.243 286.299 C 22.121 286.497,22.167 286.718,22.347 286.790 C 22.526 286.863,23.295 288.073,24.056 289.479 C 27.443 295.739,31.656 302.714,33.000 304.285 C 33.211 304.532,33.277 304.842,33.146 304.973 C 33.015 305.104,33.099 305.211,33.334 305.211 C 33.569 305.211,34.163 305.875,34.654 306.686 C 35.145 307.498,36.320 309.179,37.265 310.423 C 38.211 311.667,38.872 312.866,38.735 313.088 C 38.598 313.309,38.662 313.442,38.876 313.382 C 39.228 313.285,40.418 314.647,45.313 320.747 C 46.180 321.829,47.712 323.678,48.716 324.856 C 51.642 328.292,64.365 341.035,66.799 342.970 C 68.024 343.943,69.259 345.050,69.542 345.430 C 69.826 345.810,70.534 346.372,71.115 346.680 C 71.697 346.988,72.714 347.739,73.375 348.350 C 75.620 350.422,81.851 355.111,85.644 357.582 C 86.996 358.463,88.116 359.473,88.133 359.828 C 88.150 360.182,88.248 360.269,88.349 360.020 C 88.529 359.582,92.330 361.844,92.866 362.708 C 92.998 362.921,93.220 363.081,93.358 363.062 C 94.058 362.968,94.384 363.073,94.859 363.543 C 95.588 364.265,101.460 367.615,105.211 369.449 C 106.942 370.296,108.623 371.204,108.948 371.468 C 109.272 371.733,110.733 372.459,112.193 373.083 C 113.653 373.706,114.848 374.364,114.848 374.545 C 114.848 374.726,115.025 374.765,115.241 374.631 C 115.457 374.498,115.634 374.576,115.634 374.805 C 115.634 375.034,115.767 375.188,115.929 375.148 C 116.091 375.108,116.932 375.388,117.797 375.771 C 118.663 376.153,120.610 376.915,122.124 377.464 C 123.638 378.012,125.231 378.655,125.664 378.892 C 126.096 379.129,126.539 379.336,126.647 379.351 C 126.755 379.366,127.198 379.562,127.630 379.785 C 128.063 380.008,129.789 380.608,131.465 381.118 C 133.142 381.629,134.513 382.186,134.513 382.358 C 134.513 382.529,134.779 382.568,135.103 382.443 C 135.428 382.318,135.693 382.431,135.693 382.694 C 135.693 382.957,135.953 383.072,136.271 382.950 C 136.588 382.828,136.935 382.869,137.040 383.040 C 137.146 383.211,139.143 383.854,141.478 384.469 C 143.813 385.084,145.775 385.714,145.840 385.869 C 145.904 386.024,146.303 386.060,146.725 385.950 C 147.147 385.839,147.493 385.930,147.493 386.151 C 147.493 386.373,147.847 386.461,148.279 386.348 C 148.739 386.228,149.066 386.336,149.066 386.608 C 149.066 386.888,149.367 386.978,149.819 386.834 C 150.234 386.703,150.678 386.765,150.806 386.973 C 150.934 387.180,153.250 387.754,155.952 388.248 C 158.654 388.742,160.865 389.283,160.865 389.450 C 160.865 389.617,161.396 389.648,162.045 389.518 C 162.695 389.388,163.225 389.450,163.225 389.657 C 163.225 389.862,163.756 389.953,164.405 389.858 C 165.124 389.752,165.585 389.859,165.585 390.130 C 165.585 390.409,165.954 390.483,166.573 390.327 C 167.117 390.191,167.799 390.276,168.089 390.517 C 168.379 390.758,169.041 390.953,169.559 390.951 C 170.077 390.949,172.537 391.201,175.025 391.510 C 188.507 393.187,209.683 393.280,223.009 391.721 C 226.578 391.304,229.923 390.960,230.441 390.958 C 230.959 390.956,231.622 390.756,231.914 390.514 C 232.206 390.272,232.834 390.176,233.311 390.301 C 233.787 390.426,234.407 390.337,234.687 390.104 C 234.968 389.871,235.552 389.774,235.986 389.887 C 236.420 390.001,236.775 389.933,236.775 389.737 C 236.775 389.541,237.121 389.381,237.544 389.381 C 239.004 389.381,249.165 387.295,249.392 386.948 C 249.518 386.757,249.916 386.714,250.277 386.853 C 250.661 387.000,250.934 386.913,250.934 386.643 C 250.934 386.360,251.239 386.278,251.721 386.431 C 252.205 386.584,252.507 386.501,252.507 386.215 C 252.507 385.943,252.834 385.834,253.294 385.955 C 253.727 386.068,254.081 386.032,254.081 385.876 C 254.081 385.719,255.452 385.270,257.129 384.877 C 258.805 384.485,260.531 384.031,260.964 383.869 C 261.396 383.707,261.927 383.539,262.144 383.494 C 262.360 383.450,262.750 383.237,263.011 383.020 C 263.272 382.804,263.670 382.741,263.896 382.880 C 264.122 383.020,264.307 382.928,264.307 382.675 C 264.307 382.423,264.572 382.319,264.897 382.443 C 265.221 382.568,265.487 382.536,265.487 382.374 C 265.487 382.211,267.168 381.572,269.223 380.955 C 271.278 380.338,272.960 379.650,272.960 379.428 C 272.960 379.205,273.076 379.140,273.218 379.282 C 273.361 379.424,273.671 379.389,273.907 379.204 C 274.143 379.019,275.841 378.293,277.679 377.592 C 279.518 376.890,281.664 375.989,282.449 375.589 C 283.233 375.189,283.985 374.972,284.120 375.107 C 284.255 375.242,284.366 375.170,284.366 374.948 C 284.366 374.726,285.737 373.970,287.414 373.269 C 289.090 372.568,290.668 371.827,290.919 371.622 C 291.170 371.418,292.851 370.493,294.655 369.567 C 299.407 367.129,304.461 364.295,305.179 363.666 C 305.521 363.366,306.805 362.560,308.031 361.875 C 309.257 361.190,310.472 360.375,310.730 360.063 C 310.989 359.752,311.357 359.594,311.549 359.713 C 311.741 359.831,311.898 359.746,311.898 359.522 C 311.898 359.298,312.466 358.822,313.160 358.463 C 313.854 358.104,316.155 356.511,318.273 354.923 C 320.391 353.335,322.124 352.106,322.124 352.192 C 322.124 352.278,322.625 351.875,323.237 351.297 C 323.849 350.719,325.370 349.449,326.616 348.476 C 335.692 341.385,346.987 330.269,354.769 320.770 C 355.959 319.318,357.419 317.599,358.014 316.950 C 358.609 316.301,359.095 315.682,359.095 315.574 C 359.095 315.466,359.936 314.299,360.964 312.981 C 362.767 310.668,365.287 307.040,367.793 303.147 C 368.454 302.119,369.168 301.278,369.378 301.278 C 369.589 301.278,369.665 301.122,369.547 300.931 C 369.429 300.740,369.699 300.118,370.147 299.549 C 371.042 298.411,373.212 294.639,375.942 289.479 C 376.914 287.640,377.859 286.076,378.041 286.004 C 378.224 285.931,378.273 285.710,378.150 285.512 C 378.028 285.314,378.082 285.152,378.269 285.152 C 378.457 285.152,379.209 283.736,379.941 282.006 C 380.673 280.275,381.425 278.859,381.613 278.859 C 381.800 278.859,381.845 278.682,381.711 278.466 C 381.577 278.250,381.618 278.073,381.803 278.073 C 381.987 278.073,382.732 276.480,383.459 274.533 C 384.186 272.586,384.941 270.993,385.137 270.993 C 385.333 270.993,385.394 270.832,385.272 270.635 C 385.151 270.438,385.476 269.420,385.995 268.373 C 386.515 267.327,387.255 265.452,387.642 264.208 C 388.028 262.965,388.499 261.947,388.689 261.947 C 388.879 261.947,388.919 261.762,388.780 261.536 C 388.640 261.311,388.740 260.868,389.002 260.553 C 389.263 260.238,389.345 259.980,389.184 259.980 C 389.023 259.980,389.075 259.759,389.299 259.489 C 389.523 259.218,389.745 258.820,389.790 258.604 C 389.836 258.387,389.935 258.033,390.009 257.817 C 390.084 257.601,390.690 255.477,391.356 253.097 C 392.023 250.718,392.676 248.505,392.807 248.181 C 392.938 247.856,393.011 247.440,392.969 247.255 C 392.927 247.070,393.091 246.679,393.334 246.387 C 393.576 246.095,393.668 245.683,393.538 245.472 C 393.407 245.261,393.460 244.990,393.654 244.870 C 393.849 244.750,394.418 242.526,394.918 239.927 C 395.419 237.328,395.940 235.202,396.076 235.202 C 396.212 235.202,396.246 234.671,396.151 234.022 C 396.049 233.327,396.154 232.842,396.406 232.842 C 396.672 232.842,396.744 232.395,396.598 231.662 C 396.446 230.901,396.522 230.482,396.812 230.482 C 397.096 230.482,397.170 230.118,397.014 229.493 C 396.877 228.950,396.947 228.286,397.168 228.018 C 397.390 227.751,397.577 227.089,397.584 226.549 C 397.591 226.008,397.856 223.707,398.172 221.436 C 400.082 207.708,399.985 180.691,397.986 169.752 C 397.745 168.434,397.553 166.912,397.559 166.372 C 397.566 165.831,397.402 165.184,397.195 164.934 C 396.989 164.685,396.935 164.021,397.076 163.459 C 397.247 162.777,397.173 162.439,396.850 162.439 C 396.548 162.439,396.439 162.071,396.556 161.455 C 396.660 160.914,396.569 160.472,396.354 160.472 C 396.125 160.472,396.060 159.883,396.195 159.047 C 396.322 158.263,396.316 157.732,396.180 157.868 C 396.045 158.003,395.440 155.680,394.837 152.705 C 394.234 149.730,393.550 146.979,393.317 146.592 C 393.084 146.204,392.989 145.733,393.106 145.544 C 393.223 145.355,393.131 145.137,392.901 145.061 C 392.672 144.984,392.449 144.262,392.407 143.456 C 392.365 142.649,392.235 141.989,392.118 141.988 C 392.001 141.987,391.477 140.393,390.954 138.446 C 390.431 136.500,389.844 134.907,389.649 134.907 C 389.455 134.907,389.398 134.641,389.523 134.317 C 389.647 133.992,389.559 133.727,389.326 133.727 C 389.093 133.727,389.001 133.473,389.120 133.162 C 389.239 132.852,389.214 132.542,389.063 132.474 C 388.913 132.406,388.187 130.580,387.450 128.417 C 386.713 126.254,385.939 124.263,385.731 123.992 C 385.522 123.722,385.505 123.498,385.694 123.494 C 385.883 123.491,385.849 123.358,385.620 123.199 C 385.390 123.041,384.786 121.849,384.278 120.551 C 383.770 119.253,382.321 116.030,381.058 113.389 C 379.795 110.749,378.761 108.403,378.761 108.178 C 378.761 107.952,378.574 107.768,378.345 107.768 C 378.115 107.768,378.037 107.591,378.171 107.375 C 378.305 107.158,378.216 106.981,377.974 106.981 C 377.733 106.981,377.635 106.819,377.757 106.622 C 377.879 106.424,377.823 106.203,377.632 106.130 C 377.441 106.057,376.635 104.759,375.840 103.245 C 373.209 98.228,367.459 88.815,366.872 88.561 C 366.705 88.489,366.568 88.194,366.568 87.906 C 366.568 87.617,366.423 87.322,366.246 87.250 C 366.069 87.178,365.205 86.053,364.326 84.750 C 362.686 82.320,356.953 74.763,355.678 73.350 C 355.286 72.916,354.169 71.588,353.196 70.400 C 350.436 67.031,348.951 65.381,345.030 61.329 C 343.026 59.258,341.522 57.429,341.687 57.265 C 341.851 57.100,341.792 57.024,341.555 57.096 C 340.913 57.291,337.394 53.920,337.709 53.411 C 337.866 53.156,337.799 53.086,337.547 53.242 C 337.310 53.389,335.822 52.333,334.241 50.897 C 332.660 49.460,330.526 47.649,329.499 46.871 C 328.471 46.093,327.630 45.317,327.630 45.147 C 327.630 44.977,327.359 44.838,327.028 44.838 C 326.697 44.838,326.330 44.589,326.214 44.285 C 326.097 43.981,325.041 43.094,323.866 42.314 C 322.692 41.535,321.731 40.750,321.731 40.570 C 321.731 40.391,321.326 40.060,320.832 39.835 C 320.338 39.610,318.790 38.556,317.391 37.493 C 315.992 36.430,314.007 35.074,312.979 34.479 C 311.952 33.885,311.111 33.219,311.111 32.999 C 311.111 32.779,310.949 32.699,310.751 32.821 C 310.554 32.943,310.332 32.909,310.260 32.746 C 310.098 32.382,303.820 28.450,300.983 26.936 C 299.848 26.330,298.918 25.685,298.918 25.503 C 298.918 25.321,298.786 25.207,298.623 25.250 C 298.198 25.362,292.454 22.388,292.297 21.975 C 292.224 21.784,292.003 21.727,291.805 21.850 C 291.607 21.972,291.445 21.929,291.444 21.754 C 291.443 21.579,290.395 20.997,289.116 20.461 C 287.837 19.924,286.892 19.322,287.016 19.121 C 287.139 18.921,287.057 18.871,286.832 19.010 C 286.323 19.324,283.972 18.538,283.972 18.054 C 283.972 17.859,283.840 17.728,283.677 17.763 C 283.515 17.799,282.586 17.472,281.613 17.036 C 280.639 16.601,279.179 16.028,278.368 15.762 C 277.557 15.496,276.893 15.105,276.893 14.892 C 276.893 14.680,276.719 14.613,276.508 14.744 C 276.296 14.875,275.721 14.759,275.229 14.486 C 274.738 14.214,274.248 13.968,274.140 13.941 C 274.031 13.914,273.324 13.616,272.566 13.279 C 271.809 12.943,270.438 12.444,269.518 12.171 C 268.599 11.898,267.847 11.542,267.847 11.381 C 267.847 11.219,267.493 11.179,267.060 11.292 C 266.627 11.405,266.273 11.306,266.273 11.071 C 266.273 10.836,266.008 10.746,265.683 10.871 C 265.359 10.995,265.093 10.907,265.093 10.674 C 265.093 10.441,264.828 10.353,264.503 10.477 C 264.179 10.602,263.913 10.489,263.913 10.226 C 263.913 9.964,263.654 9.848,263.336 9.970 C 263.019 10.092,262.672 10.052,262.566 9.880 C 262.460 9.709,260.464 9.066,258.129 8.451 C 255.794 7.837,253.831 7.207,253.767 7.052 C 253.702 6.897,253.304 6.860,252.882 6.971 C 252.429 7.089,252.114 6.974,252.114 6.690 C 252.114 6.407,251.850 6.310,251.474 6.454 C 251.122 6.589,250.610 6.514,250.336 6.286 C 250.061 6.058,249.686 5.906,249.501 5.948 C 249.316 5.990,248.899 5.917,248.574 5.787 C 247.677 5.424,240.081 3.933,239.134 3.933 C 238.676 3.933,238.409 3.759,238.541 3.546 C 238.690 3.305,238.325 3.249,237.581 3.398 C 236.775 3.559,236.382 3.483,236.382 3.164 C 236.382 2.846,236.007 2.773,235.239 2.942 C 234.558 3.091,233.987 3.015,233.825 2.753 C 233.666 2.496,233.095 2.414,232.448 2.557 C 231.799 2.699,231.231 2.617,231.070 2.357 C 230.920 2.114,230.328 1.952,229.755 1.997 C 229.181 2.043,228.446 1.980,228.122 1.859 C 224.834 0.632,200.925 -0.230,188.201 0.421 M218.682 42.875 C 224.914 43.339,229.812 43.957,231.465 44.489 C 232.114 44.698,233.945 45.138,235.535 45.467 C 239.072 46.199,244.814 47.826,246.411 48.548 C 247.060 48.841,248.918 49.549,250.541 50.120 C 255.840 51.986,266.175 57.107,271.830 60.669 C 273.461 61.696,274.919 62.537,275.070 62.537 C 275.394 62.537,280.853 66.294,284.041 68.711 C 285.268 69.642,286.463 70.403,286.696 70.403 C 286.929 70.403,287.119 70.582,287.119 70.801 C 287.119 71.020,288.048 71.794,289.184 72.521 C 293.841 75.503,305.912 86.900,309.852 92.035 C 310.764 93.225,311.686 94.412,311.901 94.674 C 312.116 94.935,312.291 95.333,312.291 95.559 C 312.291 95.784,312.450 95.969,312.643 95.969 C 312.837 95.969,313.332 96.632,313.744 97.443 C 314.156 98.255,315.095 100.059,315.831 101.452 C 317.731 105.049,317.950 113.610,316.222 116.749 C 316.024 117.109,315.413 118.394,314.864 119.603 C 310.740 128.695,294.952 132.472,285.469 126.637 C 284.423 125.993,283.428 125.467,283.258 125.467 C 282.660 125.467,278.649 121.626,278.077 120.505 C 277.077 118.545,273.676 113.558,271.856 111.385 C 269.164 108.170,258.824 99.903,256.382 99.013 C 256.025 98.883,254.344 97.917,252.645 96.865 C 233.017 84.714,199.055 81.368,174.041 89.120 C 172.311 89.656,169.390 90.559,167.552 91.127 C 165.713 91.694,164.031 92.284,163.815 92.439 C 163.599 92.593,161.829 93.421,159.882 94.279 C 150.963 98.208,143.490 105.654,141.143 112.950 C 139.790 117.157,139.786 126.259,141.135 130.556 C 142.003 133.320,145.742 138.053,147.058 138.053 C 147.240 138.053,148.785 138.834,150.489 139.787 C 156.217 142.992,168.961 146.406,178.564 147.309 C 179.971 147.442,181.475 147.704,181.908 147.893 C 183.203 148.458,193.596 149.052,209.243 149.454 C 217.355 149.663,225.674 149.932,227.729 150.051 C 236.805 150.580,242.676 151.103,245.231 151.610 C 246.745 151.911,249.843 152.450,252.114 152.808 C 257.124 153.599,262.443 154.779,264.307 155.515 C 265.064 155.814,267.610 156.622,269.966 157.310 C 272.321 157.999,274.884 158.903,275.663 159.320 C 276.441 159.737,277.257 160.077,277.477 160.075 C 277.933 160.072,284.067 162.522,284.366 162.828 C 284.474 162.938,285.359 163.455,286.332 163.977 C 287.306 164.498,289.043 165.560,290.192 166.337 C 291.342 167.113,292.659 167.958,293.119 168.215 C 295.272 169.417,304.031 177.590,304.031 178.397 C 304.031 178.659,304.283 178.970,304.591 179.088 C 306.477 179.812,313.462 192.452,315.061 198.033 C 315.557 199.764,316.086 201.357,316.238 201.573 C 318.085 204.207,318.074 228.277,316.225 230.678 C 316.058 230.895,315.800 231.691,315.650 232.448 C 315.281 234.322,313.078 241.204,312.692 241.691 C 312.520 241.908,311.813 243.455,311.120 245.131 C 310.427 246.806,309.440 248.794,308.928 249.549 C 308.416 250.304,307.532 251.765,306.963 252.796 C 303.138 259.735,284.374 278.859,281.393 278.859 C 281.223 278.859,280.759 279.154,280.362 279.513 C 279.313 280.463,273.988 283.720,270.808 285.357 C 269.300 286.134,267.530 287.099,266.875 287.502 C 266.220 287.905,264.356 288.768,262.734 289.419 C 261.111 290.070,259.040 290.969,258.131 291.417 C 257.222 291.865,256.316 292.232,256.117 292.232 C 255.918 292.232,255.638 293.073,255.495 294.100 C 255.094 296.985,252.850 299.994,249.951 301.534 L 247.591 302.788 200.683 302.820 C 172.948 302.838,153.496 302.704,153.092 302.491 C 152.716 302.293,151.828 301.915,151.117 301.651 C 148.298 300.605,146.283 297.275,145.686 292.677 L 145.412 290.565 143.208 289.611 C 139.934 288.195,134.152 285.201,132.277 283.951 C 131.372 283.347,130.024 282.566,129.282 282.213 C 127.557 281.395,117.393 273.865,115.809 272.232 C 115.148 271.551,114.396 270.993,114.137 270.993 C 113.495 270.993,99.508 256.963,99.508 256.318 C 99.508 256.034,98.977 255.409,98.328 254.929 C 97.679 254.450,97.148 253.860,97.148 253.620 C 97.148 253.379,96.384 252.278,95.449 251.173 C 93.732 249.145,89.266 242.948,88.014 240.857 C 87.641 240.234,86.357 238.132,85.161 236.185 C 83.964 234.238,82.718 232.068,82.391 231.364 C 82.064 230.659,81.169 228.800,80.402 227.234 C 79.636 225.667,78.470 222.970,77.813 221.239 C 77.156 219.508,76.276 217.354,75.858 216.452 C 75.440 215.549,74.433 212.185,73.620 208.976 C 72.806 205.766,72.033 202.965,71.902 202.750 C 70.707 200.793,69.226 185.114,69.225 174.399 C 69.223 163.630,70.871 145.980,71.958 145.133 C 72.097 145.025,72.442 143.697,72.725 142.183 C 73.373 138.715,75.581 130.056,75.884 129.794 C 76.009 129.685,76.622 128.004,77.247 126.057 C 77.872 124.110,78.694 121.898,79.073 121.141 C 79.452 120.383,81.041 117.152,82.603 113.959 C 84.166 110.766,86.756 106.252,88.358 103.929 C 89.960 101.606,91.575 99.191,91.948 98.564 C 95.921 91.871,114.620 73.320,121.987 68.762 C 122.994 68.139,123.918 67.369,124.040 67.050 C 124.162 66.731,124.448 66.470,124.674 66.470 C 124.901 66.470,126.278 65.605,127.735 64.548 C 129.192 63.491,131.357 62.094,132.547 61.444 C 133.736 60.794,136.450 59.270,138.578 58.056 C 140.705 56.843,142.556 55.851,142.691 55.851 C 142.970 55.851,148.839 53.426,151.229 52.324 C 152.094 51.925,154.218 51.155,155.949 50.613 C 157.679 50.071,159.980 49.328,161.062 48.962 C 162.144 48.596,165.772 47.686,169.125 46.941 C 172.478 46.195,176.726 45.247,178.564 44.832 C 187.530 42.813,205.844 41.919,218.682 42.875 M112.127 158.644 C 110.939 162.358,110.697 177.745,111.708 185.251 C 112.458 190.818,115.318 203.165,116.298 205.058 C 116.629 205.700,117.225 207.125,117.623 208.225 C 118.020 209.326,118.606 210.940,118.925 211.813 C 119.559 213.547,122.776 219.258,124.668 222.007 C 125.324 222.960,125.860 223.854,125.860 223.992 C 125.860 224.130,127.053 225.771,128.512 227.639 C 135.059 236.024,145.323 244.545,154.472 249.193 C 155.933 249.936,157.306 250.675,157.522 250.837 C 157.738 250.999,158.977 251.606,160.275 252.187 C 161.573 252.769,163.786 253.762,165.192 254.395 C 166.598 255.027,169.607 256.110,171.878 256.799 C 174.149 257.489,176.663 258.305,177.464 258.613 C 189.252 263.141,219.453 263.148,230.482 258.625 C 231.239 258.315,233.628 257.502,235.792 256.819 C 251.106 251.983,266.854 240.556,274.921 228.424 C 281.680 218.261,279.922 206.384,270.814 200.682 C 269.939 200.134,269.135 199.557,269.027 199.399 C 268.614 198.798,260.856 194.779,258.604 193.999 C 250.836 191.309,248.866 190.897,234.415 188.942 C 230.413 188.401,225.988 187.800,224.582 187.608 C 223.176 187.415,214.503 187.248,205.310 187.237 C 196.116 187.225,186.205 187.040,183.284 186.826 C 173.756 186.126,163.599 184.815,161.849 184.058 C 161.416 183.871,160.000 183.519,158.702 183.276 C 155.478 182.672,148.565 180.887,148.083 180.534 C 147.866 180.376,146.362 179.791,144.739 179.233 C 139.580 177.460,138.720 177.091,134.984 175.054 C 132.972 173.956,131.158 173.058,130.953 173.058 C 130.748 173.058,130.580 172.889,130.580 172.683 C 130.580 172.477,129.978 172.023,129.243 171.674 C 127.667 170.926,120.333 164.840,115.750 160.478 L 112.522 157.406 112.127 158.644 M245.244 306.961 C 253.113 310.249,253.675 322.620,246.132 326.489 C 244.341 327.407,159.116 327.683,156.523 326.779 C 149.499 324.331,149.181 312.136,156.024 307.603 L 157.854 306.391 200.867 306.391 C 237.535 306.391,244.081 306.475,245.244 306.961 M238.902 332.290 C 240.180 333.092,241.419 334.090,241.655 334.509 C 241.891 334.928,242.526 335.985,243.066 336.858 C 244.342 338.921,244.460 343.639,243.284 345.526 C 241.222 348.835,240.431 349.792,238.725 351.044 L 236.866 352.409 231.412 352.419 L 225.959 352.429 225.248 353.972 C 220.338 364.625,200.029 368.942,186.234 362.265 C 182.722 360.565,177.033 355.580,176.428 353.672 C 176.161 352.832,175.972 352.802,170.942 352.802 C 164.236 352.802,161.642 351.614,159.357 347.493 C 158.394 345.758,158.436 338.178,159.418 336.361 C 160.392 334.560,163.005 332.027,164.198 331.727 C 164.745 331.590,165.192 331.320,165.192 331.127 C 165.192 330.924,180.224 330.788,200.885 330.804 L 236.578 330.832 238.902 332.290 \" stroke=\"none\" fill=\"#fcfbfb\" fill-rule=\"evenodd\"><\/path><path id=\"path2\" d=\"M203.048 42.771 C 204.941 42.843,208.038 42.843,209.931 42.771 C 211.824 42.699,210.275 42.640,206.490 42.640 C 202.704 42.640,201.155 42.699,203.048 42.771 M194.206 43.156 C 194.913 43.244,195.975 43.242,196.566 43.152 C 197.157 43.062,196.578 42.991,195.280 42.993 C 193.982 42.995,193.499 43.069,194.206 43.156 M216.421 43.153 C 217.016 43.243,217.989 43.243,218.584 43.153 C 219.179 43.063,218.692 42.989,217.502 42.989 C 216.313 42.989,215.826 43.063,216.421 43.153 M236.185 45.973 C 237.392 46.488,239.838 46.907,239.135 46.479 C 238.810 46.281,237.837 46.010,236.971 45.878 C 235.947 45.721,235.672 45.754,236.185 45.973 M171.288 46.429 C 170.740 46.678,170.978 46.713,172.075 46.546 C 172.940 46.414,173.722 46.242,173.812 46.162 C 174.150 45.864,172.043 46.087,171.288 46.429 M244.051 48.378 C 244.484 48.563,245.103 48.716,245.428 48.716 C 245.800 48.716,245.727 48.591,245.231 48.378 C 244.798 48.192,244.179 48.040,243.854 48.040 C 243.483 48.040,243.555 48.165,244.051 48.378 M246.608 49.098 C 246.932 49.298,247.640 49.581,248.181 49.725 C 248.864 49.908,248.984 49.877,248.574 49.624 C 248.250 49.423,247.542 49.141,247.001 48.996 C 246.318 48.814,246.198 48.845,246.608 49.098 M148.476 53.661 C 145.892 54.906,146.396 54.944,149.114 53.710 C 150.277 53.182,151.052 52.741,150.836 52.732 C 150.619 52.722,149.558 53.140,148.476 53.661 M257.227 53.491 C 257.984 53.905,258.781 54.244,258.997 54.244 C 259.213 54.244,258.771 53.905,258.014 53.491 C 257.257 53.076,256.460 52.737,256.244 52.737 C 256.028 52.737,256.470 53.076,257.227 53.491 M260.374 54.880 C 260.374 54.976,261.834 55.767,263.618 56.638 C 265.403 57.509,266.467 57.933,265.982 57.581 C 264.944 56.826,260.374 54.625,260.374 54.880 M140.708 57.057 C 139.897 57.486,139.233 57.924,139.233 58.031 C 139.233 58.206,142.340 56.755,142.740 56.392 C 143.193 55.983,142.011 56.369,140.708 57.057 M134.402 60.512 C 133.367 61.121,132.305 61.845,132.042 62.120 C 131.779 62.395,132.448 62.094,133.530 61.450 C 134.612 60.806,135.851 60.085,136.283 59.847 C 136.716 59.609,136.893 59.412,136.676 59.409 C 136.460 59.406,135.436 59.902,134.402 60.512 M274.533 62.653 C 274.533 62.742,275.772 63.639,277.286 64.646 C 278.800 65.652,280.039 66.393,280.039 66.291 C 280.039 66.189,279.022 65.422,277.778 64.587 C 275.023 62.736,274.533 62.444,274.533 62.653 M126.767 65.523 L 125.664 66.542 126.942 65.693 C 128.113 64.915,128.494 64.503,128.046 64.503 C 127.949 64.503,127.374 64.962,126.767 65.523 M120.810 69.834 C 118.429 71.685,116.247 73.494,115.960 73.855 C 115.673 74.216,116.765 73.446,118.387 72.145 C 120.010 70.844,122.266 69.108,123.402 68.288 C 125.281 66.931,125.763 66.470,125.302 66.470 C 125.212 66.470,123.190 67.984,120.810 69.834 M281.613 67.432 C 281.613 67.511,282.490 68.206,283.562 68.977 C 284.634 69.747,285.423 70.162,285.315 69.898 C 285.133 69.455,281.613 67.109,281.613 67.432 M286.579 71.105 C 287.040 71.476,289.419 73.370,291.866 75.313 C 299.930 81.714,308.266 90.268,312.091 96.067 C 313.717 98.533,314.235 99.006,313.275 97.150 C 310.580 91.938,288.529 70.302,286.029 70.416 C 285.871 70.423,286.119 70.733,286.579 71.105 M113.840 75.615 L 112.684 76.893 113.963 75.738 C 115.154 74.661,115.422 74.336,115.118 74.336 C 115.050 74.336,114.475 74.912,113.840 75.615 M110.521 78.466 C 109.566 79.440,108.873 80.236,108.981 80.236 C 109.089 80.236,109.959 79.440,110.914 78.466 C 111.870 77.493,112.563 76.696,112.455 76.696 C 112.347 76.696,111.477 77.493,110.521 78.466 M104.871 83.612 C 104.251 84.157,103.822 84.680,103.916 84.775 C 104.011 84.870,104.596 84.418,105.215 83.772 C 106.584 82.343,106.407 82.261,104.871 83.612 M198.530 84.841 C 199.019 84.935,199.727 84.931,200.103 84.833 C 200.479 84.734,200.079 84.657,199.213 84.662 C 198.348 84.666,198.040 84.747,198.530 84.841 M211.116 84.841 C 211.605 84.935,212.313 84.931,212.689 84.833 C 213.065 84.734,212.665 84.657,211.799 84.662 C 210.934 84.666,210.626 84.747,211.116 84.841 M181.121 86.922 C 180.061 87.192,180.041 87.223,180.924 87.230 C 181.465 87.234,182.350 87.096,182.891 86.922 C 184.213 86.499,182.785 86.499,181.121 86.922 M228.319 87.147 C 229.400 87.448,230.639 87.682,231.072 87.668 C 231.504 87.654,230.885 87.399,229.695 87.102 C 226.880 86.400,225.764 86.436,228.319 87.147 M100.295 88.692 C 99.340 89.666,98.646 90.462,98.755 90.462 C 98.863 90.462,99.733 89.666,100.688 88.692 C 101.644 87.719,102.337 86.922,102.229 86.922 C 102.121 86.922,101.250 87.719,100.295 88.692 M165.585 91.268 C 164.612 91.667,164.081 91.992,164.405 91.992 C 164.730 91.992,165.792 91.657,166.765 91.249 C 167.738 90.840,168.269 90.515,167.945 90.525 C 167.620 90.535,166.559 90.870,165.585 91.268 M240.708 90.669 C 240.708 90.898,241.961 91.406,243.461 91.785 C 244.002 91.922,243.736 91.693,242.871 91.277 C 241.201 90.474,240.708 90.335,240.708 90.669 M96.362 93.215 C 95.456 94.297,94.804 95.182,94.912 95.182 C 95.020 95.182,95.850 94.297,96.755 93.215 C 97.661 92.134,98.313 91.249,98.205 91.249 C 98.097 91.249,97.267 92.134,96.362 93.215 M157.758 94.613 C 157.022 94.933,156.519 95.293,156.639 95.414 C 156.866 95.640,159.292 94.520,159.292 94.189 C 159.292 93.945,159.310 93.939,157.758 94.613 M249.332 94.684 C 250.370 95.440,252.507 96.429,252.507 96.153 C 252.507 96.059,251.578 95.533,250.442 94.985 C 249.269 94.419,248.789 94.289,249.332 94.684 M93.754 96.460 C 92.278 98.139,89.502 102.262,89.848 102.262 C 89.954 102.262,90.779 101.155,91.684 99.803 C 92.588 98.451,93.687 96.947,94.127 96.460 C 94.566 95.973,94.837 95.575,94.729 95.575 C 94.621 95.575,94.182 95.973,93.754 96.460 M151.622 98.405 C 149.944 99.598,146.468 102.969,145.011 104.818 C 144.329 105.683,145.273 104.874,147.107 103.018 C 148.942 101.163,151.062 99.180,151.819 98.612 C 153.465 97.377,153.305 97.209,151.622 98.405 M255.261 98.033 C 256.121 98.853,261.294 102.009,261.000 101.534 C 260.863 101.312,259.383 100.307,257.711 99.300 C 256.039 98.293,254.936 97.723,255.261 98.033 M314.928 100.874 C 315.509 102.058,316.050 102.960,316.131 102.880 C 316.307 102.703,314.323 98.722,314.059 98.722 C 313.956 98.722,314.348 99.690,314.928 100.874 M262.734 102.778 C 262.734 102.875,263.383 103.450,264.177 104.056 C 264.972 104.662,265.497 104.957,265.345 104.711 C 265.034 104.208,262.734 102.505,262.734 102.778 M269.063 108.187 C 270.922 110.011,272.958 112.132,273.586 112.899 C 274.215 113.666,274.559 114.020,274.351 113.685 C 273.330 112.046,270.365 108.828,268.153 106.957 C 266.082 105.205,266.228 105.404,269.063 108.187 M85.183 109.231 C 84.409 110.468,83.776 111.662,83.777 111.885 C 83.778 112.109,84.151 111.672,84.605 110.914 C 85.060 110.157,85.782 108.963,86.209 108.260 C 86.637 107.557,86.897 106.981,86.788 106.981 C 86.679 106.981,85.957 107.993,85.183 109.231 M141.751 109.980 C 141.213 111.197,140.840 112.259,140.922 112.341 C 141.003 112.422,141.528 111.427,142.089 110.129 C 142.649 108.830,143.022 107.768,142.918 107.768 C 142.815 107.768,142.289 108.763,141.751 109.980 M80.764 117.823 C 80.213 119.026,79.831 120.080,79.914 120.164 C 79.998 120.247,80.533 119.263,81.102 117.975 C 81.671 116.688,82.053 115.634,81.951 115.634 C 81.849 115.634,81.315 116.619,80.764 117.823 M276.674 117.871 C 277.008 118.560,277.476 119.245,277.716 119.393 C 278.244 119.719,277.675 118.599,276.706 117.404 C 276.114 116.674,276.112 116.707,276.674 117.871 M314.642 118.965 C 314.097 120.126,313.790 120.990,313.960 120.885 C 314.430 120.594,315.894 117.589,315.756 117.198 C 315.689 117.009,315.188 117.804,314.642 118.965 M139.359 121.534 C 139.359 122.940,139.430 123.515,139.518 122.812 C 139.605 122.109,139.605 120.959,139.518 120.256 C 139.430 119.553,139.359 120.128,139.359 121.534 M278.794 121.007 C 279.993 122.750,284.772 126.647,285.710 126.647 C 285.921 126.647,285.292 126.139,284.312 125.518 C 283.333 124.896,281.498 123.348,280.235 122.076 C 278.897 120.729,278.296 120.283,278.794 121.007 M309.599 125.197 C 309.363 125.482,308.279 126.131,307.192 126.641 C 306.104 127.150,305.284 127.637,305.370 127.723 C 305.619 127.972,309.337 125.986,309.906 125.301 C 310.189 124.960,310.332 124.680,310.224 124.680 C 310.116 124.680,309.834 124.913,309.599 125.197 M77.380 125.736 C 77.280 125.913,77.093 126.588,76.964 127.237 C 76.730 128.411,76.732 128.410,77.322 127.093 C 77.837 125.945,77.883 124.846,77.380 125.736 M294.405 129.083 C 295.708 129.254,297.832 129.254,299.125 129.082 C 301.135 128.816,300.792 128.771,296.755 128.771 C 292.703 128.772,292.371 128.816,294.405 129.083 M75.741 130.805 C 75.596 131.381,75.554 131.929,75.647 132.021 C 75.739 132.114,75.933 131.718,76.078 131.142 C 76.223 130.566,76.265 130.018,76.173 129.925 C 76.080 129.833,75.886 130.228,75.741 130.805 M141.544 132.815 C 141.997 133.720,142.582 134.592,142.842 134.753 C 143.103 134.914,142.900 134.351,142.392 133.501 C 141.063 131.282,140.580 130.890,141.544 132.815 M145.100 137.027 C 145.407 137.399,146.027 137.899,146.477 138.139 C 147.222 138.536,147.246 138.514,146.738 137.899 C 146.432 137.528,145.812 137.027,145.362 136.787 C 144.617 136.390,144.593 136.412,145.100 137.027 M73.187 140.050 C 72.945 141.178,72.822 142.176,72.913 142.267 C 73.005 142.359,73.277 141.511,73.519 140.383 C 73.761 139.255,73.884 138.257,73.793 138.165 C 73.701 138.074,73.429 138.922,73.187 140.050 M148.673 139.489 C 148.673 139.751,154.612 142.471,154.792 142.291 C 154.872 142.211,153.528 141.505,151.805 140.722 C 150.082 139.940,148.673 139.385,148.673 139.489 M165.192 145.526 C 165.733 145.699,166.529 145.841,166.962 145.841 C 167.585 145.841,167.544 145.775,166.765 145.526 C 166.224 145.353,165.428 145.211,164.995 145.211 C 164.372 145.211,164.413 145.277,165.192 145.526 M184.169 148.550 C 184.548 148.649,185.167 148.649,185.546 148.550 C 185.924 148.451,185.615 148.371,184.857 148.371 C 184.100 148.371,183.791 148.451,184.169 148.550 M189.288 148.955 C 189.885 149.045,190.770 149.043,191.254 148.949 C 191.738 148.856,191.249 148.782,190.167 148.785 C 189.086 148.788,188.690 148.864,189.288 148.955 M197.050 149.465 C 201.916 149.771,213.413 149.945,213.143 149.709 C 213.053 149.630,208.378 149.479,202.753 149.373 C 196.750 149.260,194.395 149.298,197.050 149.465 M218.584 150.142 C 219.720 150.222,221.578 150.222,222.714 150.142 C 223.850 150.063,222.920 149.998,220.649 149.998 C 218.378 149.998,217.448 150.063,218.584 150.142 M248.771 152.606 C 249.420 152.771,250.482 152.907,251.131 152.907 C 252.123 152.908,252.060 152.857,250.737 152.583 C 248.745 152.171,247.135 152.190,248.771 152.606 M253.491 153.392 C 255.154 153.816,256.582 153.816,255.261 153.392 C 254.720 153.219,253.835 153.081,253.294 153.085 C 252.411 153.091,252.431 153.123,253.491 153.392 M266.667 156.735 C 267.424 157.027,268.309 157.266,268.633 157.266 C 268.958 157.266,268.604 157.027,267.847 156.735 C 267.089 156.444,266.205 156.205,265.880 156.205 C 265.556 156.205,265.910 156.444,266.667 156.735 M70.101 158.112 C 70.101 158.869,70.182 159.179,70.281 158.800 C 70.380 158.422,70.380 157.802,70.281 157.424 C 70.182 157.045,70.101 157.355,70.101 158.112 M114.095 158.800 C 114.334 159.179,114.999 159.826,115.574 160.239 C 116.401 160.834,116.337 160.691,115.262 159.551 C 113.771 157.968,113.433 157.751,114.095 158.800 M274.959 159.454 C 275.275 159.767,279.404 161.238,279.551 161.091 C 279.633 161.009,278.708 160.571,277.495 160.117 C 275.346 159.313,274.626 159.125,274.959 159.454 M69.480 163.119 C 69.342 164.583,69.254 167.198,69.284 168.928 C 69.326 171.323,69.417 170.717,69.664 166.394 C 70.006 160.410,69.906 158.616,69.480 163.119 M118.205 162.537 C 118.792 163.240,119.559 163.972,119.911 164.163 C 120.263 164.354,119.851 163.779,118.996 162.885 C 117.137 160.941,116.719 160.757,118.205 162.537 M283.612 162.971 C 284.138 163.418,287.512 165.233,287.512 165.070 C 287.512 164.829,284.144 162.832,283.739 162.832 C 283.579 162.832,283.522 162.894,283.612 162.971 M110.797 167.120 C 110.645 169.155,110.548 172.429,110.580 174.397 C 110.625 177.088,110.722 176.318,110.970 171.288 C 111.335 163.898,111.229 161.331,110.797 167.120 M123.107 166.495 C 123.107 166.603,123.992 167.433,125.074 168.338 C 126.155 169.244,127.040 169.896,127.040 169.788 C 127.040 169.680,126.155 168.851,125.074 167.945 C 123.992 167.039,123.107 166.387,123.107 166.495 M291.052 167.288 C 291.052 167.360,291.893 167.993,292.920 168.696 L 294.789 169.975 293.215 168.572 C 291.830 167.338,291.052 166.876,291.052 167.288 M128.195 170.720 C 129.317 171.671,133.769 174.327,133.946 174.150 C 134.012 174.083,132.530 173.102,130.652 171.968 C 128.774 170.835,127.668 170.273,128.195 170.720 M298.304 173.089 C 300.237 174.911,303.202 178.136,304.892 180.256 C 308.115 184.300,309.171 185.134,306.293 181.363 C 304.074 178.456,299.229 173.378,296.768 171.382 C 295.679 170.499,296.370 171.267,298.304 173.089 M134.513 174.433 C 134.513 174.696,139.281 177.074,139.457 176.898 C 139.536 176.819,138.456 176.190,137.057 175.500 C 135.658 174.810,134.513 174.330,134.513 174.433 M69.367 180.728 C 69.368 182.891,69.434 183.726,69.514 182.583 C 69.593 181.440,69.592 179.670,69.512 178.650 C 69.431 177.629,69.366 178.564,69.367 180.728 M111.044 180.728 C 111.045 182.242,111.116 182.813,111.201 181.997 C 111.287 181.181,111.285 179.942,111.198 179.244 C 111.111 178.546,111.042 179.213,111.044 180.728 M144.297 178.962 C 145.244 179.398,146.483 179.848,147.051 179.962 C 147.618 180.076,147.198 179.807,146.116 179.365 C 143.426 178.264,142.183 177.989,144.297 178.962 M156.342 182.705 C 157.207 182.990,158.269 183.221,158.702 183.219 C 159.135 183.216,158.604 182.968,157.522 182.667 C 155.061 181.982,154.230 182.009,156.342 182.705 M111.399 185.251 C 111.399 186.008,111.480 186.318,111.579 185.939 C 111.678 185.560,111.678 184.941,111.579 184.562 C 111.480 184.184,111.399 184.494,111.399 185.251 M69.729 186.627 C 69.732 187.709,69.808 188.105,69.899 187.507 C 69.989 186.909,69.987 186.024,69.893 185.540 C 69.800 185.057,69.726 185.546,69.729 186.627 M174.336 185.915 C 174.715 186.014,175.334 186.014,175.713 185.915 C 176.091 185.816,175.782 185.735,175.025 185.735 C 174.267 185.735,173.958 185.816,174.336 185.915 M179.154 186.436 C 181.161 186.762,185.908 186.941,185.611 186.680 C 185.521 186.601,183.589 186.442,181.318 186.327 C 178.533 186.186,177.828 186.222,179.154 186.436 M187.897 187.108 C 188.595 187.195,189.834 187.196,190.650 187.111 C 191.466 187.026,190.895 186.955,189.381 186.953 C 187.866 186.951,187.199 187.021,187.897 187.108 M210.718 187.117 C 212.502 187.189,215.423 187.189,217.207 187.117 C 218.992 187.044,217.532 186.984,213.963 186.984 C 210.393 186.984,208.933 187.044,210.718 187.117 M311.227 190.016 C 312.137 191.880,312.946 193.349,313.026 193.280 C 313.228 193.106,310.938 188.367,310.190 187.414 C 309.850 186.981,310.317 188.152,311.227 190.016 M223.500 187.488 C 223.879 187.587,224.499 187.587,224.877 187.488 C 225.256 187.389,224.946 187.309,224.189 187.309 C 223.432 187.309,223.122 187.389,223.500 187.488 M70.101 190.364 C 70.101 191.121,70.182 191.431,70.281 191.052 C 70.380 190.674,70.380 190.054,70.281 189.676 C 70.182 189.297,70.101 189.607,70.101 190.364 M244.838 190.364 C 245.487 190.529,246.460 190.664,247.001 190.664 C 247.878 190.664,247.857 190.632,246.804 190.364 C 246.155 190.199,245.182 190.064,244.641 190.064 C 243.764 190.064,243.785 190.096,244.838 190.364 M257.653 193.280 C 257.743 193.370,259.493 194.170,261.542 195.058 C 263.591 195.947,265.095 196.504,264.885 196.296 C 264.675 196.089,263.028 195.289,261.224 194.518 C 258.135 193.198,257.270 192.899,257.653 193.280 M314.121 196.264 C 314.570 198.035,315.489 200.199,315.226 198.863 C 315.102 198.238,314.748 197.176,314.437 196.504 C 314.012 195.583,313.934 195.524,314.121 196.264 M266.470 197.328 C 266.686 197.550,267.824 198.368,268.999 199.146 C 271.559 200.841,275.397 204.508,276.531 206.344 C 277.516 207.938,277.928 208.105,277.133 206.588 C 276.218 204.840,273.846 202.284,271.453 200.466 C 269.213 198.764,265.735 196.574,266.470 197.328 M114.694 201.573 C 115.018 203.019,115.243 203.333,115.235 202.327 C 115.232 201.912,115.049 201.308,114.830 200.983 C 114.538 200.552,114.502 200.712,114.694 201.573 M72.819 205.506 C 72.823 206.327,73.865 209.341,73.907 208.653 C 73.920 208.437,73.680 207.463,73.373 206.490 C 73.067 205.516,72.817 205.074,72.819 205.506 M117.742 210.029 C 118.040 211.134,120.467 216.341,120.615 216.193 C 120.696 216.112,120.047 214.559,119.173 212.743 C 118.298 210.926,117.655 209.705,117.742 210.029 M317.553 215.929 C 317.553 218.417,317.617 219.435,317.695 218.191 C 317.773 216.947,317.773 214.912,317.695 213.668 C 317.617 212.424,317.553 213.441,317.553 215.929 M76.911 218.781 C 77.058 219.267,77.340 219.839,77.538 220.050 C 77.736 220.261,77.698 219.863,77.455 219.165 C 76.957 217.736,76.497 217.412,76.911 218.781 M122.543 219.764 C 124.279 222.755,126.701 226.232,126.906 226.028 C 127.009 225.924,126.483 225.039,125.737 224.061 C 124.991 223.084,123.815 221.296,123.125 220.090 C 122.434 218.883,121.777 217.896,121.664 217.896 C 121.552 217.896,121.947 218.736,122.543 219.764 M78.691 222.812 C 78.691 223.029,78.944 223.648,79.253 224.189 C 79.562 224.730,79.815 224.995,79.815 224.779 C 79.815 224.562,79.562 223.943,79.253 223.402 C 78.944 222.861,78.691 222.596,78.691 222.812 M277.350 224.402 C 276.691 225.849,276.817 226.157,277.529 224.842 C 277.862 224.228,278.061 223.652,277.971 223.562 C 277.881 223.472,277.601 223.850,277.350 224.402 M79.843 225.537 C 79.843 225.986,82.999 232.193,83.458 232.645 C 83.809 232.991,80.379 225.819,79.994 225.402 C 79.911 225.311,79.843 225.372,79.843 225.537 M131.170 231.662 C 132.015 232.527,132.795 233.235,132.903 233.235 C 133.011 233.235,132.408 232.527,131.563 231.662 C 130.718 230.796,129.939 230.088,129.831 230.088 C 129.722 230.088,130.325 230.796,131.170 231.662 M272.250 232.547 C 269.860 235.548,263.739 241.506,260.669 243.819 C 258.271 245.625,257.524 246.499,259.685 244.970 C 264.292 241.711,275.779 230.088,274.393 230.088 C 274.291 230.088,273.327 231.195,272.250 232.547 M314.687 234.451 C 314.421 235.338,314.276 236.137,314.364 236.226 C 314.452 236.314,314.743 235.660,315.008 234.773 C 315.274 233.885,315.420 233.086,315.331 232.998 C 315.243 232.909,314.953 233.563,314.687 234.451 M84.366 234.415 C 84.701 235.064,85.064 235.595,85.173 235.595 C 85.281 235.595,85.095 235.064,84.759 234.415 C 84.424 233.766,84.060 233.235,83.952 233.235 C 83.844 233.235,84.030 233.766,84.366 234.415 M132.940 233.728 C 132.940 233.828,134.400 235.216,136.185 236.814 C 137.970 238.411,139.184 239.406,138.883 239.025 C 138.214 238.176,132.940 233.476,132.940 233.728 M87.300 239.382 C 87.792 240.276,88.621 241.515,89.144 242.136 C 89.666 242.756,89.376 242.125,88.499 240.732 C 86.619 237.745,86.040 237.094,87.300 239.382 M311.027 244.195 C 310.675 245.089,310.457 245.821,310.543 245.821 C 310.858 245.821,311.941 243.393,311.806 242.988 C 311.729 242.757,311.378 243.300,311.027 244.195 M145.133 243.995 C 145.133 244.200,149.293 246.930,151.607 248.245 C 154.014 249.612,153.098 248.896,148.756 246.017 C 145.658 243.962,145.133 243.669,145.133 243.995 M256.244 247.001 C 255.379 247.632,254.546 248.156,254.393 248.165 C 254.095 248.182,251.288 250.031,250.944 250.437 C 250.627 250.811,254.461 248.593,256.342 247.313 C 257.262 246.688,258.014 246.097,258.014 245.999 C 258.014 245.724,257.924 245.775,256.244 247.001 M158.112 251.721 C 159.735 252.565,161.239 253.255,161.455 253.255 C 161.672 253.255,160.521 252.565,158.899 251.721 C 157.276 250.877,155.772 250.186,155.556 250.186 C 155.339 250.186,156.490 250.877,158.112 251.721 M95.395 250.934 C 97.713 255.156,114.336 271.648,120.354 275.696 C 122.388 277.064,121.085 275.886,116.224 271.962 C 111.145 267.860,103.737 260.531,99.344 255.261 C 95.795 251.002,94.884 250.004,95.395 250.934 M246.608 252.507 C 244.553 253.567,243.007 254.443,243.174 254.454 C 243.592 254.482,250.541 250.972,250.541 250.734 C 250.541 250.466,250.745 250.374,246.608 252.507 M307.201 251.444 C 306.906 251.921,306.406 252.709,306.089 253.196 C 305.773 253.682,305.599 254.081,305.703 254.081 C 306.012 254.081,308.096 250.934,307.910 250.748 C 307.815 250.654,307.497 250.967,307.201 251.444 M163.618 254.277 C 164.159 254.586,164.779 254.839,164.995 254.839 C 165.211 254.839,164.946 254.586,164.405 254.277 C 163.864 253.968,163.245 253.715,163.029 253.715 C 162.812 253.715,163.078 253.968,163.618 254.277 M303.067 257.522 C 301.816 259.199,301.150 260.249,301.587 259.856 C 302.402 259.123,305.780 254.474,305.498 254.474 C 305.411 254.474,304.317 255.846,303.067 257.522 M167.552 255.737 C 167.660 255.843,168.364 256.138,169.116 256.393 C 169.868 256.647,170.311 256.686,170.099 256.479 C 169.888 256.272,169.184 255.977,168.535 255.823 C 167.886 255.669,167.443 255.630,167.552 255.737 M237.955 256.274 L 236.971 256.867 237.955 256.606 C 239.382 256.228,240.317 255.677,239.528 255.680 C 239.204 255.681,238.496 255.948,237.955 256.274 M231.858 258.407 C 231.363 258.620,231.290 258.745,231.662 258.745 C 231.986 258.745,232.606 258.593,233.038 258.407 C 233.534 258.194,233.607 258.069,233.235 258.069 C 232.911 258.069,232.291 258.221,231.858 258.407 M179.777 259.732 C 179.867 259.811,180.649 259.984,181.514 260.116 C 182.611 260.282,182.849 260.247,182.301 259.999 C 181.546 259.657,179.439 259.434,179.777 259.732 M224.975 260.177 C 224.002 260.459,223.471 260.704,223.795 260.721 C 224.120 260.738,225.270 260.506,226.352 260.205 C 227.434 259.904,227.965 259.659,227.532 259.661 C 227.099 259.663,225.949 259.895,224.975 260.177 M198.136 262.618 C 198.626 262.712,199.334 262.709,199.710 262.610 C 200.086 262.512,199.685 262.435,198.820 262.439 C 197.955 262.444,197.647 262.524,198.136 262.618 M208.756 262.618 C 209.245 262.712,209.953 262.709,210.329 262.610 C 210.705 262.512,210.305 262.435,209.440 262.439 C 208.574 262.444,208.267 262.524,208.756 262.618 M294.779 267.141 C 293.054 268.916,292.527 269.580,293.609 268.616 C 295.545 266.890,298.369 263.913,298.070 263.913 C 297.986 263.913,296.505 265.366,294.779 267.141 M289.651 271.878 L 288.496 273.156 289.774 272.001 C 290.477 271.366,291.052 270.791,291.052 270.723 C 291.052 270.419,290.728 270.687,289.651 271.878 M280.525 278.747 C 279.387 279.524,278.533 280.238,278.629 280.334 C 278.832 280.536,282.242 278.252,282.599 277.674 C 282.942 277.119,282.824 277.180,280.525 278.747 M123.500 277.838 C 123.500 277.946,124.297 278.583,125.270 279.253 C 126.244 279.922,127.040 280.382,127.040 280.274 C 127.040 280.166,126.244 279.529,125.270 278.859 C 124.297 278.190,123.500 277.730,123.500 277.838 M128.741 281.500 C 129.037 281.979,132.311 283.972,132.803 283.972 C 133.148 283.972,132.357 283.413,130.019 282.001 C 129.169 281.489,128.594 281.263,128.741 281.500 M272.468 283.804 C 270.998 284.602,271.087 284.934,272.566 284.169 C 273.215 283.834,273.746 283.475,273.746 283.372 C 273.746 283.119,273.704 283.134,272.468 283.804 M135.300 285.347 C 135.300 285.610,140.854 288.382,141.029 288.207 C 141.108 288.129,139.851 287.411,138.236 286.612 C 136.621 285.813,135.300 285.244,135.300 285.347 M267.060 286.726 C 265.438 287.570,264.218 288.269,264.351 288.279 C 264.837 288.319,269.763 285.945,270.004 285.555 C 270.340 285.012,270.404 284.987,267.060 286.726 M261.357 289.479 C 260.492 289.879,260.014 290.220,260.295 290.236 C 260.854 290.268,263.127 289.179,263.127 288.879 C 263.127 288.647,263.232 288.611,261.357 289.479 M144.227 289.762 C 145.156 290.225,145.526 290.708,145.639 291.605 L 145.793 292.822 145.856 291.554 C 145.916 290.359,144.499 289.014,143.284 289.111 C 143.111 289.125,143.536 289.418,144.227 289.762 M145.967 294.199 C 145.960 294.523,146.198 295.320,146.495 295.969 C 147.191 297.488,147.201 296.781,146.509 294.985 C 146.218 294.228,145.974 293.874,145.967 294.199 M254.081 296.885 C 254.081 297.137,253.423 298.096,252.620 299.016 C 251.234 300.603,251.225 300.628,252.457 299.508 C 253.884 298.211,254.664 297.010,254.309 296.656 C 254.183 296.530,254.081 296.633,254.081 296.885 M249.361 301.278 C 248.591 301.700,248.269 302.039,248.629 302.048 C 248.984 302.057,249.692 301.717,250.202 301.291 C 251.369 300.319,251.120 300.315,249.361 301.278 M154.671 302.351 C 155.482 302.436,156.809 302.436,157.620 302.351 C 158.432 302.267,157.768 302.197,156.146 302.197 C 154.523 302.197,153.859 302.267,154.671 302.351 M231.587 302.359 C 234.683 302.426,239.639 302.426,242.600 302.359 C 245.561 302.292,243.029 302.238,236.971 302.238 C 230.914 302.238,228.492 302.293,231.587 302.359 M179.843 306.686 C 191.470 306.744,210.497 306.744,222.124 306.686 C 233.751 306.628,224.238 306.581,200.983 306.581 C 177.729 306.581,168.215 306.628,179.843 306.686 M247.659 309.009 C 248.345 309.624,249.274 310.747,249.722 311.504 C 250.171 312.262,250.539 312.725,250.539 312.534 C 250.543 311.763,248.835 309.501,247.662 308.721 L 246.411 307.890 247.659 309.009 M154.103 309.046 C 152.905 310.441,152.914 310.880,154.118 309.759 C 154.801 309.124,155.359 308.549,155.359 308.481 C 155.359 308.114,154.616 308.449,154.103 309.046 M249.555 322.376 C 249.140 323.147,248.174 324.309,247.409 324.958 C 246.644 325.607,246.372 325.959,246.804 325.741 C 248.104 325.083,250.909 321.574,250.479 321.144 C 250.386 321.051,249.970 321.606,249.555 322.376 M152.606 322.870 C 152.606 323.562,155.506 326.451,156.198 326.448 C 156.493 326.446,156.205 326.098,155.556 325.673 C 154.907 325.248,153.977 324.325,153.491 323.622 C 153.004 322.918,152.606 322.580,152.606 322.870 M164.110 331.952 C 163.407 332.381,162.832 332.820,162.832 332.928 C 162.832 333.037,163.407 332.774,164.110 332.346 C 165.898 331.256,235.497 331.107,237.776 332.188 C 239.212 332.870,242.675 336.354,242.675 337.119 C 242.675 337.380,242.783 337.486,242.916 337.353 C 243.657 336.612,239.644 332.430,237.360 331.562 C 235.081 330.695,165.564 331.066,164.110 331.952 M243.574 341.200 C 243.577 342.281,243.653 342.677,243.743 342.079 C 243.834 341.481,243.831 340.596,243.738 340.113 C 243.645 339.629,243.571 340.118,243.574 341.200 M158.623 341.790 C 158.623 342.979,158.697 343.466,158.787 342.871 C 158.877 342.276,158.877 341.303,158.787 340.708 C 158.697 340.113,158.623 340.600,158.623 341.790 M159.294 346.345 C 159.295 346.787,160.780 349.263,161.043 349.263 C 161.147 349.263,160.852 348.599,160.388 347.788 C 159.347 345.971,159.292 345.897,159.294 346.345 M241.294 347.827 C 240.643 348.706,239.346 350.008,238.412 350.720 C 237.478 351.433,236.915 352.016,237.161 352.016 C 237.706 352.016,241.802 348.191,242.347 347.173 C 243.052 345.856,242.502 346.198,241.294 347.827 M163.170 351.206 C 163.681 351.651,164.286 352.016,164.514 352.016 C 164.998 352.016,164.975 351.996,163.422 351.087 L 162.242 350.396 163.170 351.206 M176.591 353.472 C 177.119 354.593,180.789 358.792,181.644 359.254 C 182.005 359.449,181.236 358.476,179.934 357.091 C 178.632 355.706,177.255 354.130,176.874 353.589 C 176.318 352.798,176.262 352.776,176.591 353.472 M222.374 357.012 C 221.541 358.030,221.064 358.735,221.315 358.580 C 221.850 358.249,224.341 355.162,224.073 355.162 C 223.972 355.162,223.208 355.995,222.374 357.012 M184.857 361.274 C 184.857 361.559,188.834 363.474,189.160 363.346 C 189.329 363.279,188.430 362.748,187.162 362.165 C 185.895 361.582,184.857 361.181,184.857 361.274 M215.536 362.045 C 214.562 362.566,214.011 363.001,214.310 363.011 C 214.847 363.028,217.502 361.544,217.502 361.227 C 217.502 360.993,217.494 360.997,215.536 362.045 M199.312 365.285 C 200.447 365.365,202.306 365.365,203.441 365.285 C 204.577 365.206,203.648 365.141,201.377 365.141 C 199.105 365.141,198.176 365.206,199.312 365.285 \" stroke=\"none\" fill=\"#fc7b8c\" fill-rule=\"evenodd\"><\/path><path id=\"path3\" d=\"M189.863 0.284 C 190.562 0.371,191.801 0.372,192.617 0.287 C 193.433 0.202,192.861 0.131,191.347 0.129 C 189.833 0.127,189.165 0.197,189.863 0.284 M207.169 0.284 C 207.867 0.371,209.106 0.372,209.922 0.287 C 210.738 0.202,210.167 0.131,208.653 0.129 C 207.139 0.127,206.471 0.197,207.169 0.284 M183.190 0.671 C 183.680 0.766,184.388 0.762,184.764 0.664 C 185.140 0.565,184.739 0.488,183.874 0.493 C 183.009 0.497,182.701 0.577,183.190 0.671 M215.442 0.671 C 215.931 0.766,216.639 0.762,217.015 0.664 C 217.391 0.565,216.991 0.488,216.126 0.493 C 215.261 0.497,214.953 0.577,215.442 0.671 M167.945 2.360 C 167.421 2.699,167.421 2.741,167.945 2.741 C 168.269 2.741,168.800 2.570,169.125 2.360 C 169.649 2.021,169.649 1.979,169.125 1.979 C 168.800 1.979,168.269 2.150,167.945 2.360 M231.072 2.360 C 231.205 2.576,231.580 2.753,231.905 2.753 C 232.229 2.753,232.385 2.576,232.252 2.360 C 232.118 2.144,231.743 1.967,231.419 1.967 C 231.094 1.967,230.938 2.144,231.072 2.360 M162.635 3.147 C 161.938 3.446,161.972 3.488,162.930 3.512 C 163.525 3.527,164.012 3.363,164.012 3.147 C 164.012 2.685,163.709 2.685,162.635 3.147 M236.382 3.147 C 236.382 3.363,236.780 3.537,237.266 3.534 C 237.982 3.529,238.039 3.455,237.561 3.147 C 236.799 2.654,236.382 2.654,236.382 3.147 M253.687 7.134 C 253.687 7.321,253.938 7.473,254.245 7.473 C 254.552 7.473,255.112 7.592,255.490 7.736 C 255.922 7.902,256.082 7.847,255.921 7.587 C 255.599 7.066,253.687 6.678,253.687 7.134 M132.842 10.772 C 132.247 10.988,131.760 11.326,131.760 11.524 C 131.760 11.722,132.042 11.775,132.387 11.643 C 132.731 11.511,133.439 11.296,133.960 11.165 C 134.946 10.918,135.271 10.349,134.415 10.368 C 134.145 10.374,133.437 10.556,132.842 10.772 M124.067 14.388 C 123.369 14.957,123.365 14.991,124.024 14.781 C 124.421 14.656,124.907 14.553,125.106 14.553 C 125.305 14.553,125.467 14.376,125.467 14.159 C 125.467 13.590,124.942 13.676,124.067 14.388 M275.100 14.368 C 275.520 14.686,276.051 14.940,276.280 14.933 C 276.509 14.927,276.353 14.661,275.933 14.343 C 275.513 14.026,274.982 13.772,274.753 13.778 C 274.524 13.785,274.680 14.051,275.100 14.368 M283.972 18.088 C 283.972 18.264,284.503 18.594,285.152 18.820 C 285.801 19.046,286.332 19.102,286.332 18.945 C 286.332 18.787,285.801 18.458,285.152 18.213 C 284.503 17.968,283.972 17.912,283.972 18.088 M114.356 18.390 C 113.977 18.475,113.668 18.707,113.668 18.908 C 113.668 19.369,114.094 19.364,114.836 18.894 C 115.543 18.448,115.290 18.183,114.356 18.390 M106.883 22.089 C 106.288 22.307,105.801 22.643,105.801 22.837 C 105.801 23.190,107.637 22.549,108.338 21.951 C 108.831 21.531,108.264 21.585,106.883 22.089 M292.232 21.971 C 292.232 22.148,292.675 22.494,293.215 22.741 C 293.756 22.987,294.199 23.044,294.199 22.867 C 294.199 22.690,293.756 22.344,293.215 22.097 C 292.675 21.851,292.232 21.794,292.232 21.971 M101.278 25.199 C 100.629 25.614,99.921 26.020,99.705 26.099 C 99.489 26.179,99.408 26.350,99.526 26.479 C 99.643 26.609,100.528 26.191,101.492 25.552 C 102.456 24.912,103.068 24.401,102.852 24.416 C 102.635 24.431,101.927 24.783,101.278 25.199 M299.312 25.979 C 300.354 26.689,302.065 27.558,302.065 27.377 C 302.065 27.124,299.478 25.564,299.069 25.571 C 298.878 25.575,298.987 25.758,299.312 25.979 M304.031 28.459 C 304.031 28.755,307.178 30.681,307.184 30.389 C 307.187 30.224,307.362 30.354,307.571 30.678 C 307.781 31.003,307.955 31.066,307.959 30.818 C 307.962 30.570,307.080 29.905,305.998 29.339 C 304.916 28.774,304.031 28.378,304.031 28.459 M93.684 29.484 C 92.969 29.884,92.544 30.310,92.741 30.431 C 92.937 30.553,93.690 30.216,94.413 29.682 C 95.950 28.548,95.552 28.440,93.684 29.484 M87.043 34.045 C 86.316 34.709,86.207 34.920,86.726 34.664 C 87.980 34.045,89.129 33.065,88.616 33.051 C 88.357 33.044,87.650 33.492,87.043 34.045 M311.701 33.670 C 313.206 34.830,314.115 35.101,312.957 34.045 C 312.350 33.492,311.643 33.044,311.384 33.051 C 311.126 33.058,311.268 33.336,311.701 33.670 M83.088 36.623 C 82.384 37.074,81.809 37.633,81.809 37.865 C 81.809 38.098,82.296 37.862,82.891 37.341 C 83.486 36.820,84.141 36.258,84.346 36.092 C 85.067 35.512,84.353 35.813,83.088 36.623 M316.618 36.890 C 317.375 37.542,318.082 37.989,318.190 37.884 C 318.402 37.678,317.291 36.767,316.028 36.113 C 315.595 35.889,315.860 36.238,316.618 36.890 M318.645 38.138 C 318.727 38.384,319.411 38.947,320.164 39.389 C 320.917 39.831,321.180 39.907,320.747 39.558 C 320.315 39.209,319.631 38.646,319.228 38.307 C 318.825 37.968,318.563 37.892,318.645 38.138 M78.128 40.339 C 77.077 41.083,76.458 41.685,76.752 41.676 C 77.046 41.668,77.994 41.052,78.859 40.306 C 80.848 38.592,80.580 38.604,78.128 40.339 M321.731 40.681 C 321.731 40.775,322.232 41.208,322.845 41.645 C 323.688 42.245,323.959 42.303,323.959 41.885 C 323.959 41.581,323.832 41.411,323.676 41.508 C 323.520 41.604,323.174 41.419,322.907 41.097 C 322.454 40.551,321.731 40.296,321.731 40.681 M74.533 43.265 C 73.716 43.913,72.902 44.444,72.723 44.444 C 72.544 44.444,72.190 44.833,71.936 45.307 C 71.572 45.987,71.829 45.882,73.145 44.816 C 74.065 44.071,75.195 43.155,75.658 42.782 C 76.121 42.408,76.391 42.098,76.259 42.093 C 76.126 42.088,75.350 42.616,74.533 43.265 M326.057 44.060 C 326.057 44.285,326.367 44.585,326.745 44.727 C 327.124 44.869,327.628 45.245,327.865 45.561 C 328.103 45.878,328.398 45.974,328.521 45.775 C 328.644 45.575,328.140 45.016,327.401 44.531 C 326.662 44.047,326.057 43.835,326.057 44.060 M180.138 44.458 C 179.503 44.669,179.921 44.706,181.318 44.562 C 182.507 44.439,183.555 44.273,183.645 44.195 C 183.960 43.919,181.112 44.132,180.138 44.458 M228.548 44.193 C 228.638 44.271,229.508 44.440,230.482 44.569 C 231.664 44.725,231.990 44.687,231.465 44.455 C 230.714 44.122,228.206 43.897,228.548 44.193 M331.563 48.574 C 332.071 49.115,332.664 49.558,332.880 49.558 C 333.097 49.558,332.858 49.115,332.350 48.574 C 331.842 48.033,331.249 47.591,331.033 47.591 C 330.817 47.591,331.055 48.033,331.563 48.574 M68.001 48.476 C 66.602 49.650,66.241 50.518,67.552 49.559 C 68.255 49.044,68.830 48.479,68.830 48.304 C 68.830 47.870,68.687 47.900,68.001 48.476 M63.738 52.126 C 63.208 52.647,62.863 53.161,62.970 53.268 C 63.161 53.460,65.290 51.664,65.290 51.312 C 65.290 50.897,64.639 51.238,63.738 52.126 M335.467 52.061 C 335.991 52.631,336.588 53.097,336.793 53.097 C 337.321 53.097,336.310 51.957,335.332 51.449 C 334.601 51.070,334.616 51.136,335.467 52.061 M338.643 54.794 C 338.643 54.861,339.218 55.437,339.921 56.072 L 341.200 57.227 340.044 55.949 C 338.968 54.757,338.643 54.490,338.643 54.794 M342.183 58.084 C 342.183 58.285,342.802 59.050,343.559 59.784 C 344.317 60.518,344.936 61.029,344.936 60.921 C 344.936 60.813,344.317 60.048,343.559 59.221 C 342.802 58.395,342.183 57.883,342.183 58.084 M268.437 58.808 C 268.869 59.160,269.577 59.622,270.010 59.834 L 270.796 60.220 270.010 59.580 C 269.577 59.228,268.869 58.766,268.437 58.553 L 267.650 58.167 268.437 58.808 M51.958 63.927 C 50.829 65.213,50.537 65.683,50.868 65.683 C 50.940 65.683,51.568 64.975,52.263 64.110 C 53.827 62.165,53.616 62.038,51.958 63.927 M274.959 62.664 C 275.049 62.734,275.742 63.191,276.500 63.680 L 277.876 64.568 276.696 63.555 C 276.047 62.997,275.354 62.540,275.156 62.539 C 274.957 62.538,274.869 62.594,274.959 62.664 M347.894 64.208 C 348.738 65.236,349.492 66.077,349.569 66.077 C 349.851 66.077,348.142 63.891,347.263 63.127 C 346.765 62.694,347.049 63.181,347.894 64.208 M350.442 67.055 C 350.767 67.486,351.455 68.282,351.973 68.825 L 352.913 69.813 352.089 68.598 C 351.636 67.930,350.948 67.134,350.559 66.828 C 349.900 66.310,349.892 66.326,350.442 67.055 M48.718 67.549 C 47.368 69.179,47.166 69.713,48.354 68.511 C 49.062 67.795,49.562 67.131,49.466 67.034 C 49.369 66.937,49.033 67.169,48.718 67.549 M119.174 70.830 L 117.404 72.434 119.272 70.978 C 120.910 69.701,121.396 69.220,121.042 69.224 C 120.988 69.225,120.147 69.947,119.174 70.830 M45.224 71.399 C 44.526 72.705,44.961 73.038,45.763 71.813 C 46.115 71.276,46.254 70.746,46.073 70.634 C 45.891 70.522,45.510 70.866,45.224 71.399 M354.006 71.508 C 354.534 72.174,355.105 72.729,355.274 72.741 C 355.845 72.781,354.760 71.213,353.899 70.752 C 353.087 70.317,353.092 70.353,354.006 71.508 M290.265 73.269 C 290.265 73.371,291.276 74.316,292.511 75.370 C 293.746 76.424,294.631 77.081,294.476 76.830 C 294.139 76.281,290.265 73.005,290.265 73.269 M41.832 76.008 C 40.751 77.360,39.555 78.997,39.175 79.646 C 38.496 80.806,38.497 80.809,39.203 79.852 C 39.598 79.316,40.376 78.343,40.931 77.689 C 42.409 75.948,44.171 73.550,43.972 73.550 C 43.877 73.550,42.914 74.656,41.832 76.008 M356.551 74.336 C 357.028 75.171,360.777 79.843,360.969 79.843 C 361.208 79.843,358.272 75.906,357.172 74.752 C 356.645 74.199,356.365 74.012,356.551 74.336 M296.165 78.466 C 296.899 79.223,297.588 79.843,297.696 79.843 C 297.804 79.843,297.292 79.223,296.559 78.466 C 295.825 77.709,295.136 77.089,295.028 77.089 C 294.919 77.089,295.431 77.709,296.165 78.466 M362.279 81.908 C 363.947 84.081,364.521 84.641,363.691 83.284 C 362.181 80.818,361.739 80.236,361.377 80.236 C 361.167 80.236,361.573 80.988,362.279 81.908 M37.014 82.142 C 35.850 83.778,35.980 84.079,37.217 82.609 C 37.785 81.935,38.158 81.291,38.047 81.180 C 37.935 81.069,37.471 81.502,37.014 82.142 M197.837 84.960 C 196.214 85.099,198.250 85.132,202.360 85.031 C 206.470 84.931,209.907 84.785,209.997 84.706 C 210.249 84.485,201.155 84.675,197.837 84.960 M210.456 85.098 C 210.546 85.176,212.566 85.331,214.946 85.443 C 217.709 85.573,218.633 85.532,217.502 85.330 C 215.733 85.014,210.146 84.830,210.456 85.098 M192.237 85.627 C 192.726 85.721,193.434 85.718,193.810 85.619 C 194.186 85.521,193.786 85.444,192.920 85.448 C 192.055 85.453,191.747 85.533,192.237 85.627 M34.156 86.431 C 32.920 87.905,32.031 89.567,32.879 88.817 C 33.614 88.167,35.202 85.742,34.891 85.742 C 34.805 85.742,34.474 86.052,34.156 86.431 M365.480 86.529 C 365.750 86.962,366.112 87.316,366.283 87.316 C 366.455 87.316,366.407 86.962,366.175 86.529 C 365.943 86.096,365.582 85.742,365.371 85.742 C 365.159 85.742,365.208 86.093,365.480 86.529 M172.075 89.465 C 170.524 90.175,170.874 90.187,173.058 89.499 C 174.031 89.192,174.474 88.938,174.041 88.933 C 173.609 88.928,172.724 89.167,172.075 89.465 M307.571 89.799 C 307.571 89.866,308.147 90.441,308.850 91.077 L 310.128 92.232 308.973 90.954 C 307.896 89.762,307.571 89.495,307.571 89.799 M29.537 93.314 C 28.690 94.901,28.687 94.936,29.476 94.002 C 30.613 92.658,31.167 91.642,30.765 91.642 C 30.581 91.642,30.028 92.394,29.537 93.314 M369.963 93.223 C 370.539 94.093,371.085 94.729,371.177 94.637 C 371.403 94.411,369.596 91.653,369.218 91.647 C 369.052 91.644,369.388 92.354,369.963 93.223 M244.674 92.575 C 245.079 92.937,247.394 94.002,247.394 93.826 C 247.394 93.599,245.214 92.429,244.792 92.429 C 244.637 92.429,244.584 92.495,244.674 92.575 M94.395 95.182 C 93.490 96.264,92.837 97.148,92.945 97.148 C 93.054 97.148,93.883 96.264,94.789 95.182 C 95.694 94.100,96.347 93.215,96.238 93.215 C 96.130 93.215,95.301 94.100,94.395 95.182 M252.507 96.774 C 253.872 97.700,254.649 97.970,253.687 97.184 C 253.147 96.741,252.527 96.378,252.311 96.377 C 252.094 96.375,252.183 96.554,252.507 96.774 M27.007 97.573 C 26.622 98.022,26.364 98.560,26.433 98.767 C 26.502 98.975,26.876 98.607,27.264 97.950 C 28.087 96.557,27.994 96.420,27.007 97.573 M373.438 99.090 C 374.309 100.774,374.962 100.995,374.172 99.339 C 373.804 98.567,373.354 97.935,373.172 97.935 C 372.990 97.935,373.110 98.455,373.438 99.090 M25.232 100.517 C 24.970 101.093,24.942 101.421,25.167 101.281 C 25.744 100.925,26.438 99.508,26.036 99.508 C 25.846 99.508,25.485 99.962,25.232 100.517 M148.068 101.967 L 146.116 104.031 148.181 102.080 C 149.317 101.006,150.246 100.077,150.246 100.015 C 150.246 99.721,149.881 100.048,148.068 101.967 M316.272 103.057 C 316.867 104.818,317.203 105.160,316.842 103.638 C 316.688 102.989,316.393 102.285,316.186 102.074 C 315.979 101.862,316.018 102.305,316.272 103.057 M376.866 105.211 C 377.112 105.752,377.459 106.195,377.636 106.195 C 377.813 106.195,377.756 105.752,377.510 105.211 C 377.263 104.671,376.917 104.228,376.740 104.228 C 376.563 104.228,376.620 104.671,376.866 105.211 M21.920 106.588 C 21.580 107.453,21.373 108.161,21.459 108.161 C 21.546 108.161,21.977 107.453,22.419 106.588 C 22.860 105.723,23.068 105.015,22.880 105.015 C 22.692 105.015,22.260 105.723,21.920 106.588 M86.567 106.415 C 86.113 107.185,85.920 107.705,86.138 107.570 C 86.564 107.307,87.841 105.015,87.561 105.015 C 87.469 105.015,87.022 105.645,86.567 106.415 M144.228 106.293 C 143.160 107.736,142.441 108.979,143.032 108.358 C 143.762 107.591,145.563 105.015,145.369 105.015 C 145.261 105.015,144.747 105.590,144.228 106.293 M270.010 109.341 C 271.075 110.423,272.035 111.308,272.143 111.308 C 272.252 111.308,271.468 110.423,270.403 109.341 C 269.338 108.260,268.378 107.375,268.269 107.375 C 268.161 107.375,268.944 108.260,270.010 109.341 M381.099 113.625 C 381.553 114.514,381.999 115.241,382.092 115.241 C 382.476 115.241,381.213 112.322,380.764 112.172 C 380.461 112.071,380.589 112.624,381.099 113.625 M18.213 114.061 C 17.968 114.710,17.912 115.241,18.088 115.241 C 18.264 115.241,18.594 114.710,18.820 114.061 C 19.046 113.412,19.102 112.881,18.945 112.881 C 18.787 112.881,18.458 113.412,18.213 114.061 M316.460 114.494 C 316.316 115.395,316.275 116.209,316.369 116.303 C 316.463 116.397,316.663 115.742,316.814 114.848 C 316.965 113.953,317.006 113.139,316.906 113.038 C 316.805 112.937,316.604 113.592,316.460 114.494 M139.872 116.863 C 139.549 118.479,139.607 125.869,139.949 126.729 C 140.096 127.098,140.216 124.753,140.216 121.517 C 140.216 115.043,140.222 115.116,139.872 116.863 M278.386 120.944 C 279.176 122.116,280.679 123.584,282.223 124.692 C 282.667 125.010,282.401 124.705,281.633 124.013 C 280.865 123.322,279.641 122.083,278.914 121.260 C 277.939 120.157,277.800 120.074,278.386 120.944 M14.945 121.339 C 14.716 121.941,14.435 122.585,14.321 122.771 C 14.206 122.956,14.283 123.107,14.491 123.107 C 14.908 123.107,15.848 120.731,15.549 120.432 C 15.446 120.329,15.174 120.737,14.945 121.339 M384.467 121.042 C 384.623 121.421,384.839 122.040,384.948 122.419 C 385.057 122.797,385.286 123.107,385.456 123.107 C 385.627 123.107,385.577 122.488,385.345 121.731 C 385.112 120.973,384.756 120.354,384.553 120.354 C 384.350 120.354,384.311 120.664,384.467 121.042 M78.727 121.747 C 78.068 123.194,78.193 123.502,78.906 122.187 C 79.239 121.573,79.437 120.997,79.347 120.908 C 79.257 120.818,78.978 121.196,78.727 121.747 M306.391 127.434 C 305.634 127.848,305.156 128.195,305.329 128.204 C 305.746 128.226,307.965 127.072,307.965 126.834 C 307.965 126.576,307.942 126.585,306.391 127.434 M388.498 131.563 C 388.601 132.104,388.836 132.547,389.021 132.547 C 389.205 132.547,389.254 132.812,389.129 133.137 C 389.005 133.461,389.083 133.727,389.304 133.727 C 389.719 133.727,389.707 133.476,389.203 131.662 C 388.827 130.310,388.243 130.229,388.498 131.563 M10.899 131.760 C 10.786 132.193,10.833 132.547,11.004 132.547 C 11.175 132.547,11.407 132.193,11.520 131.760 C 11.633 131.327,11.586 130.973,11.415 130.973 C 11.244 130.973,11.012 131.327,10.899 131.760 M148.673 139.016 C 148.673 139.124,149.204 139.487,149.853 139.823 C 150.501 140.159,151.032 140.345,151.032 140.237 C 151.032 140.128,150.501 139.765,149.853 139.430 C 149.204 139.094,148.673 138.908,148.673 139.016 M392.378 143.854 C 392.663 145.042,392.836 145.349,393.082 145.100 C 393.371 144.807,392.839 142.773,392.474 142.773 C 392.278 142.773,392.236 143.260,392.378 143.854 M176.111 147.377 C 176.600 147.472,177.308 147.468,177.684 147.370 C 178.060 147.271,177.660 147.194,176.794 147.198 C 175.929 147.203,175.622 147.283,176.111 147.377 M178.761 147.692 C 179.660 148.005,182.034 148.091,181.857 147.804 C 181.751 147.633,180.923 147.507,180.016 147.524 C 179.110 147.541,178.545 147.616,178.761 147.692 M236.676 150.917 C 237.163 151.010,237.960 151.010,238.446 150.917 C 238.933 150.823,238.535 150.746,237.561 150.746 C 236.588 150.746,236.190 150.823,236.676 150.917 M240.413 151.314 C 241.008 151.404,241.981 151.404,242.576 151.314 C 243.171 151.224,242.684 151.150,241.495 151.150 C 240.305 151.150,239.818 151.224,240.413 151.314 M261.357 154.966 C 261.790 155.151,262.498 155.298,262.930 155.292 C 263.563 155.283,263.524 155.219,262.734 154.966 C 261.389 154.535,260.355 154.535,261.357 154.966 M396.073 159.390 C 396.070 159.985,396.244 160.472,396.460 160.472 C 396.957 160.472,396.957 159.668,396.460 158.899 C 396.163 158.439,396.078 158.548,396.073 159.390 M396.466 161.554 C 396.463 162.040,396.637 162.439,396.853 162.439 C 397.346 162.439,397.346 162.021,396.853 161.259 C 396.545 160.782,396.471 160.838,396.466 161.554 M3.027 161.807 C 2.866 162.216,2.827 162.644,2.941 162.757 C 3.299 163.116,3.615 162.528,3.465 161.781 C 3.327 161.097,3.306 161.098,3.027 161.807 M2.643 164.142 C 2.205 165.257,2.276 165.826,2.790 165.312 C 3.027 165.076,3.154 164.553,3.073 164.152 C 2.932 163.448,2.917 163.447,2.643 164.142 M2.253 167.003 C 2.096 167.160,1.967 167.561,1.967 167.892 C 1.967 168.335,2.083 168.379,2.404 168.058 C 2.645 167.817,2.774 167.417,2.691 167.168 C 2.608 166.919,2.411 166.845,2.253 167.003 M293.553 168.642 C 293.864 169.145,296.165 170.848,296.165 170.575 C 296.165 170.478,295.515 169.903,294.721 169.297 C 293.927 168.691,293.402 168.396,293.553 168.642 M300.492 174.828 C 302.321 176.667,303.906 178.171,304.014 178.171 C 304.122 178.171,302.714 176.667,300.885 174.828 C 299.056 172.989,297.471 171.485,297.362 171.485 C 297.254 171.485,298.662 172.989,300.492 174.828 M138.227 176.773 C 138.647 177.109,139.266 177.370,139.603 177.353 C 140.133 177.327,140.136 177.293,139.626 177.104 C 139.302 176.983,138.682 176.722,138.250 176.523 C 137.476 176.167,137.475 176.171,138.227 176.773 M398.911 178.564 C 398.911 179.322,398.992 179.631,399.091 179.253 C 399.190 178.874,399.190 178.255,399.091 177.876 C 398.992 177.498,398.911 177.807,398.911 178.564 M0.878 178.958 C 0.878 179.715,0.959 180.025,1.058 179.646 C 1.157 179.267,1.157 178.648,1.058 178.269 C 0.959 177.891,0.878 178.201,0.878 178.958 M149.837 181.130 C 150.802 181.431,151.651 181.616,151.725 181.543 C 151.926 181.341,149.436 180.527,148.712 180.557 C 148.366 180.572,148.872 180.830,149.837 181.130 M399.320 184.071 C 399.320 185.044,399.397 185.442,399.491 184.956 C 399.585 184.469,399.585 183.673,399.491 183.186 C 399.397 182.699,399.320 183.097,399.320 184.071 M0.506 185.054 C 0.509 186.136,0.585 186.531,0.676 185.934 C 0.766 185.336,0.764 184.451,0.670 183.967 C 0.577 183.483,0.503 183.972,0.506 185.054 M165.388 184.857 C 167.052 185.281,168.480 185.281,167.158 184.857 C 166.618 184.684,165.733 184.546,165.192 184.550 C 164.309 184.556,164.329 184.588,165.388 184.857 M227.761 188.149 C 227.852 188.229,229.253 188.394,230.875 188.514 C 233.062 188.677,233.418 188.645,232.252 188.391 C 230.678 188.049,227.453 187.875,227.761 188.149 M112.180 189.381 C 112.184 189.813,112.323 190.698,112.488 191.347 C 112.757 192.407,112.789 192.427,112.795 191.544 C 112.799 191.003,112.661 190.118,112.488 189.577 C 112.241 188.807,112.174 188.764,112.180 189.381 M399.760 196.460 C 399.760 199.272,399.823 200.371,399.899 198.902 C 399.975 197.433,399.974 195.132,399.897 193.789 C 399.821 192.446,399.759 193.648,399.760 196.460 M254.065 192.536 C 255.030 192.837,255.880 193.022,255.953 192.949 C 256.154 192.748,253.664 191.933,252.940 191.963 C 252.594 191.978,253.100 192.236,254.065 192.536 M0.112 196.460 C 0.115 197.542,0.192 197.938,0.282 197.340 C 0.373 196.742,0.370 195.857,0.277 195.373 C 0.184 194.889,0.110 195.379,0.112 196.460 M269.420 199.823 C 270.784 200.749,271.561 201.018,270.600 200.232 C 270.059 199.789,269.440 199.426,269.223 199.425 C 269.007 199.423,269.095 199.602,269.420 199.823 M116.072 205.113 C 116.080 205.329,116.426 206.214,116.842 207.080 C 117.259 207.945,117.489 208.210,117.354 207.670 C 117.077 206.556,116.052 204.511,116.072 205.113 M0.506 207.866 C 0.509 208.948,0.585 209.344,0.676 208.746 C 0.766 208.148,0.764 207.263,0.670 206.779 C 0.577 206.296,0.503 206.785,0.506 207.866 M399.320 208.850 C 399.320 209.823,399.397 210.221,399.491 209.735 C 399.585 209.248,399.585 208.451,399.491 207.965 C 399.397 207.478,399.320 207.876,399.320 208.850 M279.056 215.733 C 279.056 218.029,279.171 219.500,279.312 219.001 C 279.453 218.501,279.568 217.030,279.568 215.733 C 279.568 214.435,279.453 212.964,279.312 212.464 C 279.171 211.965,279.056 213.436,279.056 215.733 M74.398 212.193 C 74.397 212.409,74.635 213.206,74.926 213.963 C 75.218 214.720,75.462 215.074,75.469 214.749 C 75.475 214.425,75.238 213.628,74.940 212.979 C 74.643 212.330,74.399 211.976,74.398 212.193 M0.878 213.963 C 0.878 214.720,0.959 215.029,1.058 214.651 C 1.157 214.272,1.157 213.653,1.058 213.274 C 0.959 212.896,0.878 213.206,0.878 213.963 M124.167 221.859 C 124.557 222.525,125.128 223.277,125.436 223.531 C 125.743 223.785,125.498 223.240,124.892 222.321 C 123.619 220.390,123.116 220.071,124.167 221.859 M1.967 225.126 C 1.967 225.450,2.144 225.825,2.360 225.959 C 2.576 226.092,2.753 225.936,2.753 225.612 C 2.753 225.287,2.576 224.912,2.360 224.779 C 2.144 224.645,1.967 224.801,1.967 225.126 M316.439 228.336 C 316.288 229.340,316.246 230.241,316.344 230.339 C 316.442 230.438,316.646 229.697,316.796 228.694 C 316.947 227.691,316.989 226.789,316.891 226.691 C 316.793 226.593,316.589 227.333,316.439 228.336 M2.366 227.804 C 2.377 228.791,3.134 229.605,3.140 228.637 C 3.144 228.163,2.970 227.666,2.753 227.532 C 2.537 227.398,2.363 227.521,2.366 227.804 M274.822 228.616 L 274.128 229.892 274.921 228.963 C 275.595 228.173,275.955 227.329,275.615 227.338 C 275.560 227.339,275.204 227.914,274.822 228.616 M397.140 227.966 C 396.983 228.124,396.859 228.622,396.865 229.072 C 396.876 229.829,396.909 229.838,397.287 229.189 C 397.727 228.433,397.614 227.492,397.140 227.966 M2.781 230.383 C 2.889 231.537,3.486 232.179,3.512 231.170 C 3.527 230.575,3.363 230.088,3.147 230.088 C 2.930 230.088,2.766 230.221,2.781 230.383 M396.466 231.367 C 396.471 232.082,396.545 232.139,396.853 231.662 C 397.346 230.899,397.346 230.482,396.853 230.482 C 396.637 230.482,396.463 230.880,396.466 231.367 M82.203 231.159 C 82.203 231.388,82.567 231.992,83.013 232.503 L 83.822 233.432 83.132 232.252 C 82.222 230.699,82.203 230.676,82.203 231.159 M270.772 233.892 C 270.166 234.686,269.871 235.212,270.117 235.060 C 270.620 234.749,272.323 232.448,272.050 232.448 C 271.953 232.448,271.378 233.098,270.772 233.892 M313.471 238.824 C 313.471 238.942,313.203 239.680,312.876 240.463 C 312.548 241.247,312.369 241.888,312.477 241.888 C 312.789 241.888,313.897 239.036,313.673 238.812 C 313.562 238.701,313.471 238.707,313.471 238.824 M262.119 242.380 L 260.964 243.658 262.242 242.503 C 262.945 241.867,263.520 241.292,263.520 241.224 C 263.520 240.920,263.196 241.188,262.119 242.380 M90.462 244.641 C 90.924 245.290,91.391 245.821,91.499 245.821 C 91.607 245.821,91.318 245.290,90.855 244.641 C 90.393 243.992,89.927 243.461,89.819 243.461 C 89.710 243.461,90.000 243.992,90.462 244.641 M148.279 245.571 C 148.279 245.679,148.810 246.146,149.459 246.608 C 150.108 247.070,150.639 247.359,150.639 247.251 C 150.639 247.143,150.108 246.676,149.459 246.214 C 148.810 245.752,148.279 245.463,148.279 245.571 M6.995 248.964 C 7.090 249.610,7.301 250.057,7.464 249.956 C 7.823 249.735,7.497 247.788,7.102 247.788 C 6.948 247.788,6.900 248.317,6.995 248.964 M392.768 248.223 C 392.673 248.524,392.404 249.373,392.168 250.108 C 391.651 251.725,391.651 251.721,392.102 251.721 C 392.469 251.721,393.391 248.127,393.098 247.835 C 393.011 247.747,392.862 247.922,392.768 248.223 M250.439 250.114 C 248.823 251.150,248.599 251.515,250.024 250.790 C 250.714 250.440,251.388 249.975,251.522 249.757 C 251.838 249.247,251.744 249.278,250.439 250.114 M304.818 255.654 C 304.356 256.303,304.066 256.834,304.175 256.834 C 304.283 256.834,304.749 256.303,305.211 255.654 C 305.674 255.005,305.963 254.474,305.855 254.474 C 305.747 254.474,305.280 255.005,304.818 255.654 M101.065 258.112 C 102.695 259.849,103.048 260.161,103.048 259.866 C 103.048 259.802,102.207 258.962,101.180 257.997 L 99.312 256.244 101.065 258.112 M10.917 261.357 C 11.020 261.898,11.280 262.340,11.494 262.340 C 11.708 262.340,11.776 262.060,11.645 261.718 C 11.514 261.376,11.406 260.933,11.406 260.735 C 11.406 260.536,11.254 260.374,11.067 260.374 C 10.881 260.374,10.813 260.816,10.917 261.357 M106.391 263.913 C 108.329 265.860,110.003 267.453,110.111 267.453 C 110.220 267.453,108.723 265.860,106.785 263.913 C 104.847 261.967,103.173 260.374,103.065 260.374 C 102.956 260.374,104.453 261.967,106.391 263.913 M192.429 261.825 C 192.807 261.924,193.427 261.924,193.805 261.825 C 194.184 261.726,193.874 261.645,193.117 261.645 C 192.360 261.645,192.050 261.726,192.429 261.825 M214.656 261.832 C 215.145 261.926,215.853 261.922,216.229 261.824 C 216.605 261.725,216.205 261.648,215.339 261.653 C 214.474 261.657,214.166 261.738,214.656 261.832 M197.837 262.346 C 201.353 262.671,208.310 262.836,208.030 262.588 C 207.940 262.508,204.857 262.352,201.180 262.240 C 196.621 262.102,195.557 262.136,197.837 262.346 M209.529 262.231 C 210.227 262.318,211.466 262.319,212.282 262.234 C 213.098 262.149,212.527 262.078,211.013 262.076 C 209.499 262.074,208.831 262.144,209.529 262.231 M112.078 269.125 C 113.708 270.861,114.061 271.174,114.061 270.878 C 114.061 270.815,113.220 269.975,112.193 269.010 L 110.324 267.257 112.078 269.125 M14.460 270.403 C 14.820 271.377,15.246 272.173,15.405 272.173 C 15.565 272.173,15.400 271.377,15.039 270.403 C 14.678 269.430,14.253 268.633,14.093 268.633 C 13.934 268.633,14.099 269.430,14.460 270.403 M385.447 269.420 C 385.196 269.890,385.079 270.362,385.187 270.471 C 385.295 270.579,385.589 270.283,385.841 269.813 C 386.092 269.343,386.209 268.871,386.101 268.763 C 385.993 268.654,385.699 268.950,385.447 269.420 M384.506 271.615 C 384.189 272.441,384.204 272.566,384.615 272.566 C 384.806 272.566,385.055 272.212,385.168 271.780 C 385.411 270.851,384.853 270.712,384.506 271.615 M284.562 276.346 L 282.989 277.754 284.661 276.504 C 286.099 275.428,286.618 274.909,286.234 274.932 C 286.180 274.935,285.428 275.572,284.562 276.346 M18.474 279.624 C 19.108 280.808,19.735 281.015,19.212 279.868 C 18.960 279.313,18.598 278.859,18.409 278.859 C 18.220 278.859,18.249 279.204,18.474 279.624 M380.787 280.039 C 380.560 280.688,380.504 281.219,380.662 281.219 C 380.820 281.219,381.149 280.688,381.394 280.039 C 381.639 279.390,381.695 278.859,381.519 278.859 C 381.342 278.859,381.013 279.390,380.787 280.039 M125.074 279.375 C 125.074 279.467,125.826 280.038,126.745 280.644 C 127.665 281.250,128.209 281.495,127.956 281.188 C 127.468 280.597,125.074 279.091,125.074 279.375 M20.452 283.298 C 20.452 283.860,21.392 285.546,21.704 285.546 C 21.891 285.546,21.739 285.059,21.367 284.464 C 20.483 283.052,20.452 283.012,20.452 283.298 M377.053 287.352 C 376.656 288.184,376.561 288.704,376.822 288.617 C 377.343 288.444,378.471 285.939,378.028 285.939 C 377.862 285.939,377.424 286.575,377.053 287.352 M265.093 288.102 C 264.553 288.411,264.287 288.664,264.503 288.664 C 264.720 288.664,265.339 288.411,265.880 288.102 C 266.421 287.793,266.686 287.540,266.470 287.540 C 266.254 287.540,265.634 287.793,265.093 288.102 M24.470 290.855 C 25.183 292.695,26.461 294.985,26.774 294.985 C 26.986 294.985,26.897 294.499,26.577 293.904 C 25.927 292.694,24.232 290.242,24.470 290.855 M257.227 291.417 C 255.642 292.057,255.452 292.271,255.406 293.460 C 255.356 294.752,255.359 294.755,255.525 293.566 C 255.667 292.546,255.955 292.259,257.268 291.825 C 258.132 291.540,258.930 291.161,259.040 290.983 C 259.291 290.576,259.341 290.564,257.227 291.417 M374.782 291.766 C 374.440 292.347,373.762 293.487,373.274 294.300 C 372.731 295.205,372.593 295.689,372.919 295.548 C 373.212 295.421,373.941 294.331,374.540 293.126 C 375.687 290.819,375.837 289.971,374.782 291.766 M28.712 298.281 C 28.712 298.762,30.482 301.269,30.825 301.273 C 31.014 301.276,31.001 301.057,30.797 300.787 C 30.593 300.516,30.040 299.784,29.569 299.160 C 29.098 298.536,28.712 298.141,28.712 298.281 M370.487 299.031 C 369.371 300.707,369.285 300.885,369.597 300.882 C 369.935 300.880,371.396 298.502,371.187 298.293 C 371.118 298.224,370.803 298.556,370.487 299.031 M153.335 302.558 C 153.498 302.721,174.861 302.810,200.808 302.755 L 247.984 302.655 200.511 302.458 C 174.401 302.350,153.172 302.395,153.335 302.558 M366.492 305.113 C 365.630 306.118,365.297 306.785,365.660 306.782 C 365.835 306.781,366.280 306.250,366.648 305.602 C 367.408 304.268,367.356 304.107,366.492 305.113 M33.432 305.814 C 33.432 306.145,33.696 306.518,34.019 306.642 C 34.343 306.766,34.492 307.053,34.352 307.280 C 34.204 307.520,34.285 307.576,34.546 307.415 C 34.870 307.215,34.820 306.868,34.365 306.174 C 33.633 305.057,33.432 304.979,33.432 305.814 M36.201 309.538 C 36.968 311.030,38.256 312.684,38.652 312.684 C 38.846 312.684,38.427 311.932,37.721 311.013 C 35.974 308.736,35.604 308.378,36.201 309.538 M362.520 310.914 C 361.916 311.672,361.543 312.291,361.690 312.291 C 361.982 312.291,362.806 311.320,363.442 310.226 C 364.068 309.151,363.719 309.411,362.520 310.914 M250.737 316.814 C 250.737 319.044,250.870 320.787,251.032 320.687 C 251.195 320.586,251.327 318.844,251.327 316.814 C 251.327 314.785,251.195 313.042,251.032 312.942 C 250.870 312.842,250.737 314.584,250.737 316.814 M359.956 314.242 C 359.483 314.882,359.095 315.536,359.095 315.695 C 359.095 315.854,359.538 315.384,360.079 314.651 C 360.619 313.918,361.062 313.264,361.062 313.198 C 361.062 312.877,360.742 313.178,359.956 314.242 M39.331 313.686 C 39.331 313.819,39.949 314.683,40.704 315.604 C 41.460 316.526,41.946 317.425,41.786 317.602 C 41.626 317.779,41.678 317.820,41.903 317.692 C 42.127 317.565,43.003 318.416,43.848 319.583 C 44.694 320.751,45.629 321.799,45.925 321.913 C 46.222 322.027,46.055 321.613,45.553 320.993 C 40.656 314.944,39.331 313.388,39.331 313.686 M357.840 316.912 C 356.856 318.058,356.637 318.597,357.252 318.361 C 357.558 318.244,358.006 317.715,358.247 317.186 C 358.765 316.049,358.648 315.971,357.840 316.912 M354.572 320.944 C 353.951 321.593,353.619 322.124,353.835 322.124 C 354.051 322.124,354.620 321.593,355.100 320.944 C 355.580 320.295,355.912 319.764,355.838 319.764 C 355.763 319.764,355.194 320.295,354.572 320.944 M48.378 324.694 C 48.378 325.174,49.647 326.794,50.186 327.001 C 50.525 327.131,50.332 326.653,49.722 325.854 C 48.718 324.537,48.378 324.243,48.378 324.694 M350.221 326.108 C 349.258 327.134,349.212 327.264,349.942 326.886 C 350.424 326.636,351.005 326.082,351.234 325.655 C 351.816 324.567,351.559 324.682,350.221 326.108 M182.989 331.072 C 192.886 331.130,209.081 331.130,218.977 331.072 C 228.874 331.013,220.777 330.965,200.983 330.965 C 181.190 330.965,173.092 331.013,182.989 331.072 M342.076 334.619 C 340.188 336.516,338.643 338.204,338.643 338.370 C 338.643 338.683,344.386 333.064,345.298 331.858 C 346.360 330.454,345.419 331.261,342.076 334.619 M55.457 332.581 C 55.457 332.708,56.410 333.725,57.575 334.842 C 61.172 338.292,61.699 338.567,58.614 335.383 C 55.660 332.337,55.457 332.156,55.457 332.581 M160.179 335.202 C 159.623 335.904,158.839 337.463,159.043 337.463 C 159.137 337.463,159.580 336.844,160.027 336.087 C 160.838 334.711,160.914 334.274,160.179 335.202 M243.916 340.610 C 243.878 341.367,243.762 342.694,243.660 343.559 L 243.473 345.133 243.877 343.559 C 244.098 342.694,244.214 341.367,244.133 340.610 L 243.987 339.233 243.916 340.610 M63.324 340.120 C 63.324 340.524,64.808 341.928,65.683 342.351 C 66.008 342.508,65.919 342.311,65.487 341.914 C 65.054 341.517,64.390 340.872,64.012 340.480 C 63.633 340.088,63.324 339.926,63.324 340.120 M334.907 341.504 C 334.132 342.283,333.998 342.549,334.518 342.277 C 335.434 341.797,336.971 340.192,336.442 340.267 C 336.247 340.295,335.556 340.852,334.907 341.504 M67.257 343.669 C 67.257 343.858,67.699 344.428,68.240 344.936 C 68.913 345.569,69.219 345.683,69.211 345.300 C 69.198 344.705,67.257 343.085,67.257 343.669 M331.170 344.739 C 330.662 345.280,330.423 345.723,330.640 345.723 C 330.856 345.723,331.449 345.280,331.957 344.739 C 332.465 344.199,332.703 343.756,332.487 343.756 C 332.271 343.756,331.678 344.199,331.170 344.739 M71.042 347.016 C 71.438 347.723,74.336 349.775,74.336 349.349 C 74.336 349.075,72.344 347.388,71.238 346.726 C 70.829 346.481,70.781 346.552,71.042 347.016 M159.489 347.689 C 159.824 348.338,160.187 348.869,160.296 348.869 C 160.404 348.869,160.218 348.338,159.882 347.689 C 159.546 347.040,159.183 346.509,159.075 346.509 C 158.967 346.509,159.153 347.040,159.489 347.689 M327.189 348.093 L 325.467 349.676 327.040 348.653 C 327.906 348.091,328.755 347.379,328.928 347.070 C 329.436 346.165,329.020 346.409,327.189 348.093 M323.682 350.812 C 322.726 351.625,322.554 351.909,323.107 351.768 C 323.540 351.658,324.212 351.137,324.600 350.612 C 325.521 349.366,325.338 349.406,323.682 350.812 M78.269 352.802 C 80.080 354.326,80.655 354.326,78.919 352.802 C 78.180 352.153,77.422 351.627,77.234 351.633 C 77.046 351.639,77.512 352.165,78.269 352.802 M165.143 352.519 C 165.313 352.688,167.827 352.776,170.730 352.714 L 176.008 352.603 170.422 352.408 C 167.349 352.300,164.974 352.350,165.143 352.519 M228.810 352.308 C 230.379 352.382,232.945 352.382,234.513 352.308 C 236.082 352.233,234.798 352.172,231.662 352.172 C 228.525 352.172,227.242 352.233,228.810 352.308 M320.551 353.277 C 319.794 353.929,319.528 354.268,319.961 354.032 C 321.149 353.383,322.284 352.438,322.095 352.255 C 322.003 352.166,321.308 352.626,320.551 353.277 M223.967 355.426 C 223.362 356.220,223.067 356.746,223.312 356.594 C 223.816 356.283,225.519 353.982,225.246 353.982 C 225.148 353.982,224.573 354.632,223.967 355.426 M316.924 355.854 C 315.902 356.639,315.132 357.347,315.212 357.427 C 315.436 357.652,318.519 355.421,318.749 354.867 C 319.013 354.231,319.082 354.194,316.924 355.854 M82.203 355.480 C 82.203 355.866,84.146 357.298,84.348 357.062 C 84.409 356.991,83.951 356.520,83.331 356.017 C 82.710 355.514,82.203 355.273,82.203 355.480 M86.499 358.651 C 87.239 359.325,87.947 359.775,88.071 359.651 C 88.308 359.414,87.286 358.546,85.939 357.838 C 85.506 357.610,85.758 357.976,86.499 358.651 M312.324 359.063 C 311.909 359.477,311.495 359.742,311.404 359.650 C 311.312 359.559,310.916 359.839,310.523 360.273 C 309.815 361.056,309.819 361.058,310.986 360.475 C 311.634 360.152,312.485 359.533,312.878 359.098 C 313.790 358.091,313.325 358.061,312.324 359.063 M219.272 360.137 C 218.088 361.196,217.999 361.342,218.914 360.731 C 220.001 360.004,221.369 358.679,220.992 358.717 C 220.912 358.725,220.138 359.364,219.272 360.137 M88.496 359.785 C 88.496 359.962,89.027 360.419,89.676 360.803 C 90.324 361.186,90.855 361.435,90.855 361.355 C 90.855 361.275,90.324 360.817,89.676 360.338 C 89.027 359.858,88.496 359.609,88.496 359.785 M93.215 362.952 C 93.215 363.244,94.120 363.813,95.765 364.554 C 95.977 364.650,95.885 364.462,95.560 364.137 C 94.728 363.305,93.215 362.540,93.215 362.952 M305.211 363.618 C 304.478 364.159,304.018 364.602,304.189 364.602 C 304.707 364.602,306.785 363.274,306.785 362.944 C 306.785 362.492,306.675 362.539,305.211 363.618 M211.013 364.023 C 210.147 364.308,209.794 364.547,210.226 364.554 C 210.659 364.561,211.544 364.323,212.193 364.026 C 213.679 363.345,213.073 363.344,211.013 364.023 M191.577 364.350 C 191.667 364.428,192.271 364.610,192.920 364.755 C 193.782 364.948,193.941 364.911,193.510 364.620 C 192.979 364.260,191.182 364.009,191.577 364.350 M99.115 366.480 C 99.115 366.659,99.956 367.198,100.983 367.679 C 102.143 368.222,102.553 368.315,102.065 367.924 C 100.879 366.976,99.115 366.112,99.115 366.480 M299.017 367.184 C 298.097 367.735,297.345 368.256,297.345 368.341 C 297.345 368.669,300.681 366.985,300.812 366.591 C 301.003 366.018,300.914 366.047,299.017 367.184 M105.872 370.206 C 106.595 370.891,109.452 372.179,109.145 371.682 C 108.899 371.285,106.065 369.715,105.592 369.715 C 105.460 369.715,105.586 369.936,105.872 370.206 M291.937 370.940 C 290.236 372.029,290.325 372.157,292.228 371.357 C 293.091 370.995,293.799 370.565,293.801 370.403 C 293.808 369.923,293.294 370.071,291.937 370.940 M285.152 374.238 C 284.582 374.564,284.417 374.801,284.759 374.801 C 285.084 374.802,285.693 374.543,286.113 374.225 C 287.084 373.491,286.445 373.499,285.152 374.238 M282.399 375.615 C 281.642 376.029,281.164 376.376,281.337 376.385 C 281.754 376.407,283.972 375.253,283.972 375.014 C 283.972 374.757,283.949 374.766,282.399 375.615 M123.500 378.342 C 123.500 378.522,123.810 378.758,124.189 378.867 C 124.567 378.976,125.216 379.204,125.630 379.373 C 126.129 379.578,126.295 379.539,126.122 379.260 C 125.785 378.714,123.500 377.914,123.500 378.342 M274.979 378.616 C 273.326 379.337,273.547 379.703,275.247 379.061 C 276.147 378.722,277.223 377.739,276.401 378.007 C 276.347 378.024,275.707 378.299,274.979 378.616 M132.547 381.820 C 132.547 382.034,132.989 382.294,133.530 382.397 C 134.071 382.501,134.513 382.433,134.513 382.246 C 134.513 382.060,134.351 381.908,134.152 381.908 C 133.953 381.908,133.511 381.800,133.169 381.669 C 132.827 381.538,132.547 381.605,132.547 381.820 M266.175 381.785 C 265.796 381.884,265.487 382.114,265.487 382.295 C 265.487 382.476,265.796 382.565,266.175 382.493 C 266.554 382.420,266.996 382.348,267.158 382.331 C 267.321 382.314,267.453 382.124,267.453 381.908 C 267.453 381.499,267.321 381.486,266.175 381.785 M238.741 389.381 C 238.262 389.690,238.313 389.763,239.013 389.768 C 239.487 389.771,239.984 389.597,240.118 389.381 C 240.427 388.880,239.516 388.880,238.741 389.381 M162.045 389.774 C 162.045 389.990,162.311 390.167,162.635 390.167 C 162.960 390.167,163.225 389.990,163.225 389.774 C 163.225 389.558,162.960 389.381,162.635 389.381 C 162.311 389.381,162.045 389.558,162.045 389.774 M236.775 389.774 C 236.775 389.990,237.040 390.167,237.365 390.167 C 237.689 390.167,237.955 389.990,237.955 389.774 C 237.955 389.558,237.689 389.381,237.365 389.381 C 237.040 389.381,236.775 389.558,236.775 389.774 M164.208 390.167 C 165.283 390.629,165.585 390.629,165.585 390.167 C 165.585 389.951,165.098 389.786,164.503 389.801 C 163.545 389.826,163.511 389.868,164.208 390.167 M234.612 390.167 C 234.324 390.632,234.709 390.632,235.792 390.167 C 236.550 389.841,236.547 389.828,235.716 389.801 C 235.242 389.786,234.745 389.951,234.612 390.167 M166.765 390.560 C 167.540 391.061,168.451 391.061,168.142 390.560 C 168.008 390.344,167.511 390.170,167.037 390.173 C 166.336 390.178,166.285 390.251,166.765 390.560 M231.858 390.560 C 231.549 391.061,232.460 391.061,233.235 390.560 C 233.715 390.251,233.664 390.178,232.963 390.173 C 232.489 390.170,231.992 390.344,231.858 390.560 M181.416 392.405 C 181.794 392.504,182.414 392.504,182.793 392.405 C 183.171 392.306,182.861 392.225,182.104 392.225 C 181.347 392.225,181.037 392.306,181.416 392.405 M187.321 392.809 C 187.919 392.900,188.804 392.897,189.288 392.804 C 189.771 392.711,189.282 392.637,188.201 392.640 C 187.119 392.642,186.723 392.719,187.321 392.809 M210.920 392.809 C 211.518 392.900,212.403 392.897,212.886 392.804 C 213.370 392.711,212.881 392.637,211.799 392.640 C 210.718 392.642,210.322 392.719,210.920 392.809 \" stroke=\"none\" fill=\"#fcb6c0\" fill-rule=\"evenodd\"><\/path><path id=\"path4\" d=\"M186.922 0.271 C 187.301 0.370,187.920 0.370,188.299 0.271 C 188.677 0.172,188.368 0.091,187.611 0.091 C 186.853 0.091,186.544 0.172,186.922 0.271 M211.701 0.271 C 212.080 0.370,212.699 0.370,213.078 0.271 C 213.456 0.172,213.147 0.091,212.389 0.091 C 211.632 0.091,211.323 0.172,211.701 0.271 M197.935 42.749 C 198.314 42.848,198.933 42.848,199.312 42.749 C 199.690 42.650,199.381 42.569,198.623 42.569 C 197.866 42.569,197.557 42.650,197.935 42.749 M213.668 42.749 C 214.046 42.848,214.666 42.848,215.044 42.749 C 215.423 42.650,215.113 42.569,214.356 42.569 C 213.599 42.569,213.289 42.650,213.668 42.749 M188.889 43.536 C 189.267 43.635,189.887 43.635,190.265 43.536 C 190.644 43.437,190.334 43.356,189.577 43.356 C 188.820 43.356,188.510 43.437,188.889 43.536 M222.321 43.536 C 222.699 43.635,223.319 43.635,223.697 43.536 C 224.076 43.437,223.766 43.356,223.009 43.356 C 222.252 43.356,221.942 43.437,222.321 43.536 M68.775 47.613 C 67.895 48.379,67.892 48.400,68.710 48.004 C 69.184 47.775,69.682 47.411,69.814 47.196 C 70.201 46.570,69.777 46.740,68.775 47.613 M333.498 50.094 C 334.021 50.739,335.497 51.714,335.497 51.415 C 335.497 51.340,334.921 50.858,334.218 50.343 C 333.427 49.764,333.153 49.669,333.498 50.094 M338.438 54.404 C 339.298 55.174,340.515 56.390,341.143 57.106 L 342.284 58.407 341.318 57.056 C 340.787 56.313,339.569 55.097,338.612 54.355 L 336.873 53.004 338.438 54.404 M56.932 58.596 C 55.039 60.528,53.491 62.221,53.491 62.358 C 53.491 62.612,58.590 57.547,59.943 55.949 C 61.502 54.107,60.252 55.206,56.932 58.596 M138.151 58.256 C 136.811 59.114,136.377 59.691,137.561 59.040 C 138.464 58.544,139.878 57.450,139.626 57.443 C 139.518 57.440,138.854 57.805,138.151 58.256 M345.297 61.500 C 345.821 62.145,347.296 63.120,347.296 62.821 C 347.296 62.746,346.721 62.264,346.018 61.749 C 345.227 61.170,344.952 61.075,345.297 61.500 M49.503 66.492 C 48.623 67.259,48.620 67.279,49.437 66.883 C 49.912 66.654,50.409 66.290,50.542 66.075 C 50.929 65.449,50.505 65.619,49.503 66.492 M108.948 79.646 C 107.336 81.268,106.106 82.596,106.214 82.596 C 106.323 82.596,107.730 81.268,109.341 79.646 C 110.953 78.024,112.183 76.696,112.075 76.696 C 111.967 76.696,110.559 78.024,108.948 79.646 M101.070 87.611 L 98.525 90.265 101.180 87.720 C 103.646 85.356,104.015 84.956,103.725 84.956 C 103.665 84.956,102.470 86.150,101.070 87.611 M317.146 108.751 C 317.147 110.482,317.216 111.141,317.299 110.216 C 317.382 109.291,317.381 107.875,317.297 107.069 C 317.212 106.264,317.144 107.021,317.146 108.751 M214.066 149.741 C 214.664 149.832,215.549 149.829,216.033 149.736 C 216.517 149.643,216.028 149.569,214.946 149.572 C 213.864 149.575,213.469 149.651,214.066 149.741 M225.275 150.131 C 225.764 150.225,226.472 150.221,226.848 150.123 C 227.224 150.024,226.824 149.947,225.959 149.952 C 225.093 149.956,224.786 150.037,225.275 150.131 M229.799 150.528 C 230.397 150.618,231.282 150.616,231.765 150.523 C 232.249 150.429,231.760 150.355,230.678 150.358 C 229.597 150.361,229.201 150.438,229.799 150.528 M70.655 151.902 C 70.522 152.397,70.429 153.156,70.448 153.589 C 70.467 154.022,70.644 153.685,70.842 152.841 C 71.226 151.207,71.062 150.384,70.655 151.902 M116.421 160.988 C 116.421 161.056,116.996 161.631,117.699 162.267 L 118.977 163.422 117.822 162.144 C 116.745 160.952,116.421 160.685,116.421 160.988 M122.321 166.101 C 122.321 166.169,122.896 166.744,123.599 167.380 L 124.877 168.535 123.722 167.257 C 122.645 166.065,122.321 165.798,122.321 166.101 M399.719 189.774 C 399.722 190.855,399.799 191.251,399.889 190.653 C 399.979 190.056,399.977 189.171,399.884 188.687 C 399.790 188.203,399.716 188.692,399.719 189.774 M0.132 191.937 C 0.132 193.559,0.202 194.223,0.287 193.412 C 0.371 192.601,0.371 191.273,0.287 190.462 C 0.202 189.651,0.132 190.315,0.132 191.937 M0.132 200.983 C 0.132 202.606,0.202 203.269,0.287 202.458 C 0.371 201.647,0.371 200.320,0.287 199.508 C 0.202 198.697,0.132 199.361,0.132 200.983 M399.719 203.147 C 399.722 204.228,399.799 204.624,399.889 204.026 C 399.979 203.428,399.977 202.543,399.884 202.059 C 399.790 201.576,399.716 202.065,399.719 203.147 M317.503 210.226 C 317.508 211.091,317.588 211.399,317.682 210.910 C 317.776 210.421,317.773 209.713,317.674 209.337 C 317.576 208.961,317.499 209.361,317.503 210.226 M317.495 221.436 C 317.495 222.193,317.576 222.502,317.675 222.124 C 317.774 221.745,317.774 221.126,317.675 220.747 C 317.576 220.369,317.495 220.678,317.495 221.436 M84.905 235.792 C 85.118 236.224,85.580 236.932,85.932 237.365 L 86.572 238.151 86.186 237.365 C 85.974 236.932,85.512 236.224,85.160 235.792 L 84.519 235.005 84.905 235.792 M298.132 263.913 C 296.789 265.428,295.779 266.667,295.888 266.667 C 295.996 266.667,297.183 265.428,298.525 263.913 C 299.868 262.399,300.877 261.160,300.769 261.160 C 300.661 261.160,299.474 262.399,298.132 263.913 M293.590 268.732 L 292.035 270.403 293.707 268.848 C 295.262 267.402,295.559 267.060,295.262 267.060 C 295.197 267.060,294.445 267.812,293.590 268.732 M290.244 271.681 L 288.889 273.156 290.364 271.801 C 291.175 271.055,291.839 270.392,291.839 270.326 C 291.839 270.026,291.506 270.309,290.244 271.681 M133.138 284.368 C 133.401 284.794,135.693 286.071,135.693 285.791 C 135.693 285.699,135.063 285.252,134.293 284.797 C 133.523 284.343,133.003 284.150,133.138 284.368 M368.606 302.262 C 368.360 302.802,368.223 303.245,368.301 303.245 C 368.380 303.245,368.734 302.802,369.089 302.262 C 369.443 301.721,369.580 301.278,369.394 301.278 C 369.207 301.278,368.853 301.721,368.606 302.262 M361.019 313.176 C 360.557 314.056,360.559 314.057,361.398 313.312 C 362.336 312.479,362.421 312.291,361.862 312.291 C 361.654 312.291,361.274 312.689,361.019 313.176 M151.154 316.814 C 151.157 318.112,151.230 318.596,151.317 317.889 C 151.405 317.182,151.403 316.120,151.313 315.529 C 151.224 314.938,151.152 315.516,151.154 316.814 M354.475 321.574 C 353.988 322.128,353.796 322.514,354.048 322.430 C 354.472 322.289,355.831 320.542,355.505 320.558 C 355.425 320.562,354.961 321.019,354.475 321.574 M352.333 323.992 C 351.640 324.799,351.121 325.664,351.329 325.664 C 351.409 325.664,351.867 325.133,352.347 324.484 C 353.295 323.202,353.286 322.883,352.333 323.992 M47.984 324.877 C 48.446 325.526,48.913 326.057,49.021 326.057 C 49.129 326.057,48.840 325.526,48.378 324.877 C 47.915 324.228,47.449 323.697,47.341 323.697 C 47.233 323.697,47.522 324.228,47.984 324.877 M157.268 326.944 C 157.431 327.107,177.201 327.195,201.201 327.140 L 244.838 327.040 200.905 326.844 C 176.741 326.735,157.105 326.781,157.268 326.944 M347.860 329.007 C 346.775 330.197,346.001 331.170,346.140 331.170 C 346.278 331.170,347.283 330.197,348.373 329.007 C 349.463 327.817,350.237 326.844,350.093 326.844 C 349.950 326.844,348.945 327.817,347.860 329.007 M51.524 328.723 C 51.524 328.854,52.498 329.889,53.687 331.024 C 54.877 332.158,55.851 332.986,55.851 332.864 C 55.851 332.742,54.877 331.707,53.687 330.563 C 52.498 329.420,51.524 328.592,51.524 328.723 M61.308 338.584 C 62.977 340.167,63.609 340.603,63.145 339.852 C 63.021 339.651,62.170 338.917,61.253 338.220 L 59.587 336.952 61.308 338.584 M337.620 339.135 C 335.897 341.122,335.385 341.790,335.585 341.790 C 335.701 341.790,336.448 340.993,337.245 340.020 C 338.723 338.217,339.015 337.525,337.620 339.135 M177.778 355.679 C 177.778 355.746,178.353 356.322,179.056 356.957 L 180.334 358.112 179.179 356.834 C 178.102 355.642,177.778 355.375,177.778 355.679 M196.342 393.213 C 198.224 393.285,201.410 393.285,203.422 393.214 C 205.434 393.142,203.894 393.083,200.000 393.083 C 196.106 393.082,194.460 393.141,196.342 393.213 \" stroke=\"none\" fill=\"#fcacb4\" fill-rule=\"evenodd\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\t\t\t\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"box-heading\">\n\t\t\t\t\t\t\t<a >\t\t\t\t\t\t\t\tComparing Candidates\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4147a3e0 content-align-left icon-box-vertical-align-top icon-position-left icon-vertical-align-start elementor-widget elementor-widget-the7_icon_box_widget\" data-id=\"4147a3e0\" data-element_type=\"widget\" data-widget_type=\"the7_icon_box_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"the7-box-wrapper the7-elementor-widget the7_icon_box_widget-4147a3e0\">\t\t\t<div class=\"box-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-icon-div\" >\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"svg\" width=\"400\" height=\"392.9901423877327\" viewBox=\"0, 0, 400,392.9901423877327\"><g id=\"svgg\"><path id=\"path0\" d=\"M193.314 43.309 C 155.007 46.203,120.494 64.039,96.738 93.218 C 63.997 133.435,60.098 195.681,87.593 239.239 C 101.091 260.622,119.818 277.760,140.610 287.759 L 145.919 290.312 145.919 291.792 C 145.919 295.513,148.402 299.901,151.320 301.338 L 153.196 302.262 200.393 302.228 L 247.591 302.194 249.593 301.172 C 252.890 299.487,254.370 297.363,255.041 293.354 C 255.271 291.978,255.414 291.867,258.516 290.641 C 328.287 263.078,338.631 183.447,275.516 159.768 C 256.823 152.755,243.679 150.783,209.440 149.855 C 164.379 148.633,143.627 142.430,140.276 129.180 C 137.228 117.133,141.711 105.293,152.011 98.184 C 169.276 86.268,201.577 81.428,228.122 86.779 C 247.528 90.691,268.207 103.598,276.483 116.965 C 287.486 134.737,312.441 132.616,316.478 113.565 C 318.974 101.788,308.991 87.784,285.939 70.730 C 255.989 48.573,229.081 40.607,193.314 43.309 M123.012 166.263 C 140.965 181.228,163.506 186.888,205.703 187.026 C 224.731 187.088,226.988 187.241,240.708 189.388 C 279.914 195.525,290.904 214.942,268.035 237.671 C 224.252 281.187,139.987 265.243,117.384 209.166 C 111.200 193.823,108.954 172.543,111.943 157.611 C 112.160 156.525,112.175 156.533,115.373 159.546 C 117.139 161.211,120.577 164.233,123.012 166.263 M156.932 307.613 C 150.346 311.561,149.524 321.652,155.467 325.585 L 157.071 326.647 201.019 326.647 L 244.967 326.647 246.663 325.455 C 253.221 320.846,252.177 310.416,244.850 307.354 C 242.285 306.283,158.742 306.528,156.932 307.613 M163.516 332.724 C 157.360 336.628,157.289 347.240,163.394 351.019 C 165.262 352.175,165.493 352.216,170.765 352.340 L 176.208 352.469 177.358 354.140 C 187.438 368.792,216.115 368.604,224.773 353.830 L 225.837 352.016 231.247 352.016 C 236.571 352.016,236.681 351.998,238.205 350.894 C 244.474 346.353,245.358 338.771,240.174 334.011 C 237.376 331.442,239.336 331.563,200.838 331.563 L 165.346 331.563 163.516 332.724 \" stroke=\"none\" fill=\"#f42444\" fill-rule=\"evenodd\"><\/path><path id=\"path1\" d=\"M188.201 0.421 C 184.956 0.587,180.294 0.928,177.842 1.179 C 175.390 1.431,173.282 1.535,173.159 1.412 C 173.035 1.288,172.701 1.380,172.416 1.617 C 171.936 2.015,170.708 2.238,167.748 2.466 C 167.099 2.516,166.346 2.701,166.073 2.877 C 165.801 3.053,165.226 3.085,164.795 2.949 C 164.310 2.795,164.012 2.880,164.012 3.171 C 164.012 3.491,163.566 3.570,162.626 3.418 C 161.864 3.294,161.319 3.319,161.414 3.474 C 161.510 3.628,159.293 4.180,156.487 4.699 C 153.682 5.219,151.295 5.793,151.183 5.975 C 151.070 6.157,150.806 6.199,150.595 6.069 C 150.384 5.939,149.976 6.027,149.688 6.266 C 149.401 6.505,148.878 6.589,148.526 6.454 C 148.150 6.310,147.886 6.407,147.886 6.690 C 147.886 6.978,147.569 7.089,147.099 6.966 C 146.667 6.853,146.313 6.941,146.313 7.162 C 146.313 7.384,145.959 7.472,145.526 7.359 C 145.093 7.246,144.739 7.281,144.739 7.436 C 144.739 7.592,143.142 8.131,141.189 8.634 C 139.236 9.138,137.549 9.694,137.440 9.871 C 137.331 10.047,136.981 10.092,136.664 9.970 C 136.346 9.848,136.087 9.964,136.087 10.226 C 136.087 10.489,135.821 10.602,135.497 10.477 C 135.172 10.353,134.907 10.390,134.907 10.560 C 134.907 10.730,133.535 11.286,131.858 11.796 C 130.182 12.307,128.236 12.961,127.534 13.250 C 126.832 13.539,126.144 13.758,126.005 13.737 C 125.865 13.716,125.622 13.908,125.464 14.164 C 125.306 14.420,124.711 14.656,124.142 14.689 C 123.573 14.722,123.108 14.858,123.107 14.992 C 123.107 15.125,122.001 15.631,120.649 16.117 C 119.297 16.603,117.616 17.349,116.912 17.775 C 116.209 18.201,115.634 18.434,115.634 18.293 C 115.634 18.152,115.342 18.328,114.986 18.685 C 114.629 19.042,114.009 19.248,113.608 19.143 C 113.208 19.038,112.967 19.093,113.073 19.265 C 113.179 19.437,112.250 19.985,111.009 20.482 C 109.767 20.980,108.660 21.518,108.549 21.678 C 108.437 21.838,106.844 22.747,105.009 23.697 C 100.301 26.135,95.583 28.785,94.199 29.770 C 92.039 31.306,89.483 32.815,89.184 32.729 C 89.022 32.683,88.889 32.809,88.889 33.010 C 88.889 33.211,87.871 33.995,86.627 34.754 C 85.383 35.512,82.153 37.837,79.449 39.919 C 76.745 42.001,73.544 44.455,72.335 45.373 C 71.126 46.290,69.575 47.615,68.888 48.318 C 68.201 49.021,67.459 49.486,67.241 49.351 C 67.023 49.216,66.891 49.252,66.948 49.430 C 67.146 50.041,63.238 53.433,62.613 53.193 C 62.269 53.061,62.118 53.131,62.257 53.356 C 62.536 53.807,58.110 58.338,57.697 58.024 C 57.547 57.910,57.514 57.936,57.623 58.082 C 57.733 58.228,56.450 59.777,54.772 61.524 C 53.094 63.271,50.934 65.618,49.973 66.741 C 49.011 67.863,48.038 68.676,47.809 68.546 C 47.581 68.416,47.514 68.443,47.659 68.606 C 47.898 68.872,45.576 72.283,44.830 72.763 C 44.661 72.871,43.724 74.022,42.747 75.320 C 41.769 76.618,39.631 79.449,37.994 81.613 C 36.358 83.776,35.016 85.689,35.012 85.864 C 35.008 86.039,34.801 86.056,34.551 85.901 C 34.262 85.723,34.204 85.794,34.390 86.096 C 34.563 86.375,34.140 87.289,33.370 88.306 C 32.647 89.260,31.266 91.273,30.302 92.780 C 29.337 94.287,28.381 95.417,28.176 95.290 C 27.971 95.164,27.930 95.265,28.085 95.516 C 28.392 96.013,26.816 99.115,26.256 99.115 C 26.067 99.115,26.009 99.271,26.127 99.462 C 26.245 99.653,26.015 100.228,25.615 100.740 C 25.216 101.253,23.645 104.095,22.125 107.058 C 20.604 110.021,19.224 112.321,19.057 112.171 C 18.890 112.021,18.868 112.099,19.008 112.344 C 19.320 112.891,18.546 115.241,18.054 115.241 C 17.859 115.241,17.730 115.374,17.769 115.536 C 17.807 115.698,17.390 116.813,16.842 118.013 C 16.294 119.214,15.629 120.851,15.365 121.652 C 15.101 122.452,14.711 123.107,14.499 123.107 C 14.287 123.107,14.219 123.279,14.349 123.489 C 14.479 123.700,14.333 124.275,14.024 124.768 C 13.715 125.260,12.974 127.168,12.376 129.007 C 11.778 130.846,11.148 132.406,10.976 132.474 C 10.804 132.542,10.761 132.852,10.880 133.162 C 10.999 133.473,10.907 133.727,10.674 133.727 C 10.441 133.727,10.353 133.992,10.477 134.317 C 10.602 134.641,10.541 134.907,10.342 134.907 C 10.143 134.907,9.567 136.511,9.061 138.473 C 8.430 140.920,8.029 141.876,7.783 141.521 C 7.554 141.190,7.516 141.464,7.677 142.281 C 7.824 143.029,7.768 143.559,7.541 143.559 C 7.328 143.559,7.246 143.913,7.359 144.346 C 7.472 144.779,7.384 145.133,7.162 145.133 C 6.941 145.133,6.853 145.487,6.966 145.919 C 7.089 146.389,6.978 146.706,6.690 146.706 C 6.407 146.706,6.310 146.970,6.454 147.346 C 6.589 147.698,6.495 148.233,6.244 148.535 C 5.993 148.838,5.900 149.197,6.037 149.334 C 6.174 149.471,6.133 149.777,5.946 150.013 C 5.759 150.249,5.286 152.168,4.894 154.277 C 4.503 156.386,4.068 158.112,3.929 158.112 C 3.790 158.112,3.754 158.643,3.849 159.292 C 3.951 159.986,3.846 160.472,3.594 160.472 C 3.328 160.472,3.256 160.919,3.402 161.652 C 3.554 162.413,3.478 162.832,3.188 162.832 C 2.904 162.832,2.830 163.196,2.986 163.820 C 3.126 164.377,3.029 165.056,2.765 165.375 C 2.506 165.686,2.406 166.292,2.543 166.722 C 2.679 167.151,2.616 167.823,2.402 168.215 C 1.307 170.226,0.243 188.749,0.520 200.983 C 0.757 211.453,1.765 224.046,2.431 224.858 C 2.644 225.118,2.700 225.702,2.557 226.155 C 2.413 226.609,2.506 227.234,2.765 227.546 C 3.029 227.864,3.126 228.543,2.986 229.100 C 2.831 229.720,2.904 230.088,3.184 230.088 C 3.455 230.088,3.561 230.550,3.456 231.268 C 3.361 231.917,3.449 232.448,3.653 232.448 C 3.856 232.448,3.944 232.979,3.849 233.628 C 3.754 234.277,3.789 234.808,3.927 234.808 C 4.065 234.808,4.503 236.584,4.899 238.753 C 5.296 240.923,5.774 242.794,5.963 242.910 C 6.152 243.027,6.199 243.295,6.069 243.506 C 5.939 243.716,6.027 244.124,6.266 244.412 C 6.505 244.699,6.589 245.223,6.454 245.575 C 6.310 245.951,6.407 246.214,6.690 246.214 C 6.974 246.214,7.089 246.530,6.971 246.982 C 6.860 247.404,6.938 247.806,7.143 247.874 C 7.348 247.943,7.551 248.658,7.593 249.465 C 7.635 250.271,7.768 250.931,7.889 250.932 C 8.009 250.933,8.430 252.177,8.824 253.695 C 9.218 255.214,9.687 256.547,9.866 256.658 C 10.045 256.768,10.092 257.119,9.970 257.436 C 9.848 257.754,9.964 258.014,10.226 258.014 C 10.489 258.014,10.602 258.279,10.477 258.604 C 10.353 258.928,10.441 259.194,10.674 259.194 C 10.907 259.194,10.995 259.459,10.871 259.784 C 10.746 260.108,10.782 260.374,10.951 260.374 C 11.119 260.374,11.586 261.480,11.988 262.832 C 12.391 264.184,12.957 265.864,13.247 266.566 C 13.537 267.268,13.758 267.957,13.737 268.096 C 13.716 268.235,13.860 268.457,14.057 268.589 C 14.254 268.722,15.093 270.600,15.922 272.763 C 16.750 274.926,17.560 276.785,17.721 276.893 C 17.882 277.001,18.076 277.443,18.151 277.876 C 18.227 278.309,18.521 278.907,18.803 279.205 C 19.086 279.503,19.210 280.029,19.078 280.373 C 18.946 280.717,18.959 280.877,19.108 280.728 C 19.380 280.457,21.821 285.091,21.698 285.644 C 21.662 285.806,21.820 285.939,22.049 285.939 C 22.278 285.939,22.365 286.101,22.243 286.299 C 22.121 286.497,22.167 286.718,22.347 286.790 C 22.526 286.863,23.295 288.073,24.056 289.479 C 27.443 295.739,31.656 302.714,33.000 304.285 C 33.211 304.532,33.277 304.842,33.146 304.973 C 33.015 305.104,33.099 305.211,33.334 305.211 C 33.569 305.211,34.163 305.875,34.654 306.686 C 35.145 307.498,36.320 309.179,37.265 310.423 C 38.211 311.667,38.872 312.866,38.735 313.088 C 38.598 313.309,38.662 313.442,38.876 313.382 C 39.228 313.285,40.418 314.647,45.313 320.747 C 46.180 321.829,47.712 323.678,48.716 324.856 C 51.642 328.292,64.365 341.035,66.799 342.970 C 68.024 343.943,69.259 345.050,69.542 345.430 C 69.826 345.810,70.534 346.372,71.115 346.680 C 71.697 346.988,72.714 347.739,73.375 348.350 C 75.620 350.422,81.851 355.111,85.644 357.582 C 86.996 358.463,88.116 359.473,88.133 359.828 C 88.150 360.182,88.248 360.269,88.349 360.020 C 88.529 359.582,92.330 361.844,92.866 362.708 C 92.998 362.921,93.220 363.081,93.358 363.062 C 94.058 362.968,94.384 363.073,94.859 363.543 C 95.588 364.265,101.460 367.615,105.211 369.449 C 106.942 370.296,108.623 371.204,108.948 371.468 C 109.272 371.733,110.733 372.459,112.193 373.083 C 113.653 373.706,114.848 374.364,114.848 374.545 C 114.848 374.726,115.025 374.765,115.241 374.631 C 115.457 374.498,115.634 374.576,115.634 374.805 C 115.634 375.034,115.767 375.188,115.929 375.148 C 116.091 375.108,116.932 375.388,117.797 375.771 C 118.663 376.153,120.610 376.915,122.124 377.464 C 123.638 378.012,125.231 378.655,125.664 378.892 C 126.096 379.129,126.539 379.336,126.647 379.351 C 126.755 379.366,127.198 379.562,127.630 379.785 C 128.063 380.008,129.789 380.608,131.465 381.118 C 133.142 381.629,134.513 382.186,134.513 382.358 C 134.513 382.529,134.779 382.568,135.103 382.443 C 135.428 382.318,135.693 382.431,135.693 382.694 C 135.693 382.957,135.953 383.072,136.271 382.950 C 136.588 382.828,136.935 382.869,137.040 383.040 C 137.146 383.211,139.143 383.854,141.478 384.469 C 143.813 385.084,145.775 385.714,145.840 385.869 C 145.904 386.024,146.303 386.060,146.725 385.950 C 147.147 385.839,147.493 385.930,147.493 386.151 C 147.493 386.373,147.847 386.461,148.279 386.348 C 148.739 386.228,149.066 386.336,149.066 386.608 C 149.066 386.888,149.367 386.978,149.819 386.834 C 150.234 386.703,150.678 386.765,150.806 386.973 C 150.934 387.180,153.250 387.754,155.952 388.248 C 158.654 388.742,160.865 389.283,160.865 389.450 C 160.865 389.617,161.396 389.648,162.045 389.518 C 162.695 389.388,163.225 389.450,163.225 389.657 C 163.225 389.862,163.756 389.953,164.405 389.858 C 165.124 389.752,165.585 389.859,165.585 390.130 C 165.585 390.409,165.954 390.483,166.573 390.327 C 167.117 390.191,167.799 390.276,168.089 390.517 C 168.379 390.758,169.041 390.953,169.559 390.951 C 170.077 390.949,172.537 391.201,175.025 391.510 C 188.507 393.187,209.683 393.280,223.009 391.721 C 226.578 391.304,229.923 390.960,230.441 390.958 C 230.959 390.956,231.622 390.756,231.914 390.514 C 232.206 390.272,232.834 390.176,233.311 390.301 C 233.787 390.426,234.407 390.337,234.687 390.104 C 234.968 389.871,235.552 389.774,235.986 389.887 C 236.420 390.001,236.775 389.933,236.775 389.737 C 236.775 389.541,237.121 389.381,237.544 389.381 C 239.004 389.381,249.165 387.295,249.392 386.948 C 249.518 386.757,249.916 386.714,250.277 386.853 C 250.661 387.000,250.934 386.913,250.934 386.643 C 250.934 386.360,251.239 386.278,251.721 386.431 C 252.205 386.584,252.507 386.501,252.507 386.215 C 252.507 385.943,252.834 385.834,253.294 385.955 C 253.727 386.068,254.081 386.032,254.081 385.876 C 254.081 385.719,255.452 385.270,257.129 384.877 C 258.805 384.485,260.531 384.031,260.964 383.869 C 261.396 383.707,261.927 383.539,262.144 383.494 C 262.360 383.450,262.750 383.237,263.011 383.020 C 263.272 382.804,263.670 382.741,263.896 382.880 C 264.122 383.020,264.307 382.928,264.307 382.675 C 264.307 382.423,264.572 382.319,264.897 382.443 C 265.221 382.568,265.487 382.536,265.487 382.374 C 265.487 382.211,267.168 381.572,269.223 380.955 C 271.278 380.338,272.960 379.650,272.960 379.428 C 272.960 379.205,273.076 379.140,273.218 379.282 C 273.361 379.424,273.671 379.389,273.907 379.204 C 274.143 379.019,275.841 378.293,277.679 377.592 C 279.518 376.890,281.664 375.989,282.449 375.589 C 283.233 375.189,283.985 374.972,284.120 375.107 C 284.255 375.242,284.366 375.170,284.366 374.948 C 284.366 374.726,285.737 373.970,287.414 373.269 C 289.090 372.568,290.668 371.827,290.919 371.622 C 291.170 371.418,292.851 370.493,294.655 369.567 C 299.407 367.129,304.461 364.295,305.179 363.666 C 305.521 363.366,306.805 362.560,308.031 361.875 C 309.257 361.190,310.472 360.375,310.730 360.063 C 310.989 359.752,311.357 359.594,311.549 359.713 C 311.741 359.831,311.898 359.746,311.898 359.522 C 311.898 359.298,312.466 358.822,313.160 358.463 C 313.854 358.104,316.155 356.511,318.273 354.923 C 320.391 353.335,322.124 352.106,322.124 352.192 C 322.124 352.278,322.625 351.875,323.237 351.297 C 323.849 350.719,325.370 349.449,326.616 348.476 C 335.692 341.385,346.987 330.269,354.769 320.770 C 355.959 319.318,357.419 317.599,358.014 316.950 C 358.609 316.301,359.095 315.682,359.095 315.574 C 359.095 315.466,359.936 314.299,360.964 312.981 C 362.767 310.668,365.287 307.040,367.793 303.147 C 368.454 302.119,369.168 301.278,369.378 301.278 C 369.589 301.278,369.665 301.122,369.547 300.931 C 369.429 300.740,369.699 300.118,370.147 299.549 C 371.042 298.411,373.212 294.639,375.942 289.479 C 376.914 287.640,377.859 286.076,378.041 286.004 C 378.224 285.931,378.273 285.710,378.150 285.512 C 378.028 285.314,378.082 285.152,378.269 285.152 C 378.457 285.152,379.209 283.736,379.941 282.006 C 380.673 280.275,381.425 278.859,381.613 278.859 C 381.800 278.859,381.845 278.682,381.711 278.466 C 381.577 278.250,381.618 278.073,381.803 278.073 C 381.987 278.073,382.732 276.480,383.459 274.533 C 384.186 272.586,384.941 270.993,385.137 270.993 C 385.333 270.993,385.394 270.832,385.272 270.635 C 385.151 270.438,385.476 269.420,385.995 268.373 C 386.515 267.327,387.255 265.452,387.642 264.208 C 388.028 262.965,388.499 261.947,388.689 261.947 C 388.879 261.947,388.919 261.762,388.780 261.536 C 388.640 261.311,388.740 260.868,389.002 260.553 C 389.263 260.238,389.345 259.980,389.184 259.980 C 389.023 259.980,389.075 259.759,389.299 259.489 C 389.523 259.218,389.745 258.820,389.790 258.604 C 389.836 258.387,389.935 258.033,390.009 257.817 C 390.084 257.601,390.690 255.477,391.356 253.097 C 392.023 250.718,392.676 248.505,392.807 248.181 C 392.938 247.856,393.011 247.440,392.969 247.255 C 392.927 247.070,393.091 246.679,393.334 246.387 C 393.576 246.095,393.668 245.683,393.538 245.472 C 393.407 245.261,393.460 244.990,393.654 244.870 C 393.849 244.750,394.418 242.526,394.918 239.927 C 395.419 237.328,395.940 235.202,396.076 235.202 C 396.212 235.202,396.246 234.671,396.151 234.022 C 396.049 233.327,396.154 232.842,396.406 232.842 C 396.672 232.842,396.744 232.395,396.598 231.662 C 396.446 230.901,396.522 230.482,396.812 230.482 C 397.096 230.482,397.170 230.118,397.014 229.493 C 396.877 228.950,396.947 228.286,397.168 228.018 C 397.390 227.751,397.577 227.089,397.584 226.549 C 397.591 226.008,397.856 223.707,398.172 221.436 C 400.082 207.708,399.985 180.691,397.986 169.752 C 397.745 168.434,397.553 166.912,397.559 166.372 C 397.566 165.831,397.402 165.184,397.195 164.934 C 396.989 164.685,396.935 164.021,397.076 163.459 C 397.247 162.777,397.173 162.439,396.850 162.439 C 396.548 162.439,396.439 162.071,396.556 161.455 C 396.660 160.914,396.569 160.472,396.354 160.472 C 396.125 160.472,396.060 159.883,396.195 159.047 C 396.322 158.263,396.316 157.732,396.180 157.868 C 396.045 158.003,395.440 155.680,394.837 152.705 C 394.234 149.730,393.550 146.979,393.317 146.592 C 393.084 146.204,392.989 145.733,393.106 145.544 C 393.223 145.355,393.131 145.137,392.901 145.061 C 392.672 144.984,392.449 144.262,392.407 143.456 C 392.365 142.649,392.235 141.989,392.118 141.988 C 392.001 141.987,391.477 140.393,390.954 138.446 C 390.431 136.500,389.844 134.907,389.649 134.907 C 389.455 134.907,389.398 134.641,389.523 134.317 C 389.647 133.992,389.559 133.727,389.326 133.727 C 389.093 133.727,389.001 133.473,389.120 133.162 C 389.239 132.852,389.214 132.542,389.063 132.474 C 388.913 132.406,388.187 130.580,387.450 128.417 C 386.713 126.254,385.939 124.263,385.731 123.992 C 385.522 123.722,385.505 123.498,385.694 123.494 C 385.883 123.491,385.849 123.358,385.620 123.199 C 385.390 123.041,384.786 121.849,384.278 120.551 C 383.770 119.253,382.321 116.030,381.058 113.389 C 379.795 110.749,378.761 108.403,378.761 108.178 C 378.761 107.952,378.574 107.768,378.345 107.768 C 378.115 107.768,378.037 107.591,378.171 107.375 C 378.305 107.158,378.216 106.981,377.974 106.981 C 377.733 106.981,377.635 106.819,377.757 106.622 C 377.879 106.424,377.823 106.203,377.632 106.130 C 377.441 106.057,376.635 104.759,375.840 103.245 C 373.209 98.228,367.459 88.815,366.872 88.561 C 366.705 88.489,366.568 88.194,366.568 87.906 C 366.568 87.617,366.423 87.322,366.246 87.250 C 366.069 87.178,365.205 86.053,364.326 84.750 C 362.686 82.320,356.953 74.763,355.678 73.350 C 355.286 72.916,354.169 71.588,353.196 70.400 C 350.436 67.031,348.951 65.381,345.030 61.329 C 343.026 59.258,341.522 57.429,341.687 57.265 C 341.851 57.100,341.792 57.024,341.555 57.096 C 340.913 57.291,337.394 53.920,337.709 53.411 C 337.866 53.156,337.799 53.086,337.547 53.242 C 337.310 53.389,335.822 52.333,334.241 50.897 C 332.660 49.460,330.526 47.649,329.499 46.871 C 328.471 46.093,327.630 45.317,327.630 45.147 C 327.630 44.977,327.359 44.838,327.028 44.838 C 326.697 44.838,326.330 44.589,326.214 44.285 C 326.097 43.981,325.041 43.094,323.866 42.314 C 322.692 41.535,321.731 40.750,321.731 40.570 C 321.731 40.391,321.326 40.060,320.832 39.835 C 320.338 39.610,318.790 38.556,317.391 37.493 C 315.992 36.430,314.007 35.074,312.979 34.479 C 311.952 33.885,311.111 33.219,311.111 32.999 C 311.111 32.779,310.949 32.699,310.751 32.821 C 310.554 32.943,310.332 32.909,310.260 32.746 C 310.098 32.382,303.820 28.450,300.983 26.936 C 299.848 26.330,298.918 25.685,298.918 25.503 C 298.918 25.321,298.786 25.207,298.623 25.250 C 298.198 25.362,292.454 22.388,292.297 21.975 C 292.224 21.784,292.003 21.727,291.805 21.850 C 291.607 21.972,291.445 21.929,291.444 21.754 C 291.443 21.579,290.395 20.997,289.116 20.461 C 287.837 19.924,286.892 19.322,287.016 19.121 C 287.139 18.921,287.057 18.871,286.832 19.010 C 286.323 19.324,283.972 18.538,283.972 18.054 C 283.972 17.859,283.840 17.728,283.677 17.763 C 283.515 17.799,282.586 17.472,281.613 17.036 C 280.639 16.601,279.179 16.028,278.368 15.762 C 277.557 15.496,276.893 15.105,276.893 14.892 C 276.893 14.680,276.719 14.613,276.508 14.744 C 276.296 14.875,275.721 14.759,275.229 14.486 C 274.738 14.214,274.248 13.968,274.140 13.941 C 274.031 13.914,273.324 13.616,272.566 13.279 C 271.809 12.943,270.438 12.444,269.518 12.171 C 268.599 11.898,267.847 11.542,267.847 11.381 C 267.847 11.219,267.493 11.179,267.060 11.292 C 266.627 11.405,266.273 11.306,266.273 11.071 C 266.273 10.836,266.008 10.746,265.683 10.871 C 265.359 10.995,265.093 10.907,265.093 10.674 C 265.093 10.441,264.828 10.353,264.503 10.477 C 264.179 10.602,263.913 10.489,263.913 10.226 C 263.913 9.964,263.654 9.848,263.336 9.970 C 263.019 10.092,262.672 10.052,262.566 9.880 C 262.460 9.709,260.464 9.066,258.129 8.451 C 255.794 7.837,253.831 7.207,253.767 7.052 C 253.702 6.897,253.304 6.860,252.882 6.971 C 252.429 7.089,252.114 6.974,252.114 6.690 C 252.114 6.407,251.850 6.310,251.474 6.454 C 251.122 6.589,250.610 6.514,250.336 6.286 C 250.061 6.058,249.686 5.906,249.501 5.948 C 249.316 5.990,248.899 5.917,248.574 5.787 C 247.677 5.424,240.081 3.933,239.134 3.933 C 238.676 3.933,238.409 3.759,238.541 3.546 C 238.690 3.305,238.325 3.249,237.581 3.398 C 236.775 3.559,236.382 3.483,236.382 3.164 C 236.382 2.846,236.007 2.773,235.239 2.942 C 234.558 3.091,233.987 3.015,233.825 2.753 C 233.666 2.496,233.095 2.414,232.448 2.557 C 231.799 2.699,231.231 2.617,231.070 2.357 C 230.920 2.114,230.328 1.952,229.755 1.997 C 229.181 2.043,228.446 1.980,228.122 1.859 C 224.834 0.632,200.925 -0.230,188.201 0.421 M218.682 42.875 C 224.914 43.339,229.812 43.957,231.465 44.489 C 232.114 44.698,233.945 45.138,235.535 45.467 C 239.072 46.199,244.814 47.826,246.411 48.548 C 247.060 48.841,248.918 49.549,250.541 50.120 C 255.840 51.986,266.175 57.107,271.830 60.669 C 273.461 61.696,274.919 62.537,275.070 62.537 C 275.394 62.537,280.853 66.294,284.041 68.711 C 285.268 69.642,286.463 70.403,286.696 70.403 C 286.929 70.403,287.119 70.582,287.119 70.801 C 287.119 71.020,288.048 71.794,289.184 72.521 C 293.841 75.503,305.912 86.900,309.852 92.035 C 310.764 93.225,311.686 94.412,311.901 94.674 C 312.116 94.935,312.291 95.333,312.291 95.559 C 312.291 95.784,312.450 95.969,312.643 95.969 C 312.837 95.969,313.332 96.632,313.744 97.443 C 314.156 98.255,315.095 100.059,315.831 101.452 C 317.731 105.049,317.950 113.610,316.222 116.749 C 316.024 117.109,315.413 118.394,314.864 119.603 C 310.740 128.695,294.952 132.472,285.469 126.637 C 284.423 125.993,283.428 125.467,283.258 125.467 C 282.660 125.467,278.649 121.626,278.077 120.505 C 277.077 118.545,273.676 113.558,271.856 111.385 C 269.164 108.170,258.824 99.903,256.382 99.013 C 256.025 98.883,254.344 97.917,252.645 96.865 C 233.017 84.714,199.055 81.368,174.041 89.120 C 172.311 89.656,169.390 90.559,167.552 91.127 C 165.713 91.694,164.031 92.284,163.815 92.439 C 163.599 92.593,161.829 93.421,159.882 94.279 C 150.963 98.208,143.490 105.654,141.143 112.950 C 139.790 117.157,139.786 126.259,141.135 130.556 C 142.003 133.320,145.742 138.053,147.058 138.053 C 147.240 138.053,148.785 138.834,150.489 139.787 C 156.217 142.992,168.961 146.406,178.564 147.309 C 179.971 147.442,181.475 147.704,181.908 147.893 C 183.203 148.458,193.596 149.052,209.243 149.454 C 217.355 149.663,225.674 149.932,227.729 150.051 C 236.805 150.580,242.676 151.103,245.231 151.610 C 246.745 151.911,249.843 152.450,252.114 152.808 C 257.124 153.599,262.443 154.779,264.307 155.515 C 265.064 155.814,267.610 156.622,269.966 157.310 C 272.321 157.999,274.884 158.903,275.663 159.320 C 276.441 159.737,277.257 160.077,277.477 160.075 C 277.933 160.072,284.067 162.522,284.366 162.828 C 284.474 162.938,285.359 163.455,286.332 163.977 C 287.306 164.498,289.043 165.560,290.192 166.337 C 291.342 167.113,292.659 167.958,293.119 168.215 C 295.272 169.417,304.031 177.590,304.031 178.397 C 304.031 178.659,304.283 178.970,304.591 179.088 C 306.477 179.812,313.462 192.452,315.061 198.033 C 315.557 199.764,316.086 201.357,316.238 201.573 C 318.085 204.207,318.074 228.277,316.225 230.678 C 316.058 230.895,315.800 231.691,315.650 232.448 C 315.281 234.322,313.078 241.204,312.692 241.691 C 312.520 241.908,311.813 243.455,311.120 245.131 C 310.427 246.806,309.440 248.794,308.928 249.549 C 308.416 250.304,307.532 251.765,306.963 252.796 C 303.138 259.735,284.374 278.859,281.393 278.859 C 281.223 278.859,280.759 279.154,280.362 279.513 C 279.313 280.463,273.988 283.720,270.808 285.357 C 269.300 286.134,267.530 287.099,266.875 287.502 C 266.220 287.905,264.356 288.768,262.734 289.419 C 261.111 290.070,259.040 290.969,258.131 291.417 C 257.222 291.865,256.316 292.232,256.117 292.232 C 255.918 292.232,255.638 293.073,255.495 294.100 C 255.094 296.985,252.850 299.994,249.951 301.534 L 247.591 302.788 200.683 302.820 C 172.948 302.838,153.496 302.704,153.092 302.491 C 152.716 302.293,151.828 301.915,151.117 301.651 C 148.298 300.605,146.283 297.275,145.686 292.677 L 145.412 290.565 143.208 289.611 C 139.934 288.195,134.152 285.201,132.277 283.951 C 131.372 283.347,130.024 282.566,129.282 282.213 C 127.557 281.395,117.393 273.865,115.809 272.232 C 115.148 271.551,114.396 270.993,114.137 270.993 C 113.495 270.993,99.508 256.963,99.508 256.318 C 99.508 256.034,98.977 255.409,98.328 254.929 C 97.679 254.450,97.148 253.860,97.148 253.620 C 97.148 253.379,96.384 252.278,95.449 251.173 C 93.732 249.145,89.266 242.948,88.014 240.857 C 87.641 240.234,86.357 238.132,85.161 236.185 C 83.964 234.238,82.718 232.068,82.391 231.364 C 82.064 230.659,81.169 228.800,80.402 227.234 C 79.636 225.667,78.470 222.970,77.813 221.239 C 77.156 219.508,76.276 217.354,75.858 216.452 C 75.440 215.549,74.433 212.185,73.620 208.976 C 72.806 205.766,72.033 202.965,71.902 202.750 C 70.707 200.793,69.226 185.114,69.225 174.399 C 69.223 163.630,70.871 145.980,71.958 145.133 C 72.097 145.025,72.442 143.697,72.725 142.183 C 73.373 138.715,75.581 130.056,75.884 129.794 C 76.009 129.685,76.622 128.004,77.247 126.057 C 77.872 124.110,78.694 121.898,79.073 121.141 C 79.452 120.383,81.041 117.152,82.603 113.959 C 84.166 110.766,86.756 106.252,88.358 103.929 C 89.960 101.606,91.575 99.191,91.948 98.564 C 95.921 91.871,114.620 73.320,121.987 68.762 C 122.994 68.139,123.918 67.369,124.040 67.050 C 124.162 66.731,124.448 66.470,124.674 66.470 C 124.901 66.470,126.278 65.605,127.735 64.548 C 129.192 63.491,131.357 62.094,132.547 61.444 C 133.736 60.794,136.450 59.270,138.578 58.056 C 140.705 56.843,142.556 55.851,142.691 55.851 C 142.970 55.851,148.839 53.426,151.229 52.324 C 152.094 51.925,154.218 51.155,155.949 50.613 C 157.679 50.071,159.980 49.328,161.062 48.962 C 162.144 48.596,165.772 47.686,169.125 46.941 C 172.478 46.195,176.726 45.247,178.564 44.832 C 187.530 42.813,205.844 41.919,218.682 42.875 M112.127 158.644 C 110.939 162.358,110.697 177.745,111.708 185.251 C 112.458 190.818,115.318 203.165,116.298 205.058 C 116.629 205.700,117.225 207.125,117.623 208.225 C 118.020 209.326,118.606 210.940,118.925 211.813 C 119.559 213.547,122.776 219.258,124.668 222.007 C 125.324 222.960,125.860 223.854,125.860 223.992 C 125.860 224.130,127.053 225.771,128.512 227.639 C 135.059 236.024,145.323 244.545,154.472 249.193 C 155.933 249.936,157.306 250.675,157.522 250.837 C 157.738 250.999,158.977 251.606,160.275 252.187 C 161.573 252.769,163.786 253.762,165.192 254.395 C 166.598 255.027,169.607 256.110,171.878 256.799 C 174.149 257.489,176.663 258.305,177.464 258.613 C 189.252 263.141,219.453 263.148,230.482 258.625 C 231.239 258.315,233.628 257.502,235.792 256.819 C 251.106 251.983,266.854 240.556,274.921 228.424 C 281.680 218.261,279.922 206.384,270.814 200.682 C 269.939 200.134,269.135 199.557,269.027 199.399 C 268.614 198.798,260.856 194.779,258.604 193.999 C 250.836 191.309,248.866 190.897,234.415 188.942 C 230.413 188.401,225.988 187.800,224.582 187.608 C 223.176 187.415,214.503 187.248,205.310 187.237 C 196.116 187.225,186.205 187.040,183.284 186.826 C 173.756 186.126,163.599 184.815,161.849 184.058 C 161.416 183.871,160.000 183.519,158.702 183.276 C 155.478 182.672,148.565 180.887,148.083 180.534 C 147.866 180.376,146.362 179.791,144.739 179.233 C 139.580 177.460,138.720 177.091,134.984 175.054 C 132.972 173.956,131.158 173.058,130.953 173.058 C 130.748 173.058,130.580 172.889,130.580 172.683 C 130.580 172.477,129.978 172.023,129.243 171.674 C 127.667 170.926,120.333 164.840,115.750 160.478 L 112.522 157.406 112.127 158.644 M245.244 306.961 C 253.113 310.249,253.675 322.620,246.132 326.489 C 244.341 327.407,159.116 327.683,156.523 326.779 C 149.499 324.331,149.181 312.136,156.024 307.603 L 157.854 306.391 200.867 306.391 C 237.535 306.391,244.081 306.475,245.244 306.961 M238.902 332.290 C 240.180 333.092,241.419 334.090,241.655 334.509 C 241.891 334.928,242.526 335.985,243.066 336.858 C 244.342 338.921,244.460 343.639,243.284 345.526 C 241.222 348.835,240.431 349.792,238.725 351.044 L 236.866 352.409 231.412 352.419 L 225.959 352.429 225.248 353.972 C 220.338 364.625,200.029 368.942,186.234 362.265 C 182.722 360.565,177.033 355.580,176.428 353.672 C 176.161 352.832,175.972 352.802,170.942 352.802 C 164.236 352.802,161.642 351.614,159.357 347.493 C 158.394 345.758,158.436 338.178,159.418 336.361 C 160.392 334.560,163.005 332.027,164.198 331.727 C 164.745 331.590,165.192 331.320,165.192 331.127 C 165.192 330.924,180.224 330.788,200.885 330.804 L 236.578 330.832 238.902 332.290 \" stroke=\"none\" fill=\"#fcfbfb\" fill-rule=\"evenodd\"><\/path><path id=\"path2\" d=\"M203.048 42.771 C 204.941 42.843,208.038 42.843,209.931 42.771 C 211.824 42.699,210.275 42.640,206.490 42.640 C 202.704 42.640,201.155 42.699,203.048 42.771 M194.206 43.156 C 194.913 43.244,195.975 43.242,196.566 43.152 C 197.157 43.062,196.578 42.991,195.280 42.993 C 193.982 42.995,193.499 43.069,194.206 43.156 M216.421 43.153 C 217.016 43.243,217.989 43.243,218.584 43.153 C 219.179 43.063,218.692 42.989,217.502 42.989 C 216.313 42.989,215.826 43.063,216.421 43.153 M236.185 45.973 C 237.392 46.488,239.838 46.907,239.135 46.479 C 238.810 46.281,237.837 46.010,236.971 45.878 C 235.947 45.721,235.672 45.754,236.185 45.973 M171.288 46.429 C 170.740 46.678,170.978 46.713,172.075 46.546 C 172.940 46.414,173.722 46.242,173.812 46.162 C 174.150 45.864,172.043 46.087,171.288 46.429 M244.051 48.378 C 244.484 48.563,245.103 48.716,245.428 48.716 C 245.800 48.716,245.727 48.591,245.231 48.378 C 244.798 48.192,244.179 48.040,243.854 48.040 C 243.483 48.040,243.555 48.165,244.051 48.378 M246.608 49.098 C 246.932 49.298,247.640 49.581,248.181 49.725 C 248.864 49.908,248.984 49.877,248.574 49.624 C 248.250 49.423,247.542 49.141,247.001 48.996 C 246.318 48.814,246.198 48.845,246.608 49.098 M148.476 53.661 C 145.892 54.906,146.396 54.944,149.114 53.710 C 150.277 53.182,151.052 52.741,150.836 52.732 C 150.619 52.722,149.558 53.140,148.476 53.661 M257.227 53.491 C 257.984 53.905,258.781 54.244,258.997 54.244 C 259.213 54.244,258.771 53.905,258.014 53.491 C 257.257 53.076,256.460 52.737,256.244 52.737 C 256.028 52.737,256.470 53.076,257.227 53.491 M260.374 54.880 C 260.374 54.976,261.834 55.767,263.618 56.638 C 265.403 57.509,266.467 57.933,265.982 57.581 C 264.944 56.826,260.374 54.625,260.374 54.880 M140.708 57.057 C 139.897 57.486,139.233 57.924,139.233 58.031 C 139.233 58.206,142.340 56.755,142.740 56.392 C 143.193 55.983,142.011 56.369,140.708 57.057 M134.402 60.512 C 133.367 61.121,132.305 61.845,132.042 62.120 C 131.779 62.395,132.448 62.094,133.530 61.450 C 134.612 60.806,135.851 60.085,136.283 59.847 C 136.716 59.609,136.893 59.412,136.676 59.409 C 136.460 59.406,135.436 59.902,134.402 60.512 M274.533 62.653 C 274.533 62.742,275.772 63.639,277.286 64.646 C 278.800 65.652,280.039 66.393,280.039 66.291 C 280.039 66.189,279.022 65.422,277.778 64.587 C 275.023 62.736,274.533 62.444,274.533 62.653 M126.767 65.523 L 125.664 66.542 126.942 65.693 C 128.113 64.915,128.494 64.503,128.046 64.503 C 127.949 64.503,127.374 64.962,126.767 65.523 M120.810 69.834 C 118.429 71.685,116.247 73.494,115.960 73.855 C 115.673 74.216,116.765 73.446,118.387 72.145 C 120.010 70.844,122.266 69.108,123.402 68.288 C 125.281 66.931,125.763 66.470,125.302 66.470 C 125.212 66.470,123.190 67.984,120.810 69.834 M281.613 67.432 C 281.613 67.511,282.490 68.206,283.562 68.977 C 284.634 69.747,285.423 70.162,285.315 69.898 C 285.133 69.455,281.613 67.109,281.613 67.432 M286.579 71.105 C 287.040 71.476,289.419 73.370,291.866 75.313 C 299.930 81.714,308.266 90.268,312.091 96.067 C 313.717 98.533,314.235 99.006,313.275 97.150 C 310.580 91.938,288.529 70.302,286.029 70.416 C 285.871 70.423,286.119 70.733,286.579 71.105 M113.840 75.615 L 112.684 76.893 113.963 75.738 C 115.154 74.661,115.422 74.336,115.118 74.336 C 115.050 74.336,114.475 74.912,113.840 75.615 M110.521 78.466 C 109.566 79.440,108.873 80.236,108.981 80.236 C 109.089 80.236,109.959 79.440,110.914 78.466 C 111.870 77.493,112.563 76.696,112.455 76.696 C 112.347 76.696,111.477 77.493,110.521 78.466 M104.871 83.612 C 104.251 84.157,103.822 84.680,103.916 84.775 C 104.011 84.870,104.596 84.418,105.215 83.772 C 106.584 82.343,106.407 82.261,104.871 83.612 M198.530 84.841 C 199.019 84.935,199.727 84.931,200.103 84.833 C 200.479 84.734,200.079 84.657,199.213 84.662 C 198.348 84.666,198.040 84.747,198.530 84.841 M211.116 84.841 C 211.605 84.935,212.313 84.931,212.689 84.833 C 213.065 84.734,212.665 84.657,211.799 84.662 C 210.934 84.666,210.626 84.747,211.116 84.841 M181.121 86.922 C 180.061 87.192,180.041 87.223,180.924 87.230 C 181.465 87.234,182.350 87.096,182.891 86.922 C 184.213 86.499,182.785 86.499,181.121 86.922 M228.319 87.147 C 229.400 87.448,230.639 87.682,231.072 87.668 C 231.504 87.654,230.885 87.399,229.695 87.102 C 226.880 86.400,225.764 86.436,228.319 87.147 M100.295 88.692 C 99.340 89.666,98.646 90.462,98.755 90.462 C 98.863 90.462,99.733 89.666,100.688 88.692 C 101.644 87.719,102.337 86.922,102.229 86.922 C 102.121 86.922,101.250 87.719,100.295 88.692 M165.585 91.268 C 164.612 91.667,164.081 91.992,164.405 91.992 C 164.730 91.992,165.792 91.657,166.765 91.249 C 167.738 90.840,168.269 90.515,167.945 90.525 C 167.620 90.535,166.559 90.870,165.585 91.268 M240.708 90.669 C 240.708 90.898,241.961 91.406,243.461 91.785 C 244.002 91.922,243.736 91.693,242.871 91.277 C 241.201 90.474,240.708 90.335,240.708 90.669 M96.362 93.215 C 95.456 94.297,94.804 95.182,94.912 95.182 C 95.020 95.182,95.850 94.297,96.755 93.215 C 97.661 92.134,98.313 91.249,98.205 91.249 C 98.097 91.249,97.267 92.134,96.362 93.215 M157.758 94.613 C 157.022 94.933,156.519 95.293,156.639 95.414 C 156.866 95.640,159.292 94.520,159.292 94.189 C 159.292 93.945,159.310 93.939,157.758 94.613 M249.332 94.684 C 250.370 95.440,252.507 96.429,252.507 96.153 C 252.507 96.059,251.578 95.533,250.442 94.985 C 249.269 94.419,248.789 94.289,249.332 94.684 M93.754 96.460 C 92.278 98.139,89.502 102.262,89.848 102.262 C 89.954 102.262,90.779 101.155,91.684 99.803 C 92.588 98.451,93.687 96.947,94.127 96.460 C 94.566 95.973,94.837 95.575,94.729 95.575 C 94.621 95.575,94.182 95.973,93.754 96.460 M151.622 98.405 C 149.944 99.598,146.468 102.969,145.011 104.818 C 144.329 105.683,145.273 104.874,147.107 103.018 C 148.942 101.163,151.062 99.180,151.819 98.612 C 153.465 97.377,153.305 97.209,151.622 98.405 M255.261 98.033 C 256.121 98.853,261.294 102.009,261.000 101.534 C 260.863 101.312,259.383 100.307,257.711 99.300 C 256.039 98.293,254.936 97.723,255.261 98.033 M314.928 100.874 C 315.509 102.058,316.050 102.960,316.131 102.880 C 316.307 102.703,314.323 98.722,314.059 98.722 C 313.956 98.722,314.348 99.690,314.928 100.874 M262.734 102.778 C 262.734 102.875,263.383 103.450,264.177 104.056 C 264.972 104.662,265.497 104.957,265.345 104.711 C 265.034 104.208,262.734 102.505,262.734 102.778 M269.063 108.187 C 270.922 110.011,272.958 112.132,273.586 112.899 C 274.215 113.666,274.559 114.020,274.351 113.685 C 273.330 112.046,270.365 108.828,268.153 106.957 C 266.082 105.205,266.228 105.404,269.063 108.187 M85.183 109.231 C 84.409 110.468,83.776 111.662,83.777 111.885 C 83.778 112.109,84.151 111.672,84.605 110.914 C 85.060 110.157,85.782 108.963,86.209 108.260 C 86.637 107.557,86.897 106.981,86.788 106.981 C 86.679 106.981,85.957 107.993,85.183 109.231 M141.751 109.980 C 141.213 111.197,140.840 112.259,140.922 112.341 C 141.003 112.422,141.528 111.427,142.089 110.129 C 142.649 108.830,143.022 107.768,142.918 107.768 C 142.815 107.768,142.289 108.763,141.751 109.980 M80.764 117.823 C 80.213 119.026,79.831 120.080,79.914 120.164 C 79.998 120.247,80.533 119.263,81.102 117.975 C 81.671 116.688,82.053 115.634,81.951 115.634 C 81.849 115.634,81.315 116.619,80.764 117.823 M276.674 117.871 C 277.008 118.560,277.476 119.245,277.716 119.393 C 278.244 119.719,277.675 118.599,276.706 117.404 C 276.114 116.674,276.112 116.707,276.674 117.871 M314.642 118.965 C 314.097 120.126,313.790 120.990,313.960 120.885 C 314.430 120.594,315.894 117.589,315.756 117.198 C 315.689 117.009,315.188 117.804,314.642 118.965 M139.359 121.534 C 139.359 122.940,139.430 123.515,139.518 122.812 C 139.605 122.109,139.605 120.959,139.518 120.256 C 139.430 119.553,139.359 120.128,139.359 121.534 M278.794 121.007 C 279.993 122.750,284.772 126.647,285.710 126.647 C 285.921 126.647,285.292 126.139,284.312 125.518 C 283.333 124.896,281.498 123.348,280.235 122.076 C 278.897 120.729,278.296 120.283,278.794 121.007 M309.599 125.197 C 309.363 125.482,308.279 126.131,307.192 126.641 C 306.104 127.150,305.284 127.637,305.370 127.723 C 305.619 127.972,309.337 125.986,309.906 125.301 C 310.189 124.960,310.332 124.680,310.224 124.680 C 310.116 124.680,309.834 124.913,309.599 125.197 M77.380 125.736 C 77.280 125.913,77.093 126.588,76.964 127.237 C 76.730 128.411,76.732 128.410,77.322 127.093 C 77.837 125.945,77.883 124.846,77.380 125.736 M294.405 129.083 C 295.708 129.254,297.832 129.254,299.125 129.082 C 301.135 128.816,300.792 128.771,296.755 128.771 C 292.703 128.772,292.371 128.816,294.405 129.083 M75.741 130.805 C 75.596 131.381,75.554 131.929,75.647 132.021 C 75.739 132.114,75.933 131.718,76.078 131.142 C 76.223 130.566,76.265 130.018,76.173 129.925 C 76.080 129.833,75.886 130.228,75.741 130.805 M141.544 132.815 C 141.997 133.720,142.582 134.592,142.842 134.753 C 143.103 134.914,142.900 134.351,142.392 133.501 C 141.063 131.282,140.580 130.890,141.544 132.815 M145.100 137.027 C 145.407 137.399,146.027 137.899,146.477 138.139 C 147.222 138.536,147.246 138.514,146.738 137.899 C 146.432 137.528,145.812 137.027,145.362 136.787 C 144.617 136.390,144.593 136.412,145.100 137.027 M73.187 140.050 C 72.945 141.178,72.822 142.176,72.913 142.267 C 73.005 142.359,73.277 141.511,73.519 140.383 C 73.761 139.255,73.884 138.257,73.793 138.165 C 73.701 138.074,73.429 138.922,73.187 140.050 M148.673 139.489 C 148.673 139.751,154.612 142.471,154.792 142.291 C 154.872 142.211,153.528 141.505,151.805 140.722 C 150.082 139.940,148.673 139.385,148.673 139.489 M165.192 145.526 C 165.733 145.699,166.529 145.841,166.962 145.841 C 167.585 145.841,167.544 145.775,166.765 145.526 C 166.224 145.353,165.428 145.211,164.995 145.211 C 164.372 145.211,164.413 145.277,165.192 145.526 M184.169 148.550 C 184.548 148.649,185.167 148.649,185.546 148.550 C 185.924 148.451,185.615 148.371,184.857 148.371 C 184.100 148.371,183.791 148.451,184.169 148.550 M189.288 148.955 C 189.885 149.045,190.770 149.043,191.254 148.949 C 191.738 148.856,191.249 148.782,190.167 148.785 C 189.086 148.788,188.690 148.864,189.288 148.955 M197.050 149.465 C 201.916 149.771,213.413 149.945,213.143 149.709 C 213.053 149.630,208.378 149.479,202.753 149.373 C 196.750 149.260,194.395 149.298,197.050 149.465 M218.584 150.142 C 219.720 150.222,221.578 150.222,222.714 150.142 C 223.850 150.063,222.920 149.998,220.649 149.998 C 218.378 149.998,217.448 150.063,218.584 150.142 M248.771 152.606 C 249.420 152.771,250.482 152.907,251.131 152.907 C 252.123 152.908,252.060 152.857,250.737 152.583 C 248.745 152.171,247.135 152.190,248.771 152.606 M253.491 153.392 C 255.154 153.816,256.582 153.816,255.261 153.392 C 254.720 153.219,253.835 153.081,253.294 153.085 C 252.411 153.091,252.431 153.123,253.491 153.392 M266.667 156.735 C 267.424 157.027,268.309 157.266,268.633 157.266 C 268.958 157.266,268.604 157.027,267.847 156.735 C 267.089 156.444,266.205 156.205,265.880 156.205 C 265.556 156.205,265.910 156.444,266.667 156.735 M70.101 158.112 C 70.101 158.869,70.182 159.179,70.281 158.800 C 70.380 158.422,70.380 157.802,70.281 157.424 C 70.182 157.045,70.101 157.355,70.101 158.112 M114.095 158.800 C 114.334 159.179,114.999 159.826,115.574 160.239 C 116.401 160.834,116.337 160.691,115.262 159.551 C 113.771 157.968,113.433 157.751,114.095 158.800 M274.959 159.454 C 275.275 159.767,279.404 161.238,279.551 161.091 C 279.633 161.009,278.708 160.571,277.495 160.117 C 275.346 159.313,274.626 159.125,274.959 159.454 M69.480 163.119 C 69.342 164.583,69.254 167.198,69.284 168.928 C 69.326 171.323,69.417 170.717,69.664 166.394 C 70.006 160.410,69.906 158.616,69.480 163.119 M118.205 162.537 C 118.792 163.240,119.559 163.972,119.911 164.163 C 120.263 164.354,119.851 163.779,118.996 162.885 C 117.137 160.941,116.719 160.757,118.205 162.537 M283.612 162.971 C 284.138 163.418,287.512 165.233,287.512 165.070 C 287.512 164.829,284.144 162.832,283.739 162.832 C 283.579 162.832,283.522 162.894,283.612 162.971 M110.797 167.120 C 110.645 169.155,110.548 172.429,110.580 174.397 C 110.625 177.088,110.722 176.318,110.970 171.288 C 111.335 163.898,111.229 161.331,110.797 167.120 M123.107 166.495 C 123.107 166.603,123.992 167.433,125.074 168.338 C 126.155 169.244,127.040 169.896,127.040 169.788 C 127.040 169.680,126.155 168.851,125.074 167.945 C 123.992 167.039,123.107 166.387,123.107 166.495 M291.052 167.288 C 291.052 167.360,291.893 167.993,292.920 168.696 L 294.789 169.975 293.215 168.572 C 291.830 167.338,291.052 166.876,291.052 167.288 M128.195 170.720 C 129.317 171.671,133.769 174.327,133.946 174.150 C 134.012 174.083,132.530 173.102,130.652 171.968 C 128.774 170.835,127.668 170.273,128.195 170.720 M298.304 173.089 C 300.237 174.911,303.202 178.136,304.892 180.256 C 308.115 184.300,309.171 185.134,306.293 181.363 C 304.074 178.456,299.229 173.378,296.768 171.382 C 295.679 170.499,296.370 171.267,298.304 173.089 M134.513 174.433 C 134.513 174.696,139.281 177.074,139.457 176.898 C 139.536 176.819,138.456 176.190,137.057 175.500 C 135.658 174.810,134.513 174.330,134.513 174.433 M69.367 180.728 C 69.368 182.891,69.434 183.726,69.514 182.583 C 69.593 181.440,69.592 179.670,69.512 178.650 C 69.431 177.629,69.366 178.564,69.367 180.728 M111.044 180.728 C 111.045 182.242,111.116 182.813,111.201 181.997 C 111.287 181.181,111.285 179.942,111.198 179.244 C 111.111 178.546,111.042 179.213,111.044 180.728 M144.297 178.962 C 145.244 179.398,146.483 179.848,147.051 179.962 C 147.618 180.076,147.198 179.807,146.116 179.365 C 143.426 178.264,142.183 177.989,144.297 178.962 M156.342 182.705 C 157.207 182.990,158.269 183.221,158.702 183.219 C 159.135 183.216,158.604 182.968,157.522 182.667 C 155.061 181.982,154.230 182.009,156.342 182.705 M111.399 185.251 C 111.399 186.008,111.480 186.318,111.579 185.939 C 111.678 185.560,111.678 184.941,111.579 184.562 C 111.480 184.184,111.399 184.494,111.399 185.251 M69.729 186.627 C 69.732 187.709,69.808 188.105,69.899 187.507 C 69.989 186.909,69.987 186.024,69.893 185.540 C 69.800 185.057,69.726 185.546,69.729 186.627 M174.336 185.915 C 174.715 186.014,175.334 186.014,175.713 185.915 C 176.091 185.816,175.782 185.735,175.025 185.735 C 174.267 185.735,173.958 185.816,174.336 185.915 M179.154 186.436 C 181.161 186.762,185.908 186.941,185.611 186.680 C 185.521 186.601,183.589 186.442,181.318 186.327 C 178.533 186.186,177.828 186.222,179.154 186.436 M187.897 187.108 C 188.595 187.195,189.834 187.196,190.650 187.111 C 191.466 187.026,190.895 186.955,189.381 186.953 C 187.866 186.951,187.199 187.021,187.897 187.108 M210.718 187.117 C 212.502 187.189,215.423 187.189,217.207 187.117 C 218.992 187.044,217.532 186.984,213.963 186.984 C 210.393 186.984,208.933 187.044,210.718 187.117 M311.227 190.016 C 312.137 191.880,312.946 193.349,313.026 193.280 C 313.228 193.106,310.938 188.367,310.190 187.414 C 309.850 186.981,310.317 188.152,311.227 190.016 M223.500 187.488 C 223.879 187.587,224.499 187.587,224.877 187.488 C 225.256 187.389,224.946 187.309,224.189 187.309 C 223.432 187.309,223.122 187.389,223.500 187.488 M70.101 190.364 C 70.101 191.121,70.182 191.431,70.281 191.052 C 70.380 190.674,70.380 190.054,70.281 189.676 C 70.182 189.297,70.101 189.607,70.101 190.364 M244.838 190.364 C 245.487 190.529,246.460 190.664,247.001 190.664 C 247.878 190.664,247.857 190.632,246.804 190.364 C 246.155 190.199,245.182 190.064,244.641 190.064 C 243.764 190.064,243.785 190.096,244.838 190.364 M257.653 193.280 C 257.743 193.370,259.493 194.170,261.542 195.058 C 263.591 195.947,265.095 196.504,264.885 196.296 C 264.675 196.089,263.028 195.289,261.224 194.518 C 258.135 193.198,257.270 192.899,257.653 193.280 M314.121 196.264 C 314.570 198.035,315.489 200.199,315.226 198.863 C 315.102 198.238,314.748 197.176,314.437 196.504 C 314.012 195.583,313.934 195.524,314.121 196.264 M266.470 197.328 C 266.686 197.550,267.824 198.368,268.999 199.146 C 271.559 200.841,275.397 204.508,276.531 206.344 C 277.516 207.938,277.928 208.105,277.133 206.588 C 276.218 204.840,273.846 202.284,271.453 200.466 C 269.213 198.764,265.735 196.574,266.470 197.328 M114.694 201.573 C 115.018 203.019,115.243 203.333,115.235 202.327 C 115.232 201.912,115.049 201.308,114.830 200.983 C 114.538 200.552,114.502 200.712,114.694 201.573 M72.819 205.506 C 72.823 206.327,73.865 209.341,73.907 208.653 C 73.920 208.437,73.680 207.463,73.373 206.490 C 73.067 205.516,72.817 205.074,72.819 205.506 M117.742 210.029 C 118.040 211.134,120.467 216.341,120.615 216.193 C 120.696 216.112,120.047 214.559,119.173 212.743 C 118.298 210.926,117.655 209.705,117.742 210.029 M317.553 215.929 C 317.553 218.417,317.617 219.435,317.695 218.191 C 317.773 216.947,317.773 214.912,317.695 213.668 C 317.617 212.424,317.553 213.441,317.553 215.929 M76.911 218.781 C 77.058 219.267,77.340 219.839,77.538 220.050 C 77.736 220.261,77.698 219.863,77.455 219.165 C 76.957 217.736,76.497 217.412,76.911 218.781 M122.543 219.764 C 124.279 222.755,126.701 226.232,126.906 226.028 C 127.009 225.924,126.483 225.039,125.737 224.061 C 124.991 223.084,123.815 221.296,123.125 220.090 C 122.434 218.883,121.777 217.896,121.664 217.896 C 121.552 217.896,121.947 218.736,122.543 219.764 M78.691 222.812 C 78.691 223.029,78.944 223.648,79.253 224.189 C 79.562 224.730,79.815 224.995,79.815 224.779 C 79.815 224.562,79.562 223.943,79.253 223.402 C 78.944 222.861,78.691 222.596,78.691 222.812 M277.350 224.402 C 276.691 225.849,276.817 226.157,277.529 224.842 C 277.862 224.228,278.061 223.652,277.971 223.562 C 277.881 223.472,277.601 223.850,277.350 224.402 M79.843 225.537 C 79.843 225.986,82.999 232.193,83.458 232.645 C 83.809 232.991,80.379 225.819,79.994 225.402 C 79.911 225.311,79.843 225.372,79.843 225.537 M131.170 231.662 C 132.015 232.527,132.795 233.235,132.903 233.235 C 133.011 233.235,132.408 232.527,131.563 231.662 C 130.718 230.796,129.939 230.088,129.831 230.088 C 129.722 230.088,130.325 230.796,131.170 231.662 M272.250 232.547 C 269.860 235.548,263.739 241.506,260.669 243.819 C 258.271 245.625,257.524 246.499,259.685 244.970 C 264.292 241.711,275.779 230.088,274.393 230.088 C 274.291 230.088,273.327 231.195,272.250 232.547 M314.687 234.451 C 314.421 235.338,314.276 236.137,314.364 236.226 C 314.452 236.314,314.743 235.660,315.008 234.773 C 315.274 233.885,315.420 233.086,315.331 232.998 C 315.243 232.909,314.953 233.563,314.687 234.451 M84.366 234.415 C 84.701 235.064,85.064 235.595,85.173 235.595 C 85.281 235.595,85.095 235.064,84.759 234.415 C 84.424 233.766,84.060 233.235,83.952 233.235 C 83.844 233.235,84.030 233.766,84.366 234.415 M132.940 233.728 C 132.940 233.828,134.400 235.216,136.185 236.814 C 137.970 238.411,139.184 239.406,138.883 239.025 C 138.214 238.176,132.940 233.476,132.940 233.728 M87.300 239.382 C 87.792 240.276,88.621 241.515,89.144 242.136 C 89.666 242.756,89.376 242.125,88.499 240.732 C 86.619 237.745,86.040 237.094,87.300 239.382 M311.027 244.195 C 310.675 245.089,310.457 245.821,310.543 245.821 C 310.858 245.821,311.941 243.393,311.806 242.988 C 311.729 242.757,311.378 243.300,311.027 244.195 M145.133 243.995 C 145.133 244.200,149.293 246.930,151.607 248.245 C 154.014 249.612,153.098 248.896,148.756 246.017 C 145.658 243.962,145.133 243.669,145.133 243.995 M256.244 247.001 C 255.379 247.632,254.546 248.156,254.393 248.165 C 254.095 248.182,251.288 250.031,250.944 250.437 C 250.627 250.811,254.461 248.593,256.342 247.313 C 257.262 246.688,258.014 246.097,258.014 245.999 C 258.014 245.724,257.924 245.775,256.244 247.001 M158.112 251.721 C 159.735 252.565,161.239 253.255,161.455 253.255 C 161.672 253.255,160.521 252.565,158.899 251.721 C 157.276 250.877,155.772 250.186,155.556 250.186 C 155.339 250.186,156.490 250.877,158.112 251.721 M95.395 250.934 C 97.713 255.156,114.336 271.648,120.354 275.696 C 122.388 277.064,121.085 275.886,116.224 271.962 C 111.145 267.860,103.737 260.531,99.344 255.261 C 95.795 251.002,94.884 250.004,95.395 250.934 M246.608 252.507 C 244.553 253.567,243.007 254.443,243.174 254.454 C 243.592 254.482,250.541 250.972,250.541 250.734 C 250.541 250.466,250.745 250.374,246.608 252.507 M307.201 251.444 C 306.906 251.921,306.406 252.709,306.089 253.196 C 305.773 253.682,305.599 254.081,305.703 254.081 C 306.012 254.081,308.096 250.934,307.910 250.748 C 307.815 250.654,307.497 250.967,307.201 251.444 M163.618 254.277 C 164.159 254.586,164.779 254.839,164.995 254.839 C 165.211 254.839,164.946 254.586,164.405 254.277 C 163.864 253.968,163.245 253.715,163.029 253.715 C 162.812 253.715,163.078 253.968,163.618 254.277 M303.067 257.522 C 301.816 259.199,301.150 260.249,301.587 259.856 C 302.402 259.123,305.780 254.474,305.498 254.474 C 305.411 254.474,304.317 255.846,303.067 257.522 M167.552 255.737 C 167.660 255.843,168.364 256.138,169.116 256.393 C 169.868 256.647,170.311 256.686,170.099 256.479 C 169.888 256.272,169.184 255.977,168.535 255.823 C 167.886 255.669,167.443 255.630,167.552 255.737 M237.955 256.274 L 236.971 256.867 237.955 256.606 C 239.382 256.228,240.317 255.677,239.528 255.680 C 239.204 255.681,238.496 255.948,237.955 256.274 M231.858 258.407 C 231.363 258.620,231.290 258.745,231.662 258.745 C 231.986 258.745,232.606 258.593,233.038 258.407 C 233.534 258.194,233.607 258.069,233.235 258.069 C 232.911 258.069,232.291 258.221,231.858 258.407 M179.777 259.732 C 179.867 259.811,180.649 259.984,181.514 260.116 C 182.611 260.282,182.849 260.247,182.301 259.999 C 181.546 259.657,179.439 259.434,179.777 259.732 M224.975 260.177 C 224.002 260.459,223.471 260.704,223.795 260.721 C 224.120 260.738,225.270 260.506,226.352 260.205 C 227.434 259.904,227.965 259.659,227.532 259.661 C 227.099 259.663,225.949 259.895,224.975 260.177 M198.136 262.618 C 198.626 262.712,199.334 262.709,199.710 262.610 C 200.086 262.512,199.685 262.435,198.820 262.439 C 197.955 262.444,197.647 262.524,198.136 262.618 M208.756 262.618 C 209.245 262.712,209.953 262.709,210.329 262.610 C 210.705 262.512,210.305 262.435,209.440 262.439 C 208.574 262.444,208.267 262.524,208.756 262.618 M294.779 267.141 C 293.054 268.916,292.527 269.580,293.609 268.616 C 295.545 266.890,298.369 263.913,298.070 263.913 C 297.986 263.913,296.505 265.366,294.779 267.141 M289.651 271.878 L 288.496 273.156 289.774 272.001 C 290.477 271.366,291.052 270.791,291.052 270.723 C 291.052 270.419,290.728 270.687,289.651 271.878 M280.525 278.747 C 279.387 279.524,278.533 280.238,278.629 280.334 C 278.832 280.536,282.242 278.252,282.599 277.674 C 282.942 277.119,282.824 277.180,280.525 278.747 M123.500 277.838 C 123.500 277.946,124.297 278.583,125.270 279.253 C 126.244 279.922,127.040 280.382,127.040 280.274 C 127.040 280.166,126.244 279.529,125.270 278.859 C 124.297 278.190,123.500 277.730,123.500 277.838 M128.741 281.500 C 129.037 281.979,132.311 283.972,132.803 283.972 C 133.148 283.972,132.357 283.413,130.019 282.001 C 129.169 281.489,128.594 281.263,128.741 281.500 M272.468 283.804 C 270.998 284.602,271.087 284.934,272.566 284.169 C 273.215 283.834,273.746 283.475,273.746 283.372 C 273.746 283.119,273.704 283.134,272.468 283.804 M135.300 285.347 C 135.300 285.610,140.854 288.382,141.029 288.207 C 141.108 288.129,139.851 287.411,138.236 286.612 C 136.621 285.813,135.300 285.244,135.300 285.347 M267.060 286.726 C 265.438 287.570,264.218 288.269,264.351 288.279 C 264.837 288.319,269.763 285.945,270.004 285.555 C 270.340 285.012,270.404 284.987,267.060 286.726 M261.357 289.479 C 260.492 289.879,260.014 290.220,260.295 290.236 C 260.854 290.268,263.127 289.179,263.127 288.879 C 263.127 288.647,263.232 288.611,261.357 289.479 M144.227 289.762 C 145.156 290.225,145.526 290.708,145.639 291.605 L 145.793 292.822 145.856 291.554 C 145.916 290.359,144.499 289.014,143.284 289.111 C 143.111 289.125,143.536 289.418,144.227 289.762 M145.967 294.199 C 145.960 294.523,146.198 295.320,146.495 295.969 C 147.191 297.488,147.201 296.781,146.509 294.985 C 146.218 294.228,145.974 293.874,145.967 294.199 M254.081 296.885 C 254.081 297.137,253.423 298.096,252.620 299.016 C 251.234 300.603,251.225 300.628,252.457 299.508 C 253.884 298.211,254.664 297.010,254.309 296.656 C 254.183 296.530,254.081 296.633,254.081 296.885 M249.361 301.278 C 248.591 301.700,248.269 302.039,248.629 302.048 C 248.984 302.057,249.692 301.717,250.202 301.291 C 251.369 300.319,251.120 300.315,249.361 301.278 M154.671 302.351 C 155.482 302.436,156.809 302.436,157.620 302.351 C 158.432 302.267,157.768 302.197,156.146 302.197 C 154.523 302.197,153.859 302.267,154.671 302.351 M231.587 302.359 C 234.683 302.426,239.639 302.426,242.600 302.359 C 245.561 302.292,243.029 302.238,236.971 302.238 C 230.914 302.238,228.492 302.293,231.587 302.359 M179.843 306.686 C 191.470 306.744,210.497 306.744,222.124 306.686 C 233.751 306.628,224.238 306.581,200.983 306.581 C 177.729 306.581,168.215 306.628,179.843 306.686 M247.659 309.009 C 248.345 309.624,249.274 310.747,249.722 311.504 C 250.171 312.262,250.539 312.725,250.539 312.534 C 250.543 311.763,248.835 309.501,247.662 308.721 L 246.411 307.890 247.659 309.009 M154.103 309.046 C 152.905 310.441,152.914 310.880,154.118 309.759 C 154.801 309.124,155.359 308.549,155.359 308.481 C 155.359 308.114,154.616 308.449,154.103 309.046 M249.555 322.376 C 249.140 323.147,248.174 324.309,247.409 324.958 C 246.644 325.607,246.372 325.959,246.804 325.741 C 248.104 325.083,250.909 321.574,250.479 321.144 C 250.386 321.051,249.970 321.606,249.555 322.376 M152.606 322.870 C 152.606 323.562,155.506 326.451,156.198 326.448 C 156.493 326.446,156.205 326.098,155.556 325.673 C 154.907 325.248,153.977 324.325,153.491 323.622 C 153.004 322.918,152.606 322.580,152.606 322.870 M164.110 331.952 C 163.407 332.381,162.832 332.820,162.832 332.928 C 162.832 333.037,163.407 332.774,164.110 332.346 C 165.898 331.256,235.497 331.107,237.776 332.188 C 239.212 332.870,242.675 336.354,242.675 337.119 C 242.675 337.380,242.783 337.486,242.916 337.353 C 243.657 336.612,239.644 332.430,237.360 331.562 C 235.081 330.695,165.564 331.066,164.110 331.952 M243.574 341.200 C 243.577 342.281,243.653 342.677,243.743 342.079 C 243.834 341.481,243.831 340.596,243.738 340.113 C 243.645 339.629,243.571 340.118,243.574 341.200 M158.623 341.790 C 158.623 342.979,158.697 343.466,158.787 342.871 C 158.877 342.276,158.877 341.303,158.787 340.708 C 158.697 340.113,158.623 340.600,158.623 341.790 M159.294 346.345 C 159.295 346.787,160.780 349.263,161.043 349.263 C 161.147 349.263,160.852 348.599,160.388 347.788 C 159.347 345.971,159.292 345.897,159.294 346.345 M241.294 347.827 C 240.643 348.706,239.346 350.008,238.412 350.720 C 237.478 351.433,236.915 352.016,237.161 352.016 C 237.706 352.016,241.802 348.191,242.347 347.173 C 243.052 345.856,242.502 346.198,241.294 347.827 M163.170 351.206 C 163.681 351.651,164.286 352.016,164.514 352.016 C 164.998 352.016,164.975 351.996,163.422 351.087 L 162.242 350.396 163.170 351.206 M176.591 353.472 C 177.119 354.593,180.789 358.792,181.644 359.254 C 182.005 359.449,181.236 358.476,179.934 357.091 C 178.632 355.706,177.255 354.130,176.874 353.589 C 176.318 352.798,176.262 352.776,176.591 353.472 M222.374 357.012 C 221.541 358.030,221.064 358.735,221.315 358.580 C 221.850 358.249,224.341 355.162,224.073 355.162 C 223.972 355.162,223.208 355.995,222.374 357.012 M184.857 361.274 C 184.857 361.559,188.834 363.474,189.160 363.346 C 189.329 363.279,188.430 362.748,187.162 362.165 C 185.895 361.582,184.857 361.181,184.857 361.274 M215.536 362.045 C 214.562 362.566,214.011 363.001,214.310 363.011 C 214.847 363.028,217.502 361.544,217.502 361.227 C 217.502 360.993,217.494 360.997,215.536 362.045 M199.312 365.285 C 200.447 365.365,202.306 365.365,203.441 365.285 C 204.577 365.206,203.648 365.141,201.377 365.141 C 199.105 365.141,198.176 365.206,199.312 365.285 \" stroke=\"none\" fill=\"#fc7b8c\" fill-rule=\"evenodd\"><\/path><path id=\"path3\" d=\"M189.863 0.284 C 190.562 0.371,191.801 0.372,192.617 0.287 C 193.433 0.202,192.861 0.131,191.347 0.129 C 189.833 0.127,189.165 0.197,189.863 0.284 M207.169 0.284 C 207.867 0.371,209.106 0.372,209.922 0.287 C 210.738 0.202,210.167 0.131,208.653 0.129 C 207.139 0.127,206.471 0.197,207.169 0.284 M183.190 0.671 C 183.680 0.766,184.388 0.762,184.764 0.664 C 185.140 0.565,184.739 0.488,183.874 0.493 C 183.009 0.497,182.701 0.577,183.190 0.671 M215.442 0.671 C 215.931 0.766,216.639 0.762,217.015 0.664 C 217.391 0.565,216.991 0.488,216.126 0.493 C 215.261 0.497,214.953 0.577,215.442 0.671 M167.945 2.360 C 167.421 2.699,167.421 2.741,167.945 2.741 C 168.269 2.741,168.800 2.570,169.125 2.360 C 169.649 2.021,169.649 1.979,169.125 1.979 C 168.800 1.979,168.269 2.150,167.945 2.360 M231.072 2.360 C 231.205 2.576,231.580 2.753,231.905 2.753 C 232.229 2.753,232.385 2.576,232.252 2.360 C 232.118 2.144,231.743 1.967,231.419 1.967 C 231.094 1.967,230.938 2.144,231.072 2.360 M162.635 3.147 C 161.938 3.446,161.972 3.488,162.930 3.512 C 163.525 3.527,164.012 3.363,164.012 3.147 C 164.012 2.685,163.709 2.685,162.635 3.147 M236.382 3.147 C 236.382 3.363,236.780 3.537,237.266 3.534 C 237.982 3.529,238.039 3.455,237.561 3.147 C 236.799 2.654,236.382 2.654,236.382 3.147 M253.687 7.134 C 253.687 7.321,253.938 7.473,254.245 7.473 C 254.552 7.473,255.112 7.592,255.490 7.736 C 255.922 7.902,256.082 7.847,255.921 7.587 C 255.599 7.066,253.687 6.678,253.687 7.134 M132.842 10.772 C 132.247 10.988,131.760 11.326,131.760 11.524 C 131.760 11.722,132.042 11.775,132.387 11.643 C 132.731 11.511,133.439 11.296,133.960 11.165 C 134.946 10.918,135.271 10.349,134.415 10.368 C 134.145 10.374,133.437 10.556,132.842 10.772 M124.067 14.388 C 123.369 14.957,123.365 14.991,124.024 14.781 C 124.421 14.656,124.907 14.553,125.106 14.553 C 125.305 14.553,125.467 14.376,125.467 14.159 C 125.467 13.590,124.942 13.676,124.067 14.388 M275.100 14.368 C 275.520 14.686,276.051 14.940,276.280 14.933 C 276.509 14.927,276.353 14.661,275.933 14.343 C 275.513 14.026,274.982 13.772,274.753 13.778 C 274.524 13.785,274.680 14.051,275.100 14.368 M283.972 18.088 C 283.972 18.264,284.503 18.594,285.152 18.820 C 285.801 19.046,286.332 19.102,286.332 18.945 C 286.332 18.787,285.801 18.458,285.152 18.213 C 284.503 17.968,283.972 17.912,283.972 18.088 M114.356 18.390 C 113.977 18.475,113.668 18.707,113.668 18.908 C 113.668 19.369,114.094 19.364,114.836 18.894 C 115.543 18.448,115.290 18.183,114.356 18.390 M106.883 22.089 C 106.288 22.307,105.801 22.643,105.801 22.837 C 105.801 23.190,107.637 22.549,108.338 21.951 C 108.831 21.531,108.264 21.585,106.883 22.089 M292.232 21.971 C 292.232 22.148,292.675 22.494,293.215 22.741 C 293.756 22.987,294.199 23.044,294.199 22.867 C 294.199 22.690,293.756 22.344,293.215 22.097 C 292.675 21.851,292.232 21.794,292.232 21.971 M101.278 25.199 C 100.629 25.614,99.921 26.020,99.705 26.099 C 99.489 26.179,99.408 26.350,99.526 26.479 C 99.643 26.609,100.528 26.191,101.492 25.552 C 102.456 24.912,103.068 24.401,102.852 24.416 C 102.635 24.431,101.927 24.783,101.278 25.199 M299.312 25.979 C 300.354 26.689,302.065 27.558,302.065 27.377 C 302.065 27.124,299.478 25.564,299.069 25.571 C 298.878 25.575,298.987 25.758,299.312 25.979 M304.031 28.459 C 304.031 28.755,307.178 30.681,307.184 30.389 C 307.187 30.224,307.362 30.354,307.571 30.678 C 307.781 31.003,307.955 31.066,307.959 30.818 C 307.962 30.570,307.080 29.905,305.998 29.339 C 304.916 28.774,304.031 28.378,304.031 28.459 M93.684 29.484 C 92.969 29.884,92.544 30.310,92.741 30.431 C 92.937 30.553,93.690 30.216,94.413 29.682 C 95.950 28.548,95.552 28.440,93.684 29.484 M87.043 34.045 C 86.316 34.709,86.207 34.920,86.726 34.664 C 87.980 34.045,89.129 33.065,88.616 33.051 C 88.357 33.044,87.650 33.492,87.043 34.045 M311.701 33.670 C 313.206 34.830,314.115 35.101,312.957 34.045 C 312.350 33.492,311.643 33.044,311.384 33.051 C 311.126 33.058,311.268 33.336,311.701 33.670 M83.088 36.623 C 82.384 37.074,81.809 37.633,81.809 37.865 C 81.809 38.098,82.296 37.862,82.891 37.341 C 83.486 36.820,84.141 36.258,84.346 36.092 C 85.067 35.512,84.353 35.813,83.088 36.623 M316.618 36.890 C 317.375 37.542,318.082 37.989,318.190 37.884 C 318.402 37.678,317.291 36.767,316.028 36.113 C 315.595 35.889,315.860 36.238,316.618 36.890 M318.645 38.138 C 318.727 38.384,319.411 38.947,320.164 39.389 C 320.917 39.831,321.180 39.907,320.747 39.558 C 320.315 39.209,319.631 38.646,319.228 38.307 C 318.825 37.968,318.563 37.892,318.645 38.138 M78.128 40.339 C 77.077 41.083,76.458 41.685,76.752 41.676 C 77.046 41.668,77.994 41.052,78.859 40.306 C 80.848 38.592,80.580 38.604,78.128 40.339 M321.731 40.681 C 321.731 40.775,322.232 41.208,322.845 41.645 C 323.688 42.245,323.959 42.303,323.959 41.885 C 323.959 41.581,323.832 41.411,323.676 41.508 C 323.520 41.604,323.174 41.419,322.907 41.097 C 322.454 40.551,321.731 40.296,321.731 40.681 M74.533 43.265 C 73.716 43.913,72.902 44.444,72.723 44.444 C 72.544 44.444,72.190 44.833,71.936 45.307 C 71.572 45.987,71.829 45.882,73.145 44.816 C 74.065 44.071,75.195 43.155,75.658 42.782 C 76.121 42.408,76.391 42.098,76.259 42.093 C 76.126 42.088,75.350 42.616,74.533 43.265 M326.057 44.060 C 326.057 44.285,326.367 44.585,326.745 44.727 C 327.124 44.869,327.628 45.245,327.865 45.561 C 328.103 45.878,328.398 45.974,328.521 45.775 C 328.644 45.575,328.140 45.016,327.401 44.531 C 326.662 44.047,326.057 43.835,326.057 44.060 M180.138 44.458 C 179.503 44.669,179.921 44.706,181.318 44.562 C 182.507 44.439,183.555 44.273,183.645 44.195 C 183.960 43.919,181.112 44.132,180.138 44.458 M228.548 44.193 C 228.638 44.271,229.508 44.440,230.482 44.569 C 231.664 44.725,231.990 44.687,231.465 44.455 C 230.714 44.122,228.206 43.897,228.548 44.193 M331.563 48.574 C 332.071 49.115,332.664 49.558,332.880 49.558 C 333.097 49.558,332.858 49.115,332.350 48.574 C 331.842 48.033,331.249 47.591,331.033 47.591 C 330.817 47.591,331.055 48.033,331.563 48.574 M68.001 48.476 C 66.602 49.650,66.241 50.518,67.552 49.559 C 68.255 49.044,68.830 48.479,68.830 48.304 C 68.830 47.870,68.687 47.900,68.001 48.476 M63.738 52.126 C 63.208 52.647,62.863 53.161,62.970 53.268 C 63.161 53.460,65.290 51.664,65.290 51.312 C 65.290 50.897,64.639 51.238,63.738 52.126 M335.467 52.061 C 335.991 52.631,336.588 53.097,336.793 53.097 C 337.321 53.097,336.310 51.957,335.332 51.449 C 334.601 51.070,334.616 51.136,335.467 52.061 M338.643 54.794 C 338.643 54.861,339.218 55.437,339.921 56.072 L 341.200 57.227 340.044 55.949 C 338.968 54.757,338.643 54.490,338.643 54.794 M342.183 58.084 C 342.183 58.285,342.802 59.050,343.559 59.784 C 344.317 60.518,344.936 61.029,344.936 60.921 C 344.936 60.813,344.317 60.048,343.559 59.221 C 342.802 58.395,342.183 57.883,342.183 58.084 M268.437 58.808 C 268.869 59.160,269.577 59.622,270.010 59.834 L 270.796 60.220 270.010 59.580 C 269.577 59.228,268.869 58.766,268.437 58.553 L 267.650 58.167 268.437 58.808 M51.958 63.927 C 50.829 65.213,50.537 65.683,50.868 65.683 C 50.940 65.683,51.568 64.975,52.263 64.110 C 53.827 62.165,53.616 62.038,51.958 63.927 M274.959 62.664 C 275.049 62.734,275.742 63.191,276.500 63.680 L 277.876 64.568 276.696 63.555 C 276.047 62.997,275.354 62.540,275.156 62.539 C 274.957 62.538,274.869 62.594,274.959 62.664 M347.894 64.208 C 348.738 65.236,349.492 66.077,349.569 66.077 C 349.851 66.077,348.142 63.891,347.263 63.127 C 346.765 62.694,347.049 63.181,347.894 64.208 M350.442 67.055 C 350.767 67.486,351.455 68.282,351.973 68.825 L 352.913 69.813 352.089 68.598 C 351.636 67.930,350.948 67.134,350.559 66.828 C 349.900 66.310,349.892 66.326,350.442 67.055 M48.718 67.549 C 47.368 69.179,47.166 69.713,48.354 68.511 C 49.062 67.795,49.562 67.131,49.466 67.034 C 49.369 66.937,49.033 67.169,48.718 67.549 M119.174 70.830 L 117.404 72.434 119.272 70.978 C 120.910 69.701,121.396 69.220,121.042 69.224 C 120.988 69.225,120.147 69.947,119.174 70.830 M45.224 71.399 C 44.526 72.705,44.961 73.038,45.763 71.813 C 46.115 71.276,46.254 70.746,46.073 70.634 C 45.891 70.522,45.510 70.866,45.224 71.399 M354.006 71.508 C 354.534 72.174,355.105 72.729,355.274 72.741 C 355.845 72.781,354.760 71.213,353.899 70.752 C 353.087 70.317,353.092 70.353,354.006 71.508 M290.265 73.269 C 290.265 73.371,291.276 74.316,292.511 75.370 C 293.746 76.424,294.631 77.081,294.476 76.830 C 294.139 76.281,290.265 73.005,290.265 73.269 M41.832 76.008 C 40.751 77.360,39.555 78.997,39.175 79.646 C 38.496 80.806,38.497 80.809,39.203 79.852 C 39.598 79.316,40.376 78.343,40.931 77.689 C 42.409 75.948,44.171 73.550,43.972 73.550 C 43.877 73.550,42.914 74.656,41.832 76.008 M356.551 74.336 C 357.028 75.171,360.777 79.843,360.969 79.843 C 361.208 79.843,358.272 75.906,357.172 74.752 C 356.645 74.199,356.365 74.012,356.551 74.336 M296.165 78.466 C 296.899 79.223,297.588 79.843,297.696 79.843 C 297.804 79.843,297.292 79.223,296.559 78.466 C 295.825 77.709,295.136 77.089,295.028 77.089 C 294.919 77.089,295.431 77.709,296.165 78.466 M362.279 81.908 C 363.947 84.081,364.521 84.641,363.691 83.284 C 362.181 80.818,361.739 80.236,361.377 80.236 C 361.167 80.236,361.573 80.988,362.279 81.908 M37.014 82.142 C 35.850 83.778,35.980 84.079,37.217 82.609 C 37.785 81.935,38.158 81.291,38.047 81.180 C 37.935 81.069,37.471 81.502,37.014 82.142 M197.837 84.960 C 196.214 85.099,198.250 85.132,202.360 85.031 C 206.470 84.931,209.907 84.785,209.997 84.706 C 210.249 84.485,201.155 84.675,197.837 84.960 M210.456 85.098 C 210.546 85.176,212.566 85.331,214.946 85.443 C 217.709 85.573,218.633 85.532,217.502 85.330 C 215.733 85.014,210.146 84.830,210.456 85.098 M192.237 85.627 C 192.726 85.721,193.434 85.718,193.810 85.619 C 194.186 85.521,193.786 85.444,192.920 85.448 C 192.055 85.453,191.747 85.533,192.237 85.627 M34.156 86.431 C 32.920 87.905,32.031 89.567,32.879 88.817 C 33.614 88.167,35.202 85.742,34.891 85.742 C 34.805 85.742,34.474 86.052,34.156 86.431 M365.480 86.529 C 365.750 86.962,366.112 87.316,366.283 87.316 C 366.455 87.316,366.407 86.962,366.175 86.529 C 365.943 86.096,365.582 85.742,365.371 85.742 C 365.159 85.742,365.208 86.093,365.480 86.529 M172.075 89.465 C 170.524 90.175,170.874 90.187,173.058 89.499 C 174.031 89.192,174.474 88.938,174.041 88.933 C 173.609 88.928,172.724 89.167,172.075 89.465 M307.571 89.799 C 307.571 89.866,308.147 90.441,308.850 91.077 L 310.128 92.232 308.973 90.954 C 307.896 89.762,307.571 89.495,307.571 89.799 M29.537 93.314 C 28.690 94.901,28.687 94.936,29.476 94.002 C 30.613 92.658,31.167 91.642,30.765 91.642 C 30.581 91.642,30.028 92.394,29.537 93.314 M369.963 93.223 C 370.539 94.093,371.085 94.729,371.177 94.637 C 371.403 94.411,369.596 91.653,369.218 91.647 C 369.052 91.644,369.388 92.354,369.963 93.223 M244.674 92.575 C 245.079 92.937,247.394 94.002,247.394 93.826 C 247.394 93.599,245.214 92.429,244.792 92.429 C 244.637 92.429,244.584 92.495,244.674 92.575 M94.395 95.182 C 93.490 96.264,92.837 97.148,92.945 97.148 C 93.054 97.148,93.883 96.264,94.789 95.182 C 95.694 94.100,96.347 93.215,96.238 93.215 C 96.130 93.215,95.301 94.100,94.395 95.182 M252.507 96.774 C 253.872 97.700,254.649 97.970,253.687 97.184 C 253.147 96.741,252.527 96.378,252.311 96.377 C 252.094 96.375,252.183 96.554,252.507 96.774 M27.007 97.573 C 26.622 98.022,26.364 98.560,26.433 98.767 C 26.502 98.975,26.876 98.607,27.264 97.950 C 28.087 96.557,27.994 96.420,27.007 97.573 M373.438 99.090 C 374.309 100.774,374.962 100.995,374.172 99.339 C 373.804 98.567,373.354 97.935,373.172 97.935 C 372.990 97.935,373.110 98.455,373.438 99.090 M25.232 100.517 C 24.970 101.093,24.942 101.421,25.167 101.281 C 25.744 100.925,26.438 99.508,26.036 99.508 C 25.846 99.508,25.485 99.962,25.232 100.517 M148.068 101.967 L 146.116 104.031 148.181 102.080 C 149.317 101.006,150.246 100.077,150.246 100.015 C 150.246 99.721,149.881 100.048,148.068 101.967 M316.272 103.057 C 316.867 104.818,317.203 105.160,316.842 103.638 C 316.688 102.989,316.393 102.285,316.186 102.074 C 315.979 101.862,316.018 102.305,316.272 103.057 M376.866 105.211 C 377.112 105.752,377.459 106.195,377.636 106.195 C 377.813 106.195,377.756 105.752,377.510 105.211 C 377.263 104.671,376.917 104.228,376.740 104.228 C 376.563 104.228,376.620 104.671,376.866 105.211 M21.920 106.588 C 21.580 107.453,21.373 108.161,21.459 108.161 C 21.546 108.161,21.977 107.453,22.419 106.588 C 22.860 105.723,23.068 105.015,22.880 105.015 C 22.692 105.015,22.260 105.723,21.920 106.588 M86.567 106.415 C 86.113 107.185,85.920 107.705,86.138 107.570 C 86.564 107.307,87.841 105.015,87.561 105.015 C 87.469 105.015,87.022 105.645,86.567 106.415 M144.228 106.293 C 143.160 107.736,142.441 108.979,143.032 108.358 C 143.762 107.591,145.563 105.015,145.369 105.015 C 145.261 105.015,144.747 105.590,144.228 106.293 M270.010 109.341 C 271.075 110.423,272.035 111.308,272.143 111.308 C 272.252 111.308,271.468 110.423,270.403 109.341 C 269.338 108.260,268.378 107.375,268.269 107.375 C 268.161 107.375,268.944 108.260,270.010 109.341 M381.099 113.625 C 381.553 114.514,381.999 115.241,382.092 115.241 C 382.476 115.241,381.213 112.322,380.764 112.172 C 380.461 112.071,380.589 112.624,381.099 113.625 M18.213 114.061 C 17.968 114.710,17.912 115.241,18.088 115.241 C 18.264 115.241,18.594 114.710,18.820 114.061 C 19.046 113.412,19.102 112.881,18.945 112.881 C 18.787 112.881,18.458 113.412,18.213 114.061 M316.460 114.494 C 316.316 115.395,316.275 116.209,316.369 116.303 C 316.463 116.397,316.663 115.742,316.814 114.848 C 316.965 113.953,317.006 113.139,316.906 113.038 C 316.805 112.937,316.604 113.592,316.460 114.494 M139.872 116.863 C 139.549 118.479,139.607 125.869,139.949 126.729 C 140.096 127.098,140.216 124.753,140.216 121.517 C 140.216 115.043,140.222 115.116,139.872 116.863 M278.386 120.944 C 279.176 122.116,280.679 123.584,282.223 124.692 C 282.667 125.010,282.401 124.705,281.633 124.013 C 280.865 123.322,279.641 122.083,278.914 121.260 C 277.939 120.157,277.800 120.074,278.386 120.944 M14.945 121.339 C 14.716 121.941,14.435 122.585,14.321 122.771 C 14.206 122.956,14.283 123.107,14.491 123.107 C 14.908 123.107,15.848 120.731,15.549 120.432 C 15.446 120.329,15.174 120.737,14.945 121.339 M384.467 121.042 C 384.623 121.421,384.839 122.040,384.948 122.419 C 385.057 122.797,385.286 123.107,385.456 123.107 C 385.627 123.107,385.577 122.488,385.345 121.731 C 385.112 120.973,384.756 120.354,384.553 120.354 C 384.350 120.354,384.311 120.664,384.467 121.042 M78.727 121.747 C 78.068 123.194,78.193 123.502,78.906 122.187 C 79.239 121.573,79.437 120.997,79.347 120.908 C 79.257 120.818,78.978 121.196,78.727 121.747 M306.391 127.434 C 305.634 127.848,305.156 128.195,305.329 128.204 C 305.746 128.226,307.965 127.072,307.965 126.834 C 307.965 126.576,307.942 126.585,306.391 127.434 M388.498 131.563 C 388.601 132.104,388.836 132.547,389.021 132.547 C 389.205 132.547,389.254 132.812,389.129 133.137 C 389.005 133.461,389.083 133.727,389.304 133.727 C 389.719 133.727,389.707 133.476,389.203 131.662 C 388.827 130.310,388.243 130.229,388.498 131.563 M10.899 131.760 C 10.786 132.193,10.833 132.547,11.004 132.547 C 11.175 132.547,11.407 132.193,11.520 131.760 C 11.633 131.327,11.586 130.973,11.415 130.973 C 11.244 130.973,11.012 131.327,10.899 131.760 M148.673 139.016 C 148.673 139.124,149.204 139.487,149.853 139.823 C 150.501 140.159,151.032 140.345,151.032 140.237 C 151.032 140.128,150.501 139.765,149.853 139.430 C 149.204 139.094,148.673 138.908,148.673 139.016 M392.378 143.854 C 392.663 145.042,392.836 145.349,393.082 145.100 C 393.371 144.807,392.839 142.773,392.474 142.773 C 392.278 142.773,392.236 143.260,392.378 143.854 M176.111 147.377 C 176.600 147.472,177.308 147.468,177.684 147.370 C 178.060 147.271,177.660 147.194,176.794 147.198 C 175.929 147.203,175.622 147.283,176.111 147.377 M178.761 147.692 C 179.660 148.005,182.034 148.091,181.857 147.804 C 181.751 147.633,180.923 147.507,180.016 147.524 C 179.110 147.541,178.545 147.616,178.761 147.692 M236.676 150.917 C 237.163 151.010,237.960 151.010,238.446 150.917 C 238.933 150.823,238.535 150.746,237.561 150.746 C 236.588 150.746,236.190 150.823,236.676 150.917 M240.413 151.314 C 241.008 151.404,241.981 151.404,242.576 151.314 C 243.171 151.224,242.684 151.150,241.495 151.150 C 240.305 151.150,239.818 151.224,240.413 151.314 M261.357 154.966 C 261.790 155.151,262.498 155.298,262.930 155.292 C 263.563 155.283,263.524 155.219,262.734 154.966 C 261.389 154.535,260.355 154.535,261.357 154.966 M396.073 159.390 C 396.070 159.985,396.244 160.472,396.460 160.472 C 396.957 160.472,396.957 159.668,396.460 158.899 C 396.163 158.439,396.078 158.548,396.073 159.390 M396.466 161.554 C 396.463 162.040,396.637 162.439,396.853 162.439 C 397.346 162.439,397.346 162.021,396.853 161.259 C 396.545 160.782,396.471 160.838,396.466 161.554 M3.027 161.807 C 2.866 162.216,2.827 162.644,2.941 162.757 C 3.299 163.116,3.615 162.528,3.465 161.781 C 3.327 161.097,3.306 161.098,3.027 161.807 M2.643 164.142 C 2.205 165.257,2.276 165.826,2.790 165.312 C 3.027 165.076,3.154 164.553,3.073 164.152 C 2.932 163.448,2.917 163.447,2.643 164.142 M2.253 167.003 C 2.096 167.160,1.967 167.561,1.967 167.892 C 1.967 168.335,2.083 168.379,2.404 168.058 C 2.645 167.817,2.774 167.417,2.691 167.168 C 2.608 166.919,2.411 166.845,2.253 167.003 M293.553 168.642 C 293.864 169.145,296.165 170.848,296.165 170.575 C 296.165 170.478,295.515 169.903,294.721 169.297 C 293.927 168.691,293.402 168.396,293.553 168.642 M300.492 174.828 C 302.321 176.667,303.906 178.171,304.014 178.171 C 304.122 178.171,302.714 176.667,300.885 174.828 C 299.056 172.989,297.471 171.485,297.362 171.485 C 297.254 171.485,298.662 172.989,300.492 174.828 M138.227 176.773 C 138.647 177.109,139.266 177.370,139.603 177.353 C 140.133 177.327,140.136 177.293,139.626 177.104 C 139.302 176.983,138.682 176.722,138.250 176.523 C 137.476 176.167,137.475 176.171,138.227 176.773 M398.911 178.564 C 398.911 179.322,398.992 179.631,399.091 179.253 C 399.190 178.874,399.190 178.255,399.091 177.876 C 398.992 177.498,398.911 177.807,398.911 178.564 M0.878 178.958 C 0.878 179.715,0.959 180.025,1.058 179.646 C 1.157 179.267,1.157 178.648,1.058 178.269 C 0.959 177.891,0.878 178.201,0.878 178.958 M149.837 181.130 C 150.802 181.431,151.651 181.616,151.725 181.543 C 151.926 181.341,149.436 180.527,148.712 180.557 C 148.366 180.572,148.872 180.830,149.837 181.130 M399.320 184.071 C 399.320 185.044,399.397 185.442,399.491 184.956 C 399.585 184.469,399.585 183.673,399.491 183.186 C 399.397 182.699,399.320 183.097,399.320 184.071 M0.506 185.054 C 0.509 186.136,0.585 186.531,0.676 185.934 C 0.766 185.336,0.764 184.451,0.670 183.967 C 0.577 183.483,0.503 183.972,0.506 185.054 M165.388 184.857 C 167.052 185.281,168.480 185.281,167.158 184.857 C 166.618 184.684,165.733 184.546,165.192 184.550 C 164.309 184.556,164.329 184.588,165.388 184.857 M227.761 188.149 C 227.852 188.229,229.253 188.394,230.875 188.514 C 233.062 188.677,233.418 188.645,232.252 188.391 C 230.678 188.049,227.453 187.875,227.761 188.149 M112.180 189.381 C 112.184 189.813,112.323 190.698,112.488 191.347 C 112.757 192.407,112.789 192.427,112.795 191.544 C 112.799 191.003,112.661 190.118,112.488 189.577 C 112.241 188.807,112.174 188.764,112.180 189.381 M399.760 196.460 C 399.760 199.272,399.823 200.371,399.899 198.902 C 399.975 197.433,399.974 195.132,399.897 193.789 C 399.821 192.446,399.759 193.648,399.760 196.460 M254.065 192.536 C 255.030 192.837,255.880 193.022,255.953 192.949 C 256.154 192.748,253.664 191.933,252.940 191.963 C 252.594 191.978,253.100 192.236,254.065 192.536 M0.112 196.460 C 0.115 197.542,0.192 197.938,0.282 197.340 C 0.373 196.742,0.370 195.857,0.277 195.373 C 0.184 194.889,0.110 195.379,0.112 196.460 M269.420 199.823 C 270.784 200.749,271.561 201.018,270.600 200.232 C 270.059 199.789,269.440 199.426,269.223 199.425 C 269.007 199.423,269.095 199.602,269.420 199.823 M116.072 205.113 C 116.080 205.329,116.426 206.214,116.842 207.080 C 117.259 207.945,117.489 208.210,117.354 207.670 C 117.077 206.556,116.052 204.511,116.072 205.113 M0.506 207.866 C 0.509 208.948,0.585 209.344,0.676 208.746 C 0.766 208.148,0.764 207.263,0.670 206.779 C 0.577 206.296,0.503 206.785,0.506 207.866 M399.320 208.850 C 399.320 209.823,399.397 210.221,399.491 209.735 C 399.585 209.248,399.585 208.451,399.491 207.965 C 399.397 207.478,399.320 207.876,399.320 208.850 M279.056 215.733 C 279.056 218.029,279.171 219.500,279.312 219.001 C 279.453 218.501,279.568 217.030,279.568 215.733 C 279.568 214.435,279.453 212.964,279.312 212.464 C 279.171 211.965,279.056 213.436,279.056 215.733 M74.398 212.193 C 74.397 212.409,74.635 213.206,74.926 213.963 C 75.218 214.720,75.462 215.074,75.469 214.749 C 75.475 214.425,75.238 213.628,74.940 212.979 C 74.643 212.330,74.399 211.976,74.398 212.193 M0.878 213.963 C 0.878 214.720,0.959 215.029,1.058 214.651 C 1.157 214.272,1.157 213.653,1.058 213.274 C 0.959 212.896,0.878 213.206,0.878 213.963 M124.167 221.859 C 124.557 222.525,125.128 223.277,125.436 223.531 C 125.743 223.785,125.498 223.240,124.892 222.321 C 123.619 220.390,123.116 220.071,124.167 221.859 M1.967 225.126 C 1.967 225.450,2.144 225.825,2.360 225.959 C 2.576 226.092,2.753 225.936,2.753 225.612 C 2.753 225.287,2.576 224.912,2.360 224.779 C 2.144 224.645,1.967 224.801,1.967 225.126 M316.439 228.336 C 316.288 229.340,316.246 230.241,316.344 230.339 C 316.442 230.438,316.646 229.697,316.796 228.694 C 316.947 227.691,316.989 226.789,316.891 226.691 C 316.793 226.593,316.589 227.333,316.439 228.336 M2.366 227.804 C 2.377 228.791,3.134 229.605,3.140 228.637 C 3.144 228.163,2.970 227.666,2.753 227.532 C 2.537 227.398,2.363 227.521,2.366 227.804 M274.822 228.616 L 274.128 229.892 274.921 228.963 C 275.595 228.173,275.955 227.329,275.615 227.338 C 275.560 227.339,275.204 227.914,274.822 228.616 M397.140 227.966 C 396.983 228.124,396.859 228.622,396.865 229.072 C 396.876 229.829,396.909 229.838,397.287 229.189 C 397.727 228.433,397.614 227.492,397.140 227.966 M2.781 230.383 C 2.889 231.537,3.486 232.179,3.512 231.170 C 3.527 230.575,3.363 230.088,3.147 230.088 C 2.930 230.088,2.766 230.221,2.781 230.383 M396.466 231.367 C 396.471 232.082,396.545 232.139,396.853 231.662 C 397.346 230.899,397.346 230.482,396.853 230.482 C 396.637 230.482,396.463 230.880,396.466 231.367 M82.203 231.159 C 82.203 231.388,82.567 231.992,83.013 232.503 L 83.822 233.432 83.132 232.252 C 82.222 230.699,82.203 230.676,82.203 231.159 M270.772 233.892 C 270.166 234.686,269.871 235.212,270.117 235.060 C 270.620 234.749,272.323 232.448,272.050 232.448 C 271.953 232.448,271.378 233.098,270.772 233.892 M313.471 238.824 C 313.471 238.942,313.203 239.680,312.876 240.463 C 312.548 241.247,312.369 241.888,312.477 241.888 C 312.789 241.888,313.897 239.036,313.673 238.812 C 313.562 238.701,313.471 238.707,313.471 238.824 M262.119 242.380 L 260.964 243.658 262.242 242.503 C 262.945 241.867,263.520 241.292,263.520 241.224 C 263.520 240.920,263.196 241.188,262.119 242.380 M90.462 244.641 C 90.924 245.290,91.391 245.821,91.499 245.821 C 91.607 245.821,91.318 245.290,90.855 244.641 C 90.393 243.992,89.927 243.461,89.819 243.461 C 89.710 243.461,90.000 243.992,90.462 244.641 M148.279 245.571 C 148.279 245.679,148.810 246.146,149.459 246.608 C 150.108 247.070,150.639 247.359,150.639 247.251 C 150.639 247.143,150.108 246.676,149.459 246.214 C 148.810 245.752,148.279 245.463,148.279 245.571 M6.995 248.964 C 7.090 249.610,7.301 250.057,7.464 249.956 C 7.823 249.735,7.497 247.788,7.102 247.788 C 6.948 247.788,6.900 248.317,6.995 248.964 M392.768 248.223 C 392.673 248.524,392.404 249.373,392.168 250.108 C 391.651 251.725,391.651 251.721,392.102 251.721 C 392.469 251.721,393.391 248.127,393.098 247.835 C 393.011 247.747,392.862 247.922,392.768 248.223 M250.439 250.114 C 248.823 251.150,248.599 251.515,250.024 250.790 C 250.714 250.440,251.388 249.975,251.522 249.757 C 251.838 249.247,251.744 249.278,250.439 250.114 M304.818 255.654 C 304.356 256.303,304.066 256.834,304.175 256.834 C 304.283 256.834,304.749 256.303,305.211 255.654 C 305.674 255.005,305.963 254.474,305.855 254.474 C 305.747 254.474,305.280 255.005,304.818 255.654 M101.065 258.112 C 102.695 259.849,103.048 260.161,103.048 259.866 C 103.048 259.802,102.207 258.962,101.180 257.997 L 99.312 256.244 101.065 258.112 M10.917 261.357 C 11.020 261.898,11.280 262.340,11.494 262.340 C 11.708 262.340,11.776 262.060,11.645 261.718 C 11.514 261.376,11.406 260.933,11.406 260.735 C 11.406 260.536,11.254 260.374,11.067 260.374 C 10.881 260.374,10.813 260.816,10.917 261.357 M106.391 263.913 C 108.329 265.860,110.003 267.453,110.111 267.453 C 110.220 267.453,108.723 265.860,106.785 263.913 C 104.847 261.967,103.173 260.374,103.065 260.374 C 102.956 260.374,104.453 261.967,106.391 263.913 M192.429 261.825 C 192.807 261.924,193.427 261.924,193.805 261.825 C 194.184 261.726,193.874 261.645,193.117 261.645 C 192.360 261.645,192.050 261.726,192.429 261.825 M214.656 261.832 C 215.145 261.926,215.853 261.922,216.229 261.824 C 216.605 261.725,216.205 261.648,215.339 261.653 C 214.474 261.657,214.166 261.738,214.656 261.832 M197.837 262.346 C 201.353 262.671,208.310 262.836,208.030 262.588 C 207.940 262.508,204.857 262.352,201.180 262.240 C 196.621 262.102,195.557 262.136,197.837 262.346 M209.529 262.231 C 210.227 262.318,211.466 262.319,212.282 262.234 C 213.098 262.149,212.527 262.078,211.013 262.076 C 209.499 262.074,208.831 262.144,209.529 262.231 M112.078 269.125 C 113.708 270.861,114.061 271.174,114.061 270.878 C 114.061 270.815,113.220 269.975,112.193 269.010 L 110.324 267.257 112.078 269.125 M14.460 270.403 C 14.820 271.377,15.246 272.173,15.405 272.173 C 15.565 272.173,15.400 271.377,15.039 270.403 C 14.678 269.430,14.253 268.633,14.093 268.633 C 13.934 268.633,14.099 269.430,14.460 270.403 M385.447 269.420 C 385.196 269.890,385.079 270.362,385.187 270.471 C 385.295 270.579,385.589 270.283,385.841 269.813 C 386.092 269.343,386.209 268.871,386.101 268.763 C 385.993 268.654,385.699 268.950,385.447 269.420 M384.506 271.615 C 384.189 272.441,384.204 272.566,384.615 272.566 C 384.806 272.566,385.055 272.212,385.168 271.780 C 385.411 270.851,384.853 270.712,384.506 271.615 M284.562 276.346 L 282.989 277.754 284.661 276.504 C 286.099 275.428,286.618 274.909,286.234 274.932 C 286.180 274.935,285.428 275.572,284.562 276.346 M18.474 279.624 C 19.108 280.808,19.735 281.015,19.212 279.868 C 18.960 279.313,18.598 278.859,18.409 278.859 C 18.220 278.859,18.249 279.204,18.474 279.624 M380.787 280.039 C 380.560 280.688,380.504 281.219,380.662 281.219 C 380.820 281.219,381.149 280.688,381.394 280.039 C 381.639 279.390,381.695 278.859,381.519 278.859 C 381.342 278.859,381.013 279.390,380.787 280.039 M125.074 279.375 C 125.074 279.467,125.826 280.038,126.745 280.644 C 127.665 281.250,128.209 281.495,127.956 281.188 C 127.468 280.597,125.074 279.091,125.074 279.375 M20.452 283.298 C 20.452 283.860,21.392 285.546,21.704 285.546 C 21.891 285.546,21.739 285.059,21.367 284.464 C 20.483 283.052,20.452 283.012,20.452 283.298 M377.053 287.352 C 376.656 288.184,376.561 288.704,376.822 288.617 C 377.343 288.444,378.471 285.939,378.028 285.939 C 377.862 285.939,377.424 286.575,377.053 287.352 M265.093 288.102 C 264.553 288.411,264.287 288.664,264.503 288.664 C 264.720 288.664,265.339 288.411,265.880 288.102 C 266.421 287.793,266.686 287.540,266.470 287.540 C 266.254 287.540,265.634 287.793,265.093 288.102 M24.470 290.855 C 25.183 292.695,26.461 294.985,26.774 294.985 C 26.986 294.985,26.897 294.499,26.577 293.904 C 25.927 292.694,24.232 290.242,24.470 290.855 M257.227 291.417 C 255.642 292.057,255.452 292.271,255.406 293.460 C 255.356 294.752,255.359 294.755,255.525 293.566 C 255.667 292.546,255.955 292.259,257.268 291.825 C 258.132 291.540,258.930 291.161,259.040 290.983 C 259.291 290.576,259.341 290.564,257.227 291.417 M374.782 291.766 C 374.440 292.347,373.762 293.487,373.274 294.300 C 372.731 295.205,372.593 295.689,372.919 295.548 C 373.212 295.421,373.941 294.331,374.540 293.126 C 375.687 290.819,375.837 289.971,374.782 291.766 M28.712 298.281 C 28.712 298.762,30.482 301.269,30.825 301.273 C 31.014 301.276,31.001 301.057,30.797 300.787 C 30.593 300.516,30.040 299.784,29.569 299.160 C 29.098 298.536,28.712 298.141,28.712 298.281 M370.487 299.031 C 369.371 300.707,369.285 300.885,369.597 300.882 C 369.935 300.880,371.396 298.502,371.187 298.293 C 371.118 298.224,370.803 298.556,370.487 299.031 M153.335 302.558 C 153.498 302.721,174.861 302.810,200.808 302.755 L 247.984 302.655 200.511 302.458 C 174.401 302.350,153.172 302.395,153.335 302.558 M366.492 305.113 C 365.630 306.118,365.297 306.785,365.660 306.782 C 365.835 306.781,366.280 306.250,366.648 305.602 C 367.408 304.268,367.356 304.107,366.492 305.113 M33.432 305.814 C 33.432 306.145,33.696 306.518,34.019 306.642 C 34.343 306.766,34.492 307.053,34.352 307.280 C 34.204 307.520,34.285 307.576,34.546 307.415 C 34.870 307.215,34.820 306.868,34.365 306.174 C 33.633 305.057,33.432 304.979,33.432 305.814 M36.201 309.538 C 36.968 311.030,38.256 312.684,38.652 312.684 C 38.846 312.684,38.427 311.932,37.721 311.013 C 35.974 308.736,35.604 308.378,36.201 309.538 M362.520 310.914 C 361.916 311.672,361.543 312.291,361.690 312.291 C 361.982 312.291,362.806 311.320,363.442 310.226 C 364.068 309.151,363.719 309.411,362.520 310.914 M250.737 316.814 C 250.737 319.044,250.870 320.787,251.032 320.687 C 251.195 320.586,251.327 318.844,251.327 316.814 C 251.327 314.785,251.195 313.042,251.032 312.942 C 250.870 312.842,250.737 314.584,250.737 316.814 M359.956 314.242 C 359.483 314.882,359.095 315.536,359.095 315.695 C 359.095 315.854,359.538 315.384,360.079 314.651 C 360.619 313.918,361.062 313.264,361.062 313.198 C 361.062 312.877,360.742 313.178,359.956 314.242 M39.331 313.686 C 39.331 313.819,39.949 314.683,40.704 315.604 C 41.460 316.526,41.946 317.425,41.786 317.602 C 41.626 317.779,41.678 317.820,41.903 317.692 C 42.127 317.565,43.003 318.416,43.848 319.583 C 44.694 320.751,45.629 321.799,45.925 321.913 C 46.222 322.027,46.055 321.613,45.553 320.993 C 40.656 314.944,39.331 313.388,39.331 313.686 M357.840 316.912 C 356.856 318.058,356.637 318.597,357.252 318.361 C 357.558 318.244,358.006 317.715,358.247 317.186 C 358.765 316.049,358.648 315.971,357.840 316.912 M354.572 320.944 C 353.951 321.593,353.619 322.124,353.835 322.124 C 354.051 322.124,354.620 321.593,355.100 320.944 C 355.580 320.295,355.912 319.764,355.838 319.764 C 355.763 319.764,355.194 320.295,354.572 320.944 M48.378 324.694 C 48.378 325.174,49.647 326.794,50.186 327.001 C 50.525 327.131,50.332 326.653,49.722 325.854 C 48.718 324.537,48.378 324.243,48.378 324.694 M350.221 326.108 C 349.258 327.134,349.212 327.264,349.942 326.886 C 350.424 326.636,351.005 326.082,351.234 325.655 C 351.816 324.567,351.559 324.682,350.221 326.108 M182.989 331.072 C 192.886 331.130,209.081 331.130,218.977 331.072 C 228.874 331.013,220.777 330.965,200.983 330.965 C 181.190 330.965,173.092 331.013,182.989 331.072 M342.076 334.619 C 340.188 336.516,338.643 338.204,338.643 338.370 C 338.643 338.683,344.386 333.064,345.298 331.858 C 346.360 330.454,345.419 331.261,342.076 334.619 M55.457 332.581 C 55.457 332.708,56.410 333.725,57.575 334.842 C 61.172 338.292,61.699 338.567,58.614 335.383 C 55.660 332.337,55.457 332.156,55.457 332.581 M160.179 335.202 C 159.623 335.904,158.839 337.463,159.043 337.463 C 159.137 337.463,159.580 336.844,160.027 336.087 C 160.838 334.711,160.914 334.274,160.179 335.202 M243.916 340.610 C 243.878 341.367,243.762 342.694,243.660 343.559 L 243.473 345.133 243.877 343.559 C 244.098 342.694,244.214 341.367,244.133 340.610 L 243.987 339.233 243.916 340.610 M63.324 340.120 C 63.324 340.524,64.808 341.928,65.683 342.351 C 66.008 342.508,65.919 342.311,65.487 341.914 C 65.054 341.517,64.390 340.872,64.012 340.480 C 63.633 340.088,63.324 339.926,63.324 340.120 M334.907 341.504 C 334.132 342.283,333.998 342.549,334.518 342.277 C 335.434 341.797,336.971 340.192,336.442 340.267 C 336.247 340.295,335.556 340.852,334.907 341.504 M67.257 343.669 C 67.257 343.858,67.699 344.428,68.240 344.936 C 68.913 345.569,69.219 345.683,69.211 345.300 C 69.198 344.705,67.257 343.085,67.257 343.669 M331.170 344.739 C 330.662 345.280,330.423 345.723,330.640 345.723 C 330.856 345.723,331.449 345.280,331.957 344.739 C 332.465 344.199,332.703 343.756,332.487 343.756 C 332.271 343.756,331.678 344.199,331.170 344.739 M71.042 347.016 C 71.438 347.723,74.336 349.775,74.336 349.349 C 74.336 349.075,72.344 347.388,71.238 346.726 C 70.829 346.481,70.781 346.552,71.042 347.016 M159.489 347.689 C 159.824 348.338,160.187 348.869,160.296 348.869 C 160.404 348.869,160.218 348.338,159.882 347.689 C 159.546 347.040,159.183 346.509,159.075 346.509 C 158.967 346.509,159.153 347.040,159.489 347.689 M327.189 348.093 L 325.467 349.676 327.040 348.653 C 327.906 348.091,328.755 347.379,328.928 347.070 C 329.436 346.165,329.020 346.409,327.189 348.093 M323.682 350.812 C 322.726 351.625,322.554 351.909,323.107 351.768 C 323.540 351.658,324.212 351.137,324.600 350.612 C 325.521 349.366,325.338 349.406,323.682 350.812 M78.269 352.802 C 80.080 354.326,80.655 354.326,78.919 352.802 C 78.180 352.153,77.422 351.627,77.234 351.633 C 77.046 351.639,77.512 352.165,78.269 352.802 M165.143 352.519 C 165.313 352.688,167.827 352.776,170.730 352.714 L 176.008 352.603 170.422 352.408 C 167.349 352.300,164.974 352.350,165.143 352.519 M228.810 352.308 C 230.379 352.382,232.945 352.382,234.513 352.308 C 236.082 352.233,234.798 352.172,231.662 352.172 C 228.525 352.172,227.242 352.233,228.810 352.308 M320.551 353.277 C 319.794 353.929,319.528 354.268,319.961 354.032 C 321.149 353.383,322.284 352.438,322.095 352.255 C 322.003 352.166,321.308 352.626,320.551 353.277 M223.967 355.426 C 223.362 356.220,223.067 356.746,223.312 356.594 C 223.816 356.283,225.519 353.982,225.246 353.982 C 225.148 353.982,224.573 354.632,223.967 355.426 M316.924 355.854 C 315.902 356.639,315.132 357.347,315.212 357.427 C 315.436 357.652,318.519 355.421,318.749 354.867 C 319.013 354.231,319.082 354.194,316.924 355.854 M82.203 355.480 C 82.203 355.866,84.146 357.298,84.348 357.062 C 84.409 356.991,83.951 356.520,83.331 356.017 C 82.710 355.514,82.203 355.273,82.203 355.480 M86.499 358.651 C 87.239 359.325,87.947 359.775,88.071 359.651 C 88.308 359.414,87.286 358.546,85.939 357.838 C 85.506 357.610,85.758 357.976,86.499 358.651 M312.324 359.063 C 311.909 359.477,311.495 359.742,311.404 359.650 C 311.312 359.559,310.916 359.839,310.523 360.273 C 309.815 361.056,309.819 361.058,310.986 360.475 C 311.634 360.152,312.485 359.533,312.878 359.098 C 313.790 358.091,313.325 358.061,312.324 359.063 M219.272 360.137 C 218.088 361.196,217.999 361.342,218.914 360.731 C 220.001 360.004,221.369 358.679,220.992 358.717 C 220.912 358.725,220.138 359.364,219.272 360.137 M88.496 359.785 C 88.496 359.962,89.027 360.419,89.676 360.803 C 90.324 361.186,90.855 361.435,90.855 361.355 C 90.855 361.275,90.324 360.817,89.676 360.338 C 89.027 359.858,88.496 359.609,88.496 359.785 M93.215 362.952 C 93.215 363.244,94.120 363.813,95.765 364.554 C 95.977 364.650,95.885 364.462,95.560 364.137 C 94.728 363.305,93.215 362.540,93.215 362.952 M305.211 363.618 C 304.478 364.159,304.018 364.602,304.189 364.602 C 304.707 364.602,306.785 363.274,306.785 362.944 C 306.785 362.492,306.675 362.539,305.211 363.618 M211.013 364.023 C 210.147 364.308,209.794 364.547,210.226 364.554 C 210.659 364.561,211.544 364.323,212.193 364.026 C 213.679 363.345,213.073 363.344,211.013 364.023 M191.577 364.350 C 191.667 364.428,192.271 364.610,192.920 364.755 C 193.782 364.948,193.941 364.911,193.510 364.620 C 192.979 364.260,191.182 364.009,191.577 364.350 M99.115 366.480 C 99.115 366.659,99.956 367.198,100.983 367.679 C 102.143 368.222,102.553 368.315,102.065 367.924 C 100.879 366.976,99.115 366.112,99.115 366.480 M299.017 367.184 C 298.097 367.735,297.345 368.256,297.345 368.341 C 297.345 368.669,300.681 366.985,300.812 366.591 C 301.003 366.018,300.914 366.047,299.017 367.184 M105.872 370.206 C 106.595 370.891,109.452 372.179,109.145 371.682 C 108.899 371.285,106.065 369.715,105.592 369.715 C 105.460 369.715,105.586 369.936,105.872 370.206 M291.937 370.940 C 290.236 372.029,290.325 372.157,292.228 371.357 C 293.091 370.995,293.799 370.565,293.801 370.403 C 293.808 369.923,293.294 370.071,291.937 370.940 M285.152 374.238 C 284.582 374.564,284.417 374.801,284.759 374.801 C 285.084 374.802,285.693 374.543,286.113 374.225 C 287.084 373.491,286.445 373.499,285.152 374.238 M282.399 375.615 C 281.642 376.029,281.164 376.376,281.337 376.385 C 281.754 376.407,283.972 375.253,283.972 375.014 C 283.972 374.757,283.949 374.766,282.399 375.615 M123.500 378.342 C 123.500 378.522,123.810 378.758,124.189 378.867 C 124.567 378.976,125.216 379.204,125.630 379.373 C 126.129 379.578,126.295 379.539,126.122 379.260 C 125.785 378.714,123.500 377.914,123.500 378.342 M274.979 378.616 C 273.326 379.337,273.547 379.703,275.247 379.061 C 276.147 378.722,277.223 377.739,276.401 378.007 C 276.347 378.024,275.707 378.299,274.979 378.616 M132.547 381.820 C 132.547 382.034,132.989 382.294,133.530 382.397 C 134.071 382.501,134.513 382.433,134.513 382.246 C 134.513 382.060,134.351 381.908,134.152 381.908 C 133.953 381.908,133.511 381.800,133.169 381.669 C 132.827 381.538,132.547 381.605,132.547 381.820 M266.175 381.785 C 265.796 381.884,265.487 382.114,265.487 382.295 C 265.487 382.476,265.796 382.565,266.175 382.493 C 266.554 382.420,266.996 382.348,267.158 382.331 C 267.321 382.314,267.453 382.124,267.453 381.908 C 267.453 381.499,267.321 381.486,266.175 381.785 M238.741 389.381 C 238.262 389.690,238.313 389.763,239.013 389.768 C 239.487 389.771,239.984 389.597,240.118 389.381 C 240.427 388.880,239.516 388.880,238.741 389.381 M162.045 389.774 C 162.045 389.990,162.311 390.167,162.635 390.167 C 162.960 390.167,163.225 389.990,163.225 389.774 C 163.225 389.558,162.960 389.381,162.635 389.381 C 162.311 389.381,162.045 389.558,162.045 389.774 M236.775 389.774 C 236.775 389.990,237.040 390.167,237.365 390.167 C 237.689 390.167,237.955 389.990,237.955 389.774 C 237.955 389.558,237.689 389.381,237.365 389.381 C 237.040 389.381,236.775 389.558,236.775 389.774 M164.208 390.167 C 165.283 390.629,165.585 390.629,165.585 390.167 C 165.585 389.951,165.098 389.786,164.503 389.801 C 163.545 389.826,163.511 389.868,164.208 390.167 M234.612 390.167 C 234.324 390.632,234.709 390.632,235.792 390.167 C 236.550 389.841,236.547 389.828,235.716 389.801 C 235.242 389.786,234.745 389.951,234.612 390.167 M166.765 390.560 C 167.540 391.061,168.451 391.061,168.142 390.560 C 168.008 390.344,167.511 390.170,167.037 390.173 C 166.336 390.178,166.285 390.251,166.765 390.560 M231.858 390.560 C 231.549 391.061,232.460 391.061,233.235 390.560 C 233.715 390.251,233.664 390.178,232.963 390.173 C 232.489 390.170,231.992 390.344,231.858 390.560 M181.416 392.405 C 181.794 392.504,182.414 392.504,182.793 392.405 C 183.171 392.306,182.861 392.225,182.104 392.225 C 181.347 392.225,181.037 392.306,181.416 392.405 M187.321 392.809 C 187.919 392.900,188.804 392.897,189.288 392.804 C 189.771 392.711,189.282 392.637,188.201 392.640 C 187.119 392.642,186.723 392.719,187.321 392.809 M210.920 392.809 C 211.518 392.900,212.403 392.897,212.886 392.804 C 213.370 392.711,212.881 392.637,211.799 392.640 C 210.718 392.642,210.322 392.719,210.920 392.809 \" stroke=\"none\" fill=\"#fcb6c0\" fill-rule=\"evenodd\"><\/path><path id=\"path4\" d=\"M186.922 0.271 C 187.301 0.370,187.920 0.370,188.299 0.271 C 188.677 0.172,188.368 0.091,187.611 0.091 C 186.853 0.091,186.544 0.172,186.922 0.271 M211.701 0.271 C 212.080 0.370,212.699 0.370,213.078 0.271 C 213.456 0.172,213.147 0.091,212.389 0.091 C 211.632 0.091,211.323 0.172,211.701 0.271 M197.935 42.749 C 198.314 42.848,198.933 42.848,199.312 42.749 C 199.690 42.650,199.381 42.569,198.623 42.569 C 197.866 42.569,197.557 42.650,197.935 42.749 M213.668 42.749 C 214.046 42.848,214.666 42.848,215.044 42.749 C 215.423 42.650,215.113 42.569,214.356 42.569 C 213.599 42.569,213.289 42.650,213.668 42.749 M188.889 43.536 C 189.267 43.635,189.887 43.635,190.265 43.536 C 190.644 43.437,190.334 43.356,189.577 43.356 C 188.820 43.356,188.510 43.437,188.889 43.536 M222.321 43.536 C 222.699 43.635,223.319 43.635,223.697 43.536 C 224.076 43.437,223.766 43.356,223.009 43.356 C 222.252 43.356,221.942 43.437,222.321 43.536 M68.775 47.613 C 67.895 48.379,67.892 48.400,68.710 48.004 C 69.184 47.775,69.682 47.411,69.814 47.196 C 70.201 46.570,69.777 46.740,68.775 47.613 M333.498 50.094 C 334.021 50.739,335.497 51.714,335.497 51.415 C 335.497 51.340,334.921 50.858,334.218 50.343 C 333.427 49.764,333.153 49.669,333.498 50.094 M338.438 54.404 C 339.298 55.174,340.515 56.390,341.143 57.106 L 342.284 58.407 341.318 57.056 C 340.787 56.313,339.569 55.097,338.612 54.355 L 336.873 53.004 338.438 54.404 M56.932 58.596 C 55.039 60.528,53.491 62.221,53.491 62.358 C 53.491 62.612,58.590 57.547,59.943 55.949 C 61.502 54.107,60.252 55.206,56.932 58.596 M138.151 58.256 C 136.811 59.114,136.377 59.691,137.561 59.040 C 138.464 58.544,139.878 57.450,139.626 57.443 C 139.518 57.440,138.854 57.805,138.151 58.256 M345.297 61.500 C 345.821 62.145,347.296 63.120,347.296 62.821 C 347.296 62.746,346.721 62.264,346.018 61.749 C 345.227 61.170,344.952 61.075,345.297 61.500 M49.503 66.492 C 48.623 67.259,48.620 67.279,49.437 66.883 C 49.912 66.654,50.409 66.290,50.542 66.075 C 50.929 65.449,50.505 65.619,49.503 66.492 M108.948 79.646 C 107.336 81.268,106.106 82.596,106.214 82.596 C 106.323 82.596,107.730 81.268,109.341 79.646 C 110.953 78.024,112.183 76.696,112.075 76.696 C 111.967 76.696,110.559 78.024,108.948 79.646 M101.070 87.611 L 98.525 90.265 101.180 87.720 C 103.646 85.356,104.015 84.956,103.725 84.956 C 103.665 84.956,102.470 86.150,101.070 87.611 M317.146 108.751 C 317.147 110.482,317.216 111.141,317.299 110.216 C 317.382 109.291,317.381 107.875,317.297 107.069 C 317.212 106.264,317.144 107.021,317.146 108.751 M214.066 149.741 C 214.664 149.832,215.549 149.829,216.033 149.736 C 216.517 149.643,216.028 149.569,214.946 149.572 C 213.864 149.575,213.469 149.651,214.066 149.741 M225.275 150.131 C 225.764 150.225,226.472 150.221,226.848 150.123 C 227.224 150.024,226.824 149.947,225.959 149.952 C 225.093 149.956,224.786 150.037,225.275 150.131 M229.799 150.528 C 230.397 150.618,231.282 150.616,231.765 150.523 C 232.249 150.429,231.760 150.355,230.678 150.358 C 229.597 150.361,229.201 150.438,229.799 150.528 M70.655 151.902 C 70.522 152.397,70.429 153.156,70.448 153.589 C 70.467 154.022,70.644 153.685,70.842 152.841 C 71.226 151.207,71.062 150.384,70.655 151.902 M116.421 160.988 C 116.421 161.056,116.996 161.631,117.699 162.267 L 118.977 163.422 117.822 162.144 C 116.745 160.952,116.421 160.685,116.421 160.988 M122.321 166.101 C 122.321 166.169,122.896 166.744,123.599 167.380 L 124.877 168.535 123.722 167.257 C 122.645 166.065,122.321 165.798,122.321 166.101 M399.719 189.774 C 399.722 190.855,399.799 191.251,399.889 190.653 C 399.979 190.056,399.977 189.171,399.884 188.687 C 399.790 188.203,399.716 188.692,399.719 189.774 M0.132 191.937 C 0.132 193.559,0.202 194.223,0.287 193.412 C 0.371 192.601,0.371 191.273,0.287 190.462 C 0.202 189.651,0.132 190.315,0.132 191.937 M0.132 200.983 C 0.132 202.606,0.202 203.269,0.287 202.458 C 0.371 201.647,0.371 200.320,0.287 199.508 C 0.202 198.697,0.132 199.361,0.132 200.983 M399.719 203.147 C 399.722 204.228,399.799 204.624,399.889 204.026 C 399.979 203.428,399.977 202.543,399.884 202.059 C 399.790 201.576,399.716 202.065,399.719 203.147 M317.503 210.226 C 317.508 211.091,317.588 211.399,317.682 210.910 C 317.776 210.421,317.773 209.713,317.674 209.337 C 317.576 208.961,317.499 209.361,317.503 210.226 M317.495 221.436 C 317.495 222.193,317.576 222.502,317.675 222.124 C 317.774 221.745,317.774 221.126,317.675 220.747 C 317.576 220.369,317.495 220.678,317.495 221.436 M84.905 235.792 C 85.118 236.224,85.580 236.932,85.932 237.365 L 86.572 238.151 86.186 237.365 C 85.974 236.932,85.512 236.224,85.160 235.792 L 84.519 235.005 84.905 235.792 M298.132 263.913 C 296.789 265.428,295.779 266.667,295.888 266.667 C 295.996 266.667,297.183 265.428,298.525 263.913 C 299.868 262.399,300.877 261.160,300.769 261.160 C 300.661 261.160,299.474 262.399,298.132 263.913 M293.590 268.732 L 292.035 270.403 293.707 268.848 C 295.262 267.402,295.559 267.060,295.262 267.060 C 295.197 267.060,294.445 267.812,293.590 268.732 M290.244 271.681 L 288.889 273.156 290.364 271.801 C 291.175 271.055,291.839 270.392,291.839 270.326 C 291.839 270.026,291.506 270.309,290.244 271.681 M133.138 284.368 C 133.401 284.794,135.693 286.071,135.693 285.791 C 135.693 285.699,135.063 285.252,134.293 284.797 C 133.523 284.343,133.003 284.150,133.138 284.368 M368.606 302.262 C 368.360 302.802,368.223 303.245,368.301 303.245 C 368.380 303.245,368.734 302.802,369.089 302.262 C 369.443 301.721,369.580 301.278,369.394 301.278 C 369.207 301.278,368.853 301.721,368.606 302.262 M361.019 313.176 C 360.557 314.056,360.559 314.057,361.398 313.312 C 362.336 312.479,362.421 312.291,361.862 312.291 C 361.654 312.291,361.274 312.689,361.019 313.176 M151.154 316.814 C 151.157 318.112,151.230 318.596,151.317 317.889 C 151.405 317.182,151.403 316.120,151.313 315.529 C 151.224 314.938,151.152 315.516,151.154 316.814 M354.475 321.574 C 353.988 322.128,353.796 322.514,354.048 322.430 C 354.472 322.289,355.831 320.542,355.505 320.558 C 355.425 320.562,354.961 321.019,354.475 321.574 M352.333 323.992 C 351.640 324.799,351.121 325.664,351.329 325.664 C 351.409 325.664,351.867 325.133,352.347 324.484 C 353.295 323.202,353.286 322.883,352.333 323.992 M47.984 324.877 C 48.446 325.526,48.913 326.057,49.021 326.057 C 49.129 326.057,48.840 325.526,48.378 324.877 C 47.915 324.228,47.449 323.697,47.341 323.697 C 47.233 323.697,47.522 324.228,47.984 324.877 M157.268 326.944 C 157.431 327.107,177.201 327.195,201.201 327.140 L 244.838 327.040 200.905 326.844 C 176.741 326.735,157.105 326.781,157.268 326.944 M347.860 329.007 C 346.775 330.197,346.001 331.170,346.140 331.170 C 346.278 331.170,347.283 330.197,348.373 329.007 C 349.463 327.817,350.237 326.844,350.093 326.844 C 349.950 326.844,348.945 327.817,347.860 329.007 M51.524 328.723 C 51.524 328.854,52.498 329.889,53.687 331.024 C 54.877 332.158,55.851 332.986,55.851 332.864 C 55.851 332.742,54.877 331.707,53.687 330.563 C 52.498 329.420,51.524 328.592,51.524 328.723 M61.308 338.584 C 62.977 340.167,63.609 340.603,63.145 339.852 C 63.021 339.651,62.170 338.917,61.253 338.220 L 59.587 336.952 61.308 338.584 M337.620 339.135 C 335.897 341.122,335.385 341.790,335.585 341.790 C 335.701 341.790,336.448 340.993,337.245 340.020 C 338.723 338.217,339.015 337.525,337.620 339.135 M177.778 355.679 C 177.778 355.746,178.353 356.322,179.056 356.957 L 180.334 358.112 179.179 356.834 C 178.102 355.642,177.778 355.375,177.778 355.679 M196.342 393.213 C 198.224 393.285,201.410 393.285,203.422 393.214 C 205.434 393.142,203.894 393.083,200.000 393.083 C 196.106 393.082,194.460 393.141,196.342 393.213 \" stroke=\"none\" fill=\"#fcacb4\" fill-rule=\"evenodd\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\t\t\t\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"box-heading\">\n\t\t\t\t\t\t\t<a >\t\t\t\t\t\t\t\tDesigning ideal Recruitment Profiles\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-568352f7 content-align-left icon-box-vertical-align-top icon-position-left icon-vertical-align-start elementor-widget elementor-widget-the7_icon_box_widget\" data-id=\"568352f7\" data-element_type=\"widget\" data-widget_type=\"the7_icon_box_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"the7-box-wrapper the7-elementor-widget the7_icon_box_widget-568352f7\">\t\t\t<div class=\"box-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-icon-div\" >\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"svg\" width=\"400\" height=\"392.9901423877327\" viewBox=\"0, 0, 400,392.9901423877327\"><g id=\"svgg\"><path id=\"path0\" d=\"M193.314 43.309 C 155.007 46.203,120.494 64.039,96.738 93.218 C 63.997 133.435,60.098 195.681,87.593 239.239 C 101.091 260.622,119.818 277.760,140.610 287.759 L 145.919 290.312 145.919 291.792 C 145.919 295.513,148.402 299.901,151.320 301.338 L 153.196 302.262 200.393 302.228 L 247.591 302.194 249.593 301.172 C 252.890 299.487,254.370 297.363,255.041 293.354 C 255.271 291.978,255.414 291.867,258.516 290.641 C 328.287 263.078,338.631 183.447,275.516 159.768 C 256.823 152.755,243.679 150.783,209.440 149.855 C 164.379 148.633,143.627 142.430,140.276 129.180 C 137.228 117.133,141.711 105.293,152.011 98.184 C 169.276 86.268,201.577 81.428,228.122 86.779 C 247.528 90.691,268.207 103.598,276.483 116.965 C 287.486 134.737,312.441 132.616,316.478 113.565 C 318.974 101.788,308.991 87.784,285.939 70.730 C 255.989 48.573,229.081 40.607,193.314 43.309 M123.012 166.263 C 140.965 181.228,163.506 186.888,205.703 187.026 C 224.731 187.088,226.988 187.241,240.708 189.388 C 279.914 195.525,290.904 214.942,268.035 237.671 C 224.252 281.187,139.987 265.243,117.384 209.166 C 111.200 193.823,108.954 172.543,111.943 157.611 C 112.160 156.525,112.175 156.533,115.373 159.546 C 117.139 161.211,120.577 164.233,123.012 166.263 M156.932 307.613 C 150.346 311.561,149.524 321.652,155.467 325.585 L 157.071 326.647 201.019 326.647 L 244.967 326.647 246.663 325.455 C 253.221 320.846,252.177 310.416,244.850 307.354 C 242.285 306.283,158.742 306.528,156.932 307.613 M163.516 332.724 C 157.360 336.628,157.289 347.240,163.394 351.019 C 165.262 352.175,165.493 352.216,170.765 352.340 L 176.208 352.469 177.358 354.140 C 187.438 368.792,216.115 368.604,224.773 353.830 L 225.837 352.016 231.247 352.016 C 236.571 352.016,236.681 351.998,238.205 350.894 C 244.474 346.353,245.358 338.771,240.174 334.011 C 237.376 331.442,239.336 331.563,200.838 331.563 L 165.346 331.563 163.516 332.724 \" stroke=\"none\" fill=\"#f42444\" fill-rule=\"evenodd\"><\/path><path id=\"path1\" d=\"M188.201 0.421 C 184.956 0.587,180.294 0.928,177.842 1.179 C 175.390 1.431,173.282 1.535,173.159 1.412 C 173.035 1.288,172.701 1.380,172.416 1.617 C 171.936 2.015,170.708 2.238,167.748 2.466 C 167.099 2.516,166.346 2.701,166.073 2.877 C 165.801 3.053,165.226 3.085,164.795 2.949 C 164.310 2.795,164.012 2.880,164.012 3.171 C 164.012 3.491,163.566 3.570,162.626 3.418 C 161.864 3.294,161.319 3.319,161.414 3.474 C 161.510 3.628,159.293 4.180,156.487 4.699 C 153.682 5.219,151.295 5.793,151.183 5.975 C 151.070 6.157,150.806 6.199,150.595 6.069 C 150.384 5.939,149.976 6.027,149.688 6.266 C 149.401 6.505,148.878 6.589,148.526 6.454 C 148.150 6.310,147.886 6.407,147.886 6.690 C 147.886 6.978,147.569 7.089,147.099 6.966 C 146.667 6.853,146.313 6.941,146.313 7.162 C 146.313 7.384,145.959 7.472,145.526 7.359 C 145.093 7.246,144.739 7.281,144.739 7.436 C 144.739 7.592,143.142 8.131,141.189 8.634 C 139.236 9.138,137.549 9.694,137.440 9.871 C 137.331 10.047,136.981 10.092,136.664 9.970 C 136.346 9.848,136.087 9.964,136.087 10.226 C 136.087 10.489,135.821 10.602,135.497 10.477 C 135.172 10.353,134.907 10.390,134.907 10.560 C 134.907 10.730,133.535 11.286,131.858 11.796 C 130.182 12.307,128.236 12.961,127.534 13.250 C 126.832 13.539,126.144 13.758,126.005 13.737 C 125.865 13.716,125.622 13.908,125.464 14.164 C 125.306 14.420,124.711 14.656,124.142 14.689 C 123.573 14.722,123.108 14.858,123.107 14.992 C 123.107 15.125,122.001 15.631,120.649 16.117 C 119.297 16.603,117.616 17.349,116.912 17.775 C 116.209 18.201,115.634 18.434,115.634 18.293 C 115.634 18.152,115.342 18.328,114.986 18.685 C 114.629 19.042,114.009 19.248,113.608 19.143 C 113.208 19.038,112.967 19.093,113.073 19.265 C 113.179 19.437,112.250 19.985,111.009 20.482 C 109.767 20.980,108.660 21.518,108.549 21.678 C 108.437 21.838,106.844 22.747,105.009 23.697 C 100.301 26.135,95.583 28.785,94.199 29.770 C 92.039 31.306,89.483 32.815,89.184 32.729 C 89.022 32.683,88.889 32.809,88.889 33.010 C 88.889 33.211,87.871 33.995,86.627 34.754 C 85.383 35.512,82.153 37.837,79.449 39.919 C 76.745 42.001,73.544 44.455,72.335 45.373 C 71.126 46.290,69.575 47.615,68.888 48.318 C 68.201 49.021,67.459 49.486,67.241 49.351 C 67.023 49.216,66.891 49.252,66.948 49.430 C 67.146 50.041,63.238 53.433,62.613 53.193 C 62.269 53.061,62.118 53.131,62.257 53.356 C 62.536 53.807,58.110 58.338,57.697 58.024 C 57.547 57.910,57.514 57.936,57.623 58.082 C 57.733 58.228,56.450 59.777,54.772 61.524 C 53.094 63.271,50.934 65.618,49.973 66.741 C 49.011 67.863,48.038 68.676,47.809 68.546 C 47.581 68.416,47.514 68.443,47.659 68.606 C 47.898 68.872,45.576 72.283,44.830 72.763 C 44.661 72.871,43.724 74.022,42.747 75.320 C 41.769 76.618,39.631 79.449,37.994 81.613 C 36.358 83.776,35.016 85.689,35.012 85.864 C 35.008 86.039,34.801 86.056,34.551 85.901 C 34.262 85.723,34.204 85.794,34.390 86.096 C 34.563 86.375,34.140 87.289,33.370 88.306 C 32.647 89.260,31.266 91.273,30.302 92.780 C 29.337 94.287,28.381 95.417,28.176 95.290 C 27.971 95.164,27.930 95.265,28.085 95.516 C 28.392 96.013,26.816 99.115,26.256 99.115 C 26.067 99.115,26.009 99.271,26.127 99.462 C 26.245 99.653,26.015 100.228,25.615 100.740 C 25.216 101.253,23.645 104.095,22.125 107.058 C 20.604 110.021,19.224 112.321,19.057 112.171 C 18.890 112.021,18.868 112.099,19.008 112.344 C 19.320 112.891,18.546 115.241,18.054 115.241 C 17.859 115.241,17.730 115.374,17.769 115.536 C 17.807 115.698,17.390 116.813,16.842 118.013 C 16.294 119.214,15.629 120.851,15.365 121.652 C 15.101 122.452,14.711 123.107,14.499 123.107 C 14.287 123.107,14.219 123.279,14.349 123.489 C 14.479 123.700,14.333 124.275,14.024 124.768 C 13.715 125.260,12.974 127.168,12.376 129.007 C 11.778 130.846,11.148 132.406,10.976 132.474 C 10.804 132.542,10.761 132.852,10.880 133.162 C 10.999 133.473,10.907 133.727,10.674 133.727 C 10.441 133.727,10.353 133.992,10.477 134.317 C 10.602 134.641,10.541 134.907,10.342 134.907 C 10.143 134.907,9.567 136.511,9.061 138.473 C 8.430 140.920,8.029 141.876,7.783 141.521 C 7.554 141.190,7.516 141.464,7.677 142.281 C 7.824 143.029,7.768 143.559,7.541 143.559 C 7.328 143.559,7.246 143.913,7.359 144.346 C 7.472 144.779,7.384 145.133,7.162 145.133 C 6.941 145.133,6.853 145.487,6.966 145.919 C 7.089 146.389,6.978 146.706,6.690 146.706 C 6.407 146.706,6.310 146.970,6.454 147.346 C 6.589 147.698,6.495 148.233,6.244 148.535 C 5.993 148.838,5.900 149.197,6.037 149.334 C 6.174 149.471,6.133 149.777,5.946 150.013 C 5.759 150.249,5.286 152.168,4.894 154.277 C 4.503 156.386,4.068 158.112,3.929 158.112 C 3.790 158.112,3.754 158.643,3.849 159.292 C 3.951 159.986,3.846 160.472,3.594 160.472 C 3.328 160.472,3.256 160.919,3.402 161.652 C 3.554 162.413,3.478 162.832,3.188 162.832 C 2.904 162.832,2.830 163.196,2.986 163.820 C 3.126 164.377,3.029 165.056,2.765 165.375 C 2.506 165.686,2.406 166.292,2.543 166.722 C 2.679 167.151,2.616 167.823,2.402 168.215 C 1.307 170.226,0.243 188.749,0.520 200.983 C 0.757 211.453,1.765 224.046,2.431 224.858 C 2.644 225.118,2.700 225.702,2.557 226.155 C 2.413 226.609,2.506 227.234,2.765 227.546 C 3.029 227.864,3.126 228.543,2.986 229.100 C 2.831 229.720,2.904 230.088,3.184 230.088 C 3.455 230.088,3.561 230.550,3.456 231.268 C 3.361 231.917,3.449 232.448,3.653 232.448 C 3.856 232.448,3.944 232.979,3.849 233.628 C 3.754 234.277,3.789 234.808,3.927 234.808 C 4.065 234.808,4.503 236.584,4.899 238.753 C 5.296 240.923,5.774 242.794,5.963 242.910 C 6.152 243.027,6.199 243.295,6.069 243.506 C 5.939 243.716,6.027 244.124,6.266 244.412 C 6.505 244.699,6.589 245.223,6.454 245.575 C 6.310 245.951,6.407 246.214,6.690 246.214 C 6.974 246.214,7.089 246.530,6.971 246.982 C 6.860 247.404,6.938 247.806,7.143 247.874 C 7.348 247.943,7.551 248.658,7.593 249.465 C 7.635 250.271,7.768 250.931,7.889 250.932 C 8.009 250.933,8.430 252.177,8.824 253.695 C 9.218 255.214,9.687 256.547,9.866 256.658 C 10.045 256.768,10.092 257.119,9.970 257.436 C 9.848 257.754,9.964 258.014,10.226 258.014 C 10.489 258.014,10.602 258.279,10.477 258.604 C 10.353 258.928,10.441 259.194,10.674 259.194 C 10.907 259.194,10.995 259.459,10.871 259.784 C 10.746 260.108,10.782 260.374,10.951 260.374 C 11.119 260.374,11.586 261.480,11.988 262.832 C 12.391 264.184,12.957 265.864,13.247 266.566 C 13.537 267.268,13.758 267.957,13.737 268.096 C 13.716 268.235,13.860 268.457,14.057 268.589 C 14.254 268.722,15.093 270.600,15.922 272.763 C 16.750 274.926,17.560 276.785,17.721 276.893 C 17.882 277.001,18.076 277.443,18.151 277.876 C 18.227 278.309,18.521 278.907,18.803 279.205 C 19.086 279.503,19.210 280.029,19.078 280.373 C 18.946 280.717,18.959 280.877,19.108 280.728 C 19.380 280.457,21.821 285.091,21.698 285.644 C 21.662 285.806,21.820 285.939,22.049 285.939 C 22.278 285.939,22.365 286.101,22.243 286.299 C 22.121 286.497,22.167 286.718,22.347 286.790 C 22.526 286.863,23.295 288.073,24.056 289.479 C 27.443 295.739,31.656 302.714,33.000 304.285 C 33.211 304.532,33.277 304.842,33.146 304.973 C 33.015 305.104,33.099 305.211,33.334 305.211 C 33.569 305.211,34.163 305.875,34.654 306.686 C 35.145 307.498,36.320 309.179,37.265 310.423 C 38.211 311.667,38.872 312.866,38.735 313.088 C 38.598 313.309,38.662 313.442,38.876 313.382 C 39.228 313.285,40.418 314.647,45.313 320.747 C 46.180 321.829,47.712 323.678,48.716 324.856 C 51.642 328.292,64.365 341.035,66.799 342.970 C 68.024 343.943,69.259 345.050,69.542 345.430 C 69.826 345.810,70.534 346.372,71.115 346.680 C 71.697 346.988,72.714 347.739,73.375 348.350 C 75.620 350.422,81.851 355.111,85.644 357.582 C 86.996 358.463,88.116 359.473,88.133 359.828 C 88.150 360.182,88.248 360.269,88.349 360.020 C 88.529 359.582,92.330 361.844,92.866 362.708 C 92.998 362.921,93.220 363.081,93.358 363.062 C 94.058 362.968,94.384 363.073,94.859 363.543 C 95.588 364.265,101.460 367.615,105.211 369.449 C 106.942 370.296,108.623 371.204,108.948 371.468 C 109.272 371.733,110.733 372.459,112.193 373.083 C 113.653 373.706,114.848 374.364,114.848 374.545 C 114.848 374.726,115.025 374.765,115.241 374.631 C 115.457 374.498,115.634 374.576,115.634 374.805 C 115.634 375.034,115.767 375.188,115.929 375.148 C 116.091 375.108,116.932 375.388,117.797 375.771 C 118.663 376.153,120.610 376.915,122.124 377.464 C 123.638 378.012,125.231 378.655,125.664 378.892 C 126.096 379.129,126.539 379.336,126.647 379.351 C 126.755 379.366,127.198 379.562,127.630 379.785 C 128.063 380.008,129.789 380.608,131.465 381.118 C 133.142 381.629,134.513 382.186,134.513 382.358 C 134.513 382.529,134.779 382.568,135.103 382.443 C 135.428 382.318,135.693 382.431,135.693 382.694 C 135.693 382.957,135.953 383.072,136.271 382.950 C 136.588 382.828,136.935 382.869,137.040 383.040 C 137.146 383.211,139.143 383.854,141.478 384.469 C 143.813 385.084,145.775 385.714,145.840 385.869 C 145.904 386.024,146.303 386.060,146.725 385.950 C 147.147 385.839,147.493 385.930,147.493 386.151 C 147.493 386.373,147.847 386.461,148.279 386.348 C 148.739 386.228,149.066 386.336,149.066 386.608 C 149.066 386.888,149.367 386.978,149.819 386.834 C 150.234 386.703,150.678 386.765,150.806 386.973 C 150.934 387.180,153.250 387.754,155.952 388.248 C 158.654 388.742,160.865 389.283,160.865 389.450 C 160.865 389.617,161.396 389.648,162.045 389.518 C 162.695 389.388,163.225 389.450,163.225 389.657 C 163.225 389.862,163.756 389.953,164.405 389.858 C 165.124 389.752,165.585 389.859,165.585 390.130 C 165.585 390.409,165.954 390.483,166.573 390.327 C 167.117 390.191,167.799 390.276,168.089 390.517 C 168.379 390.758,169.041 390.953,169.559 390.951 C 170.077 390.949,172.537 391.201,175.025 391.510 C 188.507 393.187,209.683 393.280,223.009 391.721 C 226.578 391.304,229.923 390.960,230.441 390.958 C 230.959 390.956,231.622 390.756,231.914 390.514 C 232.206 390.272,232.834 390.176,233.311 390.301 C 233.787 390.426,234.407 390.337,234.687 390.104 C 234.968 389.871,235.552 389.774,235.986 389.887 C 236.420 390.001,236.775 389.933,236.775 389.737 C 236.775 389.541,237.121 389.381,237.544 389.381 C 239.004 389.381,249.165 387.295,249.392 386.948 C 249.518 386.757,249.916 386.714,250.277 386.853 C 250.661 387.000,250.934 386.913,250.934 386.643 C 250.934 386.360,251.239 386.278,251.721 386.431 C 252.205 386.584,252.507 386.501,252.507 386.215 C 252.507 385.943,252.834 385.834,253.294 385.955 C 253.727 386.068,254.081 386.032,254.081 385.876 C 254.081 385.719,255.452 385.270,257.129 384.877 C 258.805 384.485,260.531 384.031,260.964 383.869 C 261.396 383.707,261.927 383.539,262.144 383.494 C 262.360 383.450,262.750 383.237,263.011 383.020 C 263.272 382.804,263.670 382.741,263.896 382.880 C 264.122 383.020,264.307 382.928,264.307 382.675 C 264.307 382.423,264.572 382.319,264.897 382.443 C 265.221 382.568,265.487 382.536,265.487 382.374 C 265.487 382.211,267.168 381.572,269.223 380.955 C 271.278 380.338,272.960 379.650,272.960 379.428 C 272.960 379.205,273.076 379.140,273.218 379.282 C 273.361 379.424,273.671 379.389,273.907 379.204 C 274.143 379.019,275.841 378.293,277.679 377.592 C 279.518 376.890,281.664 375.989,282.449 375.589 C 283.233 375.189,283.985 374.972,284.120 375.107 C 284.255 375.242,284.366 375.170,284.366 374.948 C 284.366 374.726,285.737 373.970,287.414 373.269 C 289.090 372.568,290.668 371.827,290.919 371.622 C 291.170 371.418,292.851 370.493,294.655 369.567 C 299.407 367.129,304.461 364.295,305.179 363.666 C 305.521 363.366,306.805 362.560,308.031 361.875 C 309.257 361.190,310.472 360.375,310.730 360.063 C 310.989 359.752,311.357 359.594,311.549 359.713 C 311.741 359.831,311.898 359.746,311.898 359.522 C 311.898 359.298,312.466 358.822,313.160 358.463 C 313.854 358.104,316.155 356.511,318.273 354.923 C 320.391 353.335,322.124 352.106,322.124 352.192 C 322.124 352.278,322.625 351.875,323.237 351.297 C 323.849 350.719,325.370 349.449,326.616 348.476 C 335.692 341.385,346.987 330.269,354.769 320.770 C 355.959 319.318,357.419 317.599,358.014 316.950 C 358.609 316.301,359.095 315.682,359.095 315.574 C 359.095 315.466,359.936 314.299,360.964 312.981 C 362.767 310.668,365.287 307.040,367.793 303.147 C 368.454 302.119,369.168 301.278,369.378 301.278 C 369.589 301.278,369.665 301.122,369.547 300.931 C 369.429 300.740,369.699 300.118,370.147 299.549 C 371.042 298.411,373.212 294.639,375.942 289.479 C 376.914 287.640,377.859 286.076,378.041 286.004 C 378.224 285.931,378.273 285.710,378.150 285.512 C 378.028 285.314,378.082 285.152,378.269 285.152 C 378.457 285.152,379.209 283.736,379.941 282.006 C 380.673 280.275,381.425 278.859,381.613 278.859 C 381.800 278.859,381.845 278.682,381.711 278.466 C 381.577 278.250,381.618 278.073,381.803 278.073 C 381.987 278.073,382.732 276.480,383.459 274.533 C 384.186 272.586,384.941 270.993,385.137 270.993 C 385.333 270.993,385.394 270.832,385.272 270.635 C 385.151 270.438,385.476 269.420,385.995 268.373 C 386.515 267.327,387.255 265.452,387.642 264.208 C 388.028 262.965,388.499 261.947,388.689 261.947 C 388.879 261.947,388.919 261.762,388.780 261.536 C 388.640 261.311,388.740 260.868,389.002 260.553 C 389.263 260.238,389.345 259.980,389.184 259.980 C 389.023 259.980,389.075 259.759,389.299 259.489 C 389.523 259.218,389.745 258.820,389.790 258.604 C 389.836 258.387,389.935 258.033,390.009 257.817 C 390.084 257.601,390.690 255.477,391.356 253.097 C 392.023 250.718,392.676 248.505,392.807 248.181 C 392.938 247.856,393.011 247.440,392.969 247.255 C 392.927 247.070,393.091 246.679,393.334 246.387 C 393.576 246.095,393.668 245.683,393.538 245.472 C 393.407 245.261,393.460 244.990,393.654 244.870 C 393.849 244.750,394.418 242.526,394.918 239.927 C 395.419 237.328,395.940 235.202,396.076 235.202 C 396.212 235.202,396.246 234.671,396.151 234.022 C 396.049 233.327,396.154 232.842,396.406 232.842 C 396.672 232.842,396.744 232.395,396.598 231.662 C 396.446 230.901,396.522 230.482,396.812 230.482 C 397.096 230.482,397.170 230.118,397.014 229.493 C 396.877 228.950,396.947 228.286,397.168 228.018 C 397.390 227.751,397.577 227.089,397.584 226.549 C 397.591 226.008,397.856 223.707,398.172 221.436 C 400.082 207.708,399.985 180.691,397.986 169.752 C 397.745 168.434,397.553 166.912,397.559 166.372 C 397.566 165.831,397.402 165.184,397.195 164.934 C 396.989 164.685,396.935 164.021,397.076 163.459 C 397.247 162.777,397.173 162.439,396.850 162.439 C 396.548 162.439,396.439 162.071,396.556 161.455 C 396.660 160.914,396.569 160.472,396.354 160.472 C 396.125 160.472,396.060 159.883,396.195 159.047 C 396.322 158.263,396.316 157.732,396.180 157.868 C 396.045 158.003,395.440 155.680,394.837 152.705 C 394.234 149.730,393.550 146.979,393.317 146.592 C 393.084 146.204,392.989 145.733,393.106 145.544 C 393.223 145.355,393.131 145.137,392.901 145.061 C 392.672 144.984,392.449 144.262,392.407 143.456 C 392.365 142.649,392.235 141.989,392.118 141.988 C 392.001 141.987,391.477 140.393,390.954 138.446 C 390.431 136.500,389.844 134.907,389.649 134.907 C 389.455 134.907,389.398 134.641,389.523 134.317 C 389.647 133.992,389.559 133.727,389.326 133.727 C 389.093 133.727,389.001 133.473,389.120 133.162 C 389.239 132.852,389.214 132.542,389.063 132.474 C 388.913 132.406,388.187 130.580,387.450 128.417 C 386.713 126.254,385.939 124.263,385.731 123.992 C 385.522 123.722,385.505 123.498,385.694 123.494 C 385.883 123.491,385.849 123.358,385.620 123.199 C 385.390 123.041,384.786 121.849,384.278 120.551 C 383.770 119.253,382.321 116.030,381.058 113.389 C 379.795 110.749,378.761 108.403,378.761 108.178 C 378.761 107.952,378.574 107.768,378.345 107.768 C 378.115 107.768,378.037 107.591,378.171 107.375 C 378.305 107.158,378.216 106.981,377.974 106.981 C 377.733 106.981,377.635 106.819,377.757 106.622 C 377.879 106.424,377.823 106.203,377.632 106.130 C 377.441 106.057,376.635 104.759,375.840 103.245 C 373.209 98.228,367.459 88.815,366.872 88.561 C 366.705 88.489,366.568 88.194,366.568 87.906 C 366.568 87.617,366.423 87.322,366.246 87.250 C 366.069 87.178,365.205 86.053,364.326 84.750 C 362.686 82.320,356.953 74.763,355.678 73.350 C 355.286 72.916,354.169 71.588,353.196 70.400 C 350.436 67.031,348.951 65.381,345.030 61.329 C 343.026 59.258,341.522 57.429,341.687 57.265 C 341.851 57.100,341.792 57.024,341.555 57.096 C 340.913 57.291,337.394 53.920,337.709 53.411 C 337.866 53.156,337.799 53.086,337.547 53.242 C 337.310 53.389,335.822 52.333,334.241 50.897 C 332.660 49.460,330.526 47.649,329.499 46.871 C 328.471 46.093,327.630 45.317,327.630 45.147 C 327.630 44.977,327.359 44.838,327.028 44.838 C 326.697 44.838,326.330 44.589,326.214 44.285 C 326.097 43.981,325.041 43.094,323.866 42.314 C 322.692 41.535,321.731 40.750,321.731 40.570 C 321.731 40.391,321.326 40.060,320.832 39.835 C 320.338 39.610,318.790 38.556,317.391 37.493 C 315.992 36.430,314.007 35.074,312.979 34.479 C 311.952 33.885,311.111 33.219,311.111 32.999 C 311.111 32.779,310.949 32.699,310.751 32.821 C 310.554 32.943,310.332 32.909,310.260 32.746 C 310.098 32.382,303.820 28.450,300.983 26.936 C 299.848 26.330,298.918 25.685,298.918 25.503 C 298.918 25.321,298.786 25.207,298.623 25.250 C 298.198 25.362,292.454 22.388,292.297 21.975 C 292.224 21.784,292.003 21.727,291.805 21.850 C 291.607 21.972,291.445 21.929,291.444 21.754 C 291.443 21.579,290.395 20.997,289.116 20.461 C 287.837 19.924,286.892 19.322,287.016 19.121 C 287.139 18.921,287.057 18.871,286.832 19.010 C 286.323 19.324,283.972 18.538,283.972 18.054 C 283.972 17.859,283.840 17.728,283.677 17.763 C 283.515 17.799,282.586 17.472,281.613 17.036 C 280.639 16.601,279.179 16.028,278.368 15.762 C 277.557 15.496,276.893 15.105,276.893 14.892 C 276.893 14.680,276.719 14.613,276.508 14.744 C 276.296 14.875,275.721 14.759,275.229 14.486 C 274.738 14.214,274.248 13.968,274.140 13.941 C 274.031 13.914,273.324 13.616,272.566 13.279 C 271.809 12.943,270.438 12.444,269.518 12.171 C 268.599 11.898,267.847 11.542,267.847 11.381 C 267.847 11.219,267.493 11.179,267.060 11.292 C 266.627 11.405,266.273 11.306,266.273 11.071 C 266.273 10.836,266.008 10.746,265.683 10.871 C 265.359 10.995,265.093 10.907,265.093 10.674 C 265.093 10.441,264.828 10.353,264.503 10.477 C 264.179 10.602,263.913 10.489,263.913 10.226 C 263.913 9.964,263.654 9.848,263.336 9.970 C 263.019 10.092,262.672 10.052,262.566 9.880 C 262.460 9.709,260.464 9.066,258.129 8.451 C 255.794 7.837,253.831 7.207,253.767 7.052 C 253.702 6.897,253.304 6.860,252.882 6.971 C 252.429 7.089,252.114 6.974,252.114 6.690 C 252.114 6.407,251.850 6.310,251.474 6.454 C 251.122 6.589,250.610 6.514,250.336 6.286 C 250.061 6.058,249.686 5.906,249.501 5.948 C 249.316 5.990,248.899 5.917,248.574 5.787 C 247.677 5.424,240.081 3.933,239.134 3.933 C 238.676 3.933,238.409 3.759,238.541 3.546 C 238.690 3.305,238.325 3.249,237.581 3.398 C 236.775 3.559,236.382 3.483,236.382 3.164 C 236.382 2.846,236.007 2.773,235.239 2.942 C 234.558 3.091,233.987 3.015,233.825 2.753 C 233.666 2.496,233.095 2.414,232.448 2.557 C 231.799 2.699,231.231 2.617,231.070 2.357 C 230.920 2.114,230.328 1.952,229.755 1.997 C 229.181 2.043,228.446 1.980,228.122 1.859 C 224.834 0.632,200.925 -0.230,188.201 0.421 M218.682 42.875 C 224.914 43.339,229.812 43.957,231.465 44.489 C 232.114 44.698,233.945 45.138,235.535 45.467 C 239.072 46.199,244.814 47.826,246.411 48.548 C 247.060 48.841,248.918 49.549,250.541 50.120 C 255.840 51.986,266.175 57.107,271.830 60.669 C 273.461 61.696,274.919 62.537,275.070 62.537 C 275.394 62.537,280.853 66.294,284.041 68.711 C 285.268 69.642,286.463 70.403,286.696 70.403 C 286.929 70.403,287.119 70.582,287.119 70.801 C 287.119 71.020,288.048 71.794,289.184 72.521 C 293.841 75.503,305.912 86.900,309.852 92.035 C 310.764 93.225,311.686 94.412,311.901 94.674 C 312.116 94.935,312.291 95.333,312.291 95.559 C 312.291 95.784,312.450 95.969,312.643 95.969 C 312.837 95.969,313.332 96.632,313.744 97.443 C 314.156 98.255,315.095 100.059,315.831 101.452 C 317.731 105.049,317.950 113.610,316.222 116.749 C 316.024 117.109,315.413 118.394,314.864 119.603 C 310.740 128.695,294.952 132.472,285.469 126.637 C 284.423 125.993,283.428 125.467,283.258 125.467 C 282.660 125.467,278.649 121.626,278.077 120.505 C 277.077 118.545,273.676 113.558,271.856 111.385 C 269.164 108.170,258.824 99.903,256.382 99.013 C 256.025 98.883,254.344 97.917,252.645 96.865 C 233.017 84.714,199.055 81.368,174.041 89.120 C 172.311 89.656,169.390 90.559,167.552 91.127 C 165.713 91.694,164.031 92.284,163.815 92.439 C 163.599 92.593,161.829 93.421,159.882 94.279 C 150.963 98.208,143.490 105.654,141.143 112.950 C 139.790 117.157,139.786 126.259,141.135 130.556 C 142.003 133.320,145.742 138.053,147.058 138.053 C 147.240 138.053,148.785 138.834,150.489 139.787 C 156.217 142.992,168.961 146.406,178.564 147.309 C 179.971 147.442,181.475 147.704,181.908 147.893 C 183.203 148.458,193.596 149.052,209.243 149.454 C 217.355 149.663,225.674 149.932,227.729 150.051 C 236.805 150.580,242.676 151.103,245.231 151.610 C 246.745 151.911,249.843 152.450,252.114 152.808 C 257.124 153.599,262.443 154.779,264.307 155.515 C 265.064 155.814,267.610 156.622,269.966 157.310 C 272.321 157.999,274.884 158.903,275.663 159.320 C 276.441 159.737,277.257 160.077,277.477 160.075 C 277.933 160.072,284.067 162.522,284.366 162.828 C 284.474 162.938,285.359 163.455,286.332 163.977 C 287.306 164.498,289.043 165.560,290.192 166.337 C 291.342 167.113,292.659 167.958,293.119 168.215 C 295.272 169.417,304.031 177.590,304.031 178.397 C 304.031 178.659,304.283 178.970,304.591 179.088 C 306.477 179.812,313.462 192.452,315.061 198.033 C 315.557 199.764,316.086 201.357,316.238 201.573 C 318.085 204.207,318.074 228.277,316.225 230.678 C 316.058 230.895,315.800 231.691,315.650 232.448 C 315.281 234.322,313.078 241.204,312.692 241.691 C 312.520 241.908,311.813 243.455,311.120 245.131 C 310.427 246.806,309.440 248.794,308.928 249.549 C 308.416 250.304,307.532 251.765,306.963 252.796 C 303.138 259.735,284.374 278.859,281.393 278.859 C 281.223 278.859,280.759 279.154,280.362 279.513 C 279.313 280.463,273.988 283.720,270.808 285.357 C 269.300 286.134,267.530 287.099,266.875 287.502 C 266.220 287.905,264.356 288.768,262.734 289.419 C 261.111 290.070,259.040 290.969,258.131 291.417 C 257.222 291.865,256.316 292.232,256.117 292.232 C 255.918 292.232,255.638 293.073,255.495 294.100 C 255.094 296.985,252.850 299.994,249.951 301.534 L 247.591 302.788 200.683 302.820 C 172.948 302.838,153.496 302.704,153.092 302.491 C 152.716 302.293,151.828 301.915,151.117 301.651 C 148.298 300.605,146.283 297.275,145.686 292.677 L 145.412 290.565 143.208 289.611 C 139.934 288.195,134.152 285.201,132.277 283.951 C 131.372 283.347,130.024 282.566,129.282 282.213 C 127.557 281.395,117.393 273.865,115.809 272.232 C 115.148 271.551,114.396 270.993,114.137 270.993 C 113.495 270.993,99.508 256.963,99.508 256.318 C 99.508 256.034,98.977 255.409,98.328 254.929 C 97.679 254.450,97.148 253.860,97.148 253.620 C 97.148 253.379,96.384 252.278,95.449 251.173 C 93.732 249.145,89.266 242.948,88.014 240.857 C 87.641 240.234,86.357 238.132,85.161 236.185 C 83.964 234.238,82.718 232.068,82.391 231.364 C 82.064 230.659,81.169 228.800,80.402 227.234 C 79.636 225.667,78.470 222.970,77.813 221.239 C 77.156 219.508,76.276 217.354,75.858 216.452 C 75.440 215.549,74.433 212.185,73.620 208.976 C 72.806 205.766,72.033 202.965,71.902 202.750 C 70.707 200.793,69.226 185.114,69.225 174.399 C 69.223 163.630,70.871 145.980,71.958 145.133 C 72.097 145.025,72.442 143.697,72.725 142.183 C 73.373 138.715,75.581 130.056,75.884 129.794 C 76.009 129.685,76.622 128.004,77.247 126.057 C 77.872 124.110,78.694 121.898,79.073 121.141 C 79.452 120.383,81.041 117.152,82.603 113.959 C 84.166 110.766,86.756 106.252,88.358 103.929 C 89.960 101.606,91.575 99.191,91.948 98.564 C 95.921 91.871,114.620 73.320,121.987 68.762 C 122.994 68.139,123.918 67.369,124.040 67.050 C 124.162 66.731,124.448 66.470,124.674 66.470 C 124.901 66.470,126.278 65.605,127.735 64.548 C 129.192 63.491,131.357 62.094,132.547 61.444 C 133.736 60.794,136.450 59.270,138.578 58.056 C 140.705 56.843,142.556 55.851,142.691 55.851 C 142.970 55.851,148.839 53.426,151.229 52.324 C 152.094 51.925,154.218 51.155,155.949 50.613 C 157.679 50.071,159.980 49.328,161.062 48.962 C 162.144 48.596,165.772 47.686,169.125 46.941 C 172.478 46.195,176.726 45.247,178.564 44.832 C 187.530 42.813,205.844 41.919,218.682 42.875 M112.127 158.644 C 110.939 162.358,110.697 177.745,111.708 185.251 C 112.458 190.818,115.318 203.165,116.298 205.058 C 116.629 205.700,117.225 207.125,117.623 208.225 C 118.020 209.326,118.606 210.940,118.925 211.813 C 119.559 213.547,122.776 219.258,124.668 222.007 C 125.324 222.960,125.860 223.854,125.860 223.992 C 125.860 224.130,127.053 225.771,128.512 227.639 C 135.059 236.024,145.323 244.545,154.472 249.193 C 155.933 249.936,157.306 250.675,157.522 250.837 C 157.738 250.999,158.977 251.606,160.275 252.187 C 161.573 252.769,163.786 253.762,165.192 254.395 C 166.598 255.027,169.607 256.110,171.878 256.799 C 174.149 257.489,176.663 258.305,177.464 258.613 C 189.252 263.141,219.453 263.148,230.482 258.625 C 231.239 258.315,233.628 257.502,235.792 256.819 C 251.106 251.983,266.854 240.556,274.921 228.424 C 281.680 218.261,279.922 206.384,270.814 200.682 C 269.939 200.134,269.135 199.557,269.027 199.399 C 268.614 198.798,260.856 194.779,258.604 193.999 C 250.836 191.309,248.866 190.897,234.415 188.942 C 230.413 188.401,225.988 187.800,224.582 187.608 C 223.176 187.415,214.503 187.248,205.310 187.237 C 196.116 187.225,186.205 187.040,183.284 186.826 C 173.756 186.126,163.599 184.815,161.849 184.058 C 161.416 183.871,160.000 183.519,158.702 183.276 C 155.478 182.672,148.565 180.887,148.083 180.534 C 147.866 180.376,146.362 179.791,144.739 179.233 C 139.580 177.460,138.720 177.091,134.984 175.054 C 132.972 173.956,131.158 173.058,130.953 173.058 C 130.748 173.058,130.580 172.889,130.580 172.683 C 130.580 172.477,129.978 172.023,129.243 171.674 C 127.667 170.926,120.333 164.840,115.750 160.478 L 112.522 157.406 112.127 158.644 M245.244 306.961 C 253.113 310.249,253.675 322.620,246.132 326.489 C 244.341 327.407,159.116 327.683,156.523 326.779 C 149.499 324.331,149.181 312.136,156.024 307.603 L 157.854 306.391 200.867 306.391 C 237.535 306.391,244.081 306.475,245.244 306.961 M238.902 332.290 C 240.180 333.092,241.419 334.090,241.655 334.509 C 241.891 334.928,242.526 335.985,243.066 336.858 C 244.342 338.921,244.460 343.639,243.284 345.526 C 241.222 348.835,240.431 349.792,238.725 351.044 L 236.866 352.409 231.412 352.419 L 225.959 352.429 225.248 353.972 C 220.338 364.625,200.029 368.942,186.234 362.265 C 182.722 360.565,177.033 355.580,176.428 353.672 C 176.161 352.832,175.972 352.802,170.942 352.802 C 164.236 352.802,161.642 351.614,159.357 347.493 C 158.394 345.758,158.436 338.178,159.418 336.361 C 160.392 334.560,163.005 332.027,164.198 331.727 C 164.745 331.590,165.192 331.320,165.192 331.127 C 165.192 330.924,180.224 330.788,200.885 330.804 L 236.578 330.832 238.902 332.290 \" stroke=\"none\" fill=\"#fcfbfb\" fill-rule=\"evenodd\"><\/path><path id=\"path2\" d=\"M203.048 42.771 C 204.941 42.843,208.038 42.843,209.931 42.771 C 211.824 42.699,210.275 42.640,206.490 42.640 C 202.704 42.640,201.155 42.699,203.048 42.771 M194.206 43.156 C 194.913 43.244,195.975 43.242,196.566 43.152 C 197.157 43.062,196.578 42.991,195.280 42.993 C 193.982 42.995,193.499 43.069,194.206 43.156 M216.421 43.153 C 217.016 43.243,217.989 43.243,218.584 43.153 C 219.179 43.063,218.692 42.989,217.502 42.989 C 216.313 42.989,215.826 43.063,216.421 43.153 M236.185 45.973 C 237.392 46.488,239.838 46.907,239.135 46.479 C 238.810 46.281,237.837 46.010,236.971 45.878 C 235.947 45.721,235.672 45.754,236.185 45.973 M171.288 46.429 C 170.740 46.678,170.978 46.713,172.075 46.546 C 172.940 46.414,173.722 46.242,173.812 46.162 C 174.150 45.864,172.043 46.087,171.288 46.429 M244.051 48.378 C 244.484 48.563,245.103 48.716,245.428 48.716 C 245.800 48.716,245.727 48.591,245.231 48.378 C 244.798 48.192,244.179 48.040,243.854 48.040 C 243.483 48.040,243.555 48.165,244.051 48.378 M246.608 49.098 C 246.932 49.298,247.640 49.581,248.181 49.725 C 248.864 49.908,248.984 49.877,248.574 49.624 C 248.250 49.423,247.542 49.141,247.001 48.996 C 246.318 48.814,246.198 48.845,246.608 49.098 M148.476 53.661 C 145.892 54.906,146.396 54.944,149.114 53.710 C 150.277 53.182,151.052 52.741,150.836 52.732 C 150.619 52.722,149.558 53.140,148.476 53.661 M257.227 53.491 C 257.984 53.905,258.781 54.244,258.997 54.244 C 259.213 54.244,258.771 53.905,258.014 53.491 C 257.257 53.076,256.460 52.737,256.244 52.737 C 256.028 52.737,256.470 53.076,257.227 53.491 M260.374 54.880 C 260.374 54.976,261.834 55.767,263.618 56.638 C 265.403 57.509,266.467 57.933,265.982 57.581 C 264.944 56.826,260.374 54.625,260.374 54.880 M140.708 57.057 C 139.897 57.486,139.233 57.924,139.233 58.031 C 139.233 58.206,142.340 56.755,142.740 56.392 C 143.193 55.983,142.011 56.369,140.708 57.057 M134.402 60.512 C 133.367 61.121,132.305 61.845,132.042 62.120 C 131.779 62.395,132.448 62.094,133.530 61.450 C 134.612 60.806,135.851 60.085,136.283 59.847 C 136.716 59.609,136.893 59.412,136.676 59.409 C 136.460 59.406,135.436 59.902,134.402 60.512 M274.533 62.653 C 274.533 62.742,275.772 63.639,277.286 64.646 C 278.800 65.652,280.039 66.393,280.039 66.291 C 280.039 66.189,279.022 65.422,277.778 64.587 C 275.023 62.736,274.533 62.444,274.533 62.653 M126.767 65.523 L 125.664 66.542 126.942 65.693 C 128.113 64.915,128.494 64.503,128.046 64.503 C 127.949 64.503,127.374 64.962,126.767 65.523 M120.810 69.834 C 118.429 71.685,116.247 73.494,115.960 73.855 C 115.673 74.216,116.765 73.446,118.387 72.145 C 120.010 70.844,122.266 69.108,123.402 68.288 C 125.281 66.931,125.763 66.470,125.302 66.470 C 125.212 66.470,123.190 67.984,120.810 69.834 M281.613 67.432 C 281.613 67.511,282.490 68.206,283.562 68.977 C 284.634 69.747,285.423 70.162,285.315 69.898 C 285.133 69.455,281.613 67.109,281.613 67.432 M286.579 71.105 C 287.040 71.476,289.419 73.370,291.866 75.313 C 299.930 81.714,308.266 90.268,312.091 96.067 C 313.717 98.533,314.235 99.006,313.275 97.150 C 310.580 91.938,288.529 70.302,286.029 70.416 C 285.871 70.423,286.119 70.733,286.579 71.105 M113.840 75.615 L 112.684 76.893 113.963 75.738 C 115.154 74.661,115.422 74.336,115.118 74.336 C 115.050 74.336,114.475 74.912,113.840 75.615 M110.521 78.466 C 109.566 79.440,108.873 80.236,108.981 80.236 C 109.089 80.236,109.959 79.440,110.914 78.466 C 111.870 77.493,112.563 76.696,112.455 76.696 C 112.347 76.696,111.477 77.493,110.521 78.466 M104.871 83.612 C 104.251 84.157,103.822 84.680,103.916 84.775 C 104.011 84.870,104.596 84.418,105.215 83.772 C 106.584 82.343,106.407 82.261,104.871 83.612 M198.530 84.841 C 199.019 84.935,199.727 84.931,200.103 84.833 C 200.479 84.734,200.079 84.657,199.213 84.662 C 198.348 84.666,198.040 84.747,198.530 84.841 M211.116 84.841 C 211.605 84.935,212.313 84.931,212.689 84.833 C 213.065 84.734,212.665 84.657,211.799 84.662 C 210.934 84.666,210.626 84.747,211.116 84.841 M181.121 86.922 C 180.061 87.192,180.041 87.223,180.924 87.230 C 181.465 87.234,182.350 87.096,182.891 86.922 C 184.213 86.499,182.785 86.499,181.121 86.922 M228.319 87.147 C 229.400 87.448,230.639 87.682,231.072 87.668 C 231.504 87.654,230.885 87.399,229.695 87.102 C 226.880 86.400,225.764 86.436,228.319 87.147 M100.295 88.692 C 99.340 89.666,98.646 90.462,98.755 90.462 C 98.863 90.462,99.733 89.666,100.688 88.692 C 101.644 87.719,102.337 86.922,102.229 86.922 C 102.121 86.922,101.250 87.719,100.295 88.692 M165.585 91.268 C 164.612 91.667,164.081 91.992,164.405 91.992 C 164.730 91.992,165.792 91.657,166.765 91.249 C 167.738 90.840,168.269 90.515,167.945 90.525 C 167.620 90.535,166.559 90.870,165.585 91.268 M240.708 90.669 C 240.708 90.898,241.961 91.406,243.461 91.785 C 244.002 91.922,243.736 91.693,242.871 91.277 C 241.201 90.474,240.708 90.335,240.708 90.669 M96.362 93.215 C 95.456 94.297,94.804 95.182,94.912 95.182 C 95.020 95.182,95.850 94.297,96.755 93.215 C 97.661 92.134,98.313 91.249,98.205 91.249 C 98.097 91.249,97.267 92.134,96.362 93.215 M157.758 94.613 C 157.022 94.933,156.519 95.293,156.639 95.414 C 156.866 95.640,159.292 94.520,159.292 94.189 C 159.292 93.945,159.310 93.939,157.758 94.613 M249.332 94.684 C 250.370 95.440,252.507 96.429,252.507 96.153 C 252.507 96.059,251.578 95.533,250.442 94.985 C 249.269 94.419,248.789 94.289,249.332 94.684 M93.754 96.460 C 92.278 98.139,89.502 102.262,89.848 102.262 C 89.954 102.262,90.779 101.155,91.684 99.803 C 92.588 98.451,93.687 96.947,94.127 96.460 C 94.566 95.973,94.837 95.575,94.729 95.575 C 94.621 95.575,94.182 95.973,93.754 96.460 M151.622 98.405 C 149.944 99.598,146.468 102.969,145.011 104.818 C 144.329 105.683,145.273 104.874,147.107 103.018 C 148.942 101.163,151.062 99.180,151.819 98.612 C 153.465 97.377,153.305 97.209,151.622 98.405 M255.261 98.033 C 256.121 98.853,261.294 102.009,261.000 101.534 C 260.863 101.312,259.383 100.307,257.711 99.300 C 256.039 98.293,254.936 97.723,255.261 98.033 M314.928 100.874 C 315.509 102.058,316.050 102.960,316.131 102.880 C 316.307 102.703,314.323 98.722,314.059 98.722 C 313.956 98.722,314.348 99.690,314.928 100.874 M262.734 102.778 C 262.734 102.875,263.383 103.450,264.177 104.056 C 264.972 104.662,265.497 104.957,265.345 104.711 C 265.034 104.208,262.734 102.505,262.734 102.778 M269.063 108.187 C 270.922 110.011,272.958 112.132,273.586 112.899 C 274.215 113.666,274.559 114.020,274.351 113.685 C 273.330 112.046,270.365 108.828,268.153 106.957 C 266.082 105.205,266.228 105.404,269.063 108.187 M85.183 109.231 C 84.409 110.468,83.776 111.662,83.777 111.885 C 83.778 112.109,84.151 111.672,84.605 110.914 C 85.060 110.157,85.782 108.963,86.209 108.260 C 86.637 107.557,86.897 106.981,86.788 106.981 C 86.679 106.981,85.957 107.993,85.183 109.231 M141.751 109.980 C 141.213 111.197,140.840 112.259,140.922 112.341 C 141.003 112.422,141.528 111.427,142.089 110.129 C 142.649 108.830,143.022 107.768,142.918 107.768 C 142.815 107.768,142.289 108.763,141.751 109.980 M80.764 117.823 C 80.213 119.026,79.831 120.080,79.914 120.164 C 79.998 120.247,80.533 119.263,81.102 117.975 C 81.671 116.688,82.053 115.634,81.951 115.634 C 81.849 115.634,81.315 116.619,80.764 117.823 M276.674 117.871 C 277.008 118.560,277.476 119.245,277.716 119.393 C 278.244 119.719,277.675 118.599,276.706 117.404 C 276.114 116.674,276.112 116.707,276.674 117.871 M314.642 118.965 C 314.097 120.126,313.790 120.990,313.960 120.885 C 314.430 120.594,315.894 117.589,315.756 117.198 C 315.689 117.009,315.188 117.804,314.642 118.965 M139.359 121.534 C 139.359 122.940,139.430 123.515,139.518 122.812 C 139.605 122.109,139.605 120.959,139.518 120.256 C 139.430 119.553,139.359 120.128,139.359 121.534 M278.794 121.007 C 279.993 122.750,284.772 126.647,285.710 126.647 C 285.921 126.647,285.292 126.139,284.312 125.518 C 283.333 124.896,281.498 123.348,280.235 122.076 C 278.897 120.729,278.296 120.283,278.794 121.007 M309.599 125.197 C 309.363 125.482,308.279 126.131,307.192 126.641 C 306.104 127.150,305.284 127.637,305.370 127.723 C 305.619 127.972,309.337 125.986,309.906 125.301 C 310.189 124.960,310.332 124.680,310.224 124.680 C 310.116 124.680,309.834 124.913,309.599 125.197 M77.380 125.736 C 77.280 125.913,77.093 126.588,76.964 127.237 C 76.730 128.411,76.732 128.410,77.322 127.093 C 77.837 125.945,77.883 124.846,77.380 125.736 M294.405 129.083 C 295.708 129.254,297.832 129.254,299.125 129.082 C 301.135 128.816,300.792 128.771,296.755 128.771 C 292.703 128.772,292.371 128.816,294.405 129.083 M75.741 130.805 C 75.596 131.381,75.554 131.929,75.647 132.021 C 75.739 132.114,75.933 131.718,76.078 131.142 C 76.223 130.566,76.265 130.018,76.173 129.925 C 76.080 129.833,75.886 130.228,75.741 130.805 M141.544 132.815 C 141.997 133.720,142.582 134.592,142.842 134.753 C 143.103 134.914,142.900 134.351,142.392 133.501 C 141.063 131.282,140.580 130.890,141.544 132.815 M145.100 137.027 C 145.407 137.399,146.027 137.899,146.477 138.139 C 147.222 138.536,147.246 138.514,146.738 137.899 C 146.432 137.528,145.812 137.027,145.362 136.787 C 144.617 136.390,144.593 136.412,145.100 137.027 M73.187 140.050 C 72.945 141.178,72.822 142.176,72.913 142.267 C 73.005 142.359,73.277 141.511,73.519 140.383 C 73.761 139.255,73.884 138.257,73.793 138.165 C 73.701 138.074,73.429 138.922,73.187 140.050 M148.673 139.489 C 148.673 139.751,154.612 142.471,154.792 142.291 C 154.872 142.211,153.528 141.505,151.805 140.722 C 150.082 139.940,148.673 139.385,148.673 139.489 M165.192 145.526 C 165.733 145.699,166.529 145.841,166.962 145.841 C 167.585 145.841,167.544 145.775,166.765 145.526 C 166.224 145.353,165.428 145.211,164.995 145.211 C 164.372 145.211,164.413 145.277,165.192 145.526 M184.169 148.550 C 184.548 148.649,185.167 148.649,185.546 148.550 C 185.924 148.451,185.615 148.371,184.857 148.371 C 184.100 148.371,183.791 148.451,184.169 148.550 M189.288 148.955 C 189.885 149.045,190.770 149.043,191.254 148.949 C 191.738 148.856,191.249 148.782,190.167 148.785 C 189.086 148.788,188.690 148.864,189.288 148.955 M197.050 149.465 C 201.916 149.771,213.413 149.945,213.143 149.709 C 213.053 149.630,208.378 149.479,202.753 149.373 C 196.750 149.260,194.395 149.298,197.050 149.465 M218.584 150.142 C 219.720 150.222,221.578 150.222,222.714 150.142 C 223.850 150.063,222.920 149.998,220.649 149.998 C 218.378 149.998,217.448 150.063,218.584 150.142 M248.771 152.606 C 249.420 152.771,250.482 152.907,251.131 152.907 C 252.123 152.908,252.060 152.857,250.737 152.583 C 248.745 152.171,247.135 152.190,248.771 152.606 M253.491 153.392 C 255.154 153.816,256.582 153.816,255.261 153.392 C 254.720 153.219,253.835 153.081,253.294 153.085 C 252.411 153.091,252.431 153.123,253.491 153.392 M266.667 156.735 C 267.424 157.027,268.309 157.266,268.633 157.266 C 268.958 157.266,268.604 157.027,267.847 156.735 C 267.089 156.444,266.205 156.205,265.880 156.205 C 265.556 156.205,265.910 156.444,266.667 156.735 M70.101 158.112 C 70.101 158.869,70.182 159.179,70.281 158.800 C 70.380 158.422,70.380 157.802,70.281 157.424 C 70.182 157.045,70.101 157.355,70.101 158.112 M114.095 158.800 C 114.334 159.179,114.999 159.826,115.574 160.239 C 116.401 160.834,116.337 160.691,115.262 159.551 C 113.771 157.968,113.433 157.751,114.095 158.800 M274.959 159.454 C 275.275 159.767,279.404 161.238,279.551 161.091 C 279.633 161.009,278.708 160.571,277.495 160.117 C 275.346 159.313,274.626 159.125,274.959 159.454 M69.480 163.119 C 69.342 164.583,69.254 167.198,69.284 168.928 C 69.326 171.323,69.417 170.717,69.664 166.394 C 70.006 160.410,69.906 158.616,69.480 163.119 M118.205 162.537 C 118.792 163.240,119.559 163.972,119.911 164.163 C 120.263 164.354,119.851 163.779,118.996 162.885 C 117.137 160.941,116.719 160.757,118.205 162.537 M283.612 162.971 C 284.138 163.418,287.512 165.233,287.512 165.070 C 287.512 164.829,284.144 162.832,283.739 162.832 C 283.579 162.832,283.522 162.894,283.612 162.971 M110.797 167.120 C 110.645 169.155,110.548 172.429,110.580 174.397 C 110.625 177.088,110.722 176.318,110.970 171.288 C 111.335 163.898,111.229 161.331,110.797 167.120 M123.107 166.495 C 123.107 166.603,123.992 167.433,125.074 168.338 C 126.155 169.244,127.040 169.896,127.040 169.788 C 127.040 169.680,126.155 168.851,125.074 167.945 C 123.992 167.039,123.107 166.387,123.107 166.495 M291.052 167.288 C 291.052 167.360,291.893 167.993,292.920 168.696 L 294.789 169.975 293.215 168.572 C 291.830 167.338,291.052 166.876,291.052 167.288 M128.195 170.720 C 129.317 171.671,133.769 174.327,133.946 174.150 C 134.012 174.083,132.530 173.102,130.652 171.968 C 128.774 170.835,127.668 170.273,128.195 170.720 M298.304 173.089 C 300.237 174.911,303.202 178.136,304.892 180.256 C 308.115 184.300,309.171 185.134,306.293 181.363 C 304.074 178.456,299.229 173.378,296.768 171.382 C 295.679 170.499,296.370 171.267,298.304 173.089 M134.513 174.433 C 134.513 174.696,139.281 177.074,139.457 176.898 C 139.536 176.819,138.456 176.190,137.057 175.500 C 135.658 174.810,134.513 174.330,134.513 174.433 M69.367 180.728 C 69.368 182.891,69.434 183.726,69.514 182.583 C 69.593 181.440,69.592 179.670,69.512 178.650 C 69.431 177.629,69.366 178.564,69.367 180.728 M111.044 180.728 C 111.045 182.242,111.116 182.813,111.201 181.997 C 111.287 181.181,111.285 179.942,111.198 179.244 C 111.111 178.546,111.042 179.213,111.044 180.728 M144.297 178.962 C 145.244 179.398,146.483 179.848,147.051 179.962 C 147.618 180.076,147.198 179.807,146.116 179.365 C 143.426 178.264,142.183 177.989,144.297 178.962 M156.342 182.705 C 157.207 182.990,158.269 183.221,158.702 183.219 C 159.135 183.216,158.604 182.968,157.522 182.667 C 155.061 181.982,154.230 182.009,156.342 182.705 M111.399 185.251 C 111.399 186.008,111.480 186.318,111.579 185.939 C 111.678 185.560,111.678 184.941,111.579 184.562 C 111.480 184.184,111.399 184.494,111.399 185.251 M69.729 186.627 C 69.732 187.709,69.808 188.105,69.899 187.507 C 69.989 186.909,69.987 186.024,69.893 185.540 C 69.800 185.057,69.726 185.546,69.729 186.627 M174.336 185.915 C 174.715 186.014,175.334 186.014,175.713 185.915 C 176.091 185.816,175.782 185.735,175.025 185.735 C 174.267 185.735,173.958 185.816,174.336 185.915 M179.154 186.436 C 181.161 186.762,185.908 186.941,185.611 186.680 C 185.521 186.601,183.589 186.442,181.318 186.327 C 178.533 186.186,177.828 186.222,179.154 186.436 M187.897 187.108 C 188.595 187.195,189.834 187.196,190.650 187.111 C 191.466 187.026,190.895 186.955,189.381 186.953 C 187.866 186.951,187.199 187.021,187.897 187.108 M210.718 187.117 C 212.502 187.189,215.423 187.189,217.207 187.117 C 218.992 187.044,217.532 186.984,213.963 186.984 C 210.393 186.984,208.933 187.044,210.718 187.117 M311.227 190.016 C 312.137 191.880,312.946 193.349,313.026 193.280 C 313.228 193.106,310.938 188.367,310.190 187.414 C 309.850 186.981,310.317 188.152,311.227 190.016 M223.500 187.488 C 223.879 187.587,224.499 187.587,224.877 187.488 C 225.256 187.389,224.946 187.309,224.189 187.309 C 223.432 187.309,223.122 187.389,223.500 187.488 M70.101 190.364 C 70.101 191.121,70.182 191.431,70.281 191.052 C 70.380 190.674,70.380 190.054,70.281 189.676 C 70.182 189.297,70.101 189.607,70.101 190.364 M244.838 190.364 C 245.487 190.529,246.460 190.664,247.001 190.664 C 247.878 190.664,247.857 190.632,246.804 190.364 C 246.155 190.199,245.182 190.064,244.641 190.064 C 243.764 190.064,243.785 190.096,244.838 190.364 M257.653 193.280 C 257.743 193.370,259.493 194.170,261.542 195.058 C 263.591 195.947,265.095 196.504,264.885 196.296 C 264.675 196.089,263.028 195.289,261.224 194.518 C 258.135 193.198,257.270 192.899,257.653 193.280 M314.121 196.264 C 314.570 198.035,315.489 200.199,315.226 198.863 C 315.102 198.238,314.748 197.176,314.437 196.504 C 314.012 195.583,313.934 195.524,314.121 196.264 M266.470 197.328 C 266.686 197.550,267.824 198.368,268.999 199.146 C 271.559 200.841,275.397 204.508,276.531 206.344 C 277.516 207.938,277.928 208.105,277.133 206.588 C 276.218 204.840,273.846 202.284,271.453 200.466 C 269.213 198.764,265.735 196.574,266.470 197.328 M114.694 201.573 C 115.018 203.019,115.243 203.333,115.235 202.327 C 115.232 201.912,115.049 201.308,114.830 200.983 C 114.538 200.552,114.502 200.712,114.694 201.573 M72.819 205.506 C 72.823 206.327,73.865 209.341,73.907 208.653 C 73.920 208.437,73.680 207.463,73.373 206.490 C 73.067 205.516,72.817 205.074,72.819 205.506 M117.742 210.029 C 118.040 211.134,120.467 216.341,120.615 216.193 C 120.696 216.112,120.047 214.559,119.173 212.743 C 118.298 210.926,117.655 209.705,117.742 210.029 M317.553 215.929 C 317.553 218.417,317.617 219.435,317.695 218.191 C 317.773 216.947,317.773 214.912,317.695 213.668 C 317.617 212.424,317.553 213.441,317.553 215.929 M76.911 218.781 C 77.058 219.267,77.340 219.839,77.538 220.050 C 77.736 220.261,77.698 219.863,77.455 219.165 C 76.957 217.736,76.497 217.412,76.911 218.781 M122.543 219.764 C 124.279 222.755,126.701 226.232,126.906 226.028 C 127.009 225.924,126.483 225.039,125.737 224.061 C 124.991 223.084,123.815 221.296,123.125 220.090 C 122.434 218.883,121.777 217.896,121.664 217.896 C 121.552 217.896,121.947 218.736,122.543 219.764 M78.691 222.812 C 78.691 223.029,78.944 223.648,79.253 224.189 C 79.562 224.730,79.815 224.995,79.815 224.779 C 79.815 224.562,79.562 223.943,79.253 223.402 C 78.944 222.861,78.691 222.596,78.691 222.812 M277.350 224.402 C 276.691 225.849,276.817 226.157,277.529 224.842 C 277.862 224.228,278.061 223.652,277.971 223.562 C 277.881 223.472,277.601 223.850,277.350 224.402 M79.843 225.537 C 79.843 225.986,82.999 232.193,83.458 232.645 C 83.809 232.991,80.379 225.819,79.994 225.402 C 79.911 225.311,79.843 225.372,79.843 225.537 M131.170 231.662 C 132.015 232.527,132.795 233.235,132.903 233.235 C 133.011 233.235,132.408 232.527,131.563 231.662 C 130.718 230.796,129.939 230.088,129.831 230.088 C 129.722 230.088,130.325 230.796,131.170 231.662 M272.250 232.547 C 269.860 235.548,263.739 241.506,260.669 243.819 C 258.271 245.625,257.524 246.499,259.685 244.970 C 264.292 241.711,275.779 230.088,274.393 230.088 C 274.291 230.088,273.327 231.195,272.250 232.547 M314.687 234.451 C 314.421 235.338,314.276 236.137,314.364 236.226 C 314.452 236.314,314.743 235.660,315.008 234.773 C 315.274 233.885,315.420 233.086,315.331 232.998 C 315.243 232.909,314.953 233.563,314.687 234.451 M84.366 234.415 C 84.701 235.064,85.064 235.595,85.173 235.595 C 85.281 235.595,85.095 235.064,84.759 234.415 C 84.424 233.766,84.060 233.235,83.952 233.235 C 83.844 233.235,84.030 233.766,84.366 234.415 M132.940 233.728 C 132.940 233.828,134.400 235.216,136.185 236.814 C 137.970 238.411,139.184 239.406,138.883 239.025 C 138.214 238.176,132.940 233.476,132.940 233.728 M87.300 239.382 C 87.792 240.276,88.621 241.515,89.144 242.136 C 89.666 242.756,89.376 242.125,88.499 240.732 C 86.619 237.745,86.040 237.094,87.300 239.382 M311.027 244.195 C 310.675 245.089,310.457 245.821,310.543 245.821 C 310.858 245.821,311.941 243.393,311.806 242.988 C 311.729 242.757,311.378 243.300,311.027 244.195 M145.133 243.995 C 145.133 244.200,149.293 246.930,151.607 248.245 C 154.014 249.612,153.098 248.896,148.756 246.017 C 145.658 243.962,145.133 243.669,145.133 243.995 M256.244 247.001 C 255.379 247.632,254.546 248.156,254.393 248.165 C 254.095 248.182,251.288 250.031,250.944 250.437 C 250.627 250.811,254.461 248.593,256.342 247.313 C 257.262 246.688,258.014 246.097,258.014 245.999 C 258.014 245.724,257.924 245.775,256.244 247.001 M158.112 251.721 C 159.735 252.565,161.239 253.255,161.455 253.255 C 161.672 253.255,160.521 252.565,158.899 251.721 C 157.276 250.877,155.772 250.186,155.556 250.186 C 155.339 250.186,156.490 250.877,158.112 251.721 M95.395 250.934 C 97.713 255.156,114.336 271.648,120.354 275.696 C 122.388 277.064,121.085 275.886,116.224 271.962 C 111.145 267.860,103.737 260.531,99.344 255.261 C 95.795 251.002,94.884 250.004,95.395 250.934 M246.608 252.507 C 244.553 253.567,243.007 254.443,243.174 254.454 C 243.592 254.482,250.541 250.972,250.541 250.734 C 250.541 250.466,250.745 250.374,246.608 252.507 M307.201 251.444 C 306.906 251.921,306.406 252.709,306.089 253.196 C 305.773 253.682,305.599 254.081,305.703 254.081 C 306.012 254.081,308.096 250.934,307.910 250.748 C 307.815 250.654,307.497 250.967,307.201 251.444 M163.618 254.277 C 164.159 254.586,164.779 254.839,164.995 254.839 C 165.211 254.839,164.946 254.586,164.405 254.277 C 163.864 253.968,163.245 253.715,163.029 253.715 C 162.812 253.715,163.078 253.968,163.618 254.277 M303.067 257.522 C 301.816 259.199,301.150 260.249,301.587 259.856 C 302.402 259.123,305.780 254.474,305.498 254.474 C 305.411 254.474,304.317 255.846,303.067 257.522 M167.552 255.737 C 167.660 255.843,168.364 256.138,169.116 256.393 C 169.868 256.647,170.311 256.686,170.099 256.479 C 169.888 256.272,169.184 255.977,168.535 255.823 C 167.886 255.669,167.443 255.630,167.552 255.737 M237.955 256.274 L 236.971 256.867 237.955 256.606 C 239.382 256.228,240.317 255.677,239.528 255.680 C 239.204 255.681,238.496 255.948,237.955 256.274 M231.858 258.407 C 231.363 258.620,231.290 258.745,231.662 258.745 C 231.986 258.745,232.606 258.593,233.038 258.407 C 233.534 258.194,233.607 258.069,233.235 258.069 C 232.911 258.069,232.291 258.221,231.858 258.407 M179.777 259.732 C 179.867 259.811,180.649 259.984,181.514 260.116 C 182.611 260.282,182.849 260.247,182.301 259.999 C 181.546 259.657,179.439 259.434,179.777 259.732 M224.975 260.177 C 224.002 260.459,223.471 260.704,223.795 260.721 C 224.120 260.738,225.270 260.506,226.352 260.205 C 227.434 259.904,227.965 259.659,227.532 259.661 C 227.099 259.663,225.949 259.895,224.975 260.177 M198.136 262.618 C 198.626 262.712,199.334 262.709,199.710 262.610 C 200.086 262.512,199.685 262.435,198.820 262.439 C 197.955 262.444,197.647 262.524,198.136 262.618 M208.756 262.618 C 209.245 262.712,209.953 262.709,210.329 262.610 C 210.705 262.512,210.305 262.435,209.440 262.439 C 208.574 262.444,208.267 262.524,208.756 262.618 M294.779 267.141 C 293.054 268.916,292.527 269.580,293.609 268.616 C 295.545 266.890,298.369 263.913,298.070 263.913 C 297.986 263.913,296.505 265.366,294.779 267.141 M289.651 271.878 L 288.496 273.156 289.774 272.001 C 290.477 271.366,291.052 270.791,291.052 270.723 C 291.052 270.419,290.728 270.687,289.651 271.878 M280.525 278.747 C 279.387 279.524,278.533 280.238,278.629 280.334 C 278.832 280.536,282.242 278.252,282.599 277.674 C 282.942 277.119,282.824 277.180,280.525 278.747 M123.500 277.838 C 123.500 277.946,124.297 278.583,125.270 279.253 C 126.244 279.922,127.040 280.382,127.040 280.274 C 127.040 280.166,126.244 279.529,125.270 278.859 C 124.297 278.190,123.500 277.730,123.500 277.838 M128.741 281.500 C 129.037 281.979,132.311 283.972,132.803 283.972 C 133.148 283.972,132.357 283.413,130.019 282.001 C 129.169 281.489,128.594 281.263,128.741 281.500 M272.468 283.804 C 270.998 284.602,271.087 284.934,272.566 284.169 C 273.215 283.834,273.746 283.475,273.746 283.372 C 273.746 283.119,273.704 283.134,272.468 283.804 M135.300 285.347 C 135.300 285.610,140.854 288.382,141.029 288.207 C 141.108 288.129,139.851 287.411,138.236 286.612 C 136.621 285.813,135.300 285.244,135.300 285.347 M267.060 286.726 C 265.438 287.570,264.218 288.269,264.351 288.279 C 264.837 288.319,269.763 285.945,270.004 285.555 C 270.340 285.012,270.404 284.987,267.060 286.726 M261.357 289.479 C 260.492 289.879,260.014 290.220,260.295 290.236 C 260.854 290.268,263.127 289.179,263.127 288.879 C 263.127 288.647,263.232 288.611,261.357 289.479 M144.227 289.762 C 145.156 290.225,145.526 290.708,145.639 291.605 L 145.793 292.822 145.856 291.554 C 145.916 290.359,144.499 289.014,143.284 289.111 C 143.111 289.125,143.536 289.418,144.227 289.762 M145.967 294.199 C 145.960 294.523,146.198 295.320,146.495 295.969 C 147.191 297.488,147.201 296.781,146.509 294.985 C 146.218 294.228,145.974 293.874,145.967 294.199 M254.081 296.885 C 254.081 297.137,253.423 298.096,252.620 299.016 C 251.234 300.603,251.225 300.628,252.457 299.508 C 253.884 298.211,254.664 297.010,254.309 296.656 C 254.183 296.530,254.081 296.633,254.081 296.885 M249.361 301.278 C 248.591 301.700,248.269 302.039,248.629 302.048 C 248.984 302.057,249.692 301.717,250.202 301.291 C 251.369 300.319,251.120 300.315,249.361 301.278 M154.671 302.351 C 155.482 302.436,156.809 302.436,157.620 302.351 C 158.432 302.267,157.768 302.197,156.146 302.197 C 154.523 302.197,153.859 302.267,154.671 302.351 M231.587 302.359 C 234.683 302.426,239.639 302.426,242.600 302.359 C 245.561 302.292,243.029 302.238,236.971 302.238 C 230.914 302.238,228.492 302.293,231.587 302.359 M179.843 306.686 C 191.470 306.744,210.497 306.744,222.124 306.686 C 233.751 306.628,224.238 306.581,200.983 306.581 C 177.729 306.581,168.215 306.628,179.843 306.686 M247.659 309.009 C 248.345 309.624,249.274 310.747,249.722 311.504 C 250.171 312.262,250.539 312.725,250.539 312.534 C 250.543 311.763,248.835 309.501,247.662 308.721 L 246.411 307.890 247.659 309.009 M154.103 309.046 C 152.905 310.441,152.914 310.880,154.118 309.759 C 154.801 309.124,155.359 308.549,155.359 308.481 C 155.359 308.114,154.616 308.449,154.103 309.046 M249.555 322.376 C 249.140 323.147,248.174 324.309,247.409 324.958 C 246.644 325.607,246.372 325.959,246.804 325.741 C 248.104 325.083,250.909 321.574,250.479 321.144 C 250.386 321.051,249.970 321.606,249.555 322.376 M152.606 322.870 C 152.606 323.562,155.506 326.451,156.198 326.448 C 156.493 326.446,156.205 326.098,155.556 325.673 C 154.907 325.248,153.977 324.325,153.491 323.622 C 153.004 322.918,152.606 322.580,152.606 322.870 M164.110 331.952 C 163.407 332.381,162.832 332.820,162.832 332.928 C 162.832 333.037,163.407 332.774,164.110 332.346 C 165.898 331.256,235.497 331.107,237.776 332.188 C 239.212 332.870,242.675 336.354,242.675 337.119 C 242.675 337.380,242.783 337.486,242.916 337.353 C 243.657 336.612,239.644 332.430,237.360 331.562 C 235.081 330.695,165.564 331.066,164.110 331.952 M243.574 341.200 C 243.577 342.281,243.653 342.677,243.743 342.079 C 243.834 341.481,243.831 340.596,243.738 340.113 C 243.645 339.629,243.571 340.118,243.574 341.200 M158.623 341.790 C 158.623 342.979,158.697 343.466,158.787 342.871 C 158.877 342.276,158.877 341.303,158.787 340.708 C 158.697 340.113,158.623 340.600,158.623 341.790 M159.294 346.345 C 159.295 346.787,160.780 349.263,161.043 349.263 C 161.147 349.263,160.852 348.599,160.388 347.788 C 159.347 345.971,159.292 345.897,159.294 346.345 M241.294 347.827 C 240.643 348.706,239.346 350.008,238.412 350.720 C 237.478 351.433,236.915 352.016,237.161 352.016 C 237.706 352.016,241.802 348.191,242.347 347.173 C 243.052 345.856,242.502 346.198,241.294 347.827 M163.170 351.206 C 163.681 351.651,164.286 352.016,164.514 352.016 C 164.998 352.016,164.975 351.996,163.422 351.087 L 162.242 350.396 163.170 351.206 M176.591 353.472 C 177.119 354.593,180.789 358.792,181.644 359.254 C 182.005 359.449,181.236 358.476,179.934 357.091 C 178.632 355.706,177.255 354.130,176.874 353.589 C 176.318 352.798,176.262 352.776,176.591 353.472 M222.374 357.012 C 221.541 358.030,221.064 358.735,221.315 358.580 C 221.850 358.249,224.341 355.162,224.073 355.162 C 223.972 355.162,223.208 355.995,222.374 357.012 M184.857 361.274 C 184.857 361.559,188.834 363.474,189.160 363.346 C 189.329 363.279,188.430 362.748,187.162 362.165 C 185.895 361.582,184.857 361.181,184.857 361.274 M215.536 362.045 C 214.562 362.566,214.011 363.001,214.310 363.011 C 214.847 363.028,217.502 361.544,217.502 361.227 C 217.502 360.993,217.494 360.997,215.536 362.045 M199.312 365.285 C 200.447 365.365,202.306 365.365,203.441 365.285 C 204.577 365.206,203.648 365.141,201.377 365.141 C 199.105 365.141,198.176 365.206,199.312 365.285 \" stroke=\"none\" fill=\"#fc7b8c\" fill-rule=\"evenodd\"><\/path><path id=\"path3\" d=\"M189.863 0.284 C 190.562 0.371,191.801 0.372,192.617 0.287 C 193.433 0.202,192.861 0.131,191.347 0.129 C 189.833 0.127,189.165 0.197,189.863 0.284 M207.169 0.284 C 207.867 0.371,209.106 0.372,209.922 0.287 C 210.738 0.202,210.167 0.131,208.653 0.129 C 207.139 0.127,206.471 0.197,207.169 0.284 M183.190 0.671 C 183.680 0.766,184.388 0.762,184.764 0.664 C 185.140 0.565,184.739 0.488,183.874 0.493 C 183.009 0.497,182.701 0.577,183.190 0.671 M215.442 0.671 C 215.931 0.766,216.639 0.762,217.015 0.664 C 217.391 0.565,216.991 0.488,216.126 0.493 C 215.261 0.497,214.953 0.577,215.442 0.671 M167.945 2.360 C 167.421 2.699,167.421 2.741,167.945 2.741 C 168.269 2.741,168.800 2.570,169.125 2.360 C 169.649 2.021,169.649 1.979,169.125 1.979 C 168.800 1.979,168.269 2.150,167.945 2.360 M231.072 2.360 C 231.205 2.576,231.580 2.753,231.905 2.753 C 232.229 2.753,232.385 2.576,232.252 2.360 C 232.118 2.144,231.743 1.967,231.419 1.967 C 231.094 1.967,230.938 2.144,231.072 2.360 M162.635 3.147 C 161.938 3.446,161.972 3.488,162.930 3.512 C 163.525 3.527,164.012 3.363,164.012 3.147 C 164.012 2.685,163.709 2.685,162.635 3.147 M236.382 3.147 C 236.382 3.363,236.780 3.537,237.266 3.534 C 237.982 3.529,238.039 3.455,237.561 3.147 C 236.799 2.654,236.382 2.654,236.382 3.147 M253.687 7.134 C 253.687 7.321,253.938 7.473,254.245 7.473 C 254.552 7.473,255.112 7.592,255.490 7.736 C 255.922 7.902,256.082 7.847,255.921 7.587 C 255.599 7.066,253.687 6.678,253.687 7.134 M132.842 10.772 C 132.247 10.988,131.760 11.326,131.760 11.524 C 131.760 11.722,132.042 11.775,132.387 11.643 C 132.731 11.511,133.439 11.296,133.960 11.165 C 134.946 10.918,135.271 10.349,134.415 10.368 C 134.145 10.374,133.437 10.556,132.842 10.772 M124.067 14.388 C 123.369 14.957,123.365 14.991,124.024 14.781 C 124.421 14.656,124.907 14.553,125.106 14.553 C 125.305 14.553,125.467 14.376,125.467 14.159 C 125.467 13.590,124.942 13.676,124.067 14.388 M275.100 14.368 C 275.520 14.686,276.051 14.940,276.280 14.933 C 276.509 14.927,276.353 14.661,275.933 14.343 C 275.513 14.026,274.982 13.772,274.753 13.778 C 274.524 13.785,274.680 14.051,275.100 14.368 M283.972 18.088 C 283.972 18.264,284.503 18.594,285.152 18.820 C 285.801 19.046,286.332 19.102,286.332 18.945 C 286.332 18.787,285.801 18.458,285.152 18.213 C 284.503 17.968,283.972 17.912,283.972 18.088 M114.356 18.390 C 113.977 18.475,113.668 18.707,113.668 18.908 C 113.668 19.369,114.094 19.364,114.836 18.894 C 115.543 18.448,115.290 18.183,114.356 18.390 M106.883 22.089 C 106.288 22.307,105.801 22.643,105.801 22.837 C 105.801 23.190,107.637 22.549,108.338 21.951 C 108.831 21.531,108.264 21.585,106.883 22.089 M292.232 21.971 C 292.232 22.148,292.675 22.494,293.215 22.741 C 293.756 22.987,294.199 23.044,294.199 22.867 C 294.199 22.690,293.756 22.344,293.215 22.097 C 292.675 21.851,292.232 21.794,292.232 21.971 M101.278 25.199 C 100.629 25.614,99.921 26.020,99.705 26.099 C 99.489 26.179,99.408 26.350,99.526 26.479 C 99.643 26.609,100.528 26.191,101.492 25.552 C 102.456 24.912,103.068 24.401,102.852 24.416 C 102.635 24.431,101.927 24.783,101.278 25.199 M299.312 25.979 C 300.354 26.689,302.065 27.558,302.065 27.377 C 302.065 27.124,299.478 25.564,299.069 25.571 C 298.878 25.575,298.987 25.758,299.312 25.979 M304.031 28.459 C 304.031 28.755,307.178 30.681,307.184 30.389 C 307.187 30.224,307.362 30.354,307.571 30.678 C 307.781 31.003,307.955 31.066,307.959 30.818 C 307.962 30.570,307.080 29.905,305.998 29.339 C 304.916 28.774,304.031 28.378,304.031 28.459 M93.684 29.484 C 92.969 29.884,92.544 30.310,92.741 30.431 C 92.937 30.553,93.690 30.216,94.413 29.682 C 95.950 28.548,95.552 28.440,93.684 29.484 M87.043 34.045 C 86.316 34.709,86.207 34.920,86.726 34.664 C 87.980 34.045,89.129 33.065,88.616 33.051 C 88.357 33.044,87.650 33.492,87.043 34.045 M311.701 33.670 C 313.206 34.830,314.115 35.101,312.957 34.045 C 312.350 33.492,311.643 33.044,311.384 33.051 C 311.126 33.058,311.268 33.336,311.701 33.670 M83.088 36.623 C 82.384 37.074,81.809 37.633,81.809 37.865 C 81.809 38.098,82.296 37.862,82.891 37.341 C 83.486 36.820,84.141 36.258,84.346 36.092 C 85.067 35.512,84.353 35.813,83.088 36.623 M316.618 36.890 C 317.375 37.542,318.082 37.989,318.190 37.884 C 318.402 37.678,317.291 36.767,316.028 36.113 C 315.595 35.889,315.860 36.238,316.618 36.890 M318.645 38.138 C 318.727 38.384,319.411 38.947,320.164 39.389 C 320.917 39.831,321.180 39.907,320.747 39.558 C 320.315 39.209,319.631 38.646,319.228 38.307 C 318.825 37.968,318.563 37.892,318.645 38.138 M78.128 40.339 C 77.077 41.083,76.458 41.685,76.752 41.676 C 77.046 41.668,77.994 41.052,78.859 40.306 C 80.848 38.592,80.580 38.604,78.128 40.339 M321.731 40.681 C 321.731 40.775,322.232 41.208,322.845 41.645 C 323.688 42.245,323.959 42.303,323.959 41.885 C 323.959 41.581,323.832 41.411,323.676 41.508 C 323.520 41.604,323.174 41.419,322.907 41.097 C 322.454 40.551,321.731 40.296,321.731 40.681 M74.533 43.265 C 73.716 43.913,72.902 44.444,72.723 44.444 C 72.544 44.444,72.190 44.833,71.936 45.307 C 71.572 45.987,71.829 45.882,73.145 44.816 C 74.065 44.071,75.195 43.155,75.658 42.782 C 76.121 42.408,76.391 42.098,76.259 42.093 C 76.126 42.088,75.350 42.616,74.533 43.265 M326.057 44.060 C 326.057 44.285,326.367 44.585,326.745 44.727 C 327.124 44.869,327.628 45.245,327.865 45.561 C 328.103 45.878,328.398 45.974,328.521 45.775 C 328.644 45.575,328.140 45.016,327.401 44.531 C 326.662 44.047,326.057 43.835,326.057 44.060 M180.138 44.458 C 179.503 44.669,179.921 44.706,181.318 44.562 C 182.507 44.439,183.555 44.273,183.645 44.195 C 183.960 43.919,181.112 44.132,180.138 44.458 M228.548 44.193 C 228.638 44.271,229.508 44.440,230.482 44.569 C 231.664 44.725,231.990 44.687,231.465 44.455 C 230.714 44.122,228.206 43.897,228.548 44.193 M331.563 48.574 C 332.071 49.115,332.664 49.558,332.880 49.558 C 333.097 49.558,332.858 49.115,332.350 48.574 C 331.842 48.033,331.249 47.591,331.033 47.591 C 330.817 47.591,331.055 48.033,331.563 48.574 M68.001 48.476 C 66.602 49.650,66.241 50.518,67.552 49.559 C 68.255 49.044,68.830 48.479,68.830 48.304 C 68.830 47.870,68.687 47.900,68.001 48.476 M63.738 52.126 C 63.208 52.647,62.863 53.161,62.970 53.268 C 63.161 53.460,65.290 51.664,65.290 51.312 C 65.290 50.897,64.639 51.238,63.738 52.126 M335.467 52.061 C 335.991 52.631,336.588 53.097,336.793 53.097 C 337.321 53.097,336.310 51.957,335.332 51.449 C 334.601 51.070,334.616 51.136,335.467 52.061 M338.643 54.794 C 338.643 54.861,339.218 55.437,339.921 56.072 L 341.200 57.227 340.044 55.949 C 338.968 54.757,338.643 54.490,338.643 54.794 M342.183 58.084 C 342.183 58.285,342.802 59.050,343.559 59.784 C 344.317 60.518,344.936 61.029,344.936 60.921 C 344.936 60.813,344.317 60.048,343.559 59.221 C 342.802 58.395,342.183 57.883,342.183 58.084 M268.437 58.808 C 268.869 59.160,269.577 59.622,270.010 59.834 L 270.796 60.220 270.010 59.580 C 269.577 59.228,268.869 58.766,268.437 58.553 L 267.650 58.167 268.437 58.808 M51.958 63.927 C 50.829 65.213,50.537 65.683,50.868 65.683 C 50.940 65.683,51.568 64.975,52.263 64.110 C 53.827 62.165,53.616 62.038,51.958 63.927 M274.959 62.664 C 275.049 62.734,275.742 63.191,276.500 63.680 L 277.876 64.568 276.696 63.555 C 276.047 62.997,275.354 62.540,275.156 62.539 C 274.957 62.538,274.869 62.594,274.959 62.664 M347.894 64.208 C 348.738 65.236,349.492 66.077,349.569 66.077 C 349.851 66.077,348.142 63.891,347.263 63.127 C 346.765 62.694,347.049 63.181,347.894 64.208 M350.442 67.055 C 350.767 67.486,351.455 68.282,351.973 68.825 L 352.913 69.813 352.089 68.598 C 351.636 67.930,350.948 67.134,350.559 66.828 C 349.900 66.310,349.892 66.326,350.442 67.055 M48.718 67.549 C 47.368 69.179,47.166 69.713,48.354 68.511 C 49.062 67.795,49.562 67.131,49.466 67.034 C 49.369 66.937,49.033 67.169,48.718 67.549 M119.174 70.830 L 117.404 72.434 119.272 70.978 C 120.910 69.701,121.396 69.220,121.042 69.224 C 120.988 69.225,120.147 69.947,119.174 70.830 M45.224 71.399 C 44.526 72.705,44.961 73.038,45.763 71.813 C 46.115 71.276,46.254 70.746,46.073 70.634 C 45.891 70.522,45.510 70.866,45.224 71.399 M354.006 71.508 C 354.534 72.174,355.105 72.729,355.274 72.741 C 355.845 72.781,354.760 71.213,353.899 70.752 C 353.087 70.317,353.092 70.353,354.006 71.508 M290.265 73.269 C 290.265 73.371,291.276 74.316,292.511 75.370 C 293.746 76.424,294.631 77.081,294.476 76.830 C 294.139 76.281,290.265 73.005,290.265 73.269 M41.832 76.008 C 40.751 77.360,39.555 78.997,39.175 79.646 C 38.496 80.806,38.497 80.809,39.203 79.852 C 39.598 79.316,40.376 78.343,40.931 77.689 C 42.409 75.948,44.171 73.550,43.972 73.550 C 43.877 73.550,42.914 74.656,41.832 76.008 M356.551 74.336 C 357.028 75.171,360.777 79.843,360.969 79.843 C 361.208 79.843,358.272 75.906,357.172 74.752 C 356.645 74.199,356.365 74.012,356.551 74.336 M296.165 78.466 C 296.899 79.223,297.588 79.843,297.696 79.843 C 297.804 79.843,297.292 79.223,296.559 78.466 C 295.825 77.709,295.136 77.089,295.028 77.089 C 294.919 77.089,295.431 77.709,296.165 78.466 M362.279 81.908 C 363.947 84.081,364.521 84.641,363.691 83.284 C 362.181 80.818,361.739 80.236,361.377 80.236 C 361.167 80.236,361.573 80.988,362.279 81.908 M37.014 82.142 C 35.850 83.778,35.980 84.079,37.217 82.609 C 37.785 81.935,38.158 81.291,38.047 81.180 C 37.935 81.069,37.471 81.502,37.014 82.142 M197.837 84.960 C 196.214 85.099,198.250 85.132,202.360 85.031 C 206.470 84.931,209.907 84.785,209.997 84.706 C 210.249 84.485,201.155 84.675,197.837 84.960 M210.456 85.098 C 210.546 85.176,212.566 85.331,214.946 85.443 C 217.709 85.573,218.633 85.532,217.502 85.330 C 215.733 85.014,210.146 84.830,210.456 85.098 M192.237 85.627 C 192.726 85.721,193.434 85.718,193.810 85.619 C 194.186 85.521,193.786 85.444,192.920 85.448 C 192.055 85.453,191.747 85.533,192.237 85.627 M34.156 86.431 C 32.920 87.905,32.031 89.567,32.879 88.817 C 33.614 88.167,35.202 85.742,34.891 85.742 C 34.805 85.742,34.474 86.052,34.156 86.431 M365.480 86.529 C 365.750 86.962,366.112 87.316,366.283 87.316 C 366.455 87.316,366.407 86.962,366.175 86.529 C 365.943 86.096,365.582 85.742,365.371 85.742 C 365.159 85.742,365.208 86.093,365.480 86.529 M172.075 89.465 C 170.524 90.175,170.874 90.187,173.058 89.499 C 174.031 89.192,174.474 88.938,174.041 88.933 C 173.609 88.928,172.724 89.167,172.075 89.465 M307.571 89.799 C 307.571 89.866,308.147 90.441,308.850 91.077 L 310.128 92.232 308.973 90.954 C 307.896 89.762,307.571 89.495,307.571 89.799 M29.537 93.314 C 28.690 94.901,28.687 94.936,29.476 94.002 C 30.613 92.658,31.167 91.642,30.765 91.642 C 30.581 91.642,30.028 92.394,29.537 93.314 M369.963 93.223 C 370.539 94.093,371.085 94.729,371.177 94.637 C 371.403 94.411,369.596 91.653,369.218 91.647 C 369.052 91.644,369.388 92.354,369.963 93.223 M244.674 92.575 C 245.079 92.937,247.394 94.002,247.394 93.826 C 247.394 93.599,245.214 92.429,244.792 92.429 C 244.637 92.429,244.584 92.495,244.674 92.575 M94.395 95.182 C 93.490 96.264,92.837 97.148,92.945 97.148 C 93.054 97.148,93.883 96.264,94.789 95.182 C 95.694 94.100,96.347 93.215,96.238 93.215 C 96.130 93.215,95.301 94.100,94.395 95.182 M252.507 96.774 C 253.872 97.700,254.649 97.970,253.687 97.184 C 253.147 96.741,252.527 96.378,252.311 96.377 C 252.094 96.375,252.183 96.554,252.507 96.774 M27.007 97.573 C 26.622 98.022,26.364 98.560,26.433 98.767 C 26.502 98.975,26.876 98.607,27.264 97.950 C 28.087 96.557,27.994 96.420,27.007 97.573 M373.438 99.090 C 374.309 100.774,374.962 100.995,374.172 99.339 C 373.804 98.567,373.354 97.935,373.172 97.935 C 372.990 97.935,373.110 98.455,373.438 99.090 M25.232 100.517 C 24.970 101.093,24.942 101.421,25.167 101.281 C 25.744 100.925,26.438 99.508,26.036 99.508 C 25.846 99.508,25.485 99.962,25.232 100.517 M148.068 101.967 L 146.116 104.031 148.181 102.080 C 149.317 101.006,150.246 100.077,150.246 100.015 C 150.246 99.721,149.881 100.048,148.068 101.967 M316.272 103.057 C 316.867 104.818,317.203 105.160,316.842 103.638 C 316.688 102.989,316.393 102.285,316.186 102.074 C 315.979 101.862,316.018 102.305,316.272 103.057 M376.866 105.211 C 377.112 105.752,377.459 106.195,377.636 106.195 C 377.813 106.195,377.756 105.752,377.510 105.211 C 377.263 104.671,376.917 104.228,376.740 104.228 C 376.563 104.228,376.620 104.671,376.866 105.211 M21.920 106.588 C 21.580 107.453,21.373 108.161,21.459 108.161 C 21.546 108.161,21.977 107.453,22.419 106.588 C 22.860 105.723,23.068 105.015,22.880 105.015 C 22.692 105.015,22.260 105.723,21.920 106.588 M86.567 106.415 C 86.113 107.185,85.920 107.705,86.138 107.570 C 86.564 107.307,87.841 105.015,87.561 105.015 C 87.469 105.015,87.022 105.645,86.567 106.415 M144.228 106.293 C 143.160 107.736,142.441 108.979,143.032 108.358 C 143.762 107.591,145.563 105.015,145.369 105.015 C 145.261 105.015,144.747 105.590,144.228 106.293 M270.010 109.341 C 271.075 110.423,272.035 111.308,272.143 111.308 C 272.252 111.308,271.468 110.423,270.403 109.341 C 269.338 108.260,268.378 107.375,268.269 107.375 C 268.161 107.375,268.944 108.260,270.010 109.341 M381.099 113.625 C 381.553 114.514,381.999 115.241,382.092 115.241 C 382.476 115.241,381.213 112.322,380.764 112.172 C 380.461 112.071,380.589 112.624,381.099 113.625 M18.213 114.061 C 17.968 114.710,17.912 115.241,18.088 115.241 C 18.264 115.241,18.594 114.710,18.820 114.061 C 19.046 113.412,19.102 112.881,18.945 112.881 C 18.787 112.881,18.458 113.412,18.213 114.061 M316.460 114.494 C 316.316 115.395,316.275 116.209,316.369 116.303 C 316.463 116.397,316.663 115.742,316.814 114.848 C 316.965 113.953,317.006 113.139,316.906 113.038 C 316.805 112.937,316.604 113.592,316.460 114.494 M139.872 116.863 C 139.549 118.479,139.607 125.869,139.949 126.729 C 140.096 127.098,140.216 124.753,140.216 121.517 C 140.216 115.043,140.222 115.116,139.872 116.863 M278.386 120.944 C 279.176 122.116,280.679 123.584,282.223 124.692 C 282.667 125.010,282.401 124.705,281.633 124.013 C 280.865 123.322,279.641 122.083,278.914 121.260 C 277.939 120.157,277.800 120.074,278.386 120.944 M14.945 121.339 C 14.716 121.941,14.435 122.585,14.321 122.771 C 14.206 122.956,14.283 123.107,14.491 123.107 C 14.908 123.107,15.848 120.731,15.549 120.432 C 15.446 120.329,15.174 120.737,14.945 121.339 M384.467 121.042 C 384.623 121.421,384.839 122.040,384.948 122.419 C 385.057 122.797,385.286 123.107,385.456 123.107 C 385.627 123.107,385.577 122.488,385.345 121.731 C 385.112 120.973,384.756 120.354,384.553 120.354 C 384.350 120.354,384.311 120.664,384.467 121.042 M78.727 121.747 C 78.068 123.194,78.193 123.502,78.906 122.187 C 79.239 121.573,79.437 120.997,79.347 120.908 C 79.257 120.818,78.978 121.196,78.727 121.747 M306.391 127.434 C 305.634 127.848,305.156 128.195,305.329 128.204 C 305.746 128.226,307.965 127.072,307.965 126.834 C 307.965 126.576,307.942 126.585,306.391 127.434 M388.498 131.563 C 388.601 132.104,388.836 132.547,389.021 132.547 C 389.205 132.547,389.254 132.812,389.129 133.137 C 389.005 133.461,389.083 133.727,389.304 133.727 C 389.719 133.727,389.707 133.476,389.203 131.662 C 388.827 130.310,388.243 130.229,388.498 131.563 M10.899 131.760 C 10.786 132.193,10.833 132.547,11.004 132.547 C 11.175 132.547,11.407 132.193,11.520 131.760 C 11.633 131.327,11.586 130.973,11.415 130.973 C 11.244 130.973,11.012 131.327,10.899 131.760 M148.673 139.016 C 148.673 139.124,149.204 139.487,149.853 139.823 C 150.501 140.159,151.032 140.345,151.032 140.237 C 151.032 140.128,150.501 139.765,149.853 139.430 C 149.204 139.094,148.673 138.908,148.673 139.016 M392.378 143.854 C 392.663 145.042,392.836 145.349,393.082 145.100 C 393.371 144.807,392.839 142.773,392.474 142.773 C 392.278 142.773,392.236 143.260,392.378 143.854 M176.111 147.377 C 176.600 147.472,177.308 147.468,177.684 147.370 C 178.060 147.271,177.660 147.194,176.794 147.198 C 175.929 147.203,175.622 147.283,176.111 147.377 M178.761 147.692 C 179.660 148.005,182.034 148.091,181.857 147.804 C 181.751 147.633,180.923 147.507,180.016 147.524 C 179.110 147.541,178.545 147.616,178.761 147.692 M236.676 150.917 C 237.163 151.010,237.960 151.010,238.446 150.917 C 238.933 150.823,238.535 150.746,237.561 150.746 C 236.588 150.746,236.190 150.823,236.676 150.917 M240.413 151.314 C 241.008 151.404,241.981 151.404,242.576 151.314 C 243.171 151.224,242.684 151.150,241.495 151.150 C 240.305 151.150,239.818 151.224,240.413 151.314 M261.357 154.966 C 261.790 155.151,262.498 155.298,262.930 155.292 C 263.563 155.283,263.524 155.219,262.734 154.966 C 261.389 154.535,260.355 154.535,261.357 154.966 M396.073 159.390 C 396.070 159.985,396.244 160.472,396.460 160.472 C 396.957 160.472,396.957 159.668,396.460 158.899 C 396.163 158.439,396.078 158.548,396.073 159.390 M396.466 161.554 C 396.463 162.040,396.637 162.439,396.853 162.439 C 397.346 162.439,397.346 162.021,396.853 161.259 C 396.545 160.782,396.471 160.838,396.466 161.554 M3.027 161.807 C 2.866 162.216,2.827 162.644,2.941 162.757 C 3.299 163.116,3.615 162.528,3.465 161.781 C 3.327 161.097,3.306 161.098,3.027 161.807 M2.643 164.142 C 2.205 165.257,2.276 165.826,2.790 165.312 C 3.027 165.076,3.154 164.553,3.073 164.152 C 2.932 163.448,2.917 163.447,2.643 164.142 M2.253 167.003 C 2.096 167.160,1.967 167.561,1.967 167.892 C 1.967 168.335,2.083 168.379,2.404 168.058 C 2.645 167.817,2.774 167.417,2.691 167.168 C 2.608 166.919,2.411 166.845,2.253 167.003 M293.553 168.642 C 293.864 169.145,296.165 170.848,296.165 170.575 C 296.165 170.478,295.515 169.903,294.721 169.297 C 293.927 168.691,293.402 168.396,293.553 168.642 M300.492 174.828 C 302.321 176.667,303.906 178.171,304.014 178.171 C 304.122 178.171,302.714 176.667,300.885 174.828 C 299.056 172.989,297.471 171.485,297.362 171.485 C 297.254 171.485,298.662 172.989,300.492 174.828 M138.227 176.773 C 138.647 177.109,139.266 177.370,139.603 177.353 C 140.133 177.327,140.136 177.293,139.626 177.104 C 139.302 176.983,138.682 176.722,138.250 176.523 C 137.476 176.167,137.475 176.171,138.227 176.773 M398.911 178.564 C 398.911 179.322,398.992 179.631,399.091 179.253 C 399.190 178.874,399.190 178.255,399.091 177.876 C 398.992 177.498,398.911 177.807,398.911 178.564 M0.878 178.958 C 0.878 179.715,0.959 180.025,1.058 179.646 C 1.157 179.267,1.157 178.648,1.058 178.269 C 0.959 177.891,0.878 178.201,0.878 178.958 M149.837 181.130 C 150.802 181.431,151.651 181.616,151.725 181.543 C 151.926 181.341,149.436 180.527,148.712 180.557 C 148.366 180.572,148.872 180.830,149.837 181.130 M399.320 184.071 C 399.320 185.044,399.397 185.442,399.491 184.956 C 399.585 184.469,399.585 183.673,399.491 183.186 C 399.397 182.699,399.320 183.097,399.320 184.071 M0.506 185.054 C 0.509 186.136,0.585 186.531,0.676 185.934 C 0.766 185.336,0.764 184.451,0.670 183.967 C 0.577 183.483,0.503 183.972,0.506 185.054 M165.388 184.857 C 167.052 185.281,168.480 185.281,167.158 184.857 C 166.618 184.684,165.733 184.546,165.192 184.550 C 164.309 184.556,164.329 184.588,165.388 184.857 M227.761 188.149 C 227.852 188.229,229.253 188.394,230.875 188.514 C 233.062 188.677,233.418 188.645,232.252 188.391 C 230.678 188.049,227.453 187.875,227.761 188.149 M112.180 189.381 C 112.184 189.813,112.323 190.698,112.488 191.347 C 112.757 192.407,112.789 192.427,112.795 191.544 C 112.799 191.003,112.661 190.118,112.488 189.577 C 112.241 188.807,112.174 188.764,112.180 189.381 M399.760 196.460 C 399.760 199.272,399.823 200.371,399.899 198.902 C 399.975 197.433,399.974 195.132,399.897 193.789 C 399.821 192.446,399.759 193.648,399.760 196.460 M254.065 192.536 C 255.030 192.837,255.880 193.022,255.953 192.949 C 256.154 192.748,253.664 191.933,252.940 191.963 C 252.594 191.978,253.100 192.236,254.065 192.536 M0.112 196.460 C 0.115 197.542,0.192 197.938,0.282 197.340 C 0.373 196.742,0.370 195.857,0.277 195.373 C 0.184 194.889,0.110 195.379,0.112 196.460 M269.420 199.823 C 270.784 200.749,271.561 201.018,270.600 200.232 C 270.059 199.789,269.440 199.426,269.223 199.425 C 269.007 199.423,269.095 199.602,269.420 199.823 M116.072 205.113 C 116.080 205.329,116.426 206.214,116.842 207.080 C 117.259 207.945,117.489 208.210,117.354 207.670 C 117.077 206.556,116.052 204.511,116.072 205.113 M0.506 207.866 C 0.509 208.948,0.585 209.344,0.676 208.746 C 0.766 208.148,0.764 207.263,0.670 206.779 C 0.577 206.296,0.503 206.785,0.506 207.866 M399.320 208.850 C 399.320 209.823,399.397 210.221,399.491 209.735 C 399.585 209.248,399.585 208.451,399.491 207.965 C 399.397 207.478,399.320 207.876,399.320 208.850 M279.056 215.733 C 279.056 218.029,279.171 219.500,279.312 219.001 C 279.453 218.501,279.568 217.030,279.568 215.733 C 279.568 214.435,279.453 212.964,279.312 212.464 C 279.171 211.965,279.056 213.436,279.056 215.733 M74.398 212.193 C 74.397 212.409,74.635 213.206,74.926 213.963 C 75.218 214.720,75.462 215.074,75.469 214.749 C 75.475 214.425,75.238 213.628,74.940 212.979 C 74.643 212.330,74.399 211.976,74.398 212.193 M0.878 213.963 C 0.878 214.720,0.959 215.029,1.058 214.651 C 1.157 214.272,1.157 213.653,1.058 213.274 C 0.959 212.896,0.878 213.206,0.878 213.963 M124.167 221.859 C 124.557 222.525,125.128 223.277,125.436 223.531 C 125.743 223.785,125.498 223.240,124.892 222.321 C 123.619 220.390,123.116 220.071,124.167 221.859 M1.967 225.126 C 1.967 225.450,2.144 225.825,2.360 225.959 C 2.576 226.092,2.753 225.936,2.753 225.612 C 2.753 225.287,2.576 224.912,2.360 224.779 C 2.144 224.645,1.967 224.801,1.967 225.126 M316.439 228.336 C 316.288 229.340,316.246 230.241,316.344 230.339 C 316.442 230.438,316.646 229.697,316.796 228.694 C 316.947 227.691,316.989 226.789,316.891 226.691 C 316.793 226.593,316.589 227.333,316.439 228.336 M2.366 227.804 C 2.377 228.791,3.134 229.605,3.140 228.637 C 3.144 228.163,2.970 227.666,2.753 227.532 C 2.537 227.398,2.363 227.521,2.366 227.804 M274.822 228.616 L 274.128 229.892 274.921 228.963 C 275.595 228.173,275.955 227.329,275.615 227.338 C 275.560 227.339,275.204 227.914,274.822 228.616 M397.140 227.966 C 396.983 228.124,396.859 228.622,396.865 229.072 C 396.876 229.829,396.909 229.838,397.287 229.189 C 397.727 228.433,397.614 227.492,397.140 227.966 M2.781 230.383 C 2.889 231.537,3.486 232.179,3.512 231.170 C 3.527 230.575,3.363 230.088,3.147 230.088 C 2.930 230.088,2.766 230.221,2.781 230.383 M396.466 231.367 C 396.471 232.082,396.545 232.139,396.853 231.662 C 397.346 230.899,397.346 230.482,396.853 230.482 C 396.637 230.482,396.463 230.880,396.466 231.367 M82.203 231.159 C 82.203 231.388,82.567 231.992,83.013 232.503 L 83.822 233.432 83.132 232.252 C 82.222 230.699,82.203 230.676,82.203 231.159 M270.772 233.892 C 270.166 234.686,269.871 235.212,270.117 235.060 C 270.620 234.749,272.323 232.448,272.050 232.448 C 271.953 232.448,271.378 233.098,270.772 233.892 M313.471 238.824 C 313.471 238.942,313.203 239.680,312.876 240.463 C 312.548 241.247,312.369 241.888,312.477 241.888 C 312.789 241.888,313.897 239.036,313.673 238.812 C 313.562 238.701,313.471 238.707,313.471 238.824 M262.119 242.380 L 260.964 243.658 262.242 242.503 C 262.945 241.867,263.520 241.292,263.520 241.224 C 263.520 240.920,263.196 241.188,262.119 242.380 M90.462 244.641 C 90.924 245.290,91.391 245.821,91.499 245.821 C 91.607 245.821,91.318 245.290,90.855 244.641 C 90.393 243.992,89.927 243.461,89.819 243.461 C 89.710 243.461,90.000 243.992,90.462 244.641 M148.279 245.571 C 148.279 245.679,148.810 246.146,149.459 246.608 C 150.108 247.070,150.639 247.359,150.639 247.251 C 150.639 247.143,150.108 246.676,149.459 246.214 C 148.810 245.752,148.279 245.463,148.279 245.571 M6.995 248.964 C 7.090 249.610,7.301 250.057,7.464 249.956 C 7.823 249.735,7.497 247.788,7.102 247.788 C 6.948 247.788,6.900 248.317,6.995 248.964 M392.768 248.223 C 392.673 248.524,392.404 249.373,392.168 250.108 C 391.651 251.725,391.651 251.721,392.102 251.721 C 392.469 251.721,393.391 248.127,393.098 247.835 C 393.011 247.747,392.862 247.922,392.768 248.223 M250.439 250.114 C 248.823 251.150,248.599 251.515,250.024 250.790 C 250.714 250.440,251.388 249.975,251.522 249.757 C 251.838 249.247,251.744 249.278,250.439 250.114 M304.818 255.654 C 304.356 256.303,304.066 256.834,304.175 256.834 C 304.283 256.834,304.749 256.303,305.211 255.654 C 305.674 255.005,305.963 254.474,305.855 254.474 C 305.747 254.474,305.280 255.005,304.818 255.654 M101.065 258.112 C 102.695 259.849,103.048 260.161,103.048 259.866 C 103.048 259.802,102.207 258.962,101.180 257.997 L 99.312 256.244 101.065 258.112 M10.917 261.357 C 11.020 261.898,11.280 262.340,11.494 262.340 C 11.708 262.340,11.776 262.060,11.645 261.718 C 11.514 261.376,11.406 260.933,11.406 260.735 C 11.406 260.536,11.254 260.374,11.067 260.374 C 10.881 260.374,10.813 260.816,10.917 261.357 M106.391 263.913 C 108.329 265.860,110.003 267.453,110.111 267.453 C 110.220 267.453,108.723 265.860,106.785 263.913 C 104.847 261.967,103.173 260.374,103.065 260.374 C 102.956 260.374,104.453 261.967,106.391 263.913 M192.429 261.825 C 192.807 261.924,193.427 261.924,193.805 261.825 C 194.184 261.726,193.874 261.645,193.117 261.645 C 192.360 261.645,192.050 261.726,192.429 261.825 M214.656 261.832 C 215.145 261.926,215.853 261.922,216.229 261.824 C 216.605 261.725,216.205 261.648,215.339 261.653 C 214.474 261.657,214.166 261.738,214.656 261.832 M197.837 262.346 C 201.353 262.671,208.310 262.836,208.030 262.588 C 207.940 262.508,204.857 262.352,201.180 262.240 C 196.621 262.102,195.557 262.136,197.837 262.346 M209.529 262.231 C 210.227 262.318,211.466 262.319,212.282 262.234 C 213.098 262.149,212.527 262.078,211.013 262.076 C 209.499 262.074,208.831 262.144,209.529 262.231 M112.078 269.125 C 113.708 270.861,114.061 271.174,114.061 270.878 C 114.061 270.815,113.220 269.975,112.193 269.010 L 110.324 267.257 112.078 269.125 M14.460 270.403 C 14.820 271.377,15.246 272.173,15.405 272.173 C 15.565 272.173,15.400 271.377,15.039 270.403 C 14.678 269.430,14.253 268.633,14.093 268.633 C 13.934 268.633,14.099 269.430,14.460 270.403 M385.447 269.420 C 385.196 269.890,385.079 270.362,385.187 270.471 C 385.295 270.579,385.589 270.283,385.841 269.813 C 386.092 269.343,386.209 268.871,386.101 268.763 C 385.993 268.654,385.699 268.950,385.447 269.420 M384.506 271.615 C 384.189 272.441,384.204 272.566,384.615 272.566 C 384.806 272.566,385.055 272.212,385.168 271.780 C 385.411 270.851,384.853 270.712,384.506 271.615 M284.562 276.346 L 282.989 277.754 284.661 276.504 C 286.099 275.428,286.618 274.909,286.234 274.932 C 286.180 274.935,285.428 275.572,284.562 276.346 M18.474 279.624 C 19.108 280.808,19.735 281.015,19.212 279.868 C 18.960 279.313,18.598 278.859,18.409 278.859 C 18.220 278.859,18.249 279.204,18.474 279.624 M380.787 280.039 C 380.560 280.688,380.504 281.219,380.662 281.219 C 380.820 281.219,381.149 280.688,381.394 280.039 C 381.639 279.390,381.695 278.859,381.519 278.859 C 381.342 278.859,381.013 279.390,380.787 280.039 M125.074 279.375 C 125.074 279.467,125.826 280.038,126.745 280.644 C 127.665 281.250,128.209 281.495,127.956 281.188 C 127.468 280.597,125.074 279.091,125.074 279.375 M20.452 283.298 C 20.452 283.860,21.392 285.546,21.704 285.546 C 21.891 285.546,21.739 285.059,21.367 284.464 C 20.483 283.052,20.452 283.012,20.452 283.298 M377.053 287.352 C 376.656 288.184,376.561 288.704,376.822 288.617 C 377.343 288.444,378.471 285.939,378.028 285.939 C 377.862 285.939,377.424 286.575,377.053 287.352 M265.093 288.102 C 264.553 288.411,264.287 288.664,264.503 288.664 C 264.720 288.664,265.339 288.411,265.880 288.102 C 266.421 287.793,266.686 287.540,266.470 287.540 C 266.254 287.540,265.634 287.793,265.093 288.102 M24.470 290.855 C 25.183 292.695,26.461 294.985,26.774 294.985 C 26.986 294.985,26.897 294.499,26.577 293.904 C 25.927 292.694,24.232 290.242,24.470 290.855 M257.227 291.417 C 255.642 292.057,255.452 292.271,255.406 293.460 C 255.356 294.752,255.359 294.755,255.525 293.566 C 255.667 292.546,255.955 292.259,257.268 291.825 C 258.132 291.540,258.930 291.161,259.040 290.983 C 259.291 290.576,259.341 290.564,257.227 291.417 M374.782 291.766 C 374.440 292.347,373.762 293.487,373.274 294.300 C 372.731 295.205,372.593 295.689,372.919 295.548 C 373.212 295.421,373.941 294.331,374.540 293.126 C 375.687 290.819,375.837 289.971,374.782 291.766 M28.712 298.281 C 28.712 298.762,30.482 301.269,30.825 301.273 C 31.014 301.276,31.001 301.057,30.797 300.787 C 30.593 300.516,30.040 299.784,29.569 299.160 C 29.098 298.536,28.712 298.141,28.712 298.281 M370.487 299.031 C 369.371 300.707,369.285 300.885,369.597 300.882 C 369.935 300.880,371.396 298.502,371.187 298.293 C 371.118 298.224,370.803 298.556,370.487 299.031 M153.335 302.558 C 153.498 302.721,174.861 302.810,200.808 302.755 L 247.984 302.655 200.511 302.458 C 174.401 302.350,153.172 302.395,153.335 302.558 M366.492 305.113 C 365.630 306.118,365.297 306.785,365.660 306.782 C 365.835 306.781,366.280 306.250,366.648 305.602 C 367.408 304.268,367.356 304.107,366.492 305.113 M33.432 305.814 C 33.432 306.145,33.696 306.518,34.019 306.642 C 34.343 306.766,34.492 307.053,34.352 307.280 C 34.204 307.520,34.285 307.576,34.546 307.415 C 34.870 307.215,34.820 306.868,34.365 306.174 C 33.633 305.057,33.432 304.979,33.432 305.814 M36.201 309.538 C 36.968 311.030,38.256 312.684,38.652 312.684 C 38.846 312.684,38.427 311.932,37.721 311.013 C 35.974 308.736,35.604 308.378,36.201 309.538 M362.520 310.914 C 361.916 311.672,361.543 312.291,361.690 312.291 C 361.982 312.291,362.806 311.320,363.442 310.226 C 364.068 309.151,363.719 309.411,362.520 310.914 M250.737 316.814 C 250.737 319.044,250.870 320.787,251.032 320.687 C 251.195 320.586,251.327 318.844,251.327 316.814 C 251.327 314.785,251.195 313.042,251.032 312.942 C 250.870 312.842,250.737 314.584,250.737 316.814 M359.956 314.242 C 359.483 314.882,359.095 315.536,359.095 315.695 C 359.095 315.854,359.538 315.384,360.079 314.651 C 360.619 313.918,361.062 313.264,361.062 313.198 C 361.062 312.877,360.742 313.178,359.956 314.242 M39.331 313.686 C 39.331 313.819,39.949 314.683,40.704 315.604 C 41.460 316.526,41.946 317.425,41.786 317.602 C 41.626 317.779,41.678 317.820,41.903 317.692 C 42.127 317.565,43.003 318.416,43.848 319.583 C 44.694 320.751,45.629 321.799,45.925 321.913 C 46.222 322.027,46.055 321.613,45.553 320.993 C 40.656 314.944,39.331 313.388,39.331 313.686 M357.840 316.912 C 356.856 318.058,356.637 318.597,357.252 318.361 C 357.558 318.244,358.006 317.715,358.247 317.186 C 358.765 316.049,358.648 315.971,357.840 316.912 M354.572 320.944 C 353.951 321.593,353.619 322.124,353.835 322.124 C 354.051 322.124,354.620 321.593,355.100 320.944 C 355.580 320.295,355.912 319.764,355.838 319.764 C 355.763 319.764,355.194 320.295,354.572 320.944 M48.378 324.694 C 48.378 325.174,49.647 326.794,50.186 327.001 C 50.525 327.131,50.332 326.653,49.722 325.854 C 48.718 324.537,48.378 324.243,48.378 324.694 M350.221 326.108 C 349.258 327.134,349.212 327.264,349.942 326.886 C 350.424 326.636,351.005 326.082,351.234 325.655 C 351.816 324.567,351.559 324.682,350.221 326.108 M182.989 331.072 C 192.886 331.130,209.081 331.130,218.977 331.072 C 228.874 331.013,220.777 330.965,200.983 330.965 C 181.190 330.965,173.092 331.013,182.989 331.072 M342.076 334.619 C 340.188 336.516,338.643 338.204,338.643 338.370 C 338.643 338.683,344.386 333.064,345.298 331.858 C 346.360 330.454,345.419 331.261,342.076 334.619 M55.457 332.581 C 55.457 332.708,56.410 333.725,57.575 334.842 C 61.172 338.292,61.699 338.567,58.614 335.383 C 55.660 332.337,55.457 332.156,55.457 332.581 M160.179 335.202 C 159.623 335.904,158.839 337.463,159.043 337.463 C 159.137 337.463,159.580 336.844,160.027 336.087 C 160.838 334.711,160.914 334.274,160.179 335.202 M243.916 340.610 C 243.878 341.367,243.762 342.694,243.660 343.559 L 243.473 345.133 243.877 343.559 C 244.098 342.694,244.214 341.367,244.133 340.610 L 243.987 339.233 243.916 340.610 M63.324 340.120 C 63.324 340.524,64.808 341.928,65.683 342.351 C 66.008 342.508,65.919 342.311,65.487 341.914 C 65.054 341.517,64.390 340.872,64.012 340.480 C 63.633 340.088,63.324 339.926,63.324 340.120 M334.907 341.504 C 334.132 342.283,333.998 342.549,334.518 342.277 C 335.434 341.797,336.971 340.192,336.442 340.267 C 336.247 340.295,335.556 340.852,334.907 341.504 M67.257 343.669 C 67.257 343.858,67.699 344.428,68.240 344.936 C 68.913 345.569,69.219 345.683,69.211 345.300 C 69.198 344.705,67.257 343.085,67.257 343.669 M331.170 344.739 C 330.662 345.280,330.423 345.723,330.640 345.723 C 330.856 345.723,331.449 345.280,331.957 344.739 C 332.465 344.199,332.703 343.756,332.487 343.756 C 332.271 343.756,331.678 344.199,331.170 344.739 M71.042 347.016 C 71.438 347.723,74.336 349.775,74.336 349.349 C 74.336 349.075,72.344 347.388,71.238 346.726 C 70.829 346.481,70.781 346.552,71.042 347.016 M159.489 347.689 C 159.824 348.338,160.187 348.869,160.296 348.869 C 160.404 348.869,160.218 348.338,159.882 347.689 C 159.546 347.040,159.183 346.509,159.075 346.509 C 158.967 346.509,159.153 347.040,159.489 347.689 M327.189 348.093 L 325.467 349.676 327.040 348.653 C 327.906 348.091,328.755 347.379,328.928 347.070 C 329.436 346.165,329.020 346.409,327.189 348.093 M323.682 350.812 C 322.726 351.625,322.554 351.909,323.107 351.768 C 323.540 351.658,324.212 351.137,324.600 350.612 C 325.521 349.366,325.338 349.406,323.682 350.812 M78.269 352.802 C 80.080 354.326,80.655 354.326,78.919 352.802 C 78.180 352.153,77.422 351.627,77.234 351.633 C 77.046 351.639,77.512 352.165,78.269 352.802 M165.143 352.519 C 165.313 352.688,167.827 352.776,170.730 352.714 L 176.008 352.603 170.422 352.408 C 167.349 352.300,164.974 352.350,165.143 352.519 M228.810 352.308 C 230.379 352.382,232.945 352.382,234.513 352.308 C 236.082 352.233,234.798 352.172,231.662 352.172 C 228.525 352.172,227.242 352.233,228.810 352.308 M320.551 353.277 C 319.794 353.929,319.528 354.268,319.961 354.032 C 321.149 353.383,322.284 352.438,322.095 352.255 C 322.003 352.166,321.308 352.626,320.551 353.277 M223.967 355.426 C 223.362 356.220,223.067 356.746,223.312 356.594 C 223.816 356.283,225.519 353.982,225.246 353.982 C 225.148 353.982,224.573 354.632,223.967 355.426 M316.924 355.854 C 315.902 356.639,315.132 357.347,315.212 357.427 C 315.436 357.652,318.519 355.421,318.749 354.867 C 319.013 354.231,319.082 354.194,316.924 355.854 M82.203 355.480 C 82.203 355.866,84.146 357.298,84.348 357.062 C 84.409 356.991,83.951 356.520,83.331 356.017 C 82.710 355.514,82.203 355.273,82.203 355.480 M86.499 358.651 C 87.239 359.325,87.947 359.775,88.071 359.651 C 88.308 359.414,87.286 358.546,85.939 357.838 C 85.506 357.610,85.758 357.976,86.499 358.651 M312.324 359.063 C 311.909 359.477,311.495 359.742,311.404 359.650 C 311.312 359.559,310.916 359.839,310.523 360.273 C 309.815 361.056,309.819 361.058,310.986 360.475 C 311.634 360.152,312.485 359.533,312.878 359.098 C 313.790 358.091,313.325 358.061,312.324 359.063 M219.272 360.137 C 218.088 361.196,217.999 361.342,218.914 360.731 C 220.001 360.004,221.369 358.679,220.992 358.717 C 220.912 358.725,220.138 359.364,219.272 360.137 M88.496 359.785 C 88.496 359.962,89.027 360.419,89.676 360.803 C 90.324 361.186,90.855 361.435,90.855 361.355 C 90.855 361.275,90.324 360.817,89.676 360.338 C 89.027 359.858,88.496 359.609,88.496 359.785 M93.215 362.952 C 93.215 363.244,94.120 363.813,95.765 364.554 C 95.977 364.650,95.885 364.462,95.560 364.137 C 94.728 363.305,93.215 362.540,93.215 362.952 M305.211 363.618 C 304.478 364.159,304.018 364.602,304.189 364.602 C 304.707 364.602,306.785 363.274,306.785 362.944 C 306.785 362.492,306.675 362.539,305.211 363.618 M211.013 364.023 C 210.147 364.308,209.794 364.547,210.226 364.554 C 210.659 364.561,211.544 364.323,212.193 364.026 C 213.679 363.345,213.073 363.344,211.013 364.023 M191.577 364.350 C 191.667 364.428,192.271 364.610,192.920 364.755 C 193.782 364.948,193.941 364.911,193.510 364.620 C 192.979 364.260,191.182 364.009,191.577 364.350 M99.115 366.480 C 99.115 366.659,99.956 367.198,100.983 367.679 C 102.143 368.222,102.553 368.315,102.065 367.924 C 100.879 366.976,99.115 366.112,99.115 366.480 M299.017 367.184 C 298.097 367.735,297.345 368.256,297.345 368.341 C 297.345 368.669,300.681 366.985,300.812 366.591 C 301.003 366.018,300.914 366.047,299.017 367.184 M105.872 370.206 C 106.595 370.891,109.452 372.179,109.145 371.682 C 108.899 371.285,106.065 369.715,105.592 369.715 C 105.460 369.715,105.586 369.936,105.872 370.206 M291.937 370.940 C 290.236 372.029,290.325 372.157,292.228 371.357 C 293.091 370.995,293.799 370.565,293.801 370.403 C 293.808 369.923,293.294 370.071,291.937 370.940 M285.152 374.238 C 284.582 374.564,284.417 374.801,284.759 374.801 C 285.084 374.802,285.693 374.543,286.113 374.225 C 287.084 373.491,286.445 373.499,285.152 374.238 M282.399 375.615 C 281.642 376.029,281.164 376.376,281.337 376.385 C 281.754 376.407,283.972 375.253,283.972 375.014 C 283.972 374.757,283.949 374.766,282.399 375.615 M123.500 378.342 C 123.500 378.522,123.810 378.758,124.189 378.867 C 124.567 378.976,125.216 379.204,125.630 379.373 C 126.129 379.578,126.295 379.539,126.122 379.260 C 125.785 378.714,123.500 377.914,123.500 378.342 M274.979 378.616 C 273.326 379.337,273.547 379.703,275.247 379.061 C 276.147 378.722,277.223 377.739,276.401 378.007 C 276.347 378.024,275.707 378.299,274.979 378.616 M132.547 381.820 C 132.547 382.034,132.989 382.294,133.530 382.397 C 134.071 382.501,134.513 382.433,134.513 382.246 C 134.513 382.060,134.351 381.908,134.152 381.908 C 133.953 381.908,133.511 381.800,133.169 381.669 C 132.827 381.538,132.547 381.605,132.547 381.820 M266.175 381.785 C 265.796 381.884,265.487 382.114,265.487 382.295 C 265.487 382.476,265.796 382.565,266.175 382.493 C 266.554 382.420,266.996 382.348,267.158 382.331 C 267.321 382.314,267.453 382.124,267.453 381.908 C 267.453 381.499,267.321 381.486,266.175 381.785 M238.741 389.381 C 238.262 389.690,238.313 389.763,239.013 389.768 C 239.487 389.771,239.984 389.597,240.118 389.381 C 240.427 388.880,239.516 388.880,238.741 389.381 M162.045 389.774 C 162.045 389.990,162.311 390.167,162.635 390.167 C 162.960 390.167,163.225 389.990,163.225 389.774 C 163.225 389.558,162.960 389.381,162.635 389.381 C 162.311 389.381,162.045 389.558,162.045 389.774 M236.775 389.774 C 236.775 389.990,237.040 390.167,237.365 390.167 C 237.689 390.167,237.955 389.990,237.955 389.774 C 237.955 389.558,237.689 389.381,237.365 389.381 C 237.040 389.381,236.775 389.558,236.775 389.774 M164.208 390.167 C 165.283 390.629,165.585 390.629,165.585 390.167 C 165.585 389.951,165.098 389.786,164.503 389.801 C 163.545 389.826,163.511 389.868,164.208 390.167 M234.612 390.167 C 234.324 390.632,234.709 390.632,235.792 390.167 C 236.550 389.841,236.547 389.828,235.716 389.801 C 235.242 389.786,234.745 389.951,234.612 390.167 M166.765 390.560 C 167.540 391.061,168.451 391.061,168.142 390.560 C 168.008 390.344,167.511 390.170,167.037 390.173 C 166.336 390.178,166.285 390.251,166.765 390.560 M231.858 390.560 C 231.549 391.061,232.460 391.061,233.235 390.560 C 233.715 390.251,233.664 390.178,232.963 390.173 C 232.489 390.170,231.992 390.344,231.858 390.560 M181.416 392.405 C 181.794 392.504,182.414 392.504,182.793 392.405 C 183.171 392.306,182.861 392.225,182.104 392.225 C 181.347 392.225,181.037 392.306,181.416 392.405 M187.321 392.809 C 187.919 392.900,188.804 392.897,189.288 392.804 C 189.771 392.711,189.282 392.637,188.201 392.640 C 187.119 392.642,186.723 392.719,187.321 392.809 M210.920 392.809 C 211.518 392.900,212.403 392.897,212.886 392.804 C 213.370 392.711,212.881 392.637,211.799 392.640 C 210.718 392.642,210.322 392.719,210.920 392.809 \" stroke=\"none\" fill=\"#fcb6c0\" fill-rule=\"evenodd\"><\/path><path id=\"path4\" d=\"M186.922 0.271 C 187.301 0.370,187.920 0.370,188.299 0.271 C 188.677 0.172,188.368 0.091,187.611 0.091 C 186.853 0.091,186.544 0.172,186.922 0.271 M211.701 0.271 C 212.080 0.370,212.699 0.370,213.078 0.271 C 213.456 0.172,213.147 0.091,212.389 0.091 C 211.632 0.091,211.323 0.172,211.701 0.271 M197.935 42.749 C 198.314 42.848,198.933 42.848,199.312 42.749 C 199.690 42.650,199.381 42.569,198.623 42.569 C 197.866 42.569,197.557 42.650,197.935 42.749 M213.668 42.749 C 214.046 42.848,214.666 42.848,215.044 42.749 C 215.423 42.650,215.113 42.569,214.356 42.569 C 213.599 42.569,213.289 42.650,213.668 42.749 M188.889 43.536 C 189.267 43.635,189.887 43.635,190.265 43.536 C 190.644 43.437,190.334 43.356,189.577 43.356 C 188.820 43.356,188.510 43.437,188.889 43.536 M222.321 43.536 C 222.699 43.635,223.319 43.635,223.697 43.536 C 224.076 43.437,223.766 43.356,223.009 43.356 C 222.252 43.356,221.942 43.437,222.321 43.536 M68.775 47.613 C 67.895 48.379,67.892 48.400,68.710 48.004 C 69.184 47.775,69.682 47.411,69.814 47.196 C 70.201 46.570,69.777 46.740,68.775 47.613 M333.498 50.094 C 334.021 50.739,335.497 51.714,335.497 51.415 C 335.497 51.340,334.921 50.858,334.218 50.343 C 333.427 49.764,333.153 49.669,333.498 50.094 M338.438 54.404 C 339.298 55.174,340.515 56.390,341.143 57.106 L 342.284 58.407 341.318 57.056 C 340.787 56.313,339.569 55.097,338.612 54.355 L 336.873 53.004 338.438 54.404 M56.932 58.596 C 55.039 60.528,53.491 62.221,53.491 62.358 C 53.491 62.612,58.590 57.547,59.943 55.949 C 61.502 54.107,60.252 55.206,56.932 58.596 M138.151 58.256 C 136.811 59.114,136.377 59.691,137.561 59.040 C 138.464 58.544,139.878 57.450,139.626 57.443 C 139.518 57.440,138.854 57.805,138.151 58.256 M345.297 61.500 C 345.821 62.145,347.296 63.120,347.296 62.821 C 347.296 62.746,346.721 62.264,346.018 61.749 C 345.227 61.170,344.952 61.075,345.297 61.500 M49.503 66.492 C 48.623 67.259,48.620 67.279,49.437 66.883 C 49.912 66.654,50.409 66.290,50.542 66.075 C 50.929 65.449,50.505 65.619,49.503 66.492 M108.948 79.646 C 107.336 81.268,106.106 82.596,106.214 82.596 C 106.323 82.596,107.730 81.268,109.341 79.646 C 110.953 78.024,112.183 76.696,112.075 76.696 C 111.967 76.696,110.559 78.024,108.948 79.646 M101.070 87.611 L 98.525 90.265 101.180 87.720 C 103.646 85.356,104.015 84.956,103.725 84.956 C 103.665 84.956,102.470 86.150,101.070 87.611 M317.146 108.751 C 317.147 110.482,317.216 111.141,317.299 110.216 C 317.382 109.291,317.381 107.875,317.297 107.069 C 317.212 106.264,317.144 107.021,317.146 108.751 M214.066 149.741 C 214.664 149.832,215.549 149.829,216.033 149.736 C 216.517 149.643,216.028 149.569,214.946 149.572 C 213.864 149.575,213.469 149.651,214.066 149.741 M225.275 150.131 C 225.764 150.225,226.472 150.221,226.848 150.123 C 227.224 150.024,226.824 149.947,225.959 149.952 C 225.093 149.956,224.786 150.037,225.275 150.131 M229.799 150.528 C 230.397 150.618,231.282 150.616,231.765 150.523 C 232.249 150.429,231.760 150.355,230.678 150.358 C 229.597 150.361,229.201 150.438,229.799 150.528 M70.655 151.902 C 70.522 152.397,70.429 153.156,70.448 153.589 C 70.467 154.022,70.644 153.685,70.842 152.841 C 71.226 151.207,71.062 150.384,70.655 151.902 M116.421 160.988 C 116.421 161.056,116.996 161.631,117.699 162.267 L 118.977 163.422 117.822 162.144 C 116.745 160.952,116.421 160.685,116.421 160.988 M122.321 166.101 C 122.321 166.169,122.896 166.744,123.599 167.380 L 124.877 168.535 123.722 167.257 C 122.645 166.065,122.321 165.798,122.321 166.101 M399.719 189.774 C 399.722 190.855,399.799 191.251,399.889 190.653 C 399.979 190.056,399.977 189.171,399.884 188.687 C 399.790 188.203,399.716 188.692,399.719 189.774 M0.132 191.937 C 0.132 193.559,0.202 194.223,0.287 193.412 C 0.371 192.601,0.371 191.273,0.287 190.462 C 0.202 189.651,0.132 190.315,0.132 191.937 M0.132 200.983 C 0.132 202.606,0.202 203.269,0.287 202.458 C 0.371 201.647,0.371 200.320,0.287 199.508 C 0.202 198.697,0.132 199.361,0.132 200.983 M399.719 203.147 C 399.722 204.228,399.799 204.624,399.889 204.026 C 399.979 203.428,399.977 202.543,399.884 202.059 C 399.790 201.576,399.716 202.065,399.719 203.147 M317.503 210.226 C 317.508 211.091,317.588 211.399,317.682 210.910 C 317.776 210.421,317.773 209.713,317.674 209.337 C 317.576 208.961,317.499 209.361,317.503 210.226 M317.495 221.436 C 317.495 222.193,317.576 222.502,317.675 222.124 C 317.774 221.745,317.774 221.126,317.675 220.747 C 317.576 220.369,317.495 220.678,317.495 221.436 M84.905 235.792 C 85.118 236.224,85.580 236.932,85.932 237.365 L 86.572 238.151 86.186 237.365 C 85.974 236.932,85.512 236.224,85.160 235.792 L 84.519 235.005 84.905 235.792 M298.132 263.913 C 296.789 265.428,295.779 266.667,295.888 266.667 C 295.996 266.667,297.183 265.428,298.525 263.913 C 299.868 262.399,300.877 261.160,300.769 261.160 C 300.661 261.160,299.474 262.399,298.132 263.913 M293.590 268.732 L 292.035 270.403 293.707 268.848 C 295.262 267.402,295.559 267.060,295.262 267.060 C 295.197 267.060,294.445 267.812,293.590 268.732 M290.244 271.681 L 288.889 273.156 290.364 271.801 C 291.175 271.055,291.839 270.392,291.839 270.326 C 291.839 270.026,291.506 270.309,290.244 271.681 M133.138 284.368 C 133.401 284.794,135.693 286.071,135.693 285.791 C 135.693 285.699,135.063 285.252,134.293 284.797 C 133.523 284.343,133.003 284.150,133.138 284.368 M368.606 302.262 C 368.360 302.802,368.223 303.245,368.301 303.245 C 368.380 303.245,368.734 302.802,369.089 302.262 C 369.443 301.721,369.580 301.278,369.394 301.278 C 369.207 301.278,368.853 301.721,368.606 302.262 M361.019 313.176 C 360.557 314.056,360.559 314.057,361.398 313.312 C 362.336 312.479,362.421 312.291,361.862 312.291 C 361.654 312.291,361.274 312.689,361.019 313.176 M151.154 316.814 C 151.157 318.112,151.230 318.596,151.317 317.889 C 151.405 317.182,151.403 316.120,151.313 315.529 C 151.224 314.938,151.152 315.516,151.154 316.814 M354.475 321.574 C 353.988 322.128,353.796 322.514,354.048 322.430 C 354.472 322.289,355.831 320.542,355.505 320.558 C 355.425 320.562,354.961 321.019,354.475 321.574 M352.333 323.992 C 351.640 324.799,351.121 325.664,351.329 325.664 C 351.409 325.664,351.867 325.133,352.347 324.484 C 353.295 323.202,353.286 322.883,352.333 323.992 M47.984 324.877 C 48.446 325.526,48.913 326.057,49.021 326.057 C 49.129 326.057,48.840 325.526,48.378 324.877 C 47.915 324.228,47.449 323.697,47.341 323.697 C 47.233 323.697,47.522 324.228,47.984 324.877 M157.268 326.944 C 157.431 327.107,177.201 327.195,201.201 327.140 L 244.838 327.040 200.905 326.844 C 176.741 326.735,157.105 326.781,157.268 326.944 M347.860 329.007 C 346.775 330.197,346.001 331.170,346.140 331.170 C 346.278 331.170,347.283 330.197,348.373 329.007 C 349.463 327.817,350.237 326.844,350.093 326.844 C 349.950 326.844,348.945 327.817,347.860 329.007 M51.524 328.723 C 51.524 328.854,52.498 329.889,53.687 331.024 C 54.877 332.158,55.851 332.986,55.851 332.864 C 55.851 332.742,54.877 331.707,53.687 330.563 C 52.498 329.420,51.524 328.592,51.524 328.723 M61.308 338.584 C 62.977 340.167,63.609 340.603,63.145 339.852 C 63.021 339.651,62.170 338.917,61.253 338.220 L 59.587 336.952 61.308 338.584 M337.620 339.135 C 335.897 341.122,335.385 341.790,335.585 341.790 C 335.701 341.790,336.448 340.993,337.245 340.020 C 338.723 338.217,339.015 337.525,337.620 339.135 M177.778 355.679 C 177.778 355.746,178.353 356.322,179.056 356.957 L 180.334 358.112 179.179 356.834 C 178.102 355.642,177.778 355.375,177.778 355.679 M196.342 393.213 C 198.224 393.285,201.410 393.285,203.422 393.214 C 205.434 393.142,203.894 393.083,200.000 393.083 C 196.106 393.082,194.460 393.141,196.342 393.213 \" stroke=\"none\" fill=\"#fcacb4\" fill-rule=\"evenodd\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\t\t\t\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"box-heading\">\n\t\t\t\t\t\t\t<a >\t\t\t\t\t\t\t\tDefining Training and Development Gaps\t\t\t\t\t\t\t<\/a>\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14d45ac4 elementor-section-height-min-height elementor-section-items-top elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default\" data-id=\"14d45ac4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68ab833a\" data-id=\"68ab833a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-de2379e elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"de2379e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-276b8088\" data-id=\"276b8088\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-421630eb elementor-widget elementor-widget-text-editor\" data-id=\"421630eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Digital Transformation<\/strong><br \/>starts with <strong>Cultural Transformation<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bfcd5bc elementor-widget elementor-widget-text-editor\" data-id=\"3bfcd5bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>The challenge of digital business transformation translates into HUMAN TALENT transformation.<\/p><p>Cultural transformation begins by creating high performance teams that practice assertive communication, leaders capable of taking on challenges of this new era, and generations that effectively come together.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3e5fad elementor-section-height-min-height elementor-section-items-top elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default\" data-id=\"d3e5fad\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64de2da\" data-id=\"64de2da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2bf3953 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2bf3953\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0491329\" data-id=\"0491329\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f20b65b elementor-widget elementor-widget-heading\" data-id=\"f20b65b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SCALINGSOFT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-182c2fd elementor-widget elementor-widget-heading\" data-id=\"182c2fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Happy Teams, Sustainable Growth<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f90df02 elementor-widget elementor-widget-text-editor\" data-id=\"f90df02\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tScale the sustainable growth and performance of your work teams through specialized software to design development plans and individual growth of employees, promote and maintain a strong and positive company culture, train and\nidentify potential leaders, and increase commitment\u00a0to\u00a0the\u00a0company.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb7d5ec elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb7d5ec\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74a4e70\" data-id=\"74a4e70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8149c4 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e8149c4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cfbd4fd\" data-id=\"cfbd4fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b3cd116\" data-id=\"b3cd116\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb0ea70 elementor-widget elementor-widget-heading\" data-id=\"fb0ea70\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HEADHUNTING & EXECUTIVE SEARCH<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf5ee5e elementor-widget elementor-widget-text-editor\" data-id=\"bf5ee5e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tWe believe talent makes a difference. We use top-level local and international databases to help you find the best talent.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf9329e elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf9329e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11bbccc\" data-id=\"11bbccc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c472d6 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6c472d6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-defecf4\" data-id=\"defecf4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c63879 elementor-widget elementor-widget-heading\" data-id=\"7c63879\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Executive Payroll Management<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30eda72 elementor-widget elementor-widget-text-editor\" data-id=\"30eda72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tWe offer comprehensive solutions for managing executive payroll, ensuring accuracy, legal compliance, and confidentiality. We take care of the details so you can focus on what matters most: your business.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37300cf\" data-id=\"37300cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2baa251b elementor-section-full_width elementor-section-height-min-height elementor-section-items-top elementor-reverse-mobile elementor-hidden-mobile elementor-section-height-default\" data-id=\"2baa251b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5349299e\" data-id=\"5349299e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e5c40a5 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"e5c40a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63c18f59\" data-id=\"63c18f59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-19e520bc\" data-id=\"19e520bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54aec84c elementor-widget elementor-widget-text-editor\" data-id=\"54aec84c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Outplacement \/ Professional Coaching<\/p><p style=\"text-align: center;\"><strong>Reinvent Your Career!<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5249286e elementor-widget elementor-widget-text-editor\" data-id=\"5249286e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Get ready to land your dream job:<\/strong><\/p><p style=\"text-align: center;\">Know yourself, update your CV, and train for an interview, unlocking your full potential to find new opportunities.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-516b080 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"516b080\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55b93749\" data-id=\"55b93749\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-350fc413 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"350fc413\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2711ebb1\" data-id=\"2711ebb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-153dfbf1 elementor-widget elementor-widget-heading\" data-id=\"153dfbf1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TALENT MANAGEMENT<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22ef2e8d elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"22ef2e8d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"112\" height=\"110\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/it-1w.png\" class=\"attachment-full size-full wp-image-7910\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Psychometric Assessments<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e1008fa elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"5e1008fa\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"112\" height=\"110\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/it-1w.png\" class=\"attachment-full size-full wp-image-7910\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">On-line Competency Assessments<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48bd0e8 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"48bd0e8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"112\" height=\"110\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/it-1w.png\" class=\"attachment-full size-full wp-image-7910\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Comparing Candidates<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-405f2391 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"405f2391\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"112\" height=\"110\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/it-1w.png\" class=\"attachment-full size-full wp-image-7910\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Designing ideal Recruitment Profiles<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d4c19b8 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"6d4c19b8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"112\" height=\"110\" src=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/it-1w.png\" class=\"attachment-full size-full wp-image-7910\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Defining Training and Development Gaps<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18efb359\" data-id=\"18efb359\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fbd20fa elementor-section-full_width elementor-section-height-min-height elementor-section-items-top elementor-reverse-mobile elementor-hidden-mobile elementor-section-height-default\" data-id=\"3fbd20fa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29e5c84e\" data-id=\"29e5c84e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5027817e elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"5027817e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1516ffed\" data-id=\"1516ffed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a05967a\" data-id=\"7a05967a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23d5b8ee elementor-widget elementor-widget-text-editor\" data-id=\"23d5b8ee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Digital Transformation <\/strong>starts with <strong>Cultural Transformation<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f15eabf elementor-widget elementor-widget-text-editor\" data-id=\"4f15eabf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>The challenge of digital business transformation translates into HUMAN TALENT transformation.<\/p><p>Cultural transformation begins by creating high performance teams that practice assertive communication, leaders capable of taking on challenges of this new era, and generations that effectively come together.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a61d252 elementor-section-height-min-height elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6a61d252\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45f37ac7\" data-id=\"45f37ac7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40325c8\" data-id=\"40325c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f2c8056 elementor-widget elementor-widget-heading\" data-id=\"3f2c8056\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact Us<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-812fd00 icon-box-vertical-align-center icon-vertical-align-center content-align-left icon-position-left elementor-widget elementor-widget-the7_icon_box_widget\" data-id=\"812fd00\" data-element_type=\"widget\" data-widget_type=\"the7_icon_box_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a class=\"the7-box-wrapper the7-elementor-widget box-hover the7_icon_box_widget-812fd00\" href=\"#\">\t\t\t<div class=\"box-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-div\">\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\" icomoon-the7-font-the7-mail-05\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"box-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tcarolinasanchez@ideastalento.com.gt\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/a>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a94cc17 icon-box-vertical-align-center icon-vertical-align-center content-align-left icon-position-left elementor-widget elementor-widget-the7_icon_box_widget\" data-id=\"4a94cc17\" data-element_type=\"widget\" data-widget_type=\"the7_icon_box_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a class=\"the7-box-wrapper the7-elementor-widget box-hover the7_icon_box_widget-4a94cc17\" href=\"#\">\t\t\t<div class=\"box-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-div\">\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\" icomoon-the7-font-the7-mail-05\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"box-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tcoaching@ideastalento.com.gt\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/a>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-563f915 icon-box-vertical-align-center icon-vertical-align-center content-align-left icon-position-left elementor-widget elementor-widget-the7_icon_box_widget\" data-id=\"563f915\" data-element_type=\"widget\" data-widget_type=\"the7_icon_box_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<a class=\"the7-box-wrapper the7-elementor-widget box-hover the7_icon_box_widget-563f915\" href=\"tel:+50257150677\">\t\t\t<div class=\"box-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-div\">\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t\t\t<div class=\"box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"box-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t+502 5715-0677\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/a>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>OUR SERVICES TALENT MANAGEMENT Executive Payroll Management CULTURAL TRANSFORMATION CHANGE MANAGEMENT EXPERIENCE DESIGN HEADHUNTING PSYCHOMETRIC ASSESSMENT ORGANIZATIONAL CLIMATE AND CULTURE ASSESSMENT PROFESSIONAL COACHING Scalingsoft HEADHUNTING &#038; EXECUTIVE SEARCH We believe talent makes a difference. We use top-level local and international databases to help you find the best talent. Executive Payroll Management: We offer comprehensive solutions&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OUR SERVICES - Ideas Talento<\/title>\n<meta name=\"description\" content=\"Head Hunting%Reclutamiento%Transformaci\u00f3n Cultural%Competencias Digitales%Gesti\u00f3n de Cambio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ideastalento.com\/en\/our-services\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OUR SERVICES - Ideas Talento\" \/>\n<meta property=\"og:description\" content=\"Head Hunting%Reclutamiento%Transformaci\u00f3n Cultural%Competencias Digitales%Gesti\u00f3n de Cambio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ideastalento.com\/en\/our-services\/\" \/>\n<meta property=\"og:site_name\" content=\"Ideas Talento\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/Ideastalento\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T18:23:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ideastalento.com\/en\/our-services\/\",\"url\":\"https:\/\/ideastalento.com\/en\/our-services\/\",\"name\":\"OUR SERVICES - Ideas Talento\",\"isPartOf\":{\"@id\":\"https:\/\/ideastalento.com\/en\/#website\"},\"datePublished\":\"2022-01-05T00:30:11+00:00\",\"dateModified\":\"2025-05-05T18:23:12+00:00\",\"description\":\"Head Hunting%Reclutamiento%Transformaci\u00f3n Cultural%Competencias Digitales%Gesti\u00f3n de Cambio\",\"breadcrumb\":{\"@id\":\"https:\/\/ideastalento.com\/en\/our-services\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ideastalento.com\/en\/our-services\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ideastalento.com\/en\/our-services\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ideastalento.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OUR SERVICES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ideastalento.com\/en\/#website\",\"url\":\"https:\/\/ideastalento.com\/en\/\",\"name\":\"Ideas Talento\",\"description\":\"Especialistas en desarrollo humano y transformaci\u00f3n digital\",\"publisher\":{\"@id\":\"https:\/\/ideastalento.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ideastalento.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ideastalento.com\/en\/#organization\",\"name\":\"IdeasTALENTO\",\"url\":\"https:\/\/ideastalento.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ideastalento.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ideastalento.com\/wp-content\/uploads\/job-manager-uploads\/company_logo\/2021\/10\/ISOTIPO-ROJO-1.png\",\"contentUrl\":\"https:\/\/ideastalento.com\/wp-content\/uploads\/job-manager-uploads\/company_logo\/2021\/10\/ISOTIPO-ROJO-1.png\",\"width\":913,\"height\":897,\"caption\":\"IdeasTALENTO\"},\"image\":{\"@id\":\"https:\/\/ideastalento.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/m.facebook.com\/Ideastalento\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OUR SERVICES - Ideas Talento","description":"Head Hunting%Reclutamiento%Transformaci\u00f3n Cultural%Competencias Digitales%Gesti\u00f3n de Cambio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ideastalento.com\/en\/our-services\/","og_locale":"en_US","og_type":"article","og_title":"OUR SERVICES - Ideas Talento","og_description":"Head Hunting%Reclutamiento%Transformaci\u00f3n Cultural%Competencias Digitales%Gesti\u00f3n de Cambio","og_url":"https:\/\/ideastalento.com\/en\/our-services\/","og_site_name":"Ideas Talento","article_publisher":"https:\/\/m.facebook.com\/Ideastalento\/","article_modified_time":"2025-05-05T18:23:12+00:00","og_image":[{"url":"https:\/\/ideastalento.com\/wp-content\/uploads\/2022\/01\/srv1.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ideastalento.com\/en\/our-services\/","url":"https:\/\/ideastalento.com\/en\/our-services\/","name":"OUR SERVICES - Ideas Talento","isPartOf":{"@id":"https:\/\/ideastalento.com\/en\/#website"},"datePublished":"2022-01-05T00:30:11+00:00","dateModified":"2025-05-05T18:23:12+00:00","description":"Head Hunting%Reclutamiento%Transformaci\u00f3n Cultural%Competencias Digitales%Gesti\u00f3n de Cambio","breadcrumb":{"@id":"https:\/\/ideastalento.com\/en\/our-services\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ideastalento.com\/en\/our-services\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ideastalento.com\/en\/our-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ideastalento.com\/en\/"},{"@type":"ListItem","position":2,"name":"OUR SERVICES"}]},{"@type":"WebSite","@id":"https:\/\/ideastalento.com\/en\/#website","url":"https:\/\/ideastalento.com\/en\/","name":"Ideas Talento","description":"Especialistas en desarrollo humano y transformaci\u00f3n digital","publisher":{"@id":"https:\/\/ideastalento.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ideastalento.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ideastalento.com\/en\/#organization","name":"IdeasTALENTO","url":"https:\/\/ideastalento.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ideastalento.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ideastalento.com\/wp-content\/uploads\/job-manager-uploads\/company_logo\/2021\/10\/ISOTIPO-ROJO-1.png","contentUrl":"https:\/\/ideastalento.com\/wp-content\/uploads\/job-manager-uploads\/company_logo\/2021\/10\/ISOTIPO-ROJO-1.png","width":913,"height":897,"caption":"IdeasTALENTO"},"image":{"@id":"https:\/\/ideastalento.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/Ideastalento\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/pages\/8112"}],"collection":[{"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/comments?post=8112"}],"version-history":[{"count":6,"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/pages\/8112\/revisions"}],"predecessor-version":[{"id":14293,"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/pages\/8112\/revisions\/14293"}],"wp:attachment":[{"href":"https:\/\/ideastalento.com\/en\/wp-json\/wp\/v2\/media?parent=8112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}